{"id":1070,"date":"2007-11-29T19:17:14","date_gmt":"2007-11-29T17:17:14","guid":{"rendered":"http:\/\/staging.sillon38.com\/2007\/11\/29\/producteurs-de-porc-la-confederation-paysanne-demande-plus\/"},"modified":"2007-11-29T19:17:14","modified_gmt":"2007-11-29T17:17:14","slug":"producteurs-de-porc-la-confederation-paysanne-demande-plus","status":"publish","type":"post","link":"https:\/\/www.sillon38.com\/blog\/2007\/11\/29\/producteurs-de-porc-la-confederation-paysanne-demande-plus\/","title":{"rendered":"Producteurs de porc: la conf\u00e9d\u00e9ration paysanne demande plus"},"content":{"rendered":"<p>La Conf\u00e9d\u00e9ration paysanne, qui a rencontr\u00e9 le ministre de l&rsquo;Agriculture, Michel Barnier, estime que \u00ab\u00a0pour les producteurs de porc, le compte n\u2019y est pas\u00a0\u00bb. Michel Barnier a confirm\u00e9 la mise en place des restitutions \u00e0 l\u2019exportation pour diminuer les volumes de viande de porc disponibles et s\u2019en est f\u00e9licit\u00e9.<br \/>\nMais cela ne suffit pas \u00e0 satisfaire la Conf\u00e9d\u00e9ration paysanne: \u00ab\u00a0Oui, la Politique Agricole Commune doit utiliser des outils de gestion des produits agricoles, oui, contrairement \u00e0 ce que Mme Fischer-Boel annon\u00e7ait la semaine derni\u00e8re, le march\u00e9 ne peut pas \u00eatre le seul r\u00e9gulateur des questions agricoles, non, cela ne solutionne pas le besoin de mettre en place une Organisation Commue de March\u00e9 porcine qui soit un outil permanent de r\u00e9gulation de la production, non, cet outil n\u2019est ni le bon ni suffisant. Les volumes export\u00e9s ne r\u00e8glent pas le probl\u00e8me de la surproduction, chronique aujourd\u2019hui\u00a0\u00bb.<\/p>\n<p>Le syndicat estime que cela ne r\u00e8gle pas le besoin urgent des producteurs. Que ceux-ci attendent une aide imm\u00e9diate de tr\u00e9sorerie, la participation des banques et des coop\u00e9ratives, la r\u00e9activation du m\u00e9canisme stabiporc.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Conf\u00e9d\u00e9ration paysanne, qui a rencontr\u00e9 le ministre de l&rsquo;Agriculture, Michel Barnier, estime que \u00ab\u00a0pour les producteurs de porc, le compte n\u2019y est pas\u00a0\u00bb. Michel Barnier a confirm\u00e9 la mise en place des restitutions \u00e0 l\u2019exportation pour diminuer les volumes&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[77],"tags":[],"class_list":["post-1070","post","type-post","status-publish","format-standard","hentry","category-syndicalisme-agricole"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Producteurs de porc: la conf\u00e9d\u00e9ration paysanne demande plus -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sillon38.com\/blog\/2007\/11\/29\/producteurs-de-porc-la-confederation-paysanne-demande-plus\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Producteurs de porc: la conf\u00e9d\u00e9ration paysanne demande plus -\" \/>\n<meta property=\"og:description\" content=\"La Conf\u00e9d\u00e9ration paysanne, qui a rencontr\u00e9 le ministre de l&rsquo;Agriculture, Michel Barnier, estime que \u00ab\u00a0pour les producteurs de porc, le compte n\u2019y est pas\u00a0\u00bb. Michel Barnier a confirm\u00e9 la mise en place des restitutions \u00e0 l\u2019exportation pour diminuer les volumes...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sillon38.com\/blog\/2007\/11\/29\/producteurs-de-porc-la-confederation-paysanne-demande-plus\/\" \/>\n<meta property=\"article:published_time\" content=\"2007-11-29T17:17:14+00:00\" \/>\n<meta name=\"author\" content=\"Gilbert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gilbert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2007\\\/11\\\/29\\\/producteurs-de-porc-la-confederation-paysanne-demande-plus\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2007\\\/11\\\/29\\\/producteurs-de-porc-la-confederation-paysanne-demande-plus\\\/\"},\"author\":{\"name\":\"Gilbert\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"headline\":\"Producteurs de porc: la conf\u00e9d\u00e9ration paysanne demande plus\",\"datePublished\":\"2007-11-29T17:17:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2007\\\/11\\\/29\\\/producteurs-de-porc-la-confederation-paysanne-demande-plus\\\/\"},\"wordCount\":209,\"commentCount\":0,\"articleSection\":[\"vie syndicale\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2007\\\/11\\\/29\\\/producteurs-de-porc-la-confederation-paysanne-demande-plus\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2007\\\/11\\\/29\\\/producteurs-de-porc-la-confederation-paysanne-demande-plus\\\/\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2007\\\/11\\\/29\\\/producteurs-de-porc-la-confederation-paysanne-demande-plus\\\/\",\"name\":\"Producteurs de porc: la conf\u00e9d\u00e9ration paysanne demande plus -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\"},\"datePublished\":\"2007-11-29T17:17:14+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2007\\\/11\\\/29\\\/producteurs-de-porc-la-confederation-paysanne-demande-plus\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2007\\\/11\\\/29\\\/producteurs-de-porc-la-confederation-paysanne-demande-plus\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2007\\\/11\\\/29\\\/producteurs-de-porc-la-confederation-paysanne-demande-plus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Producteurs de porc: la conf\u00e9d\u00e9ration paysanne demande plus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\",\"name\":\"\",\"description\":\"Le journal du monde rural\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\",\"name\":\"Gilbert\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Producteurs de porc: la conf\u00e9d\u00e9ration paysanne demande plus -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sillon38.com\/blog\/2007\/11\/29\/producteurs-de-porc-la-confederation-paysanne-demande-plus\/","og_locale":"fr_FR","og_type":"article","og_title":"Producteurs de porc: la conf\u00e9d\u00e9ration paysanne demande plus -","og_description":"La Conf\u00e9d\u00e9ration paysanne, qui a rencontr\u00e9 le ministre de l&rsquo;Agriculture, Michel Barnier, estime que \u00ab\u00a0pour les producteurs de porc, le compte n\u2019y est pas\u00a0\u00bb. Michel Barnier a confirm\u00e9 la mise en place des restitutions \u00e0 l\u2019exportation pour diminuer les volumes...","og_url":"https:\/\/www.sillon38.com\/blog\/2007\/11\/29\/producteurs-de-porc-la-confederation-paysanne-demande-plus\/","article_published_time":"2007-11-29T17:17:14+00:00","author":"Gilbert","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Gilbert","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sillon38.com\/blog\/2007\/11\/29\/producteurs-de-porc-la-confederation-paysanne-demande-plus\/#article","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/2007\/11\/29\/producteurs-de-porc-la-confederation-paysanne-demande-plus\/"},"author":{"name":"Gilbert","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"headline":"Producteurs de porc: la conf\u00e9d\u00e9ration paysanne demande plus","datePublished":"2007-11-29T17:17:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sillon38.com\/blog\/2007\/11\/29\/producteurs-de-porc-la-confederation-paysanne-demande-plus\/"},"wordCount":209,"commentCount":0,"articleSection":["vie syndicale"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.sillon38.com\/blog\/2007\/11\/29\/producteurs-de-porc-la-confederation-paysanne-demande-plus\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.sillon38.com\/blog\/2007\/11\/29\/producteurs-de-porc-la-confederation-paysanne-demande-plus\/","url":"https:\/\/www.sillon38.com\/blog\/2007\/11\/29\/producteurs-de-porc-la-confederation-paysanne-demande-plus\/","name":"Producteurs de porc: la conf\u00e9d\u00e9ration paysanne demande plus -","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/#website"},"datePublished":"2007-11-29T17:17:14+00:00","author":{"@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"breadcrumb":{"@id":"https:\/\/www.sillon38.com\/blog\/2007\/11\/29\/producteurs-de-porc-la-confederation-paysanne-demande-plus\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sillon38.com\/blog\/2007\/11\/29\/producteurs-de-porc-la-confederation-paysanne-demande-plus\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sillon38.com\/blog\/2007\/11\/29\/producteurs-de-porc-la-confederation-paysanne-demande-plus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.sillon38.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Producteurs de porc: la conf\u00e9d\u00e9ration paysanne demande plus"}]},{"@type":"WebSite","@id":"https:\/\/www.sillon38.com\/blog\/#website","url":"https:\/\/www.sillon38.com\/blog\/","name":"","description":"Le journal du monde rural","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sillon38.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1","name":"Gilbert"}]}},"_links":{"self":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/1070","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/comments?post=1070"}],"version-history":[{"count":0,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/1070\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/media?parent=1070"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/categories?post=1070"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/tags?post=1070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}