{"id":11705,"date":"2009-12-15T22:48:55","date_gmt":"2009-12-15T20:48:55","guid":{"rendered":"http:\/\/staging.sillon38.com\/?p=11705"},"modified":"2009-12-15T22:48:55","modified_gmt":"2009-12-15T20:48:55","slug":"chartreuse-le-depart-de-sylvain-ougier-fete-au-niveau-de-ses-competences","status":"publish","type":"post","link":"https:\/\/www.sillon38.com\/blog\/2009\/12\/15\/chartreuse-le-depart-de-sylvain-ougier-fete-au-niveau-de-ses-competences\/","title":{"rendered":"Chartreuse: le d\u00e9part de Sylvain Ougier"},"content":{"rendered":"<p><span style=\"color: #000000;\">Sylvain Ougier va donc quitter la Chartreuse apr\u00e8s avoir exerc\u00e9 son m\u00e9tier de technicien durant de nombreuses <img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-11706\" title=\"ougier\" src=\"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2009\/12\/ougier-300x300.jpg\" alt=\"ougier\" width=\"300\" height=\"300\" \/>ann\u00e9es. Cet homme tr\u00e8s appr\u00e9ci\u00e9 a r\u00e9ussi \u00e0 r\u00e9unir l&rsquo;ensemble de la fili\u00e8re pour f\u00eater son d\u00e9part. Cela se passait \u00e0 la salle des f\u00eates de Pommiers La Placette.<\/span><\/p>\n<p><span style=\"color: #000000;\">Beaucoup regretteront Sylvain \u00ab\u00a0qui a choisi de quitter la Chartreuse pour le Reblochon!\u00a0\u00bb. \u00a0 Salari\u00e9 au CRPF et au Parc naturel r\u00e9gional de Chartreuse, l&rsquo;ensemble des structures, organismes, personnes, qui ont travaill\u00e9 avec lui ont appr\u00e9ci\u00e9\u00a0 \u00ab\u00a0son \u00e9nergie durable mais \u00e9galement son sourire, sa disponibilit\u00e9, sons sens de la communication et surtout ses comp\u00e9tences professionnelles.\u00a0\u00bb <\/span><\/p>\n<p><span style=\"color: #000000;\">Son tableau de chasse est impressionnant: dessertes foresti\u00e8res, charte foresti\u00e8re, Asa, sans oublier bien s\u00fbr l&rsquo;AOC bois de Chartreuse&#8230;c&rsquo;est \u00e0 son initiative.<\/span><\/p>\n<p><span style=\"color: #000000;\">Sylvain Ougier a pr\u00e9cis\u00e9 qu&rsquo;il \u00e9tait habit\u00e9 par un double sentiment: \u00ab\u00a0la tristesse de laisser la Chartreuse, ses hommes et femmes. A leurs c\u00f4t\u00e9s\u00a0 j&rsquo;ai beaucoup appris et pris plaisir de travailler avec eux. Cependant\u00a0 un sentiment de joie m&rsquo;habite car je vais pouvoir pleinement profiter de ma vie de famille.\u00a0\u00bb\u00a0 Son \u00e9pouse exerce son m\u00e9tier d&rsquo;infirmi\u00e8re en Suisse. \u00ab\u00a0On m&rsquo;offre la possibilit\u00e9 de travailler en Haute-Savoie agr\u00e9ment\u00e9e d&rsquo;une promotion. Difficile de refuser&#8230;.\u00a0\u00bb<\/span><\/p>\n<p><span style=\"color: #000000;\">Pierre Basso, pr\u00e9sident du groupement des sylviculteurs de Chartreuse a \u00ab\u00a0pris beaucoup de plaisir \u00e0 travailler avec Sylvain. Sa disponibilit\u00e9 est l\u00e9gendaire. Il a toujours r\u00e9pondu pr\u00e9sent \u00e0 nos appels. Il a su rassembler la fili\u00e8re. Il a trait\u00e9 tous les dossiers dont il avait la charge avec beaucoup d&rsquo;efficacit\u00e9, de comp\u00e9tence et il ne faut pas oublier que la d\u00e9marche AOC, c&rsquo;est lui qui l&rsquo;a mise en place.\u00a0\u00bb<\/span><\/p>\n<p><span style=\"color: #000000;\">Il ne restait plus qu&rsquo;a boire le verre de l&rsquo;amiti\u00e9.. et souhaiter bonne chance \u00e0 Sylvain.<\/span><\/p>\n<p><span style=\"color: #000000;\"> <\/span><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-11707\" title=\"ougier 2\" src=\"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2009\/12\/ougier-2.jpg\" alt=\"ougier 2\" width=\"594\" height=\"441\" \/><\/span><\/p>\n<p><em><span style=\"color: #000000;\">Impossible de citer l&rsquo;ensemble des personnes pr\u00e9sentes autour d&rsquo;Eliane Giraud\u00a0 pour ce \u00ab\u00a0pot de d\u00e9part\u00a0\u00bb. On reconnait ici deux ex pr\u00e9sidents du groupement des sylviculteurs de Chartreuse: Maurice Luquain ( \u00e0 gauche) et Claude Michel Mazan que l&rsquo;on retrouve toujours avec beaucoup de plaisir. On retiendra \u00e9galement la pr\u00e9sence de Henri Gras, nouveau pr\u00e9sident de l&rsquo;UGDFI.<br \/>\n<\/span><\/em><\/p>\n<p><span style=\"color: #000000;\"><br \/>\n<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sylvain Ougier, technicien forestier du massif de la Chartreuse a d\u00e9cid\u00e9, pour des raisons personnelles de quitter le massif pour rejoindre la Haute-Savoie.  Son d\u00e9part a \u00e9t\u00e9 dignement f\u00eat\u00e9!<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30],"tags":[461,1181,2024],"class_list":["post-11705","post","type-post","status-publish","format-standard","hentry","category-foret-de-chartreuse","tag-aoc-bois-de-chartreuse","tag-chartreuse","tag-eliane-giraud"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chartreuse: le d\u00e9part de Sylvain Ougier -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sillon38.com\/blog\/2009\/12\/15\/chartreuse-le-depart-de-sylvain-ougier-fete-au-niveau-de-ses-competences\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chartreuse: le d\u00e9part de Sylvain Ougier -\" \/>\n<meta property=\"og:description\" content=\"Sylvain Ougier, technicien forestier du massif de la Chartreuse a d\u00e9cid\u00e9, pour des raisons personnelles de quitter le massif pour rejoindre la Haute-Savoie. Son d\u00e9part a \u00e9t\u00e9 dignement f\u00eat\u00e9!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sillon38.com\/blog\/2009\/12\/15\/chartreuse-le-depart-de-sylvain-ougier-fete-au-niveau-de-ses-competences\/\" \/>\n<meta property=\"article:published_time\" content=\"2009-12-15T20:48:55+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2009\/12\/ougier-300x300.jpg\" \/>\n<meta name=\"author\" content=\"Gilbert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gilbert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/12\\\/15\\\/chartreuse-le-depart-de-sylvain-ougier-fete-au-niveau-de-ses-competences\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/12\\\/15\\\/chartreuse-le-depart-de-sylvain-ougier-fete-au-niveau-de-ses-competences\\\/\"},\"author\":{\"name\":\"Gilbert\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"headline\":\"Chartreuse: le d\u00e9part de Sylvain Ougier\",\"datePublished\":\"2009-12-15T20:48:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/12\\\/15\\\/chartreuse-le-depart-de-sylvain-ougier-fete-au-niveau-de-ses-competences\\\/\"},\"wordCount\":391,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/12\\\/15\\\/chartreuse-le-depart-de-sylvain-ougier-fete-au-niveau-de-ses-competences\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/staging.sillon38.com\\\/wp-content\\\/uploads\\\/2009\\\/12\\\/ougier-300x300.jpg\",\"keywords\":[\"AOC Bois de Chartreuse\",\"Chartreuse\",\"Eliane Giraud\"],\"articleSection\":[\"For\u00eat de Chartreuse\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/12\\\/15\\\/chartreuse-le-depart-de-sylvain-ougier-fete-au-niveau-de-ses-competences\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/12\\\/15\\\/chartreuse-le-depart-de-sylvain-ougier-fete-au-niveau-de-ses-competences\\\/\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/12\\\/15\\\/chartreuse-le-depart-de-sylvain-ougier-fete-au-niveau-de-ses-competences\\\/\",\"name\":\"Chartreuse: le d\u00e9part de Sylvain Ougier -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/12\\\/15\\\/chartreuse-le-depart-de-sylvain-ougier-fete-au-niveau-de-ses-competences\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/12\\\/15\\\/chartreuse-le-depart-de-sylvain-ougier-fete-au-niveau-de-ses-competences\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/staging.sillon38.com\\\/wp-content\\\/uploads\\\/2009\\\/12\\\/ougier-300x300.jpg\",\"datePublished\":\"2009-12-15T20:48:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/12\\\/15\\\/chartreuse-le-depart-de-sylvain-ougier-fete-au-niveau-de-ses-competences\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/12\\\/15\\\/chartreuse-le-depart-de-sylvain-ougier-fete-au-niveau-de-ses-competences\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/12\\\/15\\\/chartreuse-le-depart-de-sylvain-ougier-fete-au-niveau-de-ses-competences\\\/#primaryimage\",\"url\":\"http:\\\/\\\/staging.sillon38.com\\\/wp-content\\\/uploads\\\/2009\\\/12\\\/ougier-300x300.jpg\",\"contentUrl\":\"http:\\\/\\\/staging.sillon38.com\\\/wp-content\\\/uploads\\\/2009\\\/12\\\/ougier-300x300.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/12\\\/15\\\/chartreuse-le-depart-de-sylvain-ougier-fete-au-niveau-de-ses-competences\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chartreuse: le d\u00e9part de Sylvain Ougier\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\",\"name\":\"\",\"description\":\"Le journal du monde rural\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\",\"name\":\"Gilbert\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chartreuse: le d\u00e9part de Sylvain Ougier -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sillon38.com\/blog\/2009\/12\/15\/chartreuse-le-depart-de-sylvain-ougier-fete-au-niveau-de-ses-competences\/","og_locale":"fr_FR","og_type":"article","og_title":"Chartreuse: le d\u00e9part de Sylvain Ougier -","og_description":"Sylvain Ougier, technicien forestier du massif de la Chartreuse a d\u00e9cid\u00e9, pour des raisons personnelles de quitter le massif pour rejoindre la Haute-Savoie. Son d\u00e9part a \u00e9t\u00e9 dignement f\u00eat\u00e9!","og_url":"https:\/\/www.sillon38.com\/blog\/2009\/12\/15\/chartreuse-le-depart-de-sylvain-ougier-fete-au-niveau-de-ses-competences\/","article_published_time":"2009-12-15T20:48:55+00:00","og_image":[{"url":"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2009\/12\/ougier-300x300.jpg","type":"","width":"","height":""}],"author":"Gilbert","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Gilbert","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sillon38.com\/blog\/2009\/12\/15\/chartreuse-le-depart-de-sylvain-ougier-fete-au-niveau-de-ses-competences\/#article","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/2009\/12\/15\/chartreuse-le-depart-de-sylvain-ougier-fete-au-niveau-de-ses-competences\/"},"author":{"name":"Gilbert","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"headline":"Chartreuse: le d\u00e9part de Sylvain Ougier","datePublished":"2009-12-15T20:48:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sillon38.com\/blog\/2009\/12\/15\/chartreuse-le-depart-de-sylvain-ougier-fete-au-niveau-de-ses-competences\/"},"wordCount":391,"commentCount":0,"image":{"@id":"https:\/\/www.sillon38.com\/blog\/2009\/12\/15\/chartreuse-le-depart-de-sylvain-ougier-fete-au-niveau-de-ses-competences\/#primaryimage"},"thumbnailUrl":"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2009\/12\/ougier-300x300.jpg","keywords":["AOC Bois de Chartreuse","Chartreuse","Eliane Giraud"],"articleSection":["For\u00eat de Chartreuse"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.sillon38.com\/blog\/2009\/12\/15\/chartreuse-le-depart-de-sylvain-ougier-fete-au-niveau-de-ses-competences\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.sillon38.com\/blog\/2009\/12\/15\/chartreuse-le-depart-de-sylvain-ougier-fete-au-niveau-de-ses-competences\/","url":"https:\/\/www.sillon38.com\/blog\/2009\/12\/15\/chartreuse-le-depart-de-sylvain-ougier-fete-au-niveau-de-ses-competences\/","name":"Chartreuse: le d\u00e9part de Sylvain Ougier -","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sillon38.com\/blog\/2009\/12\/15\/chartreuse-le-depart-de-sylvain-ougier-fete-au-niveau-de-ses-competences\/#primaryimage"},"image":{"@id":"https:\/\/www.sillon38.com\/blog\/2009\/12\/15\/chartreuse-le-depart-de-sylvain-ougier-fete-au-niveau-de-ses-competences\/#primaryimage"},"thumbnailUrl":"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2009\/12\/ougier-300x300.jpg","datePublished":"2009-12-15T20:48:55+00:00","author":{"@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"breadcrumb":{"@id":"https:\/\/www.sillon38.com\/blog\/2009\/12\/15\/chartreuse-le-depart-de-sylvain-ougier-fete-au-niveau-de-ses-competences\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sillon38.com\/blog\/2009\/12\/15\/chartreuse-le-depart-de-sylvain-ougier-fete-au-niveau-de-ses-competences\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.sillon38.com\/blog\/2009\/12\/15\/chartreuse-le-depart-de-sylvain-ougier-fete-au-niveau-de-ses-competences\/#primaryimage","url":"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2009\/12\/ougier-300x300.jpg","contentUrl":"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2009\/12\/ougier-300x300.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.sillon38.com\/blog\/2009\/12\/15\/chartreuse-le-depart-de-sylvain-ougier-fete-au-niveau-de-ses-competences\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.sillon38.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Chartreuse: le d\u00e9part de Sylvain Ougier"}]},{"@type":"WebSite","@id":"https:\/\/www.sillon38.com\/blog\/#website","url":"https:\/\/www.sillon38.com\/blog\/","name":"","description":"Le journal du monde rural","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sillon38.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1","name":"Gilbert"}]}},"_links":{"self":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/11705","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/comments?post=11705"}],"version-history":[{"count":0,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/11705\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/media?parent=11705"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/categories?post=11705"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/tags?post=11705"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}