{"id":14635,"date":"2010-05-03T21:38:41","date_gmt":"2010-05-03T19:38:41","guid":{"rendered":"http:\/\/staging.sillon38.com\/?p=14635"},"modified":"2010-05-03T21:38:41","modified_gmt":"2010-05-03T19:38:41","slug":"les-ecoliers-de-ain-beni-matharlaissez-nous-une-planete-propre","status":"publish","type":"post","link":"https:\/\/www.sillon38.com\/blog\/2010\/05\/03\/les-ecoliers-de-ain-beni-matharlaissez-nous-une-planete-propre\/","title":{"rendered":"Les \u00e9coliers de A\u00efn Beni Mathar: \u00ab\u00a0Laissez-nous une plan\u00e8te propre!\u00a0\u00bb"},"content":{"rendered":"<p><span style=\"color: #000000;\">Comme vous l&rsquo;avez vu, la d\u00e9l\u00e9gation qui s&rsquo;est rendue au Maroc oriental, sous l&rsquo;\u00e9gide de la F\u00e9d\u00e9ration des Alpages de l&rsquo;Is\u00e8re et de l&rsquo;association pastoralisme du monde,\u00a0 a fait une halte dans la commune de A\u00efn Beni Mathar.<\/span><\/p>\n<p><span style=\"color: #000000;\">Une commune qui a pris en charge son avenir \u00e0 travers la protection de son environnement. Abderrahmane Mejdoubi, \u00e9leveur ovin<em><em>:<\/em><\/em> \u00ab\u00a0La pollution de la nappe phr\u00e9atique, situ\u00e9e sous nos terres, serait une catastrophe pour l&rsquo;ensemble de la population de notre r\u00e9gion, notre \u00e9conomie, les emplois, notre troupeau, notre agriculture&#8230;\u00a0\u00bb<\/span><\/p>\n<p><span style=\"color: #000000;\">Profitant du fait que Rabat soit choisie comme la capitale mondiale de l&rsquo;environnement, dans le cadre du 40\u00e8me anniversaire de la Journ\u00e9e de la Terre, les \u00e9lus, associations, dont l&rsquo;association \u00ab\u00a0Environnement actif\u00a0\u00bb, et l&rsquo;\u00e9cole Moussa IBN Noussair de A\u00efn Beni Mathar se sont mobilis\u00e9s afin de sensibiliser la population sur les probl\u00e8mes li\u00e9s \u00e0 l&rsquo;environnement.<\/span><\/p>\n<p><span style=\"color: #000000;\">Pour ce, les \u00e9l\u00e8ves de l&rsquo;\u00e9cole, avec l&rsquo;aide de leurs instituteurs ont \u00e9crit, mis en sc\u00e8ne une pi\u00e8ce de th\u00e9\u00e2tre dont le fil conducteur est le respect de l&rsquo;environnement.<\/span><\/p>\n<p><span style=\"color: #000000;\">Les acteurs, excellents, faisant passer des messages forts: notre nature pleure, les usines polluent notre air, notre eau, halte \u00e0 la d\u00e9forestation, oui au reboisement, arr\u00eatez de tuer les animaux, stop au gaspillage de l&rsquo;eau car elle est la vie, stop \u00e0 la pollution&#8230;.En un mot: laissez nous une plan\u00e8te propre!<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong><em><em>Puissent, nos d\u00e9cideurs, entendre ces enfants mais \u00e9galement tous les enfants de la plan\u00e8te!<\/em><\/em><\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\">En parall\u00e8le<em>, <\/em>les \u00e9coliers ont fait des dessins<em> <\/em>ayant pour th\u00e8me l&rsquo;environnement<em>. <\/em>Les meilleurs d&rsquo;entre eux \u00e9tant r\u00e9compens\u00e9s.<em> <\/em><\/span><\/p>\n<p><span style=\"color: #000000;\">Voici quelques clich\u00e9s de cette visite \u00e0 l&rsquo;\u00e9cole<em> <\/em>Moussa IBN Noussair de A\u00efn Beni Mathar.<\/span><\/p>\n<p><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-14643\" title=\"ain 11\" src=\"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2010\/05\/ain-11.jpg\" alt=\"ain 11\" width=\"595\" height=\"349\" \/><\/span><\/p>\n<p><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-14792\" title=\"theatre\" src=\"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2010\/05\/theatre.jpg\" alt=\"theatre\" width=\"595\" height=\"290\" \/><br \/>\n<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-14636\" title=\"ain\" src=\"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2010\/05\/ain.jpg\" alt=\"ain\" width=\"595\" height=\"446\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-14637\" title=\"ain 5\" src=\"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2010\/05\/ain-5.jpg\" alt=\"ain 5\" width=\"595\" height=\"446\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-14644\" title=\"ain33\" src=\"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2010\/05\/ain33.jpg\" alt=\"ain33\" width=\"595\" height=\"530\" \/><\/p>\n<p><em>Bruno Bernab\u00e9, directeur des g\u00eetes de France Is\u00e8re appr\u00e9cie la qualit\u00e9 des dessins.<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-14639\" title=\"ain 2\" src=\"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2010\/05\/ain-2.jpg\" alt=\"ain 2\" width=\"595\" height=\"446\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-14648\" title=\"ain 44\" src=\"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2010\/05\/ain-44.jpg\" alt=\"ain 44\" width=\"595\" height=\"305\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A l&rsquo;occasion du 40 \u00e8me anniversaire de la Journ\u00e9e de la Terre, les \u00e9coliers de A\u00efn Beni Mathar, \u00e0 travers une pi\u00e8ce de th\u00e9\u00e2tre, nous supplient de leur laisser une plan\u00e8te propre.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[54],"tags":[165,317,885,2239],"class_list":["post-14635","post","type-post","status-publish","format-standard","hentry","category-pastoralismes-du-monde","tag-abderrahmane-mejdoubi","tag-ain-beni-mathar","tag-bruno-bernabe","tag-federation-des-alpages-de-lisere"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les \u00e9coliers de A\u00efn Beni Mathar: &quot;Laissez-nous une plan\u00e8te propre!&quot; -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sillon38.com\/blog\/2010\/05\/03\/les-ecoliers-de-ain-beni-matharlaissez-nous-une-planete-propre\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les \u00e9coliers de A\u00efn Beni Mathar: &quot;Laissez-nous une plan\u00e8te propre!&quot; -\" \/>\n<meta property=\"og:description\" content=\"A l&#039;occasion du 40 \u00e8me anniversaire de la Journ\u00e9e de la Terre, les \u00e9coliers de A\u00efn Beni Mathar, \u00e0 travers une pi\u00e8ce de th\u00e9\u00e2tre, nous supplient de leur laisser une plan\u00e8te propre.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sillon38.com\/blog\/2010\/05\/03\/les-ecoliers-de-ain-beni-matharlaissez-nous-une-planete-propre\/\" \/>\n<meta property=\"article:published_time\" content=\"2010-05-03T19:38:41+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2010\/05\/ain-11.jpg\" \/>\n<meta name=\"author\" content=\"Gilbert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gilbert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2010\\\/05\\\/03\\\/les-ecoliers-de-ain-beni-matharlaissez-nous-une-planete-propre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2010\\\/05\\\/03\\\/les-ecoliers-de-ain-beni-matharlaissez-nous-une-planete-propre\\\/\"},\"author\":{\"name\":\"Gilbert\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"headline\":\"Les \u00e9coliers de A\u00efn Beni Mathar: \u00ab\u00a0Laissez-nous une plan\u00e8te propre!\u00a0\u00bb\",\"datePublished\":\"2010-05-03T19:38:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2010\\\/05\\\/03\\\/les-ecoliers-de-ain-beni-matharlaissez-nous-une-planete-propre\\\/\"},\"wordCount\":339,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2010\\\/05\\\/03\\\/les-ecoliers-de-ain-beni-matharlaissez-nous-une-planete-propre\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/staging.sillon38.com\\\/wp-content\\\/uploads\\\/2010\\\/05\\\/ain-11.jpg\",\"keywords\":[\"Abderrahmane Mejdoubi\",\"A\u00efn Beni Mathar\",\"Bruno Bernab\u00e9\",\"F\u00e9d\u00e9ration des Alpages de l'Is\u00e8re\"],\"articleSection\":[\"pastoralismes du monde\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2010\\\/05\\\/03\\\/les-ecoliers-de-ain-beni-matharlaissez-nous-une-planete-propre\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2010\\\/05\\\/03\\\/les-ecoliers-de-ain-beni-matharlaissez-nous-une-planete-propre\\\/\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2010\\\/05\\\/03\\\/les-ecoliers-de-ain-beni-matharlaissez-nous-une-planete-propre\\\/\",\"name\":\"Les \u00e9coliers de A\u00efn Beni Mathar: \\\"Laissez-nous une plan\u00e8te propre!\\\" -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2010\\\/05\\\/03\\\/les-ecoliers-de-ain-beni-matharlaissez-nous-une-planete-propre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2010\\\/05\\\/03\\\/les-ecoliers-de-ain-beni-matharlaissez-nous-une-planete-propre\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/staging.sillon38.com\\\/wp-content\\\/uploads\\\/2010\\\/05\\\/ain-11.jpg\",\"datePublished\":\"2010-05-03T19:38:41+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2010\\\/05\\\/03\\\/les-ecoliers-de-ain-beni-matharlaissez-nous-une-planete-propre\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2010\\\/05\\\/03\\\/les-ecoliers-de-ain-beni-matharlaissez-nous-une-planete-propre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2010\\\/05\\\/03\\\/les-ecoliers-de-ain-beni-matharlaissez-nous-une-planete-propre\\\/#primaryimage\",\"url\":\"http:\\\/\\\/staging.sillon38.com\\\/wp-content\\\/uploads\\\/2010\\\/05\\\/ain-11.jpg\",\"contentUrl\":\"http:\\\/\\\/staging.sillon38.com\\\/wp-content\\\/uploads\\\/2010\\\/05\\\/ain-11.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2010\\\/05\\\/03\\\/les-ecoliers-de-ain-beni-matharlaissez-nous-une-planete-propre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les \u00e9coliers de A\u00efn Beni Mathar: \u00ab\u00a0Laissez-nous une plan\u00e8te propre!\u00a0\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\",\"name\":\"\",\"description\":\"Le journal du monde rural\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\",\"name\":\"Gilbert\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les \u00e9coliers de A\u00efn Beni Mathar: \"Laissez-nous une plan\u00e8te propre!\" -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sillon38.com\/blog\/2010\/05\/03\/les-ecoliers-de-ain-beni-matharlaissez-nous-une-planete-propre\/","og_locale":"fr_FR","og_type":"article","og_title":"Les \u00e9coliers de A\u00efn Beni Mathar: \"Laissez-nous une plan\u00e8te propre!\" -","og_description":"A l'occasion du 40 \u00e8me anniversaire de la Journ\u00e9e de la Terre, les \u00e9coliers de A\u00efn Beni Mathar, \u00e0 travers une pi\u00e8ce de th\u00e9\u00e2tre, nous supplient de leur laisser une plan\u00e8te propre.","og_url":"https:\/\/www.sillon38.com\/blog\/2010\/05\/03\/les-ecoliers-de-ain-beni-matharlaissez-nous-une-planete-propre\/","article_published_time":"2010-05-03T19:38:41+00:00","og_image":[{"url":"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2010\/05\/ain-11.jpg","type":"","width":"","height":""}],"author":"Gilbert","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Gilbert","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sillon38.com\/blog\/2010\/05\/03\/les-ecoliers-de-ain-beni-matharlaissez-nous-une-planete-propre\/#article","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/2010\/05\/03\/les-ecoliers-de-ain-beni-matharlaissez-nous-une-planete-propre\/"},"author":{"name":"Gilbert","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"headline":"Les \u00e9coliers de A\u00efn Beni Mathar: \u00ab\u00a0Laissez-nous une plan\u00e8te propre!\u00a0\u00bb","datePublished":"2010-05-03T19:38:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sillon38.com\/blog\/2010\/05\/03\/les-ecoliers-de-ain-beni-matharlaissez-nous-une-planete-propre\/"},"wordCount":339,"commentCount":0,"image":{"@id":"https:\/\/www.sillon38.com\/blog\/2010\/05\/03\/les-ecoliers-de-ain-beni-matharlaissez-nous-une-planete-propre\/#primaryimage"},"thumbnailUrl":"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2010\/05\/ain-11.jpg","keywords":["Abderrahmane Mejdoubi","A\u00efn Beni Mathar","Bruno Bernab\u00e9","F\u00e9d\u00e9ration des Alpages de l'Is\u00e8re"],"articleSection":["pastoralismes du monde"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.sillon38.com\/blog\/2010\/05\/03\/les-ecoliers-de-ain-beni-matharlaissez-nous-une-planete-propre\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.sillon38.com\/blog\/2010\/05\/03\/les-ecoliers-de-ain-beni-matharlaissez-nous-une-planete-propre\/","url":"https:\/\/www.sillon38.com\/blog\/2010\/05\/03\/les-ecoliers-de-ain-beni-matharlaissez-nous-une-planete-propre\/","name":"Les \u00e9coliers de A\u00efn Beni Mathar: \"Laissez-nous une plan\u00e8te propre!\" -","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sillon38.com\/blog\/2010\/05\/03\/les-ecoliers-de-ain-beni-matharlaissez-nous-une-planete-propre\/#primaryimage"},"image":{"@id":"https:\/\/www.sillon38.com\/blog\/2010\/05\/03\/les-ecoliers-de-ain-beni-matharlaissez-nous-une-planete-propre\/#primaryimage"},"thumbnailUrl":"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2010\/05\/ain-11.jpg","datePublished":"2010-05-03T19:38:41+00:00","author":{"@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"breadcrumb":{"@id":"https:\/\/www.sillon38.com\/blog\/2010\/05\/03\/les-ecoliers-de-ain-beni-matharlaissez-nous-une-planete-propre\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sillon38.com\/blog\/2010\/05\/03\/les-ecoliers-de-ain-beni-matharlaissez-nous-une-planete-propre\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.sillon38.com\/blog\/2010\/05\/03\/les-ecoliers-de-ain-beni-matharlaissez-nous-une-planete-propre\/#primaryimage","url":"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2010\/05\/ain-11.jpg","contentUrl":"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2010\/05\/ain-11.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.sillon38.com\/blog\/2010\/05\/03\/les-ecoliers-de-ain-beni-matharlaissez-nous-une-planete-propre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.sillon38.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Les \u00e9coliers de A\u00efn Beni Mathar: \u00ab\u00a0Laissez-nous une plan\u00e8te propre!\u00a0\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/www.sillon38.com\/blog\/#website","url":"https:\/\/www.sillon38.com\/blog\/","name":"","description":"Le journal du monde rural","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sillon38.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1","name":"Gilbert"}]}},"_links":{"self":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/14635","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/comments?post=14635"}],"version-history":[{"count":0,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/14635\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/media?parent=14635"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/categories?post=14635"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/tags?post=14635"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}