{"id":15531,"date":"2010-06-18T16:19:21","date_gmt":"2010-06-18T14:19:21","guid":{"rendered":"http:\/\/staging.sillon38.com\/?p=15531"},"modified":"2010-06-18T16:19:21","modified_gmt":"2010-06-18T14:19:21","slug":"oisans-participez-au-defi-du-facteur","status":"publish","type":"post","link":"https:\/\/www.sillon38.com\/blog\/2010\/06\/18\/oisans-participez-au-defi-du-facteur\/","title":{"rendered":"Oisans: participez au d\u00e9fi du facteur!"},"content":{"rendered":"<p><span style=\"color: #000000;\">A l\u2019heure de la communication acc\u00e9l\u00e9r\u00e9e, Le D\u00e9fi du Facteur est un petit tour historique, sportif et festif sur les chemins emprunt\u00e9s jusqu\u2019au milieu du XX\u00e8me si\u00e8cle par les facteurs pour transmettre les courriers jusque dans les villages perch\u00e9s.<\/span><\/p>\n<p><span style=\"color: #000000;\">Le D\u00e9fi du Facteur = kilom\u00e8tre vertical<br \/>\nInscrit au calendrier des courses hors-stade de l\u2019Is\u00e8re<br \/>\nDe Bourg d\u2019Oisans \u00e0 Villard Reymond<br \/>\nEn 4,6 kilom\u00e8tres<br \/>\nEt 1000 m\u00e8tres de d\u00e9nivel\u00e9e positive<br \/>\nLes atouts du trac\u00e9 : parcours en sous-bois \u00e0 l\u2019abri de la chaleur, portions roulantes, temps de r\u00e9pit, beaut\u00e9 des paysages<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>PROGRAMME <\/strong><br \/>\nSamedi 19 juin :<br \/>\n14h\u00a0 \u00e0 18h : inscriptions et retraits des dossards \u00e0 l\u2019Office de tourisme de Bourg d\u2019Oisans<\/span><\/p>\n<p><span style=\"color: #000000;\">Dimanche 20 juin :<br \/>\n8h-9h30 : inscriptions et retraits des dossards \u00e0 l\u2019Office de tourisme de Bourg d\u2019Oisans<br \/>\n9h45 : briefing des coureurs sous l\u2019arche de d\u00e9part au centre du village<br \/>\n10h : d\u00e9part<br \/>\n10h45 : arriv\u00e9e estim\u00e9e pour le premier participant au relais t\u00e9l\u00e9phonique de Villard-Reymond<br \/>\n12h30 : d\u00e9jeuner \u00e0 Villard-Reymond au g\u00eete de l\u2019Eau Blanche.<br \/>\nRemise des prix \u2013 animation musicale<\/span><\/p>\n<p><span style=\"color: #000000;\">INSCRIPTION<br \/>\nFrais d\u2019inscription : 5 \u20ac (d\u00e9jeuner inclus). Inscription sur place. Fournir licence ou attestation m\u00e9dicale d\u2019aptitude \u00e0 la pratique de la course \u00e0 pied ou lettre de d\u00e9charge (formulaire fourni).<\/span><\/p>\n<p><span style=\"color: #000000;\">TEMPS DE R\u00c9F\u00c9RENCE<br \/>\n44 minutes et 22 secondes r\u00e9alis\u00e9 par J\u00e9r\u00f4me Bosch lors de la premi\u00e8re \u00e9dition<br \/>\nLes r\u00e9sultats officiels : http:\/\/defidufacteur.blogspot.com\/ \u00e0 partir du 21 juin 2010<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le D\u00e9fi du Facteur est un petit tour historique, sportif et festif sur les chemins emprunt\u00e9s au fil des si\u00e8cles par les facteurs de l&rsquo;Oisans pour transmettre les courriers dans les villages perch\u00e9s. <\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[104,41],"tags":[850],"class_list":["post-15531","post","type-post","status-publish","format-standard","hentry","category-la-vie-des-communes","category-loisirs-detente","tag-bourg-doisans"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Oisans: participez au d\u00e9fi du facteur! -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sillon38.com\/blog\/2010\/06\/18\/oisans-participez-au-defi-du-facteur\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Oisans: participez au d\u00e9fi du facteur! -\" \/>\n<meta property=\"og:description\" content=\"Le D\u00e9fi du Facteur est un petit tour historique, sportif et festif sur les chemins emprunt\u00e9s au fil des si\u00e8cles par les facteurs de l&#039;Oisans pour transmettre les courriers dans les villages perch\u00e9s.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sillon38.com\/blog\/2010\/06\/18\/oisans-participez-au-defi-du-facteur\/\" \/>\n<meta property=\"article:published_time\" content=\"2010-06-18T14:19:21+00:00\" \/>\n<meta name=\"author\" content=\"Gilbert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gilbert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2010\\\/06\\\/18\\\/oisans-participez-au-defi-du-facteur\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2010\\\/06\\\/18\\\/oisans-participez-au-defi-du-facteur\\\/\"},\"author\":{\"name\":\"Gilbert\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"headline\":\"Oisans: participez au d\u00e9fi du facteur!\",\"datePublished\":\"2010-06-18T14:19:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2010\\\/06\\\/18\\\/oisans-participez-au-defi-du-facteur\\\/\"},\"wordCount\":259,\"commentCount\":0,\"keywords\":[\"Bourg d\u2019Oisans\"],\"articleSection\":[\"la vie des communes\",\"loisirs\\\/d\u00e9tente\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2010\\\/06\\\/18\\\/oisans-participez-au-defi-du-facteur\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2010\\\/06\\\/18\\\/oisans-participez-au-defi-du-facteur\\\/\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2010\\\/06\\\/18\\\/oisans-participez-au-defi-du-facteur\\\/\",\"name\":\"Oisans: participez au d\u00e9fi du facteur! -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\"},\"datePublished\":\"2010-06-18T14:19:21+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2010\\\/06\\\/18\\\/oisans-participez-au-defi-du-facteur\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2010\\\/06\\\/18\\\/oisans-participez-au-defi-du-facteur\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2010\\\/06\\\/18\\\/oisans-participez-au-defi-du-facteur\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Oisans: participez au d\u00e9fi du facteur!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\",\"name\":\"\",\"description\":\"Le journal du monde rural\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\",\"name\":\"Gilbert\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Oisans: participez au d\u00e9fi du facteur! -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sillon38.com\/blog\/2010\/06\/18\/oisans-participez-au-defi-du-facteur\/","og_locale":"fr_FR","og_type":"article","og_title":"Oisans: participez au d\u00e9fi du facteur! -","og_description":"Le D\u00e9fi du Facteur est un petit tour historique, sportif et festif sur les chemins emprunt\u00e9s au fil des si\u00e8cles par les facteurs de l'Oisans pour transmettre les courriers dans les villages perch\u00e9s.","og_url":"https:\/\/www.sillon38.com\/blog\/2010\/06\/18\/oisans-participez-au-defi-du-facteur\/","article_published_time":"2010-06-18T14:19:21+00:00","author":"Gilbert","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Gilbert","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sillon38.com\/blog\/2010\/06\/18\/oisans-participez-au-defi-du-facteur\/#article","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/2010\/06\/18\/oisans-participez-au-defi-du-facteur\/"},"author":{"name":"Gilbert","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"headline":"Oisans: participez au d\u00e9fi du facteur!","datePublished":"2010-06-18T14:19:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sillon38.com\/blog\/2010\/06\/18\/oisans-participez-au-defi-du-facteur\/"},"wordCount":259,"commentCount":0,"keywords":["Bourg d\u2019Oisans"],"articleSection":["la vie des communes","loisirs\/d\u00e9tente"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.sillon38.com\/blog\/2010\/06\/18\/oisans-participez-au-defi-du-facteur\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.sillon38.com\/blog\/2010\/06\/18\/oisans-participez-au-defi-du-facteur\/","url":"https:\/\/www.sillon38.com\/blog\/2010\/06\/18\/oisans-participez-au-defi-du-facteur\/","name":"Oisans: participez au d\u00e9fi du facteur! -","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/#website"},"datePublished":"2010-06-18T14:19:21+00:00","author":{"@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"breadcrumb":{"@id":"https:\/\/www.sillon38.com\/blog\/2010\/06\/18\/oisans-participez-au-defi-du-facteur\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sillon38.com\/blog\/2010\/06\/18\/oisans-participez-au-defi-du-facteur\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sillon38.com\/blog\/2010\/06\/18\/oisans-participez-au-defi-du-facteur\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.sillon38.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Oisans: participez au d\u00e9fi du facteur!"}]},{"@type":"WebSite","@id":"https:\/\/www.sillon38.com\/blog\/#website","url":"https:\/\/www.sillon38.com\/blog\/","name":"","description":"Le journal du monde rural","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sillon38.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1","name":"Gilbert"}]}},"_links":{"self":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/15531","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/comments?post=15531"}],"version-history":[{"count":0,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/15531\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/media?parent=15531"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/categories?post=15531"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/tags?post=15531"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}