{"id":15805,"date":"2010-07-06T13:22:49","date_gmt":"2010-07-06T11:22:49","guid":{"rendered":"http:\/\/staging.sillon38.com\/?p=15805"},"modified":"2010-07-06T13:22:49","modified_gmt":"2010-07-06T11:22:49","slug":"accord-entre-eleveurs-et-veterinaires","status":"publish","type":"post","link":"https:\/\/www.sillon38.com\/blog\/2010\/07\/06\/accord-entre-eleveurs-et-veterinaires\/","title":{"rendered":"Accord entre \u00e9leveurs et v\u00e9t\u00e9rinaires"},"content":{"rendered":"<p>Bruno Le Maire, Ministre de l&rsquo;Alimentation, de l&rsquo;Agriculture et de la P\u00eache, a re\u00e7u le 29 juin\u00a0 les organisations professionnelles agricoles et v\u00e9t\u00e9rinaires venues lui remettre les conclusions de leurs travaux sur les actes de m\u00e9decine et de chirurgie des animaux d\u2019\u00e9levage.<br \/>\nCet accord s\u2019inscrit dans le prolongement des \u00c9tats g\u00e9n\u00e9raux du sanitaire lanc\u00e9s par le ministre le 19 janvier dernier pour dessiner la r\u00e9novation du dispositif sanitaire fran\u00e7ais.<br \/>\nLe Conseil sup\u00e9rieur de l\u2019ordre des v\u00e9t\u00e9rinaires, le Syndicat national des v\u00e9t\u00e9rinaires d\u2019exercices lib\u00e9raux, la Soci\u00e9t\u00e9 nationale des groupements techniques v\u00e9t\u00e9rinaires, l\u2019Association v\u00e9t\u00e9rinaire \u00e9quine fran\u00e7aise, la F\u00e9d\u00e9ration nationale des syndicats d&rsquo;exploitants agricoles, COOP de France et l\u2019Union nationale des coop\u00e9ratives agricoles d&rsquo;\u00e9levage et d&rsquo;ins\u00e9mination animale ont pr\u00e9sent\u00e9, le 22 juin dernier, une proposition de texte de r\u00e9vision du code rural appel\u00e9 \u00e0 \u00eatre port\u00e9 par une ordonnance l\u00e9gislative pr\u00e9vue \u00e0 l\u2019article 2, adopt\u00e9\u00a0 par les d\u00e9put\u00e9s dans la loi de modernisation de l\u2019agriculture et de la p\u00eache.<\/p>\n<blockquote><p>Cet accord traduit la volont\u00e9 des partenaires de pr\u00e9server les pr\u00e9rogatives du v\u00e9t\u00e9rinaire rattach\u00e9es \u00e0 son dipl\u00f4me et de s\u00e9curiser la pratique des soins des animaux r\u00e9alis\u00e9s par des \u00e9leveurs ou des techniciens. Sur la base de ce consensus, une liste de soins qui pourront \u00eatre r\u00e9alis\u00e9s par des non v\u00e9t\u00e9rinaires sera fix\u00e9e par arr\u00eat\u00e9 pour chaque esp\u00e8ce.<\/p><\/blockquote>\n<p>Bruno Le Maire salue le travail responsable des organisations professionnelles concern\u00e9es qui augure bien des avanc\u00e9es qui se concr\u00e9tiseront suite aux \u00c9tats g\u00e9n\u00e9raux du sanitaire et au vote de la loi modernisation de l\u2019agriculture et de la p\u00eache en cours d\u2019examen \u00e0 l\u2019Assembl\u00e9e nationale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans la perspective de la r\u00e9novation du dispositif sanitaire fran\u00e7ais, un accord pr\u00e9servant les pr\u00e9rogatives du v\u00e9t\u00e9rinaire et s\u00e9curisant la pratique des soins aux animaux prodigu\u00e9s par des \u00e9leveurs ou des techniciens a \u00e9t\u00e9 trouv\u00e9.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19,62],"tags":[2148,3469],"class_list":["post-15805","post","type-post","status-publish","format-standard","hentry","category-elevage","category-prophylaxie","tag-etats-generaux-du-sanitaire","tag-lma"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Accord entre \u00e9leveurs et v\u00e9t\u00e9rinaires -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sillon38.com\/blog\/2010\/07\/06\/accord-entre-eleveurs-et-veterinaires\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Accord entre \u00e9leveurs et v\u00e9t\u00e9rinaires -\" \/>\n<meta property=\"og:description\" content=\"Dans la perspective de la r\u00e9novation du dispositif sanitaire fran\u00e7ais, un accord pr\u00e9servant les pr\u00e9rogatives du v\u00e9t\u00e9rinaire et s\u00e9curisant la pratique des soins aux animaux prodigu\u00e9s par des \u00e9leveurs ou des techniciens a \u00e9t\u00e9 trouv\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sillon38.com\/blog\/2010\/07\/06\/accord-entre-eleveurs-et-veterinaires\/\" \/>\n<meta property=\"article:published_time\" content=\"2010-07-06T11:22:49+00:00\" \/>\n<meta name=\"author\" content=\"Gilbert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gilbert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2010\\\/07\\\/06\\\/accord-entre-eleveurs-et-veterinaires\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2010\\\/07\\\/06\\\/accord-entre-eleveurs-et-veterinaires\\\/\"},\"author\":{\"name\":\"Gilbert\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"headline\":\"Accord entre \u00e9leveurs et v\u00e9t\u00e9rinaires\",\"datePublished\":\"2010-07-06T11:22:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2010\\\/07\\\/06\\\/accord-entre-eleveurs-et-veterinaires\\\/\"},\"wordCount\":329,\"commentCount\":0,\"keywords\":[\"Etats g\u00e9n\u00e9raux du sanitaire\",\"LMA\"],\"articleSection\":[\"\u00e9levage\",\"prophylaxie\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2010\\\/07\\\/06\\\/accord-entre-eleveurs-et-veterinaires\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2010\\\/07\\\/06\\\/accord-entre-eleveurs-et-veterinaires\\\/\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2010\\\/07\\\/06\\\/accord-entre-eleveurs-et-veterinaires\\\/\",\"name\":\"Accord entre \u00e9leveurs et v\u00e9t\u00e9rinaires -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\"},\"datePublished\":\"2010-07-06T11:22:49+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2010\\\/07\\\/06\\\/accord-entre-eleveurs-et-veterinaires\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2010\\\/07\\\/06\\\/accord-entre-eleveurs-et-veterinaires\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2010\\\/07\\\/06\\\/accord-entre-eleveurs-et-veterinaires\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Accord entre \u00e9leveurs et v\u00e9t\u00e9rinaires\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\",\"name\":\"\",\"description\":\"Le journal du monde rural\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\",\"name\":\"Gilbert\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Accord entre \u00e9leveurs et v\u00e9t\u00e9rinaires -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sillon38.com\/blog\/2010\/07\/06\/accord-entre-eleveurs-et-veterinaires\/","og_locale":"fr_FR","og_type":"article","og_title":"Accord entre \u00e9leveurs et v\u00e9t\u00e9rinaires -","og_description":"Dans la perspective de la r\u00e9novation du dispositif sanitaire fran\u00e7ais, un accord pr\u00e9servant les pr\u00e9rogatives du v\u00e9t\u00e9rinaire et s\u00e9curisant la pratique des soins aux animaux prodigu\u00e9s par des \u00e9leveurs ou des techniciens a \u00e9t\u00e9 trouv\u00e9.","og_url":"https:\/\/www.sillon38.com\/blog\/2010\/07\/06\/accord-entre-eleveurs-et-veterinaires\/","article_published_time":"2010-07-06T11:22:49+00:00","author":"Gilbert","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Gilbert","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sillon38.com\/blog\/2010\/07\/06\/accord-entre-eleveurs-et-veterinaires\/#article","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/2010\/07\/06\/accord-entre-eleveurs-et-veterinaires\/"},"author":{"name":"Gilbert","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"headline":"Accord entre \u00e9leveurs et v\u00e9t\u00e9rinaires","datePublished":"2010-07-06T11:22:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sillon38.com\/blog\/2010\/07\/06\/accord-entre-eleveurs-et-veterinaires\/"},"wordCount":329,"commentCount":0,"keywords":["Etats g\u00e9n\u00e9raux du sanitaire","LMA"],"articleSection":["\u00e9levage","prophylaxie"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.sillon38.com\/blog\/2010\/07\/06\/accord-entre-eleveurs-et-veterinaires\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.sillon38.com\/blog\/2010\/07\/06\/accord-entre-eleveurs-et-veterinaires\/","url":"https:\/\/www.sillon38.com\/blog\/2010\/07\/06\/accord-entre-eleveurs-et-veterinaires\/","name":"Accord entre \u00e9leveurs et v\u00e9t\u00e9rinaires -","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/#website"},"datePublished":"2010-07-06T11:22:49+00:00","author":{"@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"breadcrumb":{"@id":"https:\/\/www.sillon38.com\/blog\/2010\/07\/06\/accord-entre-eleveurs-et-veterinaires\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sillon38.com\/blog\/2010\/07\/06\/accord-entre-eleveurs-et-veterinaires\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sillon38.com\/blog\/2010\/07\/06\/accord-entre-eleveurs-et-veterinaires\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.sillon38.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Accord entre \u00e9leveurs et v\u00e9t\u00e9rinaires"}]},{"@type":"WebSite","@id":"https:\/\/www.sillon38.com\/blog\/#website","url":"https:\/\/www.sillon38.com\/blog\/","name":"","description":"Le journal du monde rural","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sillon38.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1","name":"Gilbert"}]}},"_links":{"self":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/15805","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/comments?post=15805"}],"version-history":[{"count":0,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/15805\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/media?parent=15805"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/categories?post=15805"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/tags?post=15805"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}