{"id":176,"date":"2007-08-18T18:51:26","date_gmt":"2007-08-18T16:51:26","guid":{"rendered":"http:\/\/staging.sillon38.com\/2007\/08\/18\/le-passage-lelevage-iserois-en-lumiere\/"},"modified":"2007-08-18T18:51:26","modified_gmt":"2007-08-18T16:51:26","slug":"le-passage-lelevage-iserois-en-lumiere","status":"publish","type":"post","link":"https:\/\/www.sillon38.com\/blog\/2007\/08\/18\/le-passage-lelevage-iserois-en-lumiere\/","title":{"rendered":"Le Passage: l\u2019\u00e9levage is\u00e9rois en lumi\u00e8re"},"content":{"rendered":"<p>Le Passage, village rural des Terres froides, a accueilli hier, pour  sa premi\u00e8re journ\u00e9e, le concours d\u00e9partemental d&rsquo;\u00e9levage. Un cheptel de qualit\u00e9 et de toutes races, des \u00e9leveurs motiv\u00e9s et un public nombreux ont fait de cet \u00e9v\u00e9nement une grande f\u00eate du monde agricole sous le soleil<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2007\/08\/p1000098.jpg\" alt=\"p1000098.jpg\" \/><\/p>\n<p><img decoding=\"async\" src=\"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2007\/08\/p1000096.jpg\" alt=\"p1000096.jpg\" \/><\/p>\n<p>La d\u00e9termination de l&rsquo;association des \u00e9leveurs de l&rsquo;Is\u00e8re, emmen\u00e9e par Jean-Luc Guillaud, a port\u00e9 ses fruits en d\u00e9pit d&rsquo;un contexte pas vraiment favorable au rassemblement d&rsquo;animaux. Mais les menaces de la fi\u00e8vre aphteuse n&rsquo;ont pas eu raison de l&rsquo;\u00e9v\u00e9nement, les mesures de confinement sanitaire ayant \u00e9t\u00e9 officiellement lev\u00e9es  le 10 ao\u00fbt pour l&rsquo;Hexagone. La tra\u00e7abilit\u00e9 mise en place depuis plusieurs ann\u00e9es pour les bovins a sans aucun doute pes\u00e9 dans la balance. Le secteur aviaire n&rsquo;a pas eu cette chance. Et, en raison des menaces du virus de la grippe aviaire, les volailles \u00e9taient absentes du champ de foire, am\u00e9nag\u00e9 pr\u00e8s du stade, en partie sur les terres priv\u00e9es du ch\u00e2teau, mises \u00e0 la dispositon de la commune. Les bovins &#8211; vaches, taureaux, g\u00e9nisses et veaux &#8211; y avaient toute leur place et ont fait le spectacle. Pour cette premi\u00e8re journ\u00e9e concouraient sur le ring les Montb\u00e9liardes, les Simmental, Charolaises, Limousines et Blondes d&rsquo;Aquitaine, un cheptel de haute qualit\u00e9 g\u00e9n\u00e9tique, venu en bonne partie du Nord-Is\u00e8re mais \u00e9galement du sud du d\u00e9partement, notamment du Vercors, du Tri\u00e8ves, du Gr\u00e9sivaudan. Elles et ils ont d\u00e9fil\u00e9 sur le podium, sous l&rsquo;oeil aiguis\u00e9 des juges qui en quelques minutes appr\u00e9cient l&rsquo;animal \u00e0 sa juste valeur, tenant compte notamment de la d\u00e9marche, de la mamelle, de la largeur du bassin, de la culotte, de la ligne de dos.<\/p>\n<p>Chevaux et ovins \u00e9taient \u00e9galement de la partie mais en petit nombre.<\/p>\n<p>Au terme de cette premi\u00e8re journ\u00e9e, marqu\u00e9e par la visite des \u00e9lus de la commune, du canton et du d\u00e9partement, Jean-Luc Guillaud pouvait s&rsquo;estimer satisfait: \u00ab\u00a0Notre cheptel est de tr\u00e8s haute qualit\u00e9 g\u00e9n\u00e9tique et soutient parfaitement la comparaison avec les meilleurs d\u00e9partements d&rsquo;\u00e9levage de France\u00a0\u00bb, soulignait-il.<\/p>\n<p>Le concours se poursuit aujourd&rsquo;hui \u00e0 Le Passage (canton de Virieu-sur-Bourbre) avec le concours des races Abondance et Prim&rsquo;Holstein, la pr\u00e9sentation de vaches H\u00e9rens et Villard-de-Lans. Les r\u00e9sultats officiels seront communiqu\u00e9s dimanche soir.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Passage, village rural des Terres froides, a accueilli hier, pour sa premi\u00e8re journ\u00e9e, le concours d\u00e9partemental d&rsquo;\u00e9levage. Un cheptel de qualit\u00e9 et de toutes races, des \u00e9leveurs motiv\u00e9s et un public nombreux ont fait de cet \u00e9v\u00e9nement une grande&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[94],"tags":[],"class_list":["post-176","post","type-post","status-publish","format-standard","hentry","category-comices"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le Passage: l\u2019\u00e9levage is\u00e9rois en lumi\u00e8re -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sillon38.com\/blog\/2007\/08\/18\/le-passage-lelevage-iserois-en-lumiere\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le Passage: l\u2019\u00e9levage is\u00e9rois en lumi\u00e8re -\" \/>\n<meta property=\"og:description\" content=\"Le Passage, village rural des Terres froides, a accueilli hier, pour sa premi\u00e8re journ\u00e9e, le concours d\u00e9partemental d&rsquo;\u00e9levage. Un cheptel de qualit\u00e9 et de toutes races, des \u00e9leveurs motiv\u00e9s et un public nombreux ont fait de cet \u00e9v\u00e9nement une grande...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sillon38.com\/blog\/2007\/08\/18\/le-passage-lelevage-iserois-en-lumiere\/\" \/>\n<meta property=\"article:published_time\" content=\"2007-08-18T16:51:26+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2007\/08\/p1000098.jpg\" \/>\n<meta name=\"author\" content=\"Gilbert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gilbert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2007\\\/08\\\/18\\\/le-passage-lelevage-iserois-en-lumiere\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2007\\\/08\\\/18\\\/le-passage-lelevage-iserois-en-lumiere\\\/\"},\"author\":{\"name\":\"Gilbert\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"headline\":\"Le Passage: l\u2019\u00e9levage is\u00e9rois en lumi\u00e8re\",\"datePublished\":\"2007-08-18T16:51:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2007\\\/08\\\/18\\\/le-passage-lelevage-iserois-en-lumiere\\\/\"},\"wordCount\":428,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2007\\\/08\\\/18\\\/le-passage-lelevage-iserois-en-lumiere\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/staging.sillon38.com\\\/wp-content\\\/uploads\\\/2007\\\/08\\\/p1000098.jpg\",\"articleSection\":[\"comices\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2007\\\/08\\\/18\\\/le-passage-lelevage-iserois-en-lumiere\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2007\\\/08\\\/18\\\/le-passage-lelevage-iserois-en-lumiere\\\/\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2007\\\/08\\\/18\\\/le-passage-lelevage-iserois-en-lumiere\\\/\",\"name\":\"Le Passage: l\u2019\u00e9levage is\u00e9rois en lumi\u00e8re -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2007\\\/08\\\/18\\\/le-passage-lelevage-iserois-en-lumiere\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2007\\\/08\\\/18\\\/le-passage-lelevage-iserois-en-lumiere\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/staging.sillon38.com\\\/wp-content\\\/uploads\\\/2007\\\/08\\\/p1000098.jpg\",\"datePublished\":\"2007-08-18T16:51:26+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2007\\\/08\\\/18\\\/le-passage-lelevage-iserois-en-lumiere\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2007\\\/08\\\/18\\\/le-passage-lelevage-iserois-en-lumiere\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2007\\\/08\\\/18\\\/le-passage-lelevage-iserois-en-lumiere\\\/#primaryimage\",\"url\":\"http:\\\/\\\/staging.sillon38.com\\\/wp-content\\\/uploads\\\/2007\\\/08\\\/p1000098.jpg\",\"contentUrl\":\"http:\\\/\\\/staging.sillon38.com\\\/wp-content\\\/uploads\\\/2007\\\/08\\\/p1000098.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2007\\\/08\\\/18\\\/le-passage-lelevage-iserois-en-lumiere\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le Passage: l\u2019\u00e9levage is\u00e9rois en lumi\u00e8re\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\",\"name\":\"\",\"description\":\"Le journal du monde rural\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\",\"name\":\"Gilbert\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le Passage: l\u2019\u00e9levage is\u00e9rois en lumi\u00e8re -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sillon38.com\/blog\/2007\/08\/18\/le-passage-lelevage-iserois-en-lumiere\/","og_locale":"fr_FR","og_type":"article","og_title":"Le Passage: l\u2019\u00e9levage is\u00e9rois en lumi\u00e8re -","og_description":"Le Passage, village rural des Terres froides, a accueilli hier, pour sa premi\u00e8re journ\u00e9e, le concours d\u00e9partemental d&rsquo;\u00e9levage. Un cheptel de qualit\u00e9 et de toutes races, des \u00e9leveurs motiv\u00e9s et un public nombreux ont fait de cet \u00e9v\u00e9nement une grande...","og_url":"https:\/\/www.sillon38.com\/blog\/2007\/08\/18\/le-passage-lelevage-iserois-en-lumiere\/","article_published_time":"2007-08-18T16:51:26+00:00","og_image":[{"url":"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2007\/08\/p1000098.jpg","type":"","width":"","height":""}],"author":"Gilbert","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Gilbert","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sillon38.com\/blog\/2007\/08\/18\/le-passage-lelevage-iserois-en-lumiere\/#article","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/2007\/08\/18\/le-passage-lelevage-iserois-en-lumiere\/"},"author":{"name":"Gilbert","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"headline":"Le Passage: l\u2019\u00e9levage is\u00e9rois en lumi\u00e8re","datePublished":"2007-08-18T16:51:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sillon38.com\/blog\/2007\/08\/18\/le-passage-lelevage-iserois-en-lumiere\/"},"wordCount":428,"commentCount":0,"image":{"@id":"https:\/\/www.sillon38.com\/blog\/2007\/08\/18\/le-passage-lelevage-iserois-en-lumiere\/#primaryimage"},"thumbnailUrl":"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2007\/08\/p1000098.jpg","articleSection":["comices"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.sillon38.com\/blog\/2007\/08\/18\/le-passage-lelevage-iserois-en-lumiere\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.sillon38.com\/blog\/2007\/08\/18\/le-passage-lelevage-iserois-en-lumiere\/","url":"https:\/\/www.sillon38.com\/blog\/2007\/08\/18\/le-passage-lelevage-iserois-en-lumiere\/","name":"Le Passage: l\u2019\u00e9levage is\u00e9rois en lumi\u00e8re -","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sillon38.com\/blog\/2007\/08\/18\/le-passage-lelevage-iserois-en-lumiere\/#primaryimage"},"image":{"@id":"https:\/\/www.sillon38.com\/blog\/2007\/08\/18\/le-passage-lelevage-iserois-en-lumiere\/#primaryimage"},"thumbnailUrl":"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2007\/08\/p1000098.jpg","datePublished":"2007-08-18T16:51:26+00:00","author":{"@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"breadcrumb":{"@id":"https:\/\/www.sillon38.com\/blog\/2007\/08\/18\/le-passage-lelevage-iserois-en-lumiere\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sillon38.com\/blog\/2007\/08\/18\/le-passage-lelevage-iserois-en-lumiere\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.sillon38.com\/blog\/2007\/08\/18\/le-passage-lelevage-iserois-en-lumiere\/#primaryimage","url":"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2007\/08\/p1000098.jpg","contentUrl":"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2007\/08\/p1000098.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.sillon38.com\/blog\/2007\/08\/18\/le-passage-lelevage-iserois-en-lumiere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.sillon38.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Le Passage: l\u2019\u00e9levage is\u00e9rois en lumi\u00e8re"}]},{"@type":"WebSite","@id":"https:\/\/www.sillon38.com\/blog\/#website","url":"https:\/\/www.sillon38.com\/blog\/","name":"","description":"Le journal du monde rural","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sillon38.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1","name":"Gilbert"}]}},"_links":{"self":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/comments?post=176"}],"version-history":[{"count":0,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/176\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/media?parent=176"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/categories?post=176"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/tags?post=176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}