{"id":19945,"date":"2011-01-07T10:18:00","date_gmt":"2011-01-07T08:18:00","guid":{"rendered":"http:\/\/staging.sillon38.com\/?p=19945"},"modified":"2011-01-07T10:18:00","modified_gmt":"2011-01-07T08:18:00","slug":"center-parc-de-roybon-deux-nouveaux-recours","status":"publish","type":"post","link":"https:\/\/www.sillon38.com\/blog\/2011\/01\/07\/center-parc-de-roybon-deux-nouveaux-recours\/","title":{"rendered":"Center Parcs de Roybon: deux nouveaux recours"},"content":{"rendered":"<p><span style=\"color: #000000;\">L&rsquo;association \u00ab\u00a0pour les Chambarans sans Center Parcs\u00a0\u00bb vient de d\u00e9poser deux nouveaux recours devant le tribunal administratif de Grenoble.<\/span><\/p>\n<p><span style=\"color: #000000;\">Ce 5 janvier, suite \u00e0 un refus d\u2019annulation de l\u2019autorisation de  d\u00e9frichement  de la pr\u00e9fecture, les avocats de l&rsquo;association \u00ab\u00a0pour les Chambarans sans Center Parcs\u00a0\u00bb ont d\u00e9pos\u00e9 un recours au  Tribunal Administratif de Grenoble, \u00e0 l\u2019encontre de cette autorisation.<\/span><\/p>\n<p><span style=\"color: #000000;\">Suite au refus d\u2019annulation de la mairie de Roybon du permis de  construire,\u00a0 un recours au  Tribunal Administratif de Grenoble a \u00e9t\u00e9 \u00e9galement d\u00e9pos\u00e9 ce 5 janvier.<\/span><\/p>\n<p><span style=\"color: #000000;\">Le Center Parc de Roybon, le cinqui\u00e8me centre de vacances pr\u00e9vu en France devrait ouvrir ses portes courant 2013&#8230;.il regrouperait un millier de \u00ab\u00a0cottages\u00a0\u00bb sur une surface de 200 hectares. Le groupe Pierre et vacances initiateur du projet annonce la cr\u00e9ation de 700 emplois.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;association \u00ab\u00a0pour les Chambarans sans Center Parcs\u00a0\u00bb vient de d\u00e9poser deux nouveaux recours devant le tribunal administratif de Grenoble.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[47],"tags":[1040,4449],"class_list":["post-19945","post","type-post","status-publish","format-standard","hentry","category-nature","tag-center-parcs-roybon","tag-pour-les-chambarans-sans-center-parcs"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Center Parcs de Roybon: deux nouveaux recours -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sillon38.com\/blog\/2011\/01\/07\/center-parc-de-roybon-deux-nouveaux-recours\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Center Parcs de Roybon: deux nouveaux recours -\" \/>\n<meta property=\"og:description\" content=\"L&#039;association &quot;pour les Chambarans sans Center Parcs&quot; vient de d\u00e9poser deux nouveaux recours devant le tribunal administratif de Grenoble.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sillon38.com\/blog\/2011\/01\/07\/center-parc-de-roybon-deux-nouveaux-recours\/\" \/>\n<meta property=\"article:published_time\" content=\"2011-01-07T08:18:00+00:00\" \/>\n<meta name=\"author\" content=\"Gilbert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gilbert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/01\\\/07\\\/center-parc-de-roybon-deux-nouveaux-recours\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/01\\\/07\\\/center-parc-de-roybon-deux-nouveaux-recours\\\/\"},\"author\":{\"name\":\"Gilbert\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"headline\":\"Center Parcs de Roybon: deux nouveaux recours\",\"datePublished\":\"2011-01-07T08:18:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/01\\\/07\\\/center-parc-de-roybon-deux-nouveaux-recours\\\/\"},\"wordCount\":144,\"commentCount\":0,\"keywords\":[\"Center parcs Roybon\",\"pour les Chambarans sans Center Parcs\"],\"articleSection\":[\"nature\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/01\\\/07\\\/center-parc-de-roybon-deux-nouveaux-recours\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/01\\\/07\\\/center-parc-de-roybon-deux-nouveaux-recours\\\/\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/01\\\/07\\\/center-parc-de-roybon-deux-nouveaux-recours\\\/\",\"name\":\"Center Parcs de Roybon: deux nouveaux recours -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\"},\"datePublished\":\"2011-01-07T08:18:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/01\\\/07\\\/center-parc-de-roybon-deux-nouveaux-recours\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/01\\\/07\\\/center-parc-de-roybon-deux-nouveaux-recours\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/01\\\/07\\\/center-parc-de-roybon-deux-nouveaux-recours\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Center Parcs de Roybon: deux nouveaux recours\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\",\"name\":\"\",\"description\":\"Le journal du monde rural\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\",\"name\":\"Gilbert\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Center Parcs de Roybon: deux nouveaux recours -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sillon38.com\/blog\/2011\/01\/07\/center-parc-de-roybon-deux-nouveaux-recours\/","og_locale":"fr_FR","og_type":"article","og_title":"Center Parcs de Roybon: deux nouveaux recours -","og_description":"L'association \"pour les Chambarans sans Center Parcs\" vient de d\u00e9poser deux nouveaux recours devant le tribunal administratif de Grenoble.","og_url":"https:\/\/www.sillon38.com\/blog\/2011\/01\/07\/center-parc-de-roybon-deux-nouveaux-recours\/","article_published_time":"2011-01-07T08:18:00+00:00","author":"Gilbert","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Gilbert","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sillon38.com\/blog\/2011\/01\/07\/center-parc-de-roybon-deux-nouveaux-recours\/#article","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/2011\/01\/07\/center-parc-de-roybon-deux-nouveaux-recours\/"},"author":{"name":"Gilbert","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"headline":"Center Parcs de Roybon: deux nouveaux recours","datePublished":"2011-01-07T08:18:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sillon38.com\/blog\/2011\/01\/07\/center-parc-de-roybon-deux-nouveaux-recours\/"},"wordCount":144,"commentCount":0,"keywords":["Center parcs Roybon","pour les Chambarans sans Center Parcs"],"articleSection":["nature"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.sillon38.com\/blog\/2011\/01\/07\/center-parc-de-roybon-deux-nouveaux-recours\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.sillon38.com\/blog\/2011\/01\/07\/center-parc-de-roybon-deux-nouveaux-recours\/","url":"https:\/\/www.sillon38.com\/blog\/2011\/01\/07\/center-parc-de-roybon-deux-nouveaux-recours\/","name":"Center Parcs de Roybon: deux nouveaux recours -","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/#website"},"datePublished":"2011-01-07T08:18:00+00:00","author":{"@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"breadcrumb":{"@id":"https:\/\/www.sillon38.com\/blog\/2011\/01\/07\/center-parc-de-roybon-deux-nouveaux-recours\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sillon38.com\/blog\/2011\/01\/07\/center-parc-de-roybon-deux-nouveaux-recours\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sillon38.com\/blog\/2011\/01\/07\/center-parc-de-roybon-deux-nouveaux-recours\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.sillon38.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Center Parcs de Roybon: deux nouveaux recours"}]},{"@type":"WebSite","@id":"https:\/\/www.sillon38.com\/blog\/#website","url":"https:\/\/www.sillon38.com\/blog\/","name":"","description":"Le journal du monde rural","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sillon38.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1","name":"Gilbert"}]}},"_links":{"self":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/19945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/comments?post=19945"}],"version-history":[{"count":0,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/19945\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/media?parent=19945"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/categories?post=19945"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/tags?post=19945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}