{"id":20104,"date":"2011-01-18T19:20:30","date_gmt":"2011-01-18T17:20:30","guid":{"rendered":"http:\/\/staging.sillon38.com\/?p=20104"},"modified":"2011-01-18T19:20:30","modified_gmt":"2011-01-18T17:20:30","slug":"les-vignerons-de-rhone-alpes-toujours-plus-nombreux-a-millesime-bio","status":"publish","type":"post","link":"https:\/\/www.sillon38.com\/blog\/2011\/01\/18\/les-vignerons-de-rhone-alpes-toujours-plus-nombreux-a-millesime-bio\/","title":{"rendered":"Les vignerons de Rh\u00f4ne-Alpes toujours plus nombreux \u00e0 Mill\u00e9sime Bio !"},"content":{"rendered":"<p><strong><em>Le  plus grand salon professionnel des vins bio accueillera du 24 au 26  janvier prochains 44 vignerons de Rh\u00f4ne-Alpes. C\u00f4tes du Rh\u00f4ne, Vins de  Savoie, Beaujolais\u2026, les l\u00e9gendaires vignobles de la r\u00e9gion y seront  repr\u00e9sent\u00e9s. Corabio et Organics Cluster accompagnent et permettent \u00e0 12  vignerons bio de la r\u00e9gion d\u2019exp\u00e9rimenter leur premi\u00e8re participation  au salon.<\/em><\/strong><\/p>\n<p><span style=\"color: #000000;\">La  viticulture bio est en pleine expansion. La fili\u00e8re en Rh\u00f4ne-Alpes suit  la tendance avec une forte dynamique de conversion depuis 3 ans. Avec  306 exploitations viticoles bio \u00e0 fin 2010, on compte 50 nouveaux  vignerons par rapport \u00e0 2009. Les vignes bio de Rh\u00f4ne-Alpes s\u2019\u00e9tendent  sur 2700 ha \u00e0 travers de grands terroirs : <strong>C\u00f4tes du Rh\u00f4ne septentrionales et m\u00e9ridionales, C\u00f4teaux du Lyonnais et du Tricastin, Beaujolais, Clairette de Die, <\/strong><strong>Vins de pays des c\u00f4teaux de l\u2019Ard\u00e8che, de la Dr\u00f4me, Vins de Savoie, du Bugey,<\/strong><\/span><strong> C\u00f4tes du Vivarais, Beaujolais, C\u00f4tes Roannaises, du Forez\u2026 <\/strong><\/p>\n<p><span style=\"color: #ff0000;\"> <strong>Une place de choix pour les vignerons rh\u00f4nalpins\u00a0!<\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\">Du  24 au 26 janvier, le salon Mill\u00e9sime Bio, qui se d\u00e9roulera au Parc des Expositions \u00e0 Montpellier, attend plus de 500 producteurs  et n\u00e9gociants. Avec une progression de 58% de la fr\u00e9quentation du salon  et des vins provenant de 25 pays diff\u00e9rents, ce salon professionnel est  devenu une v\u00e9ritable r\u00e9f\u00e9rence pour le march\u00e9 des vins issus de raisins  de l\u2019agriculture biologique. <strong>44 vignerons bio de Rh\u00f4ne-Alpes <\/strong>(dont<strong> <\/strong>42 caves particuli\u00e8res et 2 caves coop\u00e9ratives) y tiendrons une place de choix.<\/span><\/p>\n<p><span style=\"color: #000000;\"> Parmi  eux, 12 vignerons b\u00e9n\u00e9ficieront d\u2019un accompagnement sp\u00e9cifique de  Corabio (la Coordination Rh\u00f4ne-Alpes des producteurs bio) et d\u2019Organics  Cluster (renforcement de la comp\u00e9titivit\u00e9 des entreprises du secteur  bio). L\u2019op\u00e9ration, renouvel\u00e9e cette ann\u00e9e, a pour but d\u2019offrir  l\u2019opportunit\u00e9 \u00e0 12 vignerons rh\u00f4nalpins de participer \u00e0 ce salon pour la  premi\u00e8re fois, dans des conditions pr\u00e9f\u00e9rentielles. Une belle vitrine,  notamment pour les nouveaux producteurs\u00a0!<\/span><\/p>\n<p><span style=\"color: #000000;\"> Cette  pr\u00e9sence collective valorise la diversit\u00e9 des terroirs de la r\u00e9gion\u00a0:  Beaujolais (Domaines de la Ronze, de la Grand Cour, de Buis-Rond), C\u00f4tes  du Rh\u00f4ne (Domaines Viret, de la Rosi\u00e8re, des Treilles, des Amphores, du  Serre des Vignes), Vins du Bugey (Domaine Jean-Christophe Pellerin),  Vins de pays des C\u00f4teaux de l\u2019Ard\u00e8che (Mas de Vinobre), et Ferme \u00e0  whisky du Domaine des Hautes Glaces. Vous les trouverez, regroup\u00e9s par 3  sur les <strong>stands 278, 280, 290 et 292 du hall 6.<\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\">Pour plus d\u2019informations, t\u00e9l\u00e9chargez le guide de Corabio pr\u00e9sentant 50 vignerons bio de Rh\u00f4ne-Alpes sur <a href=\"http:\/\/www.corabio.org\/\">www.corabio.org<\/a><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le plus grand salon professionnel des vins bio accueillera du 24 au 26 janvier prochains, \u00e0 Montpellier, 44 vignerons de Rh\u00f4ne-Alpes. C\u00f4tes du Rh\u00f4ne, Vins de Savoie, Beaujolais\u2026, les l\u00e9gendaires vignobles de la r\u00e9gion y seront repr\u00e9sent\u00e9s. Corabio et Organics Cluster accompagnent et permettent \u00e0 12 vignerons bio de la r\u00e9gion d\u2019exp\u00e9rimenter leur premi\u00e8re participation au salon.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,27,78],"tags":[782,1602,3879,4748,5730],"class_list":["post-20104","post","type-post","status-publish","format-standard","hentry","category-bio","category-foiressalons","category-viticulture","tag-bio","tag-corabio","tag-montpellier","tag-rhone-alpes","tag-viticulture"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les vignerons de Rh\u00f4ne-Alpes toujours plus nombreux \u00e0 Mill\u00e9sime Bio ! -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sillon38.com\/blog\/2011\/01\/18\/les-vignerons-de-rhone-alpes-toujours-plus-nombreux-a-millesime-bio\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les vignerons de Rh\u00f4ne-Alpes toujours plus nombreux \u00e0 Mill\u00e9sime Bio ! -\" \/>\n<meta property=\"og:description\" content=\"Le plus grand salon professionnel des vins bio accueillera du 24 au 26 janvier prochains, \u00e0 Montpellier, 44 vignerons de Rh\u00f4ne-Alpes. C\u00f4tes du Rh\u00f4ne, Vins de Savoie, Beaujolais\u2026, les l\u00e9gendaires vignobles de la r\u00e9gion y seront repr\u00e9sent\u00e9s. Corabio et Organics Cluster accompagnent et permettent \u00e0 12 vignerons bio de la r\u00e9gion d\u2019exp\u00e9rimenter leur premi\u00e8re participation au salon.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sillon38.com\/blog\/2011\/01\/18\/les-vignerons-de-rhone-alpes-toujours-plus-nombreux-a-millesime-bio\/\" \/>\n<meta property=\"article:published_time\" content=\"2011-01-18T17:20:30+00:00\" \/>\n<meta name=\"author\" content=\"Gilbert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gilbert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/01\\\/18\\\/les-vignerons-de-rhone-alpes-toujours-plus-nombreux-a-millesime-bio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/01\\\/18\\\/les-vignerons-de-rhone-alpes-toujours-plus-nombreux-a-millesime-bio\\\/\"},\"author\":{\"name\":\"Gilbert\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"headline\":\"Les vignerons de Rh\u00f4ne-Alpes toujours plus nombreux \u00e0 Mill\u00e9sime Bio !\",\"datePublished\":\"2011-01-18T17:20:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/01\\\/18\\\/les-vignerons-de-rhone-alpes-toujours-plus-nombreux-a-millesime-bio\\\/\"},\"wordCount\":442,\"commentCount\":0,\"keywords\":[\"bio\",\"Corabio\",\"Montpellier\",\"Rh\u00f4ne Alpes\",\"viticulture\"],\"articleSection\":[\"bio\",\"foires\\\/salons\",\"viticulture\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/01\\\/18\\\/les-vignerons-de-rhone-alpes-toujours-plus-nombreux-a-millesime-bio\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/01\\\/18\\\/les-vignerons-de-rhone-alpes-toujours-plus-nombreux-a-millesime-bio\\\/\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/01\\\/18\\\/les-vignerons-de-rhone-alpes-toujours-plus-nombreux-a-millesime-bio\\\/\",\"name\":\"Les vignerons de Rh\u00f4ne-Alpes toujours plus nombreux \u00e0 Mill\u00e9sime Bio ! -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\"},\"datePublished\":\"2011-01-18T17:20:30+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/01\\\/18\\\/les-vignerons-de-rhone-alpes-toujours-plus-nombreux-a-millesime-bio\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/01\\\/18\\\/les-vignerons-de-rhone-alpes-toujours-plus-nombreux-a-millesime-bio\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/01\\\/18\\\/les-vignerons-de-rhone-alpes-toujours-plus-nombreux-a-millesime-bio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les vignerons de Rh\u00f4ne-Alpes toujours plus nombreux \u00e0 Mill\u00e9sime Bio !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\",\"name\":\"\",\"description\":\"Le journal du monde rural\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\",\"name\":\"Gilbert\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les vignerons de Rh\u00f4ne-Alpes toujours plus nombreux \u00e0 Mill\u00e9sime Bio ! -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sillon38.com\/blog\/2011\/01\/18\/les-vignerons-de-rhone-alpes-toujours-plus-nombreux-a-millesime-bio\/","og_locale":"fr_FR","og_type":"article","og_title":"Les vignerons de Rh\u00f4ne-Alpes toujours plus nombreux \u00e0 Mill\u00e9sime Bio ! -","og_description":"Le plus grand salon professionnel des vins bio accueillera du 24 au 26 janvier prochains, \u00e0 Montpellier, 44 vignerons de Rh\u00f4ne-Alpes. C\u00f4tes du Rh\u00f4ne, Vins de Savoie, Beaujolais\u2026, les l\u00e9gendaires vignobles de la r\u00e9gion y seront repr\u00e9sent\u00e9s. Corabio et Organics Cluster accompagnent et permettent \u00e0 12 vignerons bio de la r\u00e9gion d\u2019exp\u00e9rimenter leur premi\u00e8re participation au salon.","og_url":"https:\/\/www.sillon38.com\/blog\/2011\/01\/18\/les-vignerons-de-rhone-alpes-toujours-plus-nombreux-a-millesime-bio\/","article_published_time":"2011-01-18T17:20:30+00:00","author":"Gilbert","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Gilbert","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sillon38.com\/blog\/2011\/01\/18\/les-vignerons-de-rhone-alpes-toujours-plus-nombreux-a-millesime-bio\/#article","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/2011\/01\/18\/les-vignerons-de-rhone-alpes-toujours-plus-nombreux-a-millesime-bio\/"},"author":{"name":"Gilbert","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"headline":"Les vignerons de Rh\u00f4ne-Alpes toujours plus nombreux \u00e0 Mill\u00e9sime Bio !","datePublished":"2011-01-18T17:20:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sillon38.com\/blog\/2011\/01\/18\/les-vignerons-de-rhone-alpes-toujours-plus-nombreux-a-millesime-bio\/"},"wordCount":442,"commentCount":0,"keywords":["bio","Corabio","Montpellier","Rh\u00f4ne Alpes","viticulture"],"articleSection":["bio","foires\/salons","viticulture"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.sillon38.com\/blog\/2011\/01\/18\/les-vignerons-de-rhone-alpes-toujours-plus-nombreux-a-millesime-bio\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.sillon38.com\/blog\/2011\/01\/18\/les-vignerons-de-rhone-alpes-toujours-plus-nombreux-a-millesime-bio\/","url":"https:\/\/www.sillon38.com\/blog\/2011\/01\/18\/les-vignerons-de-rhone-alpes-toujours-plus-nombreux-a-millesime-bio\/","name":"Les vignerons de Rh\u00f4ne-Alpes toujours plus nombreux \u00e0 Mill\u00e9sime Bio ! -","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/#website"},"datePublished":"2011-01-18T17:20:30+00:00","author":{"@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"breadcrumb":{"@id":"https:\/\/www.sillon38.com\/blog\/2011\/01\/18\/les-vignerons-de-rhone-alpes-toujours-plus-nombreux-a-millesime-bio\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sillon38.com\/blog\/2011\/01\/18\/les-vignerons-de-rhone-alpes-toujours-plus-nombreux-a-millesime-bio\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sillon38.com\/blog\/2011\/01\/18\/les-vignerons-de-rhone-alpes-toujours-plus-nombreux-a-millesime-bio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.sillon38.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Les vignerons de Rh\u00f4ne-Alpes toujours plus nombreux \u00e0 Mill\u00e9sime Bio !"}]},{"@type":"WebSite","@id":"https:\/\/www.sillon38.com\/blog\/#website","url":"https:\/\/www.sillon38.com\/blog\/","name":"","description":"Le journal du monde rural","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sillon38.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1","name":"Gilbert"}]}},"_links":{"self":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/20104","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/comments?post=20104"}],"version-history":[{"count":0,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/20104\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/media?parent=20104"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/categories?post=20104"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/tags?post=20104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}