{"id":20307,"date":"2011-02-03T22:00:22","date_gmt":"2011-02-03T20:00:22","guid":{"rendered":"http:\/\/staging.sillon38.com\/?p=20307"},"modified":"2011-02-03T22:00:22","modified_gmt":"2011-02-03T20:00:22","slug":"5-medailles-pour-les-vignerons-de-rhone-alpes","status":"publish","type":"post","link":"https:\/\/www.sillon38.com\/blog\/2011\/02\/03\/5-medailles-pour-les-vignerons-de-rhone-alpes\/","title":{"rendered":"5 m\u00e9dailles pour les vignerons de Rh\u00f4ne-Alpes!"},"content":{"rendered":"<p><strong><em> <\/em><\/strong><\/p>\n<p><strong><em> <\/em><\/strong><\/p>\n<p><span style=\"color: #000000;\"><strong><em>39  vignerons et 2 caves coop\u00e9ratives ont repr\u00e9sent\u00e9 dignement la r\u00e9gion  Rh\u00f4ne-Alpes\u00a0au salon Mill\u00e9sime Bio qui s\u2019est d\u00e9roul\u00e9 du 24 au 26 janvier  au parc des expositions de Montpellier. <\/em><\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\"><strong><em>Rh\u00f4ne-Alpes remporte ainsi 5  m\u00e9dailles dans le cadre du concours international des vins de l\u2019agriculture biologique organis\u00e9 par l\u2019AIVB du Languedoc Roussillon.<\/em><\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\"><strong><em> <\/em><\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\"><strong> <\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\">Mill\u00e9sime  Bio, le salon mondial et professionnel des vins issus de l\u2019agriculture  biologique a accueilli du 24 au 26 janvier derniers plus de 500  producteurs et n\u00e9gociants. De plus en plus d\u2019acheteurs venant du monde  entier et des vins de 25 pays diff\u00e9rents ont fait de ce salon  professionnel une v\u00e9ritable r\u00e9f\u00e9rence pour le march\u00e9 des vins issus de  raisins de l\u2019agriculture biologique.<\/span><\/p>\n<p><span style=\"color: #000000;\"> Rh\u00f4ne-Alpes  \u00e9tait repr\u00e9sent\u00e9 sur le salon \u00e0 travers 39 vignerons et 2 caves  coop\u00e9ratives. Parmi eux, 5 ont remport\u00e9 une m\u00e9daille dans le cadre du  Challenge Mill\u00e9sime Bio qui r\u00e9compense les vins b\u00e9n\u00e9ficiant de qualit\u00e9s  gustatives remarquables. Le concours organis\u00e9 par l\u2019Association  Interprofessionnelle des Vins Biologiques du Languedoc Roussillon  (AIVB-LR) a pour triple objectif de promouvoir la qualit\u00e9 des vins issus  de l\u2019agriculture bio, d\u2019encourager les vignerons \u00e0 une recherche  permanente de qualit\u00e9, et de constituer une r\u00e9f\u00e9rence incontournable  pour l\u2019offre des vins issus de l\u2019agriculture bio.<\/span><\/p>\n<p><span style=\"color: #000000;\"> La  r\u00e9colte 2009, Vin de Savoie Blanc du Domaine Giachino remporte ainsi\u00a0  une m\u00e9daille d\u2019or. Les domaines Achard-Vincent (Clairette de Die), Barou  (Condrieu) et de la Grand\u2019Cour (Fleurie) remportent une m\u00e9daille  d\u2019argent, ce dernier faisant partie des 12 vignerons soutenus par  Organics Cluster et Corabio pour leur premi\u00e8re participation au salon.  Enfin le Domaine Barou re\u00e7oit \u00e9galement une m\u00e9daille de bronze pour son  AOC Saint-Joseph, Rouge, 2009.<\/span><\/p>\n<p><span style=\"color: #000000;\"> Mill\u00e9sime  Bio a \u00e9galement \u00e9t\u00e9 l\u2019occasion d\u2019\u00e9voquer la question de la  certification europ\u00e9enne des vins bio au cours du s\u00e9minaire organis\u00e9 par  l\u2019Agence Bio. En effet, le r\u00e8glement europ\u00e9en de l\u2019AB permettrait la  mise en place d\u2019un cahier des charges de la vinification. Mais des  divergences d\u2019int\u00e9r\u00eat entre pays du Nord et pays du Sud sur les  quantit\u00e9s de sulfite n\u2019ont pas permis un accord europ\u00e9en. <\/span><\/p>\n<p><span style=\"color: #000000;\">Conscients de  la n\u00e9cessit\u00e9 d\u2019offrir aux consommateurs non seulement du vin issu de  raisins bio mais surtout un vin bio, les vignerons \u0153uvrent actuellement \u00e0  rassembler les crit\u00e8res de diverses chartes de vinification priv\u00e9es au  sein d\u2019une charte europ\u00e9enne.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>39 vignerons et 2 caves coop\u00e9ratives ont repr\u00e9sent\u00e9 la r\u00e9gion Rh\u00f4ne-Alpes au salon Mill\u00e9sime Bio. La r\u00e9gion d\u00e9croche 5 m\u00e9dailles au concours international des vins de l\u2019agriculture biologique.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,78],"tags":[3879,4748,5717],"class_list":["post-20307","post","type-post","status-publish","format-standard","hentry","category-bio","category-viticulture","tag-montpellier","tag-rhone-alpes","tag-vins-bio"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>5 m\u00e9dailles pour les vignerons de Rh\u00f4ne-Alpes! -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sillon38.com\/blog\/2011\/02\/03\/5-medailles-pour-les-vignerons-de-rhone-alpes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"5 m\u00e9dailles pour les vignerons de Rh\u00f4ne-Alpes! -\" \/>\n<meta property=\"og:description\" content=\"39 vignerons et 2 caves coop\u00e9ratives ont repr\u00e9sent\u00e9 la r\u00e9gion Rh\u00f4ne-Alpes au salon Mill\u00e9sime Bio. La r\u00e9gion d\u00e9croche 5 m\u00e9dailles au concours international des vins de l\u2019agriculture biologique.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sillon38.com\/blog\/2011\/02\/03\/5-medailles-pour-les-vignerons-de-rhone-alpes\/\" \/>\n<meta property=\"article:published_time\" content=\"2011-02-03T20:00:22+00:00\" \/>\n<meta name=\"author\" content=\"Gilbert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gilbert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/02\\\/03\\\/5-medailles-pour-les-vignerons-de-rhone-alpes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/02\\\/03\\\/5-medailles-pour-les-vignerons-de-rhone-alpes\\\/\"},\"author\":{\"name\":\"Gilbert\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"headline\":\"5 m\u00e9dailles pour les vignerons de Rh\u00f4ne-Alpes!\",\"datePublished\":\"2011-02-03T20:00:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/02\\\/03\\\/5-medailles-pour-les-vignerons-de-rhone-alpes\\\/\"},\"wordCount\":431,\"commentCount\":0,\"keywords\":[\"Montpellier\",\"Rh\u00f4ne Alpes\",\"vins bio\"],\"articleSection\":[\"bio\",\"viticulture\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/02\\\/03\\\/5-medailles-pour-les-vignerons-de-rhone-alpes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/02\\\/03\\\/5-medailles-pour-les-vignerons-de-rhone-alpes\\\/\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/02\\\/03\\\/5-medailles-pour-les-vignerons-de-rhone-alpes\\\/\",\"name\":\"5 m\u00e9dailles pour les vignerons de Rh\u00f4ne-Alpes! -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\"},\"datePublished\":\"2011-02-03T20:00:22+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/02\\\/03\\\/5-medailles-pour-les-vignerons-de-rhone-alpes\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/02\\\/03\\\/5-medailles-pour-les-vignerons-de-rhone-alpes\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/02\\\/03\\\/5-medailles-pour-les-vignerons-de-rhone-alpes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"5 m\u00e9dailles pour les vignerons de Rh\u00f4ne-Alpes!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\",\"name\":\"\",\"description\":\"Le journal du monde rural\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\",\"name\":\"Gilbert\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"5 m\u00e9dailles pour les vignerons de Rh\u00f4ne-Alpes! -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sillon38.com\/blog\/2011\/02\/03\/5-medailles-pour-les-vignerons-de-rhone-alpes\/","og_locale":"fr_FR","og_type":"article","og_title":"5 m\u00e9dailles pour les vignerons de Rh\u00f4ne-Alpes! -","og_description":"39 vignerons et 2 caves coop\u00e9ratives ont repr\u00e9sent\u00e9 la r\u00e9gion Rh\u00f4ne-Alpes au salon Mill\u00e9sime Bio. La r\u00e9gion d\u00e9croche 5 m\u00e9dailles au concours international des vins de l\u2019agriculture biologique.","og_url":"https:\/\/www.sillon38.com\/blog\/2011\/02\/03\/5-medailles-pour-les-vignerons-de-rhone-alpes\/","article_published_time":"2011-02-03T20:00:22+00:00","author":"Gilbert","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Gilbert","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sillon38.com\/blog\/2011\/02\/03\/5-medailles-pour-les-vignerons-de-rhone-alpes\/#article","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/2011\/02\/03\/5-medailles-pour-les-vignerons-de-rhone-alpes\/"},"author":{"name":"Gilbert","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"headline":"5 m\u00e9dailles pour les vignerons de Rh\u00f4ne-Alpes!","datePublished":"2011-02-03T20:00:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sillon38.com\/blog\/2011\/02\/03\/5-medailles-pour-les-vignerons-de-rhone-alpes\/"},"wordCount":431,"commentCount":0,"keywords":["Montpellier","Rh\u00f4ne Alpes","vins bio"],"articleSection":["bio","viticulture"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.sillon38.com\/blog\/2011\/02\/03\/5-medailles-pour-les-vignerons-de-rhone-alpes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.sillon38.com\/blog\/2011\/02\/03\/5-medailles-pour-les-vignerons-de-rhone-alpes\/","url":"https:\/\/www.sillon38.com\/blog\/2011\/02\/03\/5-medailles-pour-les-vignerons-de-rhone-alpes\/","name":"5 m\u00e9dailles pour les vignerons de Rh\u00f4ne-Alpes! -","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/#website"},"datePublished":"2011-02-03T20:00:22+00:00","author":{"@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"breadcrumb":{"@id":"https:\/\/www.sillon38.com\/blog\/2011\/02\/03\/5-medailles-pour-les-vignerons-de-rhone-alpes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sillon38.com\/blog\/2011\/02\/03\/5-medailles-pour-les-vignerons-de-rhone-alpes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sillon38.com\/blog\/2011\/02\/03\/5-medailles-pour-les-vignerons-de-rhone-alpes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.sillon38.com\/blog\/"},{"@type":"ListItem","position":2,"name":"5 m\u00e9dailles pour les vignerons de Rh\u00f4ne-Alpes!"}]},{"@type":"WebSite","@id":"https:\/\/www.sillon38.com\/blog\/#website","url":"https:\/\/www.sillon38.com\/blog\/","name":"","description":"Le journal du monde rural","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sillon38.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1","name":"Gilbert"}]}},"_links":{"self":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/20307","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/comments?post=20307"}],"version-history":[{"count":0,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/20307\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/media?parent=20307"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/categories?post=20307"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/tags?post=20307"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}