{"id":20343,"date":"2011-02-04T18:44:00","date_gmt":"2011-02-04T16:44:00","guid":{"rendered":"http:\/\/staging.sillon38.com\/?p=20343"},"modified":"2011-02-04T18:44:00","modified_gmt":"2011-02-04T16:44:00","slug":"lancement-de-lannee-internationale-des-forets","status":"publish","type":"post","link":"https:\/\/www.sillon38.com\/blog\/2011\/02\/04\/lancement-de-lannee-internationale-des-forets\/","title":{"rendered":"Lancement de l\u2019Ann\u00e9e internationale des for\u00eats"},"content":{"rendered":"<p><span style=\"color: #000000;\">Des millions de personnes tributaires des for\u00eats jouent un r\u00f4le vital dans la gestion, la conservation et le d\u00e9veloppement durables des for\u00eats de la plan\u00e8te. Et pourtant on tend \u00e0 sous-estimer leurs droits d&rsquo;utiliser et de tirer parti des ressources foresti\u00e8res locales, indique le nouveau rapport de la FAO Situation des for\u00eats du monde 2011 (SOFO), pr\u00e9sent\u00e9 lors de la c\u00e9r\u00e9monie d&rsquo;ouverture de l&rsquo;Ann\u00e9e internationale des for\u00eats \u00e0 New York. <\/span><\/p>\n<p><span style=\"color: #000000;\">\u00ab\u00a0L&rsquo;Ann\u00e9e internationale des for\u00eats doit servir \u00e0 mettre en lumi\u00e8re le lien entre peuples et for\u00eats, et les avantages que peuvent en tirer les populations locales lorsqu&rsquo;elles g\u00e8rent leurs for\u00eats dans une optique durable et innovante\u00a0\u00bb, a soulign\u00e9 Eduardo Rojas, Sous-Directeur g\u00e9n\u00e9ral de la FAO pour les for\u00eats.  Vers une &lsquo;\u00e9conomie plus verte&rsquo;  L&rsquo;int\u00e9r\u00eat accru suscit\u00e9 par la durabilit\u00e9 sociale et environnementale constitue un enjeu singulier pour l&rsquo;industrie foresti\u00e8re qui devra innover et se r\u00e9organiser pour \u00eatre en mesure de r\u00e9pondre aux demandes du XXI\u00e8me si\u00e8cle.<\/span><\/p>\n<p><span style=\"color: #000000;\"> Elle devra \u00e9galement contribuer \u00e0 modifier la perception g\u00e9n\u00e9ralement n\u00e9gative du bois qu&rsquo;ont les consommateurs, en ce sens qu&rsquo;ils pensent qu&rsquo;il est \u00e9thiquement incorrect d&rsquo;abattre des arbres.  Le rapport de la FAO souligne qu&rsquo;au contraire, le secteur forestier est un \u00e9l\u00e9ment important d&rsquo;une \u00e9conomie plus verte et les produits ligneux pr\u00e9sentent des caract\u00e9ristiques environnementales s\u00e9duisantes. Le bois et les produits ligneux, comme les mat\u00e9riaux naturels, sont issus de ressources renouvelables qui pi\u00e8gent le carbone et offrent de vastes possibilit\u00e9s de recyclage.<\/span><\/p>\n<p><span style=\"color: #000000;\"> Une utilisation plus durable des ressources, le recours \u00e0 davantage de r\u00e9sidus dans la fabrication des produits, une meilleure efficacit\u00e9 \u00e9nerg\u00e9tique et la r\u00e9duction des \u00e9missions sont les r\u00e9ponses qu&rsquo;apporte l&rsquo;industrie foresti\u00e8re aux multiples pr\u00e9occupations environnementales et sociales.  Par exemple, la production foresti\u00e8re totale en 2010 est constitu\u00e9e \u00e0 37 pour cent de papier recycl\u00e9, de d\u00e9chets du bois et de fibres non ligneuses, pourcentage appel\u00e9 \u00e0 s&rsquo;\u00e9tablir \u00e0 45 pour cent en 2030, augmentation due en grande partie \u00e0 la Chine et \u00e0 l&rsquo;Inde. <\/span><\/p>\n<p><span style=\"color: #000000;\"> Par ailleurs, la plupart des produits ligneux solides, comme le bois sci\u00e9 et le contreplaqu\u00e9, sont produits avec une quantit\u00e9 relativement limit\u00e9e d&rsquo;\u00e9nergie. La production et l&rsquo;utilisation sont ainsi \u00e0 faible empreinte carbone, d&rsquo;autant plus que les produits du bois stockent le carbone. <\/span><\/p>\n<p><span style=\"color: #000000;\">La production de p\u00e2te et de papier est plus gourmande en \u00e9nergie mais elle est soumise \u00e0 une plus forte pression pour r\u00e9duire son intensit\u00e9 \u00e9nerg\u00e9tique et ses \u00e9missions de carbone en adoptant des technologies am\u00e9lior\u00e9es et les \u00e9changes de droits d&rsquo;\u00e9mission.   De nombreux gouvernements estiment que le secteur forestier offre des possibilit\u00e9s importantes de promotion d&rsquo;une &lsquo;\u00e9conomie plus verte&rsquo;, notamment par la bio\u00e9nergie, les activit\u00e9s de promotion du bois et de nouveaux produits \u00e0 base de bois et biomat\u00e9riels. <\/span><\/p>\n<p><span style=\"color: #000000;\">Ainsi, divers pays d\u00e9velopp\u00e9s ont renforc\u00e9 leur soutien en faveur des industries foresti\u00e8res ces derni\u00e8res ann\u00e9es.  REDD+ doit affronter les probl\u00e8mes locaux  Le rapport de la FAO souligne \u00e9galement la n\u00e9cessit\u00e9 urgente de mesures destin\u00e9es \u00e0 prot\u00e9ger les acquis que procurent les for\u00eats en mati\u00e8re de soutien aux moyens d&rsquo;existence locaux face au changement climatique. <\/span><\/p>\n<p><span style=\"color: #000000;\"> Les r\u00e9centes d\u00e9cisions prises \u00e0 Cancun en d\u00e9cembre 2010 sur REDD+ devraient s&rsquo;aligner sur une plus vaste r\u00e9forme de la gouvernance foresti\u00e8re et permettre la participation des communaut\u00e9s autochtones et locales. Leurs droits doivent \u00eatre respect\u00e9s dans le cadre des activit\u00e9s et strat\u00e9gies nationales REDD+, sugg\u00e8re le rapport.  En outre, les pays devront adopter des l\u00e9gislations pour pr\u00e9ciser les droits carbone et garantir une r\u00e9partition \u00e9quitable des co\u00fbts et des b\u00e9n\u00e9fices tir\u00e9s des m\u00e9canismes REDD+.  Les strat\u00e9gies d&rsquo;adaptation sont sous-estim\u00e9es  Si les mesures REDD+ attirent une attention et des financements croissants, le r\u00f4le des for\u00eats dans l&rsquo;adaptation au changement climatique est crucial &#8211; bien que souvent sous-estim\u00e9 &#8211; par les gouvernements. <\/span><\/p>\n<p><span style=\"color: #000000;\">Le rapport insiste sur l&rsquo;importance de la contribution des for\u00eats \u00e0 la r\u00e9alisation des strat\u00e9gies nationales d&rsquo;adaptation.  Les mesures foresti\u00e8res ont le pouvoir d&rsquo;att\u00e9nuer les impacts du changement climatique sur les \u00e9cosyst\u00e8mes et les secteurs de la soci\u00e9t\u00e9 fortement vuln\u00e9rables. Par exemple, enrayer le d\u00e9frichement des mangroves (dont un cinqui\u00e8me aurait disparu \u00e0 l&rsquo;\u00e9chelle mondiale depuis 1980) contribuerait \u00e0 prot\u00e9ger le littoral face aux temp\u00eates plus fr\u00e9quentes et plus intenses et aux tsunamis.  La plantation de for\u00eats et d&rsquo;arbres pour la protection de l&rsquo;environnement et des revenus pourrait aider les communaut\u00e9s pauvres des pays arides \u00e0 \u00eatre moins sujettes aux s\u00e9cheresses.<\/span><\/p>\n<p><span style=\"color: #000000;\"> Parmi les exemples de mesures d&rsquo;adaptation dans les pays en d\u00e9veloppement figurent l&rsquo;am\u00e9nagement et la conservation des mangroves au Bangladesh, la pr\u00e9vention des feux de brousse \u00e0 Samoa et les programmes de reboisement en Ha\u00efti.  Le rapport \u00e9voque les liens \u00e9troits entre for\u00eats, moyens d&rsquo;existence ruraux et stabilit\u00e9 environnementale, qui soulignent la n\u00e9cessit\u00e9 d&rsquo;apporter un soutien financier concret aux mesures d&rsquo;adaptation des for\u00eats.<\/span><\/p>\n<p><span style=\"color: #000000;\"> \u00ab\u00a0Faute d&rsquo;accorder cette attention aux probl\u00e8mes \u00e0 l&rsquo;\u00e9chelon local, on court le risque d&rsquo;affaiblir les modes de vie traditionnels et de mettre en p\u00e9ril certaines des for\u00eats les plus biologiquement vari\u00e9es et importantes sur le plan environnemental\u00a0\u00bb, souligne le rapport.<\/span><\/p>\n<blockquote><p><span style=\"color: #000000;\"><strong><span style=\"color: #008000;\">En France, Nathalie Kosciusko-Morizet, ministre de l&rsquo;\u00e9cologie et du d\u00e9veloppement durable a lanc\u00e9 l&rsquo;ann\u00e9e de la for\u00eat dans le Vercors<\/span><\/strong><br \/>\n<\/span><\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Le secteur forestier doit innover<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,28],"tags":[2203,2507,3957],"class_list":["post-20343","post","type-post","status-publish","format-standard","hentry","category-a-la-une","category-foret","tag-fao","tag-foret","tag-new-york"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lancement de l\u2019Ann\u00e9e internationale des for\u00eats -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sillon38.com\/blog\/2011\/02\/04\/lancement-de-lannee-internationale-des-forets\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lancement de l\u2019Ann\u00e9e internationale des for\u00eats -\" \/>\n<meta property=\"og:description\" content=\"Le secteur forestier doit innover\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sillon38.com\/blog\/2011\/02\/04\/lancement-de-lannee-internationale-des-forets\/\" \/>\n<meta property=\"article:published_time\" content=\"2011-02-04T16:44:00+00:00\" \/>\n<meta name=\"author\" content=\"Gilbert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gilbert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/02\\\/04\\\/lancement-de-lannee-internationale-des-forets\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/02\\\/04\\\/lancement-de-lannee-internationale-des-forets\\\/\"},\"author\":{\"name\":\"Gilbert\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"headline\":\"Lancement de l\u2019Ann\u00e9e internationale des for\u00eats\",\"datePublished\":\"2011-02-04T16:44:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/02\\\/04\\\/lancement-de-lannee-internationale-des-forets\\\/\"},\"wordCount\":978,\"commentCount\":0,\"keywords\":[\"FAO\",\"for\u00eat\",\"New York\"],\"articleSection\":[\"\u00c0 la une\",\"for\u00eat\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/02\\\/04\\\/lancement-de-lannee-internationale-des-forets\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/02\\\/04\\\/lancement-de-lannee-internationale-des-forets\\\/\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/02\\\/04\\\/lancement-de-lannee-internationale-des-forets\\\/\",\"name\":\"Lancement de l\u2019Ann\u00e9e internationale des for\u00eats -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\"},\"datePublished\":\"2011-02-04T16:44:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/02\\\/04\\\/lancement-de-lannee-internationale-des-forets\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/02\\\/04\\\/lancement-de-lannee-internationale-des-forets\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/02\\\/04\\\/lancement-de-lannee-internationale-des-forets\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lancement de l\u2019Ann\u00e9e internationale des for\u00eats\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\",\"name\":\"\",\"description\":\"Le journal du monde rural\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\",\"name\":\"Gilbert\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lancement de l\u2019Ann\u00e9e internationale des for\u00eats -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sillon38.com\/blog\/2011\/02\/04\/lancement-de-lannee-internationale-des-forets\/","og_locale":"fr_FR","og_type":"article","og_title":"Lancement de l\u2019Ann\u00e9e internationale des for\u00eats -","og_description":"Le secteur forestier doit innover","og_url":"https:\/\/www.sillon38.com\/blog\/2011\/02\/04\/lancement-de-lannee-internationale-des-forets\/","article_published_time":"2011-02-04T16:44:00+00:00","author":"Gilbert","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Gilbert","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sillon38.com\/blog\/2011\/02\/04\/lancement-de-lannee-internationale-des-forets\/#article","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/2011\/02\/04\/lancement-de-lannee-internationale-des-forets\/"},"author":{"name":"Gilbert","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"headline":"Lancement de l\u2019Ann\u00e9e internationale des for\u00eats","datePublished":"2011-02-04T16:44:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sillon38.com\/blog\/2011\/02\/04\/lancement-de-lannee-internationale-des-forets\/"},"wordCount":978,"commentCount":0,"keywords":["FAO","for\u00eat","New York"],"articleSection":["\u00c0 la une","for\u00eat"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.sillon38.com\/blog\/2011\/02\/04\/lancement-de-lannee-internationale-des-forets\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.sillon38.com\/blog\/2011\/02\/04\/lancement-de-lannee-internationale-des-forets\/","url":"https:\/\/www.sillon38.com\/blog\/2011\/02\/04\/lancement-de-lannee-internationale-des-forets\/","name":"Lancement de l\u2019Ann\u00e9e internationale des for\u00eats -","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/#website"},"datePublished":"2011-02-04T16:44:00+00:00","author":{"@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"breadcrumb":{"@id":"https:\/\/www.sillon38.com\/blog\/2011\/02\/04\/lancement-de-lannee-internationale-des-forets\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sillon38.com\/blog\/2011\/02\/04\/lancement-de-lannee-internationale-des-forets\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sillon38.com\/blog\/2011\/02\/04\/lancement-de-lannee-internationale-des-forets\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.sillon38.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Lancement de l\u2019Ann\u00e9e internationale des for\u00eats"}]},{"@type":"WebSite","@id":"https:\/\/www.sillon38.com\/blog\/#website","url":"https:\/\/www.sillon38.com\/blog\/","name":"","description":"Le journal du monde rural","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sillon38.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1","name":"Gilbert"}]}},"_links":{"self":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/20343","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/comments?post=20343"}],"version-history":[{"count":0,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/20343\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/media?parent=20343"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/categories?post=20343"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/tags?post=20343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}