{"id":21118,"date":"2011-03-08T19:49:30","date_gmt":"2011-03-08T17:49:30","guid":{"rendered":"http:\/\/staging.sillon38.com\/?p=21118"},"modified":"2011-03-08T19:49:30","modified_gmt":"2011-03-08T17:49:30","slug":"le-gouvernement-met-en-place-le-nouveau-cadre-de-regulation-du-photovoltaique","status":"publish","type":"post","link":"https:\/\/www.sillon38.com\/blog\/2011\/03\/08\/le-gouvernement-met-en-place-le-nouveau-cadre-de-regulation-du-photovoltaique\/","title":{"rendered":"Le Gouvernement met en place le nouveau cadre de r\u00e9gulation du photovolta\u00efque"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" title=\"Cr\u00e9dits photo : Laurent Mignaux\/MEDDTL\" src=\"http:\/\/www.developpement-durable.gouv.fr\/IMG\/LM013076-1.jpg\" alt=\"Fabrication de panneaux photovolta\u00efques  \u00e0 Lannion  dans les C\u00f4tes d'Armor\" hspace=\"10\" vspace=\"10\" width=\"250\" height=\"166\" align=\"left\" \/><span style=\"color: #000000;\">Le  nouveau dispositif comporte un syst\u00e8me de tarifs ajust\u00e9s  trimestriellement pour les installations de moins de 100 kWc (environ 1  000 m\u00e8tres carr\u00e9 de panneaux) et des appels d\u2019offres pour les autres  installations.<\/span><\/p>\n<p><span style=\"color: #000000;\">Les exigences seront accrues sur la qualit\u00e9 environnementale et  industrielle des projets avec notamment l\u2019int\u00e9gration d\u2019obligations de  recyclage en fin de vie et de d\u00e9mant\u00e8lement \u00e0 compter de l\u2019\u00e9t\u00e9 2011 et  de l\u2019obligation de fourniture d\u2019une analyse de cycle de vie \u00e0 compter du  1er janvier 2012. Les projets hors installations r\u00e9sidentielles devront  aussi fournir une attestation bancaire ou une offre de pr\u00eat afin  d\u2019attester de la durabilit\u00e9 et du s\u00e9rieux des projets.<\/span><\/p>\n<p><span style=\"color: #000000;\">Les tarifs d\u2019achat sont valables \u00e0 partir du 10 mars 2011 et sont fix\u00e9s \u00e0  20 % en dessous du tarif en vigueur au 1er septembre 2010 puis ajust\u00e9s  trimestriellement en fonction des volumes de projets d\u00e9pos\u00e9s et des  baisses de co\u00fbts attendues estim\u00e9es \u00e0 10 % par an.<\/span><\/p>\n<p><span style=\"color: #000000;\">Suivant les recommandations du Conseil sup\u00e9rieur de l\u2019\u00e9nergie et de la  Commission de r\u00e9gulation de l\u2019\u00e9nergie, le premier trimestre s&rsquo;arr\u00eatera  le 30 juin 2011 pour une meilleure lisibilit\u00e9 des dates d&rsquo;\u00e9volution. Le  dispositif d\u2019attestation bancaire a \u00e9galement \u00e9t\u00e9 simplifi\u00e9.<\/span><\/p>\n<p><span style=\"color: #000000;\">De plus, devant le succ\u00e8s des \u00e9nergies renouvelables en Corse et en  outremer, afin de garantir la s\u00fbret\u00e9 des r\u00e9seaux dans ces territoires et  poursuivre un d\u00e9veloppement r\u00e9gul\u00e9, le seuil \u00e0 partir duquel des  dispositifs d\u2019effacement doivent \u00eatre mis en place pour pr\u00e9venir des  saturations est abaiss\u00e9. Cette mesure sera totalement transparente pour  les installations photovolta\u00efques domestiques. Une flexibilit\u00e9 nouvelle  est introduite pour les grandes installations avec l&rsquo;encouragement de  dispositifs de stockage d&rsquo;\u00e9nergie.<\/span><\/p>\n<p><span style=\"color: #000000;\"> <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>pr\u00e8s consultation du Conseil sup\u00e9rieur de l\u2019\u00e9nergie et de la Commission de r\u00e9gulation de l\u2019\u00e9nergie, les textes r\u00e9glementaires sur le nouveau cadre de r\u00e9gulation du photovolta\u00efque ont \u00e9t\u00e9 publi\u00e9s au Journal officiel le 5 mars 2011.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[2054,4276],"class_list":["post-21118","post","type-post","status-publish","format-standard","hentry","category-energies","tag-energie","tag-photovoltaique"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le Gouvernement met en place le nouveau cadre de r\u00e9gulation du photovolta\u00efque -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sillon38.com\/blog\/2011\/03\/08\/le-gouvernement-met-en-place-le-nouveau-cadre-de-regulation-du-photovoltaique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le Gouvernement met en place le nouveau cadre de r\u00e9gulation du photovolta\u00efque -\" \/>\n<meta property=\"og:description\" content=\"pr\u00e8s consultation du Conseil sup\u00e9rieur de l\u2019\u00e9nergie et de la Commission de r\u00e9gulation de l\u2019\u00e9nergie, les textes r\u00e9glementaires sur le nouveau cadre de r\u00e9gulation du photovolta\u00efque ont \u00e9t\u00e9 publi\u00e9s au Journal officiel le 5 mars 2011.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sillon38.com\/blog\/2011\/03\/08\/le-gouvernement-met-en-place-le-nouveau-cadre-de-regulation-du-photovoltaique\/\" \/>\n<meta property=\"article:published_time\" content=\"2011-03-08T17:49:30+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.developpement-durable.gouv.fr\/IMG\/LM013076-1.jpg\" \/>\n<meta name=\"author\" content=\"Gilbert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gilbert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/03\\\/08\\\/le-gouvernement-met-en-place-le-nouveau-cadre-de-regulation-du-photovoltaique\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/03\\\/08\\\/le-gouvernement-met-en-place-le-nouveau-cadre-de-regulation-du-photovoltaique\\\/\"},\"author\":{\"name\":\"Gilbert\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"headline\":\"Le Gouvernement met en place le nouveau cadre de r\u00e9gulation du photovolta\u00efque\",\"datePublished\":\"2011-03-08T17:49:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/03\\\/08\\\/le-gouvernement-met-en-place-le-nouveau-cadre-de-regulation-du-photovoltaique\\\/\"},\"wordCount\":302,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/03\\\/08\\\/le-gouvernement-met-en-place-le-nouveau-cadre-de-regulation-du-photovoltaique\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.developpement-durable.gouv.fr\\\/IMG\\\/LM013076-1.jpg\",\"keywords\":[\"\u00e9nergie\",\"photovolta\u00efque\"],\"articleSection\":[\"\u00e9nergies\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/03\\\/08\\\/le-gouvernement-met-en-place-le-nouveau-cadre-de-regulation-du-photovoltaique\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/03\\\/08\\\/le-gouvernement-met-en-place-le-nouveau-cadre-de-regulation-du-photovoltaique\\\/\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/03\\\/08\\\/le-gouvernement-met-en-place-le-nouveau-cadre-de-regulation-du-photovoltaique\\\/\",\"name\":\"Le Gouvernement met en place le nouveau cadre de r\u00e9gulation du photovolta\u00efque -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/03\\\/08\\\/le-gouvernement-met-en-place-le-nouveau-cadre-de-regulation-du-photovoltaique\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/03\\\/08\\\/le-gouvernement-met-en-place-le-nouveau-cadre-de-regulation-du-photovoltaique\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.developpement-durable.gouv.fr\\\/IMG\\\/LM013076-1.jpg\",\"datePublished\":\"2011-03-08T17:49:30+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/03\\\/08\\\/le-gouvernement-met-en-place-le-nouveau-cadre-de-regulation-du-photovoltaique\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/03\\\/08\\\/le-gouvernement-met-en-place-le-nouveau-cadre-de-regulation-du-photovoltaique\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/03\\\/08\\\/le-gouvernement-met-en-place-le-nouveau-cadre-de-regulation-du-photovoltaique\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.developpement-durable.gouv.fr\\\/IMG\\\/LM013076-1.jpg\",\"contentUrl\":\"http:\\\/\\\/www.developpement-durable.gouv.fr\\\/IMG\\\/LM013076-1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/03\\\/08\\\/le-gouvernement-met-en-place-le-nouveau-cadre-de-regulation-du-photovoltaique\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le Gouvernement met en place le nouveau cadre de r\u00e9gulation du photovolta\u00efque\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\",\"name\":\"\",\"description\":\"Le journal du monde rural\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\",\"name\":\"Gilbert\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le Gouvernement met en place le nouveau cadre de r\u00e9gulation du photovolta\u00efque -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sillon38.com\/blog\/2011\/03\/08\/le-gouvernement-met-en-place-le-nouveau-cadre-de-regulation-du-photovoltaique\/","og_locale":"fr_FR","og_type":"article","og_title":"Le Gouvernement met en place le nouveau cadre de r\u00e9gulation du photovolta\u00efque -","og_description":"pr\u00e8s consultation du Conseil sup\u00e9rieur de l\u2019\u00e9nergie et de la Commission de r\u00e9gulation de l\u2019\u00e9nergie, les textes r\u00e9glementaires sur le nouveau cadre de r\u00e9gulation du photovolta\u00efque ont \u00e9t\u00e9 publi\u00e9s au Journal officiel le 5 mars 2011.","og_url":"https:\/\/www.sillon38.com\/blog\/2011\/03\/08\/le-gouvernement-met-en-place-le-nouveau-cadre-de-regulation-du-photovoltaique\/","article_published_time":"2011-03-08T17:49:30+00:00","og_image":[{"url":"http:\/\/www.developpement-durable.gouv.fr\/IMG\/LM013076-1.jpg","type":"","width":"","height":""}],"author":"Gilbert","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Gilbert","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sillon38.com\/blog\/2011\/03\/08\/le-gouvernement-met-en-place-le-nouveau-cadre-de-regulation-du-photovoltaique\/#article","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/2011\/03\/08\/le-gouvernement-met-en-place-le-nouveau-cadre-de-regulation-du-photovoltaique\/"},"author":{"name":"Gilbert","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"headline":"Le Gouvernement met en place le nouveau cadre de r\u00e9gulation du photovolta\u00efque","datePublished":"2011-03-08T17:49:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sillon38.com\/blog\/2011\/03\/08\/le-gouvernement-met-en-place-le-nouveau-cadre-de-regulation-du-photovoltaique\/"},"wordCount":302,"commentCount":0,"image":{"@id":"https:\/\/www.sillon38.com\/blog\/2011\/03\/08\/le-gouvernement-met-en-place-le-nouveau-cadre-de-regulation-du-photovoltaique\/#primaryimage"},"thumbnailUrl":"http:\/\/www.developpement-durable.gouv.fr\/IMG\/LM013076-1.jpg","keywords":["\u00e9nergie","photovolta\u00efque"],"articleSection":["\u00e9nergies"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.sillon38.com\/blog\/2011\/03\/08\/le-gouvernement-met-en-place-le-nouveau-cadre-de-regulation-du-photovoltaique\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.sillon38.com\/blog\/2011\/03\/08\/le-gouvernement-met-en-place-le-nouveau-cadre-de-regulation-du-photovoltaique\/","url":"https:\/\/www.sillon38.com\/blog\/2011\/03\/08\/le-gouvernement-met-en-place-le-nouveau-cadre-de-regulation-du-photovoltaique\/","name":"Le Gouvernement met en place le nouveau cadre de r\u00e9gulation du photovolta\u00efque -","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sillon38.com\/blog\/2011\/03\/08\/le-gouvernement-met-en-place-le-nouveau-cadre-de-regulation-du-photovoltaique\/#primaryimage"},"image":{"@id":"https:\/\/www.sillon38.com\/blog\/2011\/03\/08\/le-gouvernement-met-en-place-le-nouveau-cadre-de-regulation-du-photovoltaique\/#primaryimage"},"thumbnailUrl":"http:\/\/www.developpement-durable.gouv.fr\/IMG\/LM013076-1.jpg","datePublished":"2011-03-08T17:49:30+00:00","author":{"@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"breadcrumb":{"@id":"https:\/\/www.sillon38.com\/blog\/2011\/03\/08\/le-gouvernement-met-en-place-le-nouveau-cadre-de-regulation-du-photovoltaique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sillon38.com\/blog\/2011\/03\/08\/le-gouvernement-met-en-place-le-nouveau-cadre-de-regulation-du-photovoltaique\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.sillon38.com\/blog\/2011\/03\/08\/le-gouvernement-met-en-place-le-nouveau-cadre-de-regulation-du-photovoltaique\/#primaryimage","url":"http:\/\/www.developpement-durable.gouv.fr\/IMG\/LM013076-1.jpg","contentUrl":"http:\/\/www.developpement-durable.gouv.fr\/IMG\/LM013076-1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.sillon38.com\/blog\/2011\/03\/08\/le-gouvernement-met-en-place-le-nouveau-cadre-de-regulation-du-photovoltaique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.sillon38.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Le Gouvernement met en place le nouveau cadre de r\u00e9gulation du photovolta\u00efque"}]},{"@type":"WebSite","@id":"https:\/\/www.sillon38.com\/blog\/#website","url":"https:\/\/www.sillon38.com\/blog\/","name":"","description":"Le journal du monde rural","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sillon38.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1","name":"Gilbert"}]}},"_links":{"self":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/21118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/comments?post=21118"}],"version-history":[{"count":0,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/21118\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/media?parent=21118"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/categories?post=21118"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/tags?post=21118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}