{"id":22177,"date":"2011-05-12T18:23:19","date_gmt":"2011-05-12T16:23:19","guid":{"rendered":"http:\/\/staging.sillon38.com\/?p=22177"},"modified":"2011-05-12T18:23:19","modified_gmt":"2011-05-12T16:23:19","slug":"les-banques-alimentaires-lancent-le-label-entreprise-solidaire-des-banques-alimentaires","status":"publish","type":"post","link":"https:\/\/www.sillon38.com\/blog\/2011\/05\/12\/les-banques-alimentaires-lancent-le-label-entreprise-solidaire-des-banques-alimentaires\/","title":{"rendered":"Les Banques Alimentaires lancent le label \u00ab Entreprise solidaire des Banques Alimentaires \u00bb"},"content":{"rendered":"<p><span style=\"color: #000000;\"><strong><em>Afin de resserrer les liens avec les entreprises engag\u00e9es \u00e0 leurs c\u00f4t\u00e9s dans la lutte contre le gaspillage alimentaire et la pr\u00e9carit\u00e9 et les remercier de cette fid\u00e9lit\u00e9, les Banques Alimentaires ont cr\u00e9\u00e9 le label \u00abEntreprise Solidaire des Banques Alimentaires\u00bb. <\/em><\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\"><strong><em><a href=\"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2011\/05\/ba-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-22178\" title=\"ba\" src=\"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2011\/05\/ba-1.jpg\" alt=\"ba\" width=\"469\" height=\"112\" srcset=\"https:\/\/www.sillon38.com\/blog\/wp-content\/uploads\/2011\/05\/ba-1.jpg 469w, https:\/\/www.sillon38.com\/blog\/wp-content\/uploads\/2011\/05\/ba-1-300x72.jpg 300w\" sizes=\"auto, (max-width: 469px) 100vw, 469px\" \/><\/a><br \/>\n<\/em><\/strong><\/span><\/p>\n<p><span style=\"color: #ff6600;\"><strong> Un engagement responsable et solidaire<\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\">Depuis de nombreuses ann\u00e9es, des entreprises soutiennent l\u2019action des Banques alimentaires et leur ont permis de moderniser leur logistique, d\u2019accro\u00eetre et de renouveler les comp\u00e9tences des \u00e9quipes, d\u2019\u00e9tendre leur communication avec un objectif commun, lutter contre la pr\u00e9carit\u00e9 et apporter une alimentation saine et vari\u00e9e aux personnes d\u00e9munies.<\/span><\/p>\n<p><span style=\"color: #000000;\">Le label \u00ab\u00a0Entreprise solidaire des Banques Alimentaires\u00a0\u00bb est lanc\u00e9 officiellement aujourd\u2019hui. Il sera remis par le pr\u00e9sident de la FFBA, Alain Seug\u00e9, \u00e0 des entreprises solidaires telles que Auchan, Axa Atout Coeur, Cargill, Fondation Carrefour, Casino, <a href=\"http:\/\/www.ca-sudrhonealpes.fr\/\"><strong><span style=\"color: #008000;\">Cr\u00e9dit Agricole<\/span><\/strong><\/a>, GrDF, Kraft Foods , Malakoff M\u00e9d\u00e9ric, M&amp;C Saatchi Gad ou Sita. <\/span><\/p>\n<p><span style=\"color: #000000;\"> <\/span><span style=\"color: #ff6600;\"><strong>Un label d\u00e9di\u00e9 aux entreprises,<\/strong><\/span><\/p>\n<p><strong> <\/strong><\/p>\n<p><span style=\"color: #000000;\">Ce label, cr\u00e9\u00e9 sp\u00e9cialement, se pr\u00e9sente sous la forme d\u2019un logo repr\u00e9sentant c\u00f4te \u00e0 c\u00f4te la Banque Alimentaire (en orange) et l\u2019entreprise m\u00e9c\u00e8ne (en gris). Il donne une identit\u00e9 visuelle et visible aux conventions de m\u00e9c\u00e9nat. Ce label pourra \u00eatre d\u00e9clin\u00e9 ensuite pour chaque Banque Alimentaire pour renforcer les accords locaux avec des entreprises.<\/span><\/p>\n<p><span style=\"color: #000000;\">\u00ab\u00a0L\u2019objectif de ce label est simple\u00a0: d\u2019une part remercier les entreprises m\u00e9c\u00e8nes qui nous soutiennent et d\u2019autre part pour elles, d\u2019afficher clairement leur engagement aux c\u00f4t\u00e9s des Banques Alimentaires.\u00a0\u00bb souligne Alain Seug\u00e9, Pr\u00e9sident de la F\u00e9d\u00e9ration fran\u00e7aise des Banques Alimentaires.<\/span><\/p>\n<p><span style=\"color: #000000;\">\u00ab\u00a0En soutenant la F\u00e9d\u00e9ration fran\u00e7aise des banques alimentaires, le Cr\u00e9dit Agricole met en pratique les valeurs mutualistes qui placent l\u2019homme au c\u0153ur des comportements \u00e9conomiques et sociaux. La pr\u00e9sence du Cr\u00e9dit Agricole au c\u0153ur des territoires permettra\u00a0de multiplier les initiatives locales \u00bb indique Bertrand Corbeau, Directeur g\u00e9n\u00e9ral de la F\u00e9d\u00e9ration nationale du Cr\u00e9dit Agricole.<\/span><\/p>\n<p><span style=\"color: #000000;\">Toutes ces entreprises accompagnement la mission des Banques Alimentaires avec un seul credo\u00a0: Ensemble, aidons l\u2019homme \u00e0 se restaurer.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Afin de resserrer les liens avec les entreprises engag\u00e9es \u00e0 leurs c\u00f4t\u00e9s dans la lutte contre le gaspillage alimentaire et la pr\u00e9carit\u00e9 et les remercier de cette fid\u00e9lit\u00e9, les Banques Alimentaires ont cr\u00e9\u00e9 le label \u00abEntreprise Solidaire des Banques Alimentaires\u00bb. <\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[80],"tags":[665,1648],"class_list":["post-22177","post","type-post","status-publish","format-standard","hentry","category-zoom","tag-banque-alimentaire","tag-credit-agricole"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les Banques Alimentaires lancent le label \u00ab Entreprise solidaire des Banques Alimentaires \u00bb -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sillon38.com\/blog\/2011\/05\/12\/les-banques-alimentaires-lancent-le-label-entreprise-solidaire-des-banques-alimentaires\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les Banques Alimentaires lancent le label \u00ab Entreprise solidaire des Banques Alimentaires \u00bb -\" \/>\n<meta property=\"og:description\" content=\"Afin de resserrer les liens avec les entreprises engag\u00e9es \u00e0 leurs c\u00f4t\u00e9s dans la lutte contre le gaspillage alimentaire et la pr\u00e9carit\u00e9 et les remercier de cette fid\u00e9lit\u00e9, les Banques Alimentaires ont cr\u00e9\u00e9 le label \u00abEntreprise Solidaire des Banques Alimentaires\u00bb.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sillon38.com\/blog\/2011\/05\/12\/les-banques-alimentaires-lancent-le-label-entreprise-solidaire-des-banques-alimentaires\/\" \/>\n<meta property=\"article:published_time\" content=\"2011-05-12T16:23:19+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2011\/05\/ba-1.jpg\" \/>\n<meta name=\"author\" content=\"Gilbert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gilbert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/05\\\/12\\\/les-banques-alimentaires-lancent-le-label-entreprise-solidaire-des-banques-alimentaires\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/05\\\/12\\\/les-banques-alimentaires-lancent-le-label-entreprise-solidaire-des-banques-alimentaires\\\/\"},\"author\":{\"name\":\"Gilbert\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"headline\":\"Les Banques Alimentaires lancent le label \u00ab Entreprise solidaire des Banques Alimentaires \u00bb\",\"datePublished\":\"2011-05-12T16:23:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/05\\\/12\\\/les-banques-alimentaires-lancent-le-label-entreprise-solidaire-des-banques-alimentaires\\\/\"},\"wordCount\":381,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/05\\\/12\\\/les-banques-alimentaires-lancent-le-label-entreprise-solidaire-des-banques-alimentaires\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/staging.sillon38.com\\\/wp-content\\\/uploads\\\/2011\\\/05\\\/ba-1.jpg\",\"keywords\":[\"banque alimentaire\",\"Cr\u00e9dit Agricole\"],\"articleSection\":[\"zoom\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/05\\\/12\\\/les-banques-alimentaires-lancent-le-label-entreprise-solidaire-des-banques-alimentaires\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/05\\\/12\\\/les-banques-alimentaires-lancent-le-label-entreprise-solidaire-des-banques-alimentaires\\\/\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/05\\\/12\\\/les-banques-alimentaires-lancent-le-label-entreprise-solidaire-des-banques-alimentaires\\\/\",\"name\":\"Les Banques Alimentaires lancent le label \u00ab Entreprise solidaire des Banques Alimentaires \u00bb -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/05\\\/12\\\/les-banques-alimentaires-lancent-le-label-entreprise-solidaire-des-banques-alimentaires\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/05\\\/12\\\/les-banques-alimentaires-lancent-le-label-entreprise-solidaire-des-banques-alimentaires\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/staging.sillon38.com\\\/wp-content\\\/uploads\\\/2011\\\/05\\\/ba-1.jpg\",\"datePublished\":\"2011-05-12T16:23:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/05\\\/12\\\/les-banques-alimentaires-lancent-le-label-entreprise-solidaire-des-banques-alimentaires\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/05\\\/12\\\/les-banques-alimentaires-lancent-le-label-entreprise-solidaire-des-banques-alimentaires\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/05\\\/12\\\/les-banques-alimentaires-lancent-le-label-entreprise-solidaire-des-banques-alimentaires\\\/#primaryimage\",\"url\":\"http:\\\/\\\/staging.sillon38.com\\\/wp-content\\\/uploads\\\/2011\\\/05\\\/ba-1.jpg\",\"contentUrl\":\"http:\\\/\\\/staging.sillon38.com\\\/wp-content\\\/uploads\\\/2011\\\/05\\\/ba-1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2011\\\/05\\\/12\\\/les-banques-alimentaires-lancent-le-label-entreprise-solidaire-des-banques-alimentaires\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les Banques Alimentaires lancent le label \u00ab Entreprise solidaire des Banques Alimentaires \u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\",\"name\":\"\",\"description\":\"Le journal du monde rural\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\",\"name\":\"Gilbert\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les Banques Alimentaires lancent le label \u00ab Entreprise solidaire des Banques Alimentaires \u00bb -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sillon38.com\/blog\/2011\/05\/12\/les-banques-alimentaires-lancent-le-label-entreprise-solidaire-des-banques-alimentaires\/","og_locale":"fr_FR","og_type":"article","og_title":"Les Banques Alimentaires lancent le label \u00ab Entreprise solidaire des Banques Alimentaires \u00bb -","og_description":"Afin de resserrer les liens avec les entreprises engag\u00e9es \u00e0 leurs c\u00f4t\u00e9s dans la lutte contre le gaspillage alimentaire et la pr\u00e9carit\u00e9 et les remercier de cette fid\u00e9lit\u00e9, les Banques Alimentaires ont cr\u00e9\u00e9 le label \u00abEntreprise Solidaire des Banques Alimentaires\u00bb.","og_url":"https:\/\/www.sillon38.com\/blog\/2011\/05\/12\/les-banques-alimentaires-lancent-le-label-entreprise-solidaire-des-banques-alimentaires\/","article_published_time":"2011-05-12T16:23:19+00:00","og_image":[{"url":"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2011\/05\/ba-1.jpg","type":"","width":"","height":""}],"author":"Gilbert","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Gilbert","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sillon38.com\/blog\/2011\/05\/12\/les-banques-alimentaires-lancent-le-label-entreprise-solidaire-des-banques-alimentaires\/#article","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/2011\/05\/12\/les-banques-alimentaires-lancent-le-label-entreprise-solidaire-des-banques-alimentaires\/"},"author":{"name":"Gilbert","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"headline":"Les Banques Alimentaires lancent le label \u00ab Entreprise solidaire des Banques Alimentaires \u00bb","datePublished":"2011-05-12T16:23:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sillon38.com\/blog\/2011\/05\/12\/les-banques-alimentaires-lancent-le-label-entreprise-solidaire-des-banques-alimentaires\/"},"wordCount":381,"commentCount":0,"image":{"@id":"https:\/\/www.sillon38.com\/blog\/2011\/05\/12\/les-banques-alimentaires-lancent-le-label-entreprise-solidaire-des-banques-alimentaires\/#primaryimage"},"thumbnailUrl":"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2011\/05\/ba-1.jpg","keywords":["banque alimentaire","Cr\u00e9dit Agricole"],"articleSection":["zoom"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.sillon38.com\/blog\/2011\/05\/12\/les-banques-alimentaires-lancent-le-label-entreprise-solidaire-des-banques-alimentaires\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.sillon38.com\/blog\/2011\/05\/12\/les-banques-alimentaires-lancent-le-label-entreprise-solidaire-des-banques-alimentaires\/","url":"https:\/\/www.sillon38.com\/blog\/2011\/05\/12\/les-banques-alimentaires-lancent-le-label-entreprise-solidaire-des-banques-alimentaires\/","name":"Les Banques Alimentaires lancent le label \u00ab Entreprise solidaire des Banques Alimentaires \u00bb -","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sillon38.com\/blog\/2011\/05\/12\/les-banques-alimentaires-lancent-le-label-entreprise-solidaire-des-banques-alimentaires\/#primaryimage"},"image":{"@id":"https:\/\/www.sillon38.com\/blog\/2011\/05\/12\/les-banques-alimentaires-lancent-le-label-entreprise-solidaire-des-banques-alimentaires\/#primaryimage"},"thumbnailUrl":"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2011\/05\/ba-1.jpg","datePublished":"2011-05-12T16:23:19+00:00","author":{"@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"breadcrumb":{"@id":"https:\/\/www.sillon38.com\/blog\/2011\/05\/12\/les-banques-alimentaires-lancent-le-label-entreprise-solidaire-des-banques-alimentaires\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sillon38.com\/blog\/2011\/05\/12\/les-banques-alimentaires-lancent-le-label-entreprise-solidaire-des-banques-alimentaires\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.sillon38.com\/blog\/2011\/05\/12\/les-banques-alimentaires-lancent-le-label-entreprise-solidaire-des-banques-alimentaires\/#primaryimage","url":"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2011\/05\/ba-1.jpg","contentUrl":"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2011\/05\/ba-1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.sillon38.com\/blog\/2011\/05\/12\/les-banques-alimentaires-lancent-le-label-entreprise-solidaire-des-banques-alimentaires\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.sillon38.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Les Banques Alimentaires lancent le label \u00ab Entreprise solidaire des Banques Alimentaires \u00bb"}]},{"@type":"WebSite","@id":"https:\/\/www.sillon38.com\/blog\/#website","url":"https:\/\/www.sillon38.com\/blog\/","name":"","description":"Le journal du monde rural","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sillon38.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1","name":"Gilbert"}]}},"_links":{"self":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/22177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/comments?post=22177"}],"version-history":[{"count":0,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/22177\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/media?parent=22177"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/categories?post=22177"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/tags?post=22177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}