{"id":2771,"date":"2008-05-22T22:23:49","date_gmt":"2008-05-22T20:23:49","guid":{"rendered":"http:\/\/staging.sillon38.com\/2008\/05\/22\/journees-de-ramassage-des-dechets-en-montagne\/"},"modified":"2008-05-22T22:23:49","modified_gmt":"2008-05-22T20:23:49","slug":"journees-de-ramassage-des-dechets-en-montagne","status":"publish","type":"post","link":"https:\/\/www.sillon38.com\/blog\/2008\/05\/22\/journees-de-ramassage-des-dechets-en-montagne\/","title":{"rendered":"Journ\u00e9es de ramassage des d\u00e9chets en montagne"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2008\/05\/bandeau-nettoyage.jpg\" alt=\"bandeau-nettoyage.jpg\" \/><\/p>\n<p><img decoding=\"async\" src=\"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2008\/05\/nettoyage.jpg\" alt=\"nettoyage.jpg\" \/><\/p>\n<p>23 mai : Collet d\u2019Allevard, Lyc\u00e9e de Meylan, www.lgm.ac-grenoble.fr<\/p>\n<p>24 mai : St Martin de Belleville, Mairie, www.mairie-smb.com<br \/>\nCol de Porte, www.chartreusepropre.org<br \/>\nLes Gets, Remont\u00e9es M\u00e9caniques, www.sagets.fr<br \/>\nLa Bresse, Mairie, www.labresse.net<br \/>\nNouvelle Z\u00e9lande, Arthur\u2019s Pass, www.arianlemal.fr<\/p>\n<p>25 mai : Alpes du Grand Serre, OT et Fend la Bise, www.alpedugrandserre.net<br \/>\nCh\u00e2tel, Kulture Montagne, www.bellesplantes.canalblog.com<br \/>\nLac Blanc, La Delirium Tribu, www.deliriumtribu.com<br \/>\nGrand Bornand, Adh\u00e9rente MR et mairie, www.legrandbornand.com<\/p>\n<p>28\/29 mai : Serre Chevalier, Domaine Skiable, www.serre-chevalier.com<\/p>\n<p>31 mai : La Mongie, Mathieu Crepel, www.mathieucrepel.com<\/p>\n<p>1er Juin : Morillon Village, Office de tourisme, www.ot-morillon.fr<br \/>\nLa Plagne, Office de tourisme et adh\u00e9rente MR, www.la-plagne.com<br \/>\nBeille, Office de tourisme, www.beille.fr<\/p>\n<p>7 juin : St Jean d\u2019Aulps, Remont\u00e9es M\u00e9caniques, www.saintjeandaulps.com<\/p>\n<p>8 juin : Val d\u2019Allos, Office de tourisme, www.valdallos.com<br \/>\nLans en Vercors, La Passerelle<\/p>\n<p>16 juin : Valmorel, Domaine Skiable, www.valmorel.com<\/p>\n<p>21 juin : Tignes, Eko-Tignes &amp; Co, www.tignes.net Val d\u2019Is\u00e8re, VieValdis, www.association-vievaldis.org<\/p>\n<p>28 juin : Pralognan en Vanoise, Sivom de Bozel, www.sivomdebozel.info<\/p>\n<p>8 juillet : Les Arcs, L\u2019Esprit des Arcs et Antenne MR, www.espritdesarcs.fr<\/p>\n<p>11 juillet : Morillon 1110 Les Esserts, Office de tourisme, www.ot-morillon.fr<\/p>\n<p><strong>Dates \u00e0 confirmer :<\/strong><br \/>\nAuron \/ Chamonix \/ La Clusaz \/ Les Deux Alpes \/ M\u00e9ribel \/ Sept Laux \/ Chamrousse \/ Valloire \/ Valmorel \/ La Rosi\u00e8re \/ Vaujany \/ Ar\u00e8ches Beaufort \/ Le Champsaur \/<br \/>\nLe Queyras \/  Font Romeu \/ Les Angles \/ Valloire \/ Gerardmer<\/p>\n<p>Renseignements : <a href=\"http:\/\/www.mountain-riders.org\">mountain-rider.org <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>23 mai : Collet d\u2019Allevard, Lyc\u00e9e de Meylan, www.lgm.ac-grenoble.fr 24 mai : St Martin de Belleville, Mairie, www.mairie-smb.com Col de Porte, www.chartreusepropre.org Les Gets, Remont\u00e9es M\u00e9caniques, www.sagets.fr La Bresse, Mairie, www.labresse.net Nouvelle Z\u00e9lande, Arthur\u2019s Pass, www.arianlemal.fr 25 mai : Alpes&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[97],"tags":[],"class_list":["post-2771","post","type-post","status-publish","format-standard","hentry","category-dechets"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Journ\u00e9es de ramassage des d\u00e9chets en montagne -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sillon38.com\/blog\/2008\/05\/22\/journees-de-ramassage-des-dechets-en-montagne\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Journ\u00e9es de ramassage des d\u00e9chets en montagne -\" \/>\n<meta property=\"og:description\" content=\"23 mai : Collet d\u2019Allevard, Lyc\u00e9e de Meylan, www.lgm.ac-grenoble.fr 24 mai : St Martin de Belleville, Mairie, www.mairie-smb.com Col de Porte, www.chartreusepropre.org Les Gets, Remont\u00e9es M\u00e9caniques, www.sagets.fr La Bresse, Mairie, www.labresse.net Nouvelle Z\u00e9lande, Arthur\u2019s Pass, www.arianlemal.fr 25 mai : Alpes...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sillon38.com\/blog\/2008\/05\/22\/journees-de-ramassage-des-dechets-en-montagne\/\" \/>\n<meta property=\"article:published_time\" content=\"2008-05-22T20:23:49+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2008\/05\/bandeau-nettoyage.jpg\" \/>\n<meta name=\"author\" content=\"Gilbert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gilbert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2008\\\/05\\\/22\\\/journees-de-ramassage-des-dechets-en-montagne\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2008\\\/05\\\/22\\\/journees-de-ramassage-des-dechets-en-montagne\\\/\"},\"author\":{\"name\":\"Gilbert\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"headline\":\"Journ\u00e9es de ramassage des d\u00e9chets en montagne\",\"datePublished\":\"2008-05-22T20:23:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2008\\\/05\\\/22\\\/journees-de-ramassage-des-dechets-en-montagne\\\/\"},\"wordCount\":263,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2008\\\/05\\\/22\\\/journees-de-ramassage-des-dechets-en-montagne\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/staging.sillon38.com\\\/wp-content\\\/uploads\\\/2008\\\/05\\\/bandeau-nettoyage.jpg\",\"articleSection\":[\"d\u00e9chets\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2008\\\/05\\\/22\\\/journees-de-ramassage-des-dechets-en-montagne\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2008\\\/05\\\/22\\\/journees-de-ramassage-des-dechets-en-montagne\\\/\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2008\\\/05\\\/22\\\/journees-de-ramassage-des-dechets-en-montagne\\\/\",\"name\":\"Journ\u00e9es de ramassage des d\u00e9chets en montagne -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2008\\\/05\\\/22\\\/journees-de-ramassage-des-dechets-en-montagne\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2008\\\/05\\\/22\\\/journees-de-ramassage-des-dechets-en-montagne\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/staging.sillon38.com\\\/wp-content\\\/uploads\\\/2008\\\/05\\\/bandeau-nettoyage.jpg\",\"datePublished\":\"2008-05-22T20:23:49+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2008\\\/05\\\/22\\\/journees-de-ramassage-des-dechets-en-montagne\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2008\\\/05\\\/22\\\/journees-de-ramassage-des-dechets-en-montagne\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2008\\\/05\\\/22\\\/journees-de-ramassage-des-dechets-en-montagne\\\/#primaryimage\",\"url\":\"http:\\\/\\\/staging.sillon38.com\\\/wp-content\\\/uploads\\\/2008\\\/05\\\/bandeau-nettoyage.jpg\",\"contentUrl\":\"http:\\\/\\\/staging.sillon38.com\\\/wp-content\\\/uploads\\\/2008\\\/05\\\/bandeau-nettoyage.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2008\\\/05\\\/22\\\/journees-de-ramassage-des-dechets-en-montagne\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Journ\u00e9es de ramassage des d\u00e9chets en montagne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\",\"name\":\"\",\"description\":\"Le journal du monde rural\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\",\"name\":\"Gilbert\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Journ\u00e9es de ramassage des d\u00e9chets en montagne -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sillon38.com\/blog\/2008\/05\/22\/journees-de-ramassage-des-dechets-en-montagne\/","og_locale":"fr_FR","og_type":"article","og_title":"Journ\u00e9es de ramassage des d\u00e9chets en montagne -","og_description":"23 mai : Collet d\u2019Allevard, Lyc\u00e9e de Meylan, www.lgm.ac-grenoble.fr 24 mai : St Martin de Belleville, Mairie, www.mairie-smb.com Col de Porte, www.chartreusepropre.org Les Gets, Remont\u00e9es M\u00e9caniques, www.sagets.fr La Bresse, Mairie, www.labresse.net Nouvelle Z\u00e9lande, Arthur\u2019s Pass, www.arianlemal.fr 25 mai : Alpes...","og_url":"https:\/\/www.sillon38.com\/blog\/2008\/05\/22\/journees-de-ramassage-des-dechets-en-montagne\/","article_published_time":"2008-05-22T20:23:49+00:00","og_image":[{"url":"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2008\/05\/bandeau-nettoyage.jpg","type":"","width":"","height":""}],"author":"Gilbert","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Gilbert","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sillon38.com\/blog\/2008\/05\/22\/journees-de-ramassage-des-dechets-en-montagne\/#article","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/2008\/05\/22\/journees-de-ramassage-des-dechets-en-montagne\/"},"author":{"name":"Gilbert","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"headline":"Journ\u00e9es de ramassage des d\u00e9chets en montagne","datePublished":"2008-05-22T20:23:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sillon38.com\/blog\/2008\/05\/22\/journees-de-ramassage-des-dechets-en-montagne\/"},"wordCount":263,"commentCount":0,"image":{"@id":"https:\/\/www.sillon38.com\/blog\/2008\/05\/22\/journees-de-ramassage-des-dechets-en-montagne\/#primaryimage"},"thumbnailUrl":"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2008\/05\/bandeau-nettoyage.jpg","articleSection":["d\u00e9chets"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.sillon38.com\/blog\/2008\/05\/22\/journees-de-ramassage-des-dechets-en-montagne\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.sillon38.com\/blog\/2008\/05\/22\/journees-de-ramassage-des-dechets-en-montagne\/","url":"https:\/\/www.sillon38.com\/blog\/2008\/05\/22\/journees-de-ramassage-des-dechets-en-montagne\/","name":"Journ\u00e9es de ramassage des d\u00e9chets en montagne -","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sillon38.com\/blog\/2008\/05\/22\/journees-de-ramassage-des-dechets-en-montagne\/#primaryimage"},"image":{"@id":"https:\/\/www.sillon38.com\/blog\/2008\/05\/22\/journees-de-ramassage-des-dechets-en-montagne\/#primaryimage"},"thumbnailUrl":"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2008\/05\/bandeau-nettoyage.jpg","datePublished":"2008-05-22T20:23:49+00:00","author":{"@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"breadcrumb":{"@id":"https:\/\/www.sillon38.com\/blog\/2008\/05\/22\/journees-de-ramassage-des-dechets-en-montagne\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sillon38.com\/blog\/2008\/05\/22\/journees-de-ramassage-des-dechets-en-montagne\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.sillon38.com\/blog\/2008\/05\/22\/journees-de-ramassage-des-dechets-en-montagne\/#primaryimage","url":"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2008\/05\/bandeau-nettoyage.jpg","contentUrl":"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2008\/05\/bandeau-nettoyage.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.sillon38.com\/blog\/2008\/05\/22\/journees-de-ramassage-des-dechets-en-montagne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.sillon38.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Journ\u00e9es de ramassage des d\u00e9chets en montagne"}]},{"@type":"WebSite","@id":"https:\/\/www.sillon38.com\/blog\/#website","url":"https:\/\/www.sillon38.com\/blog\/","name":"","description":"Le journal du monde rural","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sillon38.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1","name":"Gilbert"}]}},"_links":{"self":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/2771","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/comments?post=2771"}],"version-history":[{"count":0,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/2771\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/media?parent=2771"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/categories?post=2771"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/tags?post=2771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}