{"id":3213,"date":"2008-07-01T13:25:55","date_gmt":"2008-07-01T11:25:55","guid":{"rendered":"http:\/\/staging.sillon38.com\/2008\/07\/01\/ferme\/"},"modified":"2008-07-01T13:25:55","modified_gmt":"2008-07-01T11:25:55","slug":"ferme","status":"publish","type":"post","link":"https:\/\/www.sillon38.com\/blog\/2008\/07\/01\/ferme\/","title":{"rendered":"La cl\u00e9 sous la porte"},"content":{"rendered":"<p>Comme pr\u00e9vu, les derni\u00e8res b\u00eates sont entr\u00e9es \u00e0 l&rsquo;abattoir vendredi dernier et les carcasses sont reparties ce lundi et ce mardi 2 juillet avant midi. Une matin\u00e9e de mardi ou le directeur de l&rsquo;abattoir, Jean-Marc Vallet a re\u00e7u individuellement les salari\u00e9s afin de leur faire part des diff\u00e9rentes modalit\u00e9s de licenciements, leurs droits, des possibilit\u00e9s d&rsquo;avenir&#8230;<\/p>\n<p>Les portes de l&rsquo;abattoir sont d\u00e9finitivement ferm\u00e9es. Charge \u00e0 J.M. Vallet de s&rsquo;occuper des derniers dossiers tels la vente du mat\u00e9riel. Il a jusqu&rsquo;\u00e0 fin ao\u00fbt pur remplir cette t\u00e2che.<\/p>\n<p>Une page vient de se tourner dans le monde de la viande!<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2008\/07\/la-cote.jpg\" alt=\"la-cote.jpg\" \/><\/p>\n<p><em>Il est peu avant midi, ce mardi 2 juillet 2008, les derni\u00e8res carcasses vont quitter l&rsquo;abattoir. Dans quelques minutes, l&rsquo;abattoir de La C\u00f4te aura v\u00e9cu!<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comme pr\u00e9vu, les derni\u00e8res b\u00eates sont entr\u00e9es \u00e0 l&rsquo;abattoir vendredi dernier et les carcasses sont reparties ce lundi et ce mardi 2 juillet avant midi. Une matin\u00e9e de mardi ou le directeur de l&rsquo;abattoir, Jean-Marc Vallet a re\u00e7u individuellement les&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-3213","post","type-post","status-publish","format-standard","hentry","category-filiere-viande"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La cl\u00e9 sous la porte -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sillon38.com\/blog\/2008\/07\/01\/ferme\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La cl\u00e9 sous la porte -\" \/>\n<meta property=\"og:description\" content=\"Comme pr\u00e9vu, les derni\u00e8res b\u00eates sont entr\u00e9es \u00e0 l&rsquo;abattoir vendredi dernier et les carcasses sont reparties ce lundi et ce mardi 2 juillet avant midi. Une matin\u00e9e de mardi ou le directeur de l&rsquo;abattoir, Jean-Marc Vallet a re\u00e7u individuellement les...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sillon38.com\/blog\/2008\/07\/01\/ferme\/\" \/>\n<meta property=\"article:published_time\" content=\"2008-07-01T11:25:55+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2008\/07\/la-cote.jpg\" \/>\n<meta name=\"author\" content=\"Gilbert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gilbert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2008\\\/07\\\/01\\\/ferme\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2008\\\/07\\\/01\\\/ferme\\\/\"},\"author\":{\"name\":\"Gilbert\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"headline\":\"La cl\u00e9 sous la porte\",\"datePublished\":\"2008-07-01T11:25:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2008\\\/07\\\/01\\\/ferme\\\/\"},\"wordCount\":149,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2008\\\/07\\\/01\\\/ferme\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/staging.sillon38.com\\\/wp-content\\\/uploads\\\/2008\\\/07\\\/la-cote.jpg\",\"articleSection\":[\"fili\u00e8re viande\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2008\\\/07\\\/01\\\/ferme\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2008\\\/07\\\/01\\\/ferme\\\/\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2008\\\/07\\\/01\\\/ferme\\\/\",\"name\":\"La cl\u00e9 sous la porte -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2008\\\/07\\\/01\\\/ferme\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2008\\\/07\\\/01\\\/ferme\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/staging.sillon38.com\\\/wp-content\\\/uploads\\\/2008\\\/07\\\/la-cote.jpg\",\"datePublished\":\"2008-07-01T11:25:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2008\\\/07\\\/01\\\/ferme\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2008\\\/07\\\/01\\\/ferme\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2008\\\/07\\\/01\\\/ferme\\\/#primaryimage\",\"url\":\"http:\\\/\\\/staging.sillon38.com\\\/wp-content\\\/uploads\\\/2008\\\/07\\\/la-cote.jpg\",\"contentUrl\":\"http:\\\/\\\/staging.sillon38.com\\\/wp-content\\\/uploads\\\/2008\\\/07\\\/la-cote.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2008\\\/07\\\/01\\\/ferme\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La cl\u00e9 sous la porte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\",\"name\":\"\",\"description\":\"Le journal du monde rural\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\",\"name\":\"Gilbert\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La cl\u00e9 sous la porte -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sillon38.com\/blog\/2008\/07\/01\/ferme\/","og_locale":"fr_FR","og_type":"article","og_title":"La cl\u00e9 sous la porte -","og_description":"Comme pr\u00e9vu, les derni\u00e8res b\u00eates sont entr\u00e9es \u00e0 l&rsquo;abattoir vendredi dernier et les carcasses sont reparties ce lundi et ce mardi 2 juillet avant midi. Une matin\u00e9e de mardi ou le directeur de l&rsquo;abattoir, Jean-Marc Vallet a re\u00e7u individuellement les...","og_url":"https:\/\/www.sillon38.com\/blog\/2008\/07\/01\/ferme\/","article_published_time":"2008-07-01T11:25:55+00:00","og_image":[{"url":"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2008\/07\/la-cote.jpg","type":"","width":"","height":""}],"author":"Gilbert","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Gilbert","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sillon38.com\/blog\/2008\/07\/01\/ferme\/#article","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/2008\/07\/01\/ferme\/"},"author":{"name":"Gilbert","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"headline":"La cl\u00e9 sous la porte","datePublished":"2008-07-01T11:25:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sillon38.com\/blog\/2008\/07\/01\/ferme\/"},"wordCount":149,"commentCount":0,"image":{"@id":"https:\/\/www.sillon38.com\/blog\/2008\/07\/01\/ferme\/#primaryimage"},"thumbnailUrl":"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2008\/07\/la-cote.jpg","articleSection":["fili\u00e8re viande"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.sillon38.com\/blog\/2008\/07\/01\/ferme\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.sillon38.com\/blog\/2008\/07\/01\/ferme\/","url":"https:\/\/www.sillon38.com\/blog\/2008\/07\/01\/ferme\/","name":"La cl\u00e9 sous la porte -","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sillon38.com\/blog\/2008\/07\/01\/ferme\/#primaryimage"},"image":{"@id":"https:\/\/www.sillon38.com\/blog\/2008\/07\/01\/ferme\/#primaryimage"},"thumbnailUrl":"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2008\/07\/la-cote.jpg","datePublished":"2008-07-01T11:25:55+00:00","author":{"@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"breadcrumb":{"@id":"https:\/\/www.sillon38.com\/blog\/2008\/07\/01\/ferme\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sillon38.com\/blog\/2008\/07\/01\/ferme\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.sillon38.com\/blog\/2008\/07\/01\/ferme\/#primaryimage","url":"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2008\/07\/la-cote.jpg","contentUrl":"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2008\/07\/la-cote.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.sillon38.com\/blog\/2008\/07\/01\/ferme\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.sillon38.com\/blog\/"},{"@type":"ListItem","position":2,"name":"La cl\u00e9 sous la porte"}]},{"@type":"WebSite","@id":"https:\/\/www.sillon38.com\/blog\/#website","url":"https:\/\/www.sillon38.com\/blog\/","name":"","description":"Le journal du monde rural","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sillon38.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1","name":"Gilbert"}]}},"_links":{"self":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/3213","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/comments?post=3213"}],"version-history":[{"count":0,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/3213\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/media?parent=3213"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/categories?post=3213"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/tags?post=3213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}