{"id":33509,"date":"2013-01-08T13:27:23","date_gmt":"2013-01-08T11:27:23","guid":{"rendered":"http:\/\/staging.sillon38.com\/?p=33509"},"modified":"2013-01-08T13:27:23","modified_gmt":"2013-01-08T11:27:23","slug":"pays-voironnais-une-plateforme-pour-valoriser-le-bois-local","status":"publish","type":"post","link":"https:\/\/www.sillon38.com\/blog\/2013\/01\/08\/pays-voironnais-une-plateforme-pour-valoriser-le-bois-local\/","title":{"rendered":"Pays voironnais: une plateforme pour valoriser le bois local"},"content":{"rendered":"<p><span style=\"color: #000080;\">La plateforme de bois d\u00e9chiquet\u00e9 r\u00e9alis\u00e9e par le Pays Voironnais est op\u00e9rationnelle depuis plus d\u2019un an.<\/span><\/p>\n<p><span style=\"color: #000080;\"> Situ\u00e9e en bout de la zone d\u2019activit\u00e9 \u00e9conomique du Bas Guillermet \u00e0 Charavines, elle sert \u00e0 valoriser le bois local en plaquettes foresti\u00e8res. Sur une surface de 8 000 m\u00b2, la plateforme assure donc le broyage de coupes de bois des communes alentours, notamment Bilieu et Le Pin.<\/span><\/p>\n<p><span style=\"color: #000080;\"> Lely Environnement, \u00e0 qui la gestion en a \u00e9t\u00e9 confi\u00e9e, est d\u2019ailleurs charg\u00e9 de veiller \u00e0 la tra\u00e7abilit\u00e9 du bois et \u00e0 sa qualit\u00e9, afin de privil\u00e9gier l\u2019approvisionnement local. <\/span><\/p>\n<p><span style=\"color: #000080;\">Une fois produites, les plaquettes foresti\u00e8res sont s\u00e9ch\u00e9es \u00e0 l\u2019abri des intemp\u00e9ries dans un hangar d\u00e9di\u00e9 \u00e0 cet effet. D\u2019une surface de 1000 m2 au sol, il peut ainsi accueillir 4\u00a0000 m3 de bois soit environ 1200 tonnes. Les plaquettes peuvent ensuite \u00eatre livr\u00e9es aupr\u00e8s des chaufferies du territoire et \u00e0 proximit\u00e9 (dans un rayon de 30 km), dont la consommation est actuellement d\u2019environ 2000 tonnes dont 1200 rien que sur le Pays Voironnais. <\/span><\/p>\n<p><span style=\"color: #000080;\"> Avec des perspectives de d\u00e9veloppement importantes des collectivit\u00e9s voire de l\u2019habitat collectif, cet \u00e9quipement vient contribuer au d\u00e9veloppement d\u2019une fili\u00e8re bois \u00e9conomiquement viable en s\u2019appuyant sur le fort potentiel local.<\/span><\/p>\n<p><span style=\"color: #000080;\"> Le territoire est en effet couvert \u00e0 31% par la for\u00eat, qui est \u00e0 ce jour peu exploit\u00e9e, avec des parcelles de bois d\u2019\u0153uvre inexploitables en l\u2019\u00e9tat. Gr\u00e2ce \u00e0 des coupes d\u2019am\u00e9lioration des espaces forestiers et de celles de bois d\u00e9class\u00e9 non utilisable pour d\u2019autres usages, le Pays Voironnais mise ainsi sur le bois \u00e9nergie, pour cr\u00e9er une dynamique globale autour de la for\u00eat et aussi contribuer au d\u00e9veloppement des \u00e9nergies renouvelables sur le territoire et \u00e0 l\u2019am\u00e9lioration de l\u2019autonomie \u00e9nerg\u00e9tique du territoire. <\/span><\/p>\n<blockquote><p><span style=\"color: #000080;\"> <strong>P\u00f4le d\u2019Excellence Rurale<\/strong><\/span><\/p>\n<p><span style=\"color: #000080;\">La plateforme de bois d\u00e9chiquet\u00e9 du Pays Voironnais s\u2019inscrit dans le cadre du P\u00f4le d\u2019Excellence Rurale \u00ab bois \u00e9nergie \u00bb, men\u00e9 en partenariat avec le Parc Naturel de Chartreuse, et destin\u00e9 \u00e0 valoriser la ressource foresti\u00e8re et aider \u00e0 structurer la fili\u00e8re bois locale, tout en cr\u00e9ant des emplois en zone rurale et en favorisant l\u2019utilisation d\u2019une \u00e9nergie renouvelable.<\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p><\/blockquote>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<p><span style=\"color: #000080;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-33510\" title=\"charavines\" src=\"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2013\/01\/charavines-1.png\" alt=\"charavines\" width=\"595\" height=\"466\" srcset=\"https:\/\/www.sillon38.com\/blog\/wp-content\/uploads\/2013\/01\/charavines-1.png 595w, https:\/\/www.sillon38.com\/blog\/wp-content\/uploads\/2013\/01\/charavines-1-300x235.png 300w\" sizes=\"auto, (max-width: 595px) 100vw, 595px\" \/><\/span><\/p>\n<p><span style=\"color: #000080;\">L&rsquo;inauguration de cette plateforme a \u00e9t\u00e9 inaugur\u00e9 par Jean-Paul Bret, Pr\u00e9sident de la Communaut\u00e9\u00a0 du Pays Voironnais, Roland Revil, 1<sup>er<\/sup> Vice Pr\u00e9sident charg\u00e9 du p\u00f4le d\u00e9veloppement \u00e9conomique,\u00a0 Charles Bazus, Vice-Pr\u00e9sident charg\u00e9 de l\u2019agriculture, de la for\u00eat et du d\u00e9veloppement rural et en pr\u00e9sence en particulier de Mich\u00e8le Bonneton d\u00e9put\u00e9e, Eliane Giraud conseill\u00e8re R\u00e9gionale et pr\u00e9sidente du Parc R\u00e9gional de chartreuse. Chacun a soulign\u00e9 l&rsquo;importance d&rsquo;une telle initiative qui valorise le bois local <\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La plateforme de bois d\u00e9chiquet\u00e9 r\u00e9alis\u00e9e par le Pays Voironnais est op\u00e9rationnelle valorise le bois local \u00e0 travers des plaquettes foresti\u00e8res.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[81,28],"tags":[2024,4119,4210],"class_list":["post-33509","post","type-post","status-publish","format-standard","hentry","category-filierebois","category-foret","tag-eliane-giraud","tag-parc-de-chartreuse","tag-pays-voironnais"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pays voironnais: une plateforme pour valoriser le bois local -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sillon38.com\/blog\/2013\/01\/08\/pays-voironnais-une-plateforme-pour-valoriser-le-bois-local\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pays voironnais: une plateforme pour valoriser le bois local -\" \/>\n<meta property=\"og:description\" content=\"La plateforme de bois d\u00e9chiquet\u00e9 r\u00e9alis\u00e9e par le Pays Voironnais est op\u00e9rationnelle valorise le bois local \u00e0 travers des plaquettes foresti\u00e8res.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sillon38.com\/blog\/2013\/01\/08\/pays-voironnais-une-plateforme-pour-valoriser-le-bois-local\/\" \/>\n<meta property=\"article:published_time\" content=\"2013-01-08T11:27:23+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2013\/01\/charavines-1.png\" \/>\n<meta name=\"author\" content=\"Gilbert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gilbert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2013\\\/01\\\/08\\\/pays-voironnais-une-plateforme-pour-valoriser-le-bois-local\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2013\\\/01\\\/08\\\/pays-voironnais-une-plateforme-pour-valoriser-le-bois-local\\\/\"},\"author\":{\"name\":\"Gilbert\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"headline\":\"Pays voironnais: une plateforme pour valoriser le bois local\",\"datePublished\":\"2013-01-08T11:27:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2013\\\/01\\\/08\\\/pays-voironnais-une-plateforme-pour-valoriser-le-bois-local\\\/\"},\"wordCount\":474,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2013\\\/01\\\/08\\\/pays-voironnais-une-plateforme-pour-valoriser-le-bois-local\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/staging.sillon38.com\\\/wp-content\\\/uploads\\\/2013\\\/01\\\/charavines-1.png\",\"keywords\":[\"Eliane Giraud\",\"Parc de Chartreuse\",\"pays voironnais\"],\"articleSection\":[\"- fili\u00e8re bois\",\"for\u00eat\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2013\\\/01\\\/08\\\/pays-voironnais-une-plateforme-pour-valoriser-le-bois-local\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2013\\\/01\\\/08\\\/pays-voironnais-une-plateforme-pour-valoriser-le-bois-local\\\/\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2013\\\/01\\\/08\\\/pays-voironnais-une-plateforme-pour-valoriser-le-bois-local\\\/\",\"name\":\"Pays voironnais: une plateforme pour valoriser le bois local -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2013\\\/01\\\/08\\\/pays-voironnais-une-plateforme-pour-valoriser-le-bois-local\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2013\\\/01\\\/08\\\/pays-voironnais-une-plateforme-pour-valoriser-le-bois-local\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/staging.sillon38.com\\\/wp-content\\\/uploads\\\/2013\\\/01\\\/charavines-1.png\",\"datePublished\":\"2013-01-08T11:27:23+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2013\\\/01\\\/08\\\/pays-voironnais-une-plateforme-pour-valoriser-le-bois-local\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2013\\\/01\\\/08\\\/pays-voironnais-une-plateforme-pour-valoriser-le-bois-local\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2013\\\/01\\\/08\\\/pays-voironnais-une-plateforme-pour-valoriser-le-bois-local\\\/#primaryimage\",\"url\":\"http:\\\/\\\/staging.sillon38.com\\\/wp-content\\\/uploads\\\/2013\\\/01\\\/charavines-1.png\",\"contentUrl\":\"http:\\\/\\\/staging.sillon38.com\\\/wp-content\\\/uploads\\\/2013\\\/01\\\/charavines-1.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2013\\\/01\\\/08\\\/pays-voironnais-une-plateforme-pour-valoriser-le-bois-local\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pays voironnais: une plateforme pour valoriser le bois local\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\",\"name\":\"\",\"description\":\"Le journal du monde rural\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\",\"name\":\"Gilbert\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pays voironnais: une plateforme pour valoriser le bois local -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sillon38.com\/blog\/2013\/01\/08\/pays-voironnais-une-plateforme-pour-valoriser-le-bois-local\/","og_locale":"fr_FR","og_type":"article","og_title":"Pays voironnais: une plateforme pour valoriser le bois local -","og_description":"La plateforme de bois d\u00e9chiquet\u00e9 r\u00e9alis\u00e9e par le Pays Voironnais est op\u00e9rationnelle valorise le bois local \u00e0 travers des plaquettes foresti\u00e8res.","og_url":"https:\/\/www.sillon38.com\/blog\/2013\/01\/08\/pays-voironnais-une-plateforme-pour-valoriser-le-bois-local\/","article_published_time":"2013-01-08T11:27:23+00:00","og_image":[{"url":"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2013\/01\/charavines-1.png","type":"","width":"","height":""}],"author":"Gilbert","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Gilbert","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sillon38.com\/blog\/2013\/01\/08\/pays-voironnais-une-plateforme-pour-valoriser-le-bois-local\/#article","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/2013\/01\/08\/pays-voironnais-une-plateforme-pour-valoriser-le-bois-local\/"},"author":{"name":"Gilbert","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"headline":"Pays voironnais: une plateforme pour valoriser le bois local","datePublished":"2013-01-08T11:27:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sillon38.com\/blog\/2013\/01\/08\/pays-voironnais-une-plateforme-pour-valoriser-le-bois-local\/"},"wordCount":474,"commentCount":0,"image":{"@id":"https:\/\/www.sillon38.com\/blog\/2013\/01\/08\/pays-voironnais-une-plateforme-pour-valoriser-le-bois-local\/#primaryimage"},"thumbnailUrl":"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2013\/01\/charavines-1.png","keywords":["Eliane Giraud","Parc de Chartreuse","pays voironnais"],"articleSection":["- fili\u00e8re bois","for\u00eat"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.sillon38.com\/blog\/2013\/01\/08\/pays-voironnais-une-plateforme-pour-valoriser-le-bois-local\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.sillon38.com\/blog\/2013\/01\/08\/pays-voironnais-une-plateforme-pour-valoriser-le-bois-local\/","url":"https:\/\/www.sillon38.com\/blog\/2013\/01\/08\/pays-voironnais-une-plateforme-pour-valoriser-le-bois-local\/","name":"Pays voironnais: une plateforme pour valoriser le bois local -","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sillon38.com\/blog\/2013\/01\/08\/pays-voironnais-une-plateforme-pour-valoriser-le-bois-local\/#primaryimage"},"image":{"@id":"https:\/\/www.sillon38.com\/blog\/2013\/01\/08\/pays-voironnais-une-plateforme-pour-valoriser-le-bois-local\/#primaryimage"},"thumbnailUrl":"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2013\/01\/charavines-1.png","datePublished":"2013-01-08T11:27:23+00:00","author":{"@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"breadcrumb":{"@id":"https:\/\/www.sillon38.com\/blog\/2013\/01\/08\/pays-voironnais-une-plateforme-pour-valoriser-le-bois-local\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sillon38.com\/blog\/2013\/01\/08\/pays-voironnais-une-plateforme-pour-valoriser-le-bois-local\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.sillon38.com\/blog\/2013\/01\/08\/pays-voironnais-une-plateforme-pour-valoriser-le-bois-local\/#primaryimage","url":"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2013\/01\/charavines-1.png","contentUrl":"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2013\/01\/charavines-1.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.sillon38.com\/blog\/2013\/01\/08\/pays-voironnais-une-plateforme-pour-valoriser-le-bois-local\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.sillon38.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Pays voironnais: une plateforme pour valoriser le bois local"}]},{"@type":"WebSite","@id":"https:\/\/www.sillon38.com\/blog\/#website","url":"https:\/\/www.sillon38.com\/blog\/","name":"","description":"Le journal du monde rural","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sillon38.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1","name":"Gilbert"}]}},"_links":{"self":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/33509","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/comments?post=33509"}],"version-history":[{"count":0,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/33509\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/media?parent=33509"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/categories?post=33509"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/tags?post=33509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}