{"id":3374,"date":"2008-07-21T09:56:58","date_gmt":"2008-07-21T07:56:58","guid":{"rendered":"http:\/\/staging.sillon38.com\/2008\/07\/21\/ces-bienfaits-pour-la-biodiversite-remarques-par-l%e2%80%99inra\/"},"modified":"2008-07-21T09:56:58","modified_gmt":"2008-07-21T07:56:58","slug":"ces-bienfaits-pour-la-biodiversite-remarques-par-linra","status":"publish","type":"post","link":"https:\/\/www.sillon38.com\/blog\/2008\/07\/21\/ces-bienfaits-pour-la-biodiversite-remarques-par-linra\/","title":{"rendered":"ses bienfaits  pour la biodiversit\u00e9 remarqu\u00e9s par l\u2019INRA."},"content":{"rendered":"<p class=\"MsoBodyText\" style=\"margin: 0cm 0cm 0pt; text-align: justify\"><font color=\"#000080\" face=\"Arial\" size=\"2\"><strong><em><span style=\"font-size: 10pt; font-family: 'Helvetica','sans-serif'\"><o:p><font color=\"#000000\"> <\/font><\/o:p><\/span><\/em><\/strong><\/font><\/p>\n<p class=\"MsoBodyText\" style=\"margin: 0cm 0cm 0pt; text-align: justify\"><font color=\"#000080\" face=\"Arial\" size=\"2\"><strong><span style=\"font-size: 22pt; font-family: 'Helvetica','sans-serif'\"><\/span><em><span style=\"font-size: 10pt; font-family: 'Helvetica','sans-serif'\"><font color=\"#000000\">D\u2019apr\u00e8s une expertise scientifique de l\u2019INRA publi\u00e9e d\u00e9but  juillet, l\u2019agriculture biologique est un mode de production b\u00e9n\u00e9fique \u00e0 la  biodiversit\u00e9, et son impact positif est d\u2019autant plus fort que l\u2019exploitation  ainsi qualifi\u00e9e s\u2019inscrit dans un paysage  diversifi\u00e9.<o:p><\/o:p><\/font><\/span><\/em><\/strong><\/font><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify\"><span style=\"z-index: 251660288; left: -1px; width: 638px; position: relative; top: 6px; height: 8px\"><\/span><span style=\"font-size: 9pt; font-family: 'Helvetica','sans-serif'\"><o:p><font color=\"#000080\" face=\"Arial\" size=\"2\"><font color=\"#000000\"> <\/font><\/font><\/o:p><\/span><font color=\"#000080\" face=\"Arial\" size=\"2\"><br clear=\"all\" \/><\/font><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify\"><span style=\"font-size: 10pt; font-family: 'Helvetica','sans-serif'\"><font color=\"#000080\" face=\"Arial\" size=\"2\"><font color=\"#000000\">L\u2019ESCo (Expertise Scientifique Collective) r\u00e9alis\u00e9e entre juin  2007 et juin 2008 \u00e0 la demande des minist\u00e8res de l\u2019Agriculture et de l\u2019Ecologie  m\u00e9rite une attention particuli\u00e8re.<o:p><\/o:p><\/font><\/font><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify\"><span style=\"font-size: 10pt; font-family: 'Helvetica','sans-serif'\"><o:p><font color=\"#000080\" face=\"Arial\" size=\"2\"><font color=\"#000000\"> <\/font><\/font><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify\"><span style=\"font-size: 10pt; font-family: 'Helvetica','sans-serif'\"><font color=\"#000080\" face=\"Arial\" size=\"2\"><font color=\"#000000\">Elle souligne notamment que <em>\u00ab Certaines pratiques agricoles  limitent d\u00e9j\u00e0 les impacts n\u00e9gatifs de l&rsquo;agriculture sur la biodiversit\u00e9 et  tirent meilleur parti des services qu&rsquo;elle offre. Bien que son cahier des  charges n\u2019y fasse pas explicitement r\u00e9f\u00e9rence, l\u2019agriculture biologique (AB)  appara\u00eet comme un mode de production favorable \u00e0 la biodiversit\u00e9. L\u2019impact  positif de l\u2019AB sur la biodiversit\u00e9 est d\u2019autant plus fort que l\u2019exploitation  ainsi qualifi\u00e9e s\u2019inscrit dans un paysage  diversifi\u00e9.<o:p><\/o:p><\/em><\/font><\/font><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify\"><font color=\"#000080\" face=\"Arial\" size=\"2\"><em><span style=\"font-size: 10pt; font-family: 'Helvetica','sans-serif'\"><font color=\"#000000\">Plus g\u00e9n\u00e9ralement, l\u2019organisation de rotations longues et  diversifi\u00e9es, une r\u00e9partition adapt\u00e9e des cultures dans les territoires,  l\u2019utilisation de cultures associ\u00e9es, l\u2019implantation de couverts interm\u00e9diaires  et de cultures d\u00e9rob\u00e9es, l\u2019utilisation de vari\u00e9t\u00e9s moins sensibles aux maladies,  la simplification du travail du sol\u2026 sont autant d\u2019\u00e9l\u00e9ments importants pour la  biodiversit\u00e9 dans les r\u00e9gions de grandes  cultures.<o:p><\/o:p><\/font><\/span><\/em><\/font><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify\"><span style=\"font-size: 10pt; font-family: 'Helvetica','sans-serif'\"><o:p><font color=\"#000080\" face=\"Arial\" size=\"2\"><font color=\"#000000\"> <\/font><\/font><\/o:p><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify\"><span style=\"font-size: 10pt; font-family: 'Helvetica','sans-serif'\"><font color=\"#000080\" face=\"Arial\" size=\"2\"><font color=\"#000000\">Elle note \u00e9galement que <em>\u00ab Dans les zones d\u2019arboriculture du sud  de la France, la r\u00e9duction d&#8217;emploi des pesticides et la promotion d\u2019une  production fruiti\u00e8re int\u00e9gr\u00e9e incluant la diversification des esp\u00e8ces v\u00e9g\u00e9tales  par l\u2019enherbement des vergers, pr\u00e9servent et utilisent mieux la  biodiversit\u00e9 \u00bb.<o:p><\/o:p><\/em><\/font><\/font><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify\"><font color=\"#000080\" face=\"Arial\" size=\"2\"><em><span style=\"font-size: 10pt; font-family: 'Helvetica','sans-serif'\"><o:p><font color=\"#000000\"> <\/font><\/o:p><\/span><\/em><\/font><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify\"><span style=\"font-size: 10pt; font-family: 'Helvetica','sans-serif'\"><font color=\"#000080\" face=\"Arial\" size=\"2\"><font color=\"#000000\">Si les bienfaits de l\u2019agriculture biologique pour la biodiversit\u00e9  ne sont \u00e9videmment pas une d\u00e9couverte puisqu\u2019ils sont l\u2019essence de ce mode de  production, le fait que ce soit ainsi soulign\u00e9 par une expertise de l\u2019INRA \u00e0 la  demande des minist\u00e8res de l\u2019Ecologie et de l\u2019Agriculture a valeur de symbole.  Apr\u00e8s les grandes crises sanitaires des derni\u00e8res ann\u00e9es et l\u2019impact du Grenelle  de l\u2019Environnement sur la prise de conscience des citoyens et des consommateurs,  l\u2019agriculture biologique s\u2019impose de plus en plus comme le mode de production  agricole le mieux \u00e0 m\u00eame de conjuguer agriculture et pr\u00e9servation de  l\u2019environnement.<o:p><\/o:p><\/font><\/font><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify\"><span style=\"font-size: 10pt; font-family: 'Helvetica','sans-serif'\"><font color=\"#000080\" face=\"Arial\" size=\"2\"><font color=\"#000000\">L\u2019opinion favorable des citoyens pour l\u2019AB est largement confirm\u00e9e  par l\u2019engouement des consommateurs qui se traduit par une augmentation de la  consommation des produits bio de 10% depuis bient\u00f4t 10  ans.<o:p><\/o:p><\/font><\/font><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify\"><span style=\"font-size: 10pt; font-family: 'Helvetica','sans-serif'\"><font color=\"#000080\" face=\"Arial\" size=\"2\"><font color=\"#000000\">Pour que ce mouvement soit pleinement profitable \u00e0  l\u2019environnement, il ne manque plus que la production bio se d\u00e9veloppe dans les  m\u00eames proportions, ce qui n\u2019est pas le cas aujourd\u2019hui, afin de r\u00e9duire le  volume d\u2019importation des produits bio.<o:p><\/o:p><\/font><\/font><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify\"><span style=\"font-size: 10pt; font-family: 'Helvetica','sans-serif'\"><font color=\"#000080\" face=\"Arial\" size=\"2\"><font color=\"#000000\">C\u2019est la priorit\u00e9 de Corabio et des groupements de producteurs bio  qui travaillent \u00e0 d\u00e9velopper les installations et les conversions en  bio.<o:p><\/o:p><\/font><\/font><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify\"><font color=\"#000080\" face=\"Arial\" size=\"2\"><em><span style=\"font-size: 9pt; font-family: 'Helvetica','sans-serif'\"><o:p><font color=\"#000000\"> <\/font><\/o:p><\/span><\/em><\/font><\/p>\n","protected":false},"excerpt":{"rendered":"<p>D\u2019apr\u00e8s une expertise scientifique de l\u2019INRA publi\u00e9e d\u00e9but juillet, l\u2019agriculture biologique est un mode de production b\u00e9n\u00e9fique \u00e0 la biodiversit\u00e9, et son impact positif est d\u2019autant plus fort que l\u2019exploitation ainsi qualifi\u00e9e s\u2019inscrit dans un paysage diversifi\u00e9. L\u2019ESCo (Expertise Scientifique&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-3374","post","type-post","status-publish","format-standard","hentry","category-bio"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ses bienfaits pour la biodiversit\u00e9 remarqu\u00e9s par l\u2019INRA. -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sillon38.com\/blog\/2008\/07\/21\/ces-bienfaits-pour-la-biodiversite-remarques-par-linra\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ses bienfaits pour la biodiversit\u00e9 remarqu\u00e9s par l\u2019INRA. -\" \/>\n<meta property=\"og:description\" content=\"D\u2019apr\u00e8s une expertise scientifique de l\u2019INRA publi\u00e9e d\u00e9but juillet, l\u2019agriculture biologique est un mode de production b\u00e9n\u00e9fique \u00e0 la biodiversit\u00e9, et son impact positif est d\u2019autant plus fort que l\u2019exploitation ainsi qualifi\u00e9e s\u2019inscrit dans un paysage diversifi\u00e9. L\u2019ESCo (Expertise Scientifique...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sillon38.com\/blog\/2008\/07\/21\/ces-bienfaits-pour-la-biodiversite-remarques-par-linra\/\" \/>\n<meta property=\"article:published_time\" content=\"2008-07-21T07:56:58+00:00\" \/>\n<meta name=\"author\" content=\"Gilbert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gilbert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2008\\\/07\\\/21\\\/ces-bienfaits-pour-la-biodiversite-remarques-par-linra\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2008\\\/07\\\/21\\\/ces-bienfaits-pour-la-biodiversite-remarques-par-linra\\\/\"},\"author\":{\"name\":\"Gilbert\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"headline\":\"ses bienfaits pour la biodiversit\u00e9 remarqu\u00e9s par l\u2019INRA.\",\"datePublished\":\"2008-07-21T07:56:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2008\\\/07\\\/21\\\/ces-bienfaits-pour-la-biodiversite-remarques-par-linra\\\/\"},\"wordCount\":511,\"commentCount\":0,\"articleSection\":[\"bio\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2008\\\/07\\\/21\\\/ces-bienfaits-pour-la-biodiversite-remarques-par-linra\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2008\\\/07\\\/21\\\/ces-bienfaits-pour-la-biodiversite-remarques-par-linra\\\/\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2008\\\/07\\\/21\\\/ces-bienfaits-pour-la-biodiversite-remarques-par-linra\\\/\",\"name\":\"ses bienfaits pour la biodiversit\u00e9 remarqu\u00e9s par l\u2019INRA. -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\"},\"datePublished\":\"2008-07-21T07:56:58+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2008\\\/07\\\/21\\\/ces-bienfaits-pour-la-biodiversite-remarques-par-linra\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2008\\\/07\\\/21\\\/ces-bienfaits-pour-la-biodiversite-remarques-par-linra\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2008\\\/07\\\/21\\\/ces-bienfaits-pour-la-biodiversite-remarques-par-linra\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ses bienfaits pour la biodiversit\u00e9 remarqu\u00e9s par l\u2019INRA.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\",\"name\":\"\",\"description\":\"Le journal du monde rural\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\",\"name\":\"Gilbert\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ses bienfaits pour la biodiversit\u00e9 remarqu\u00e9s par l\u2019INRA. -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sillon38.com\/blog\/2008\/07\/21\/ces-bienfaits-pour-la-biodiversite-remarques-par-linra\/","og_locale":"fr_FR","og_type":"article","og_title":"ses bienfaits pour la biodiversit\u00e9 remarqu\u00e9s par l\u2019INRA. -","og_description":"D\u2019apr\u00e8s une expertise scientifique de l\u2019INRA publi\u00e9e d\u00e9but juillet, l\u2019agriculture biologique est un mode de production b\u00e9n\u00e9fique \u00e0 la biodiversit\u00e9, et son impact positif est d\u2019autant plus fort que l\u2019exploitation ainsi qualifi\u00e9e s\u2019inscrit dans un paysage diversifi\u00e9. L\u2019ESCo (Expertise Scientifique...","og_url":"https:\/\/www.sillon38.com\/blog\/2008\/07\/21\/ces-bienfaits-pour-la-biodiversite-remarques-par-linra\/","article_published_time":"2008-07-21T07:56:58+00:00","author":"Gilbert","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Gilbert","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sillon38.com\/blog\/2008\/07\/21\/ces-bienfaits-pour-la-biodiversite-remarques-par-linra\/#article","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/2008\/07\/21\/ces-bienfaits-pour-la-biodiversite-remarques-par-linra\/"},"author":{"name":"Gilbert","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"headline":"ses bienfaits pour la biodiversit\u00e9 remarqu\u00e9s par l\u2019INRA.","datePublished":"2008-07-21T07:56:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sillon38.com\/blog\/2008\/07\/21\/ces-bienfaits-pour-la-biodiversite-remarques-par-linra\/"},"wordCount":511,"commentCount":0,"articleSection":["bio"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.sillon38.com\/blog\/2008\/07\/21\/ces-bienfaits-pour-la-biodiversite-remarques-par-linra\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.sillon38.com\/blog\/2008\/07\/21\/ces-bienfaits-pour-la-biodiversite-remarques-par-linra\/","url":"https:\/\/www.sillon38.com\/blog\/2008\/07\/21\/ces-bienfaits-pour-la-biodiversite-remarques-par-linra\/","name":"ses bienfaits pour la biodiversit\u00e9 remarqu\u00e9s par l\u2019INRA. -","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/#website"},"datePublished":"2008-07-21T07:56:58+00:00","author":{"@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"breadcrumb":{"@id":"https:\/\/www.sillon38.com\/blog\/2008\/07\/21\/ces-bienfaits-pour-la-biodiversite-remarques-par-linra\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sillon38.com\/blog\/2008\/07\/21\/ces-bienfaits-pour-la-biodiversite-remarques-par-linra\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sillon38.com\/blog\/2008\/07\/21\/ces-bienfaits-pour-la-biodiversite-remarques-par-linra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.sillon38.com\/blog\/"},{"@type":"ListItem","position":2,"name":"ses bienfaits pour la biodiversit\u00e9 remarqu\u00e9s par l\u2019INRA."}]},{"@type":"WebSite","@id":"https:\/\/www.sillon38.com\/blog\/#website","url":"https:\/\/www.sillon38.com\/blog\/","name":"","description":"Le journal du monde rural","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sillon38.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1","name":"Gilbert"}]}},"_links":{"self":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/3374","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/comments?post=3374"}],"version-history":[{"count":0,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/3374\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/media?parent=3374"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/categories?post=3374"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/tags?post=3374"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}