{"id":36522,"date":"2013-04-29T12:28:48","date_gmt":"2013-04-29T10:28:48","guid":{"rendered":"http:\/\/staging.sillon38.com\/?p=36522"},"modified":"2013-04-29T12:28:48","modified_gmt":"2013-04-29T10:28:48","slug":"la-sncf-vous-donne-la-cle-des-champs","status":"publish","type":"post","link":"https:\/\/www.sillon38.com\/blog\/2013\/04\/29\/la-sncf-vous-donne-la-cle-des-champs\/","title":{"rendered":"La SNCF vous donne la cl\u00e9 des champs"},"content":{"rendered":"<p><span style=\"color: #000080;\"><strong>Les agriculteurs c\u00e9r\u00e9aliers s\u2019associent \u00e0 la SNCF pour une op\u00e9ration qui transforme les fen\u00eatres de TGV en \u00ab\u00a0<em>\u00e9crans du savoir<\/em> \u00bb agricole et rural. Jusqu&rsquo; au 12 mai 2013, la \u00ab\u00a0SNCF vous donne la cl\u00e9 des champs\u00a0\u00bb\u00a0!<\/strong><\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<p><span style=\"color: #000080;\"> <img loading=\"lazy\" decoding=\"async\" style=\"height: 410px; width: 580px;\" title=\"Passion c\u00e9r\u00e9ales et SNCF vous donnent la cl\u00e9 des champs \" src=\"http:\/\/alimentation.gouv.fr\/local\/cache-vignettes\/L580xH410\/Couv_livret_SNCF_Passion_Cereales_cle861b73-6b702.jpg\" alt=\"Passion c\u00e9r\u00e9ales et SNCF vous donnent la cl\u00e9 des champs \" width=\"580\" height=\"410\" \/><\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<p><span style=\"color: #000080;\"><strong>La  SNCF invite les jeunes voyageurs \u00e0 d\u00e9couvrir la diversit\u00e9 des paysages  agricoles<\/strong> et \u00e0 reconna\u00eetre les \u00e9l\u00e9ments et les cultures qui composent la campagne fran\u00e7aise. <\/span><\/p>\n<p><span style=\"color: #000080;\">\u00ab\u00a0<em>\u00c0  travers cette op\u00e9ration in\u00e9dite, nous souhaitons r\u00e9v\u00e9ler aux enfants le  patrimoine culturel, naturel et alimentaire immense que composent les  productions c\u00e9r\u00e9ali\u00e8res fran\u00e7aises<\/em> \u00bb explique Jean\u2010Fran\u00e7ois Gleizes, agriculteur et Pr\u00e9sident de Passion C\u00e9r\u00e9ales.<\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<p><span style=\"color: #000080;\"><strong>Gr\u00e2ce \u00e0 un carnet d\u2019observation<\/strong> illustr\u00e9 et avec  l\u2019aide de leurs parents, grands\u2010parents ou la complicit\u00e9 d\u2019animateurs,  les enfants apprendront \u00e0 rep\u00e9rer dans les territoires travers\u00e9s, les  fermes, cultures et autres \u00e9l\u00e9ments de la biodiversit\u00e9.<\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<p><span style=\"color: #000080;\"><strong>50 000 carnets seront offerts en gares parisiennes<\/strong> via le Pack Famille, un petit sac ludique contenant des jeux pour  agr\u00e9menter le voyage. Ces carnets sont \u00e9galement distribu\u00e9s \u00e0 bord des  TGV Family circulant pendant les vacances de P\u00e2ques.<\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<p><span style=\"color: #000080;\"><strong>Certains voyageurs seront guid\u00e9s \u00e0 travers les paysages par des agriculteurs c\u00e9r\u00e9aliers qui embarqueront \u00e0 bord de TGV<\/strong> \u00e9v\u00e8nements dans toute la France.<\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<p><span style=\"color: #000080;\"><strong>Enfin, un jeu concours accessible sur Internet<\/strong> et \u00e0  bord, propose aux enfants de dessiner les paysages travers\u00e9s. Un  tirage au sort d\u00e9signera les heureux gagnants .<\/span><\/p>\n<blockquote><p><span style=\"color: #ff6600;\"><strong>Pour plus de renseignements:<\/strong><\/span><\/p>\n<p><a class=\"sncfcom-colors-external-automatic\" title=\"Carnet d'observation illustr\u00e9\" href=\"http:\/\/medias.sncf.com\/sncfcom\/pdf\/passion%20cereales\/Livret%20final%20TELECHARGEMENT.pdf\" target=\"_blank\" rel=\"noopener\">T\u00e9l\u00e9chargez le carnet d&rsquo;observation illustr\u00e9<\/a><\/p>\n<p><a class=\"sncfcom-colors-external-automatic\" title=\"R\u00e8glement du jeu-concours\" href=\"http:\/\/medias.sncf.com\/sncfcom\/pdf\/passion%20cereales\/Reglement%20et%20Avenant%20Jeu%20Concours%20SNCF%20vous%20donne%20la%20cle%20des%20champs.pdf\" target=\"_blank\" rel=\"noopener\">Retrouvez le r\u00e8glement du jeu-concours<\/a><\/p>\n<hr \/>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Alors que l&rsquo;op\u00e9ration \u00ab\u00a0prenez la cl\u00e9 des champs\u00a0\u00bb est organis\u00e9e ce week-end en Is\u00e8re et dans les Savoie, les agriculteurs c\u00e9r\u00e9aliers sont associ\u00e9s \u00e0 la SNCF autour de animation: \u00ab\u00a0la SNCF vous donne la cl\u00e9 des champs \u00ab\u00a0.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,10],"tags":[4164,5085],"class_list":["post-36522","post","type-post","status-publish","format-standard","hentry","category-agriculture","category-cereales","tag-passion-cereales","tag-sncf"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La SNCF vous donne la cl\u00e9 des champs -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sillon38.com\/blog\/2013\/04\/29\/la-sncf-vous-donne-la-cle-des-champs\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La SNCF vous donne la cl\u00e9 des champs -\" \/>\n<meta property=\"og:description\" content=\"Alors que l&#039;op\u00e9ration &quot;prenez la cl\u00e9 des champs&quot; est organis\u00e9e ce week-end en Is\u00e8re et dans les Savoie, les agriculteurs c\u00e9r\u00e9aliers sont associ\u00e9s \u00e0 la SNCF autour de animation: &quot;la SNCF vous donne la cl\u00e9 des champs &quot;.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sillon38.com\/blog\/2013\/04\/29\/la-sncf-vous-donne-la-cle-des-champs\/\" \/>\n<meta property=\"article:published_time\" content=\"2013-04-29T10:28:48+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/alimentation.gouv.fr\/local\/cache-vignettes\/L580xH410\/Couv_livret_SNCF_Passion_Cereales_cle861b73-6b702.jpg\" \/>\n<meta name=\"author\" content=\"Gilbert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gilbert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2013\\\/04\\\/29\\\/la-sncf-vous-donne-la-cle-des-champs\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2013\\\/04\\\/29\\\/la-sncf-vous-donne-la-cle-des-champs\\\/\"},\"author\":{\"name\":\"Gilbert\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"headline\":\"La SNCF vous donne la cl\u00e9 des champs\",\"datePublished\":\"2013-04-29T10:28:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2013\\\/04\\\/29\\\/la-sncf-vous-donne-la-cle-des-champs\\\/\"},\"wordCount\":268,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2013\\\/04\\\/29\\\/la-sncf-vous-donne-la-cle-des-champs\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/alimentation.gouv.fr\\\/local\\\/cache-vignettes\\\/L580xH410\\\/Couv_livret_SNCF_Passion_Cereales_cle861b73-6b702.jpg\",\"keywords\":[\"Passion C\u00e9r\u00e9ales\",\"SNCF\"],\"articleSection\":[\"agriculture\",\"c\u00e9r\u00e9ales\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2013\\\/04\\\/29\\\/la-sncf-vous-donne-la-cle-des-champs\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2013\\\/04\\\/29\\\/la-sncf-vous-donne-la-cle-des-champs\\\/\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2013\\\/04\\\/29\\\/la-sncf-vous-donne-la-cle-des-champs\\\/\",\"name\":\"La SNCF vous donne la cl\u00e9 des champs -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2013\\\/04\\\/29\\\/la-sncf-vous-donne-la-cle-des-champs\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2013\\\/04\\\/29\\\/la-sncf-vous-donne-la-cle-des-champs\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/alimentation.gouv.fr\\\/local\\\/cache-vignettes\\\/L580xH410\\\/Couv_livret_SNCF_Passion_Cereales_cle861b73-6b702.jpg\",\"datePublished\":\"2013-04-29T10:28:48+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2013\\\/04\\\/29\\\/la-sncf-vous-donne-la-cle-des-champs\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2013\\\/04\\\/29\\\/la-sncf-vous-donne-la-cle-des-champs\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2013\\\/04\\\/29\\\/la-sncf-vous-donne-la-cle-des-champs\\\/#primaryimage\",\"url\":\"http:\\\/\\\/alimentation.gouv.fr\\\/local\\\/cache-vignettes\\\/L580xH410\\\/Couv_livret_SNCF_Passion_Cereales_cle861b73-6b702.jpg\",\"contentUrl\":\"http:\\\/\\\/alimentation.gouv.fr\\\/local\\\/cache-vignettes\\\/L580xH410\\\/Couv_livret_SNCF_Passion_Cereales_cle861b73-6b702.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2013\\\/04\\\/29\\\/la-sncf-vous-donne-la-cle-des-champs\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La SNCF vous donne la cl\u00e9 des champs\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\",\"name\":\"\",\"description\":\"Le journal du monde rural\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\",\"name\":\"Gilbert\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La SNCF vous donne la cl\u00e9 des champs -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sillon38.com\/blog\/2013\/04\/29\/la-sncf-vous-donne-la-cle-des-champs\/","og_locale":"fr_FR","og_type":"article","og_title":"La SNCF vous donne la cl\u00e9 des champs -","og_description":"Alors que l'op\u00e9ration \"prenez la cl\u00e9 des champs\" est organis\u00e9e ce week-end en Is\u00e8re et dans les Savoie, les agriculteurs c\u00e9r\u00e9aliers sont associ\u00e9s \u00e0 la SNCF autour de animation: \"la SNCF vous donne la cl\u00e9 des champs \".","og_url":"https:\/\/www.sillon38.com\/blog\/2013\/04\/29\/la-sncf-vous-donne-la-cle-des-champs\/","article_published_time":"2013-04-29T10:28:48+00:00","og_image":[{"url":"http:\/\/alimentation.gouv.fr\/local\/cache-vignettes\/L580xH410\/Couv_livret_SNCF_Passion_Cereales_cle861b73-6b702.jpg","type":"","width":"","height":""}],"author":"Gilbert","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Gilbert","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sillon38.com\/blog\/2013\/04\/29\/la-sncf-vous-donne-la-cle-des-champs\/#article","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/2013\/04\/29\/la-sncf-vous-donne-la-cle-des-champs\/"},"author":{"name":"Gilbert","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"headline":"La SNCF vous donne la cl\u00e9 des champs","datePublished":"2013-04-29T10:28:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sillon38.com\/blog\/2013\/04\/29\/la-sncf-vous-donne-la-cle-des-champs\/"},"wordCount":268,"commentCount":0,"image":{"@id":"https:\/\/www.sillon38.com\/blog\/2013\/04\/29\/la-sncf-vous-donne-la-cle-des-champs\/#primaryimage"},"thumbnailUrl":"http:\/\/alimentation.gouv.fr\/local\/cache-vignettes\/L580xH410\/Couv_livret_SNCF_Passion_Cereales_cle861b73-6b702.jpg","keywords":["Passion C\u00e9r\u00e9ales","SNCF"],"articleSection":["agriculture","c\u00e9r\u00e9ales"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.sillon38.com\/blog\/2013\/04\/29\/la-sncf-vous-donne-la-cle-des-champs\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.sillon38.com\/blog\/2013\/04\/29\/la-sncf-vous-donne-la-cle-des-champs\/","url":"https:\/\/www.sillon38.com\/blog\/2013\/04\/29\/la-sncf-vous-donne-la-cle-des-champs\/","name":"La SNCF vous donne la cl\u00e9 des champs -","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sillon38.com\/blog\/2013\/04\/29\/la-sncf-vous-donne-la-cle-des-champs\/#primaryimage"},"image":{"@id":"https:\/\/www.sillon38.com\/blog\/2013\/04\/29\/la-sncf-vous-donne-la-cle-des-champs\/#primaryimage"},"thumbnailUrl":"http:\/\/alimentation.gouv.fr\/local\/cache-vignettes\/L580xH410\/Couv_livret_SNCF_Passion_Cereales_cle861b73-6b702.jpg","datePublished":"2013-04-29T10:28:48+00:00","author":{"@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"breadcrumb":{"@id":"https:\/\/www.sillon38.com\/blog\/2013\/04\/29\/la-sncf-vous-donne-la-cle-des-champs\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sillon38.com\/blog\/2013\/04\/29\/la-sncf-vous-donne-la-cle-des-champs\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.sillon38.com\/blog\/2013\/04\/29\/la-sncf-vous-donne-la-cle-des-champs\/#primaryimage","url":"http:\/\/alimentation.gouv.fr\/local\/cache-vignettes\/L580xH410\/Couv_livret_SNCF_Passion_Cereales_cle861b73-6b702.jpg","contentUrl":"http:\/\/alimentation.gouv.fr\/local\/cache-vignettes\/L580xH410\/Couv_livret_SNCF_Passion_Cereales_cle861b73-6b702.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.sillon38.com\/blog\/2013\/04\/29\/la-sncf-vous-donne-la-cle-des-champs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.sillon38.com\/blog\/"},{"@type":"ListItem","position":2,"name":"La SNCF vous donne la cl\u00e9 des champs"}]},{"@type":"WebSite","@id":"https:\/\/www.sillon38.com\/blog\/#website","url":"https:\/\/www.sillon38.com\/blog\/","name":"","description":"Le journal du monde rural","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sillon38.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1","name":"Gilbert"}]}},"_links":{"self":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/36522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/comments?post=36522"}],"version-history":[{"count":0,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/36522\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/media?parent=36522"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/categories?post=36522"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/tags?post=36522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}