{"id":40628,"date":"2013-10-19T17:41:32","date_gmt":"2013-10-19T15:41:32","guid":{"rendered":"http:\/\/staging.sillon38.com\/?p=40628"},"modified":"2013-10-19T17:41:32","modified_gmt":"2013-10-19T15:41:32","slug":"les-trufficulteurs-de-lisere-en-seance-de-formation","status":"publish","type":"post","link":"https:\/\/www.sillon38.com\/blog\/2013\/10\/19\/les-trufficulteurs-de-lisere-en-seance-de-formation\/","title":{"rendered":"Les trufficulteurs de l&rsquo;Is\u00e8re en s\u00e9ance de formation&#8230;"},"content":{"rendered":"<p><span style=\"color: #000080;\">Le syndicat des trufficulteurs de l&rsquo;Is\u00e8re a organis\u00e9 une journ\u00e9e de formation qui a r\u00e9uni une trentaine de participants.<\/span><\/p>\n<p><span style=\"color: #000080;\">Ceux ci ont l&rsquo;espace de la matin\u00e9e \u00e9cout\u00e9 avec beaucoup d&rsquo;attention la conf\u00e9rence de Roger Ribes, trufficulteur en Roussillon et de son associ\u00e9e Nina Wollner.. <\/span><\/p>\n<p><span style=\"color: #000080;\">Paul chamard-Bois, pr\u00e9sident du syndicat des trufficulteurs de l&rsquo;Is\u00e8re: \u00a0\u00bb L&rsquo;intervention des deux conf\u00e9renciers \u00e9tait tr\u00e8s int\u00e9ressante.. Nous avons appris beaucoup de choses. En un mot on a \u00e9tudi\u00e9 comment mener une truffi\u00e8re de A\u00e0 Z, de la plantation \u00e0 la r\u00e9colte.. On a appr\u00e9hend\u00e9 les pi\u00e8ges \u00e0 \u00e9viter, on a bien not\u00e9 certaines astuces.. ficelles.. Roger Ribes qui est \u00ab\u00a0cal\u00e9\u00a0\u00bb en ce qui concerne les exp\u00e9riences, la recherche nous a d\u00e9montr\u00e9 que la trufficulture, les m\u00e9thodes culturales \u00e9voluent.. qu&rsquo;il faut s&rsquo;adapter.. Un exemple tout simple: nous sommes tr\u00e8s nombreux \u00e0 laisser pousser les arbres en hauteur.. Nous avons, pour la plupart d&rsquo;entre nous appris qu&rsquo;il faut les tailler \u00e0 1,50 m\u00e8tre de hauteur. On s&rsquo;est \u00e9galement rendu compte que la truffe demande un travail presqu&rsquo;au quotidien&#8230; \u00ab\u00a0<\/span><\/p>\n<p><span style=\"color: #000080;\">L&rsquo;apr\u00e8s midi l&rsquo;ensemble des personnes pr\u00e9sente s&rsquo;est rendu \u00e0 Herbeys sur la truffi\u00e8re de G\u00e9rard Amblard pour une le\u00e7on sur le terrain&#8230; <\/span><\/p>\n<p><span style=\"color: #000080;\">L<a href=\"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2013\/10\/FOR-TRUFFES.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-40629\" title=\"FOR TRUFFES\" src=\"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2013\/10\/FOR-TRUFFES.jpg\" alt=\"FOR TRUFFES\" width=\"595\" height=\"335\" srcset=\"https:\/\/www.sillon38.com\/blog\/wp-content\/uploads\/2013\/10\/FOR-TRUFFES.jpg 595w, https:\/\/www.sillon38.com\/blog\/wp-content\/uploads\/2013\/10\/FOR-TRUFFES-300x169.jpg 300w\" sizes=\"auto, (max-width: 595px) 100vw, 595px\" \/><\/a>&lsquo;occasion de demander \u00e0 Roger Ribes de nous donner ses impressions.. \u00a0\u00bb J&rsquo;ai trouv\u00e9 des trufficulteurs passionn\u00e9s mais manquant de formation&#8230; Je pense qu&rsquo;ils doivent \u00eatre mieux accompagn\u00e9s. Prenons un exemple concret: le lieu ou nous sommes. Il faut absolument tailler les arbres en chapeau \u00e0 une hauteur de 1,50 m\u00e8tre, supprimer l&rsquo;herbe qui entoure les arbres&#8230; Je dis partout ou je passe,\u00a0 la truffe est une culture passionnante \u00e0 mener mais il faut l&rsquo;aider&#8230; \u00ab\u00a0<\/span><\/p>\n<p><span style=\"color: #000080;\">En attendant, il a trouv\u00e9 les trufficulteurs de l&rsquo;Is\u00e8re \u00a0\u00bb sympas, accueillants et tr\u00e8s avides de conseils.. \u00a0\u00bb<br \/>\n<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le syndicat des trufficulteur de l&rsquo;Is\u00e8re a organis\u00e9 une journ\u00e9e formation tr\u00e8s instructive&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[74],"tags":[4191,5247],"class_list":["post-40628","post","type-post","status-publish","format-standard","hentry","category-trufficulture","tag-paul-chamard-bois","tag-syndicat-des-trufficulteurs-isere"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les trufficulteurs de l&#039;Is\u00e8re en s\u00e9ance de formation... -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sillon38.com\/blog\/2013\/10\/19\/les-trufficulteurs-de-lisere-en-seance-de-formation\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les trufficulteurs de l&#039;Is\u00e8re en s\u00e9ance de formation... -\" \/>\n<meta property=\"og:description\" content=\"Le syndicat des trufficulteur de l&#039;Is\u00e8re a organis\u00e9 une journ\u00e9e formation tr\u00e8s instructive...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sillon38.com\/blog\/2013\/10\/19\/les-trufficulteurs-de-lisere-en-seance-de-formation\/\" \/>\n<meta property=\"article:published_time\" content=\"2013-10-19T15:41:32+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2013\/10\/FOR-TRUFFES.jpg\" \/>\n<meta name=\"author\" content=\"Gilbert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gilbert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2013\\\/10\\\/19\\\/les-trufficulteurs-de-lisere-en-seance-de-formation\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2013\\\/10\\\/19\\\/les-trufficulteurs-de-lisere-en-seance-de-formation\\\/\"},\"author\":{\"name\":\"Gilbert\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"headline\":\"Les trufficulteurs de l&rsquo;Is\u00e8re en s\u00e9ance de formation&#8230;\",\"datePublished\":\"2013-10-19T15:41:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2013\\\/10\\\/19\\\/les-trufficulteurs-de-lisere-en-seance-de-formation\\\/\"},\"wordCount\":333,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2013\\\/10\\\/19\\\/les-trufficulteurs-de-lisere-en-seance-de-formation\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/staging.sillon38.com\\\/wp-content\\\/uploads\\\/2013\\\/10\\\/FOR-TRUFFES.jpg\",\"keywords\":[\"Paul chamard-Bois\",\"syndicat des trufficulteurs Is\u00e8re\"],\"articleSection\":[\"trufficulture\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2013\\\/10\\\/19\\\/les-trufficulteurs-de-lisere-en-seance-de-formation\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2013\\\/10\\\/19\\\/les-trufficulteurs-de-lisere-en-seance-de-formation\\\/\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2013\\\/10\\\/19\\\/les-trufficulteurs-de-lisere-en-seance-de-formation\\\/\",\"name\":\"Les trufficulteurs de l'Is\u00e8re en s\u00e9ance de formation... -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2013\\\/10\\\/19\\\/les-trufficulteurs-de-lisere-en-seance-de-formation\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2013\\\/10\\\/19\\\/les-trufficulteurs-de-lisere-en-seance-de-formation\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/staging.sillon38.com\\\/wp-content\\\/uploads\\\/2013\\\/10\\\/FOR-TRUFFES.jpg\",\"datePublished\":\"2013-10-19T15:41:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2013\\\/10\\\/19\\\/les-trufficulteurs-de-lisere-en-seance-de-formation\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2013\\\/10\\\/19\\\/les-trufficulteurs-de-lisere-en-seance-de-formation\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2013\\\/10\\\/19\\\/les-trufficulteurs-de-lisere-en-seance-de-formation\\\/#primaryimage\",\"url\":\"http:\\\/\\\/staging.sillon38.com\\\/wp-content\\\/uploads\\\/2013\\\/10\\\/FOR-TRUFFES.jpg\",\"contentUrl\":\"http:\\\/\\\/staging.sillon38.com\\\/wp-content\\\/uploads\\\/2013\\\/10\\\/FOR-TRUFFES.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2013\\\/10\\\/19\\\/les-trufficulteurs-de-lisere-en-seance-de-formation\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les trufficulteurs de l&rsquo;Is\u00e8re en s\u00e9ance de formation&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\",\"name\":\"\",\"description\":\"Le journal du monde rural\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\",\"name\":\"Gilbert\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les trufficulteurs de l'Is\u00e8re en s\u00e9ance de formation... -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sillon38.com\/blog\/2013\/10\/19\/les-trufficulteurs-de-lisere-en-seance-de-formation\/","og_locale":"fr_FR","og_type":"article","og_title":"Les trufficulteurs de l'Is\u00e8re en s\u00e9ance de formation... -","og_description":"Le syndicat des trufficulteur de l'Is\u00e8re a organis\u00e9 une journ\u00e9e formation tr\u00e8s instructive...","og_url":"https:\/\/www.sillon38.com\/blog\/2013\/10\/19\/les-trufficulteurs-de-lisere-en-seance-de-formation\/","article_published_time":"2013-10-19T15:41:32+00:00","og_image":[{"url":"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2013\/10\/FOR-TRUFFES.jpg","type":"","width":"","height":""}],"author":"Gilbert","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Gilbert","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sillon38.com\/blog\/2013\/10\/19\/les-trufficulteurs-de-lisere-en-seance-de-formation\/#article","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/2013\/10\/19\/les-trufficulteurs-de-lisere-en-seance-de-formation\/"},"author":{"name":"Gilbert","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"headline":"Les trufficulteurs de l&rsquo;Is\u00e8re en s\u00e9ance de formation&#8230;","datePublished":"2013-10-19T15:41:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sillon38.com\/blog\/2013\/10\/19\/les-trufficulteurs-de-lisere-en-seance-de-formation\/"},"wordCount":333,"commentCount":0,"image":{"@id":"https:\/\/www.sillon38.com\/blog\/2013\/10\/19\/les-trufficulteurs-de-lisere-en-seance-de-formation\/#primaryimage"},"thumbnailUrl":"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2013\/10\/FOR-TRUFFES.jpg","keywords":["Paul chamard-Bois","syndicat des trufficulteurs Is\u00e8re"],"articleSection":["trufficulture"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.sillon38.com\/blog\/2013\/10\/19\/les-trufficulteurs-de-lisere-en-seance-de-formation\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.sillon38.com\/blog\/2013\/10\/19\/les-trufficulteurs-de-lisere-en-seance-de-formation\/","url":"https:\/\/www.sillon38.com\/blog\/2013\/10\/19\/les-trufficulteurs-de-lisere-en-seance-de-formation\/","name":"Les trufficulteurs de l'Is\u00e8re en s\u00e9ance de formation... -","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sillon38.com\/blog\/2013\/10\/19\/les-trufficulteurs-de-lisere-en-seance-de-formation\/#primaryimage"},"image":{"@id":"https:\/\/www.sillon38.com\/blog\/2013\/10\/19\/les-trufficulteurs-de-lisere-en-seance-de-formation\/#primaryimage"},"thumbnailUrl":"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2013\/10\/FOR-TRUFFES.jpg","datePublished":"2013-10-19T15:41:32+00:00","author":{"@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"breadcrumb":{"@id":"https:\/\/www.sillon38.com\/blog\/2013\/10\/19\/les-trufficulteurs-de-lisere-en-seance-de-formation\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sillon38.com\/blog\/2013\/10\/19\/les-trufficulteurs-de-lisere-en-seance-de-formation\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.sillon38.com\/blog\/2013\/10\/19\/les-trufficulteurs-de-lisere-en-seance-de-formation\/#primaryimage","url":"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2013\/10\/FOR-TRUFFES.jpg","contentUrl":"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2013\/10\/FOR-TRUFFES.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.sillon38.com\/blog\/2013\/10\/19\/les-trufficulteurs-de-lisere-en-seance-de-formation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.sillon38.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Les trufficulteurs de l&rsquo;Is\u00e8re en s\u00e9ance de formation&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/www.sillon38.com\/blog\/#website","url":"https:\/\/www.sillon38.com\/blog\/","name":"","description":"Le journal du monde rural","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sillon38.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1","name":"Gilbert"}]}},"_links":{"self":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/40628","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/comments?post=40628"}],"version-history":[{"count":0,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/40628\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/media?parent=40628"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/categories?post=40628"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/tags?post=40628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}