{"id":41508,"date":"2013-12-10T19:41:37","date_gmt":"2013-12-10T17:41:37","guid":{"rendered":"http:\/\/staging.sillon38.com\/?p=41508"},"modified":"2013-12-10T19:41:37","modified_gmt":"2013-12-10T17:41:37","slug":"episode-de-pollution-de-lair-sur-la-zone-du-bassin-lyonnais-et-nord-isere-limitation-de-la-vitesse","status":"publish","type":"post","link":"https:\/\/www.sillon38.com\/blog\/2013\/12\/10\/episode-de-pollution-de-lair-sur-la-zone-du-bassin-lyonnais-et-nord-isere-limitation-de-la-vitesse\/","title":{"rendered":"\u00c9pisode de pollution de l\u2019air sur la zone du bassin lyonnais et Nord Is\u00e8re Limitation de la vitesse"},"content":{"rendered":"<p><span style=\"color: #000080;\">Ce lundi 9 d\u00e9cembre, avec la reprise des activit\u00e9s et des conditions m\u00e9t\u00e9orologiques d\u00e9favorables \u00e0 la dispersion des polluants, les concentrations de poussi\u00e8res ont vu leurs niveaux augmenter fortement. Le seuil d\u2019alerte a \u00e9t\u00e9 atteint sur le Bassin Lyonnais &#8211; Nord Is\u00e8re.<br \/>\n<\/span> <span style=\"color: #000080;\">Ainsi, le dispositif pr\u00e9fectoral est activ\u00e9 au niveau d\u2019alerte pour le Bassin lyonnais Nord-Is\u00e8re.<br \/>\n<\/span> <span style=\"color: #000080;\">En cons\u00e9quence et au vu de l\u2019arr\u00eat\u00e9 inter pr\u00e9fectoral n\u00b0 2011\u2013 004 du 05 janvier 2011 relatif \u00e0 la proc\u00e9dure d\u2019information et d\u2019alerte de la population en cas de pointe de pollution en r\u00e9gion Rh\u00f4ne-Alpes, une mesure de limitation de vitesse s\u2019applique notamment sur le du Nord Is\u00e8re :<br \/>\n<\/span> <span style=\"color: #000080;\"><br \/>\nLes v\u00e9hicules l\u00e9gers doivent respecter une vitesse inf\u00e9rieure de 20 km\/h par rapport \u00e0 la vitesse maximale autoris\u00e9e, si cette derni\u00e8re est sup\u00e9rieure \u00e0 70 km\/h.<br \/>\n<\/span> <span style=\"color: #000080;\"><br \/>\nLes poids lourds et autocars ne se voient pas appliquer la m\u00eame r\u00e9duction de vitesse mais ne peuvent circuler \u00e0 une vitesse sup\u00e9rieure \u00e0 la vitesse maximale autoris\u00e9e ainsi d\u00e9termin\u00e9e pour les v\u00e9hicules l\u00e9gers.<br \/>\n<\/span> <span style=\"color: #000080;\"><br \/>\nEn outre, le bassin grenoblois est au niveau \u00ab\u00a0information\u00a0\u00bb du dispositif de suivi de la qualit\u00e9 de l\u2019air. Il est donc recommand\u00e9 aux personnes sensibles d\u2019\u00e9viter les activit\u00e9s physiques intenses.<br \/>\n<\/span> <span style=\"color: #000080;\"><br \/>\nL\u2019ensemble des valeurs de pollution atmosph\u00e9rique mesur\u00e9es par les r\u00e9seaux de surveillance de la qualit\u00e9 de l\u2019air est disponible sur Internet \u00e0 l\u2019adresse suivante\u00a0: <a href=\"http:\/\/www.air-rhonealpes.fr\">http:\/\/www.air-rhonealpes.fr<\/a><br \/>\n<\/span> <span style=\"color: #000080;\"><br \/>\n<\/span> <span style=\"color: #000080;\"><span style=\"text-decoration: underline;\"><strong>Recommandations comportementales, destin\u00e9es \u00e0 l\u2019ensemble de la population de l\u2019Is\u00e8re, afin de r\u00e9duire la pollution atmosph\u00e9rique :<\/strong><\/span><br \/>\n<\/span> <span style=\"color: #000080;\"><br \/>\n&#8211; limiter l\u2019usage des v\u00e9hicules automobiles et de tous autres engins \u00e0 moteur thermique\u00a0;<br \/>\n&#8211; les usagers de la route doivent :<br \/>\n<\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<ul>\n<li><span style=\"color: #000080;\">privil\u00e9gier, pour leurs trajets courts, les modes de d\u00e9placement non polluants (marche \u00e0 pied et v\u00e9lo) ;<\/span><\/li>\n<li><span style=\"color: #000080;\">diff\u00e9rer si possible leurs d\u00e9placements internes aux agglom\u00e9rations pouvant l\u2019\u00eatre ;<\/span><\/li>\n<li><span style=\"color: #000080;\">pratiquer si possible le co-voiturage dans les autres cas ou emprunter les r\u00e9seaux de transport en commun.<br \/>\n<\/span><\/li>\n<\/ul>\n<p><span style=\"color: #000080;\"><br \/>\n<\/span> <span style=\"color: #000080;\"><span style=\"text-decoration: underline;\"><strong>Pour plus d\u2019informations sur les recommandations sanitaires, vous pouvez\u00a0:<\/strong><\/span><br \/>\n<\/span> <span style=\"color: #000080;\"><br \/>\n<\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<ul>\n<li><span style=\"color: #000080;\">prendre connaissance de la totalit\u00e9 des recommandations du Conseil sup\u00e9rieur d\u2019Hygi\u00e8ne Publique de France \u00e0 l\u2019adresse suivante\u00a0: <a href=\"http:\/\/www.air-rhonealpes.fr\">www.air-rhonealpes.fr<\/a> ;<\/span><\/li>\n<li><span style=\"color: #000080;\">contacter l\u2019Agence R\u00e9gionale de Sant\u00e9 ou sa d\u00e9l\u00e9gation d\u00e9partementale\u00a0: <a href=\"http:\/\/www.ars.rhonealpes.sante.fr\/Internet.rhonealpes.0.html\">http:\/\/www.ars.rhonealpes.sante.fr\/Internet.rhonealpes.0.html<\/a><\/span><\/li>\n<\/ul>\n<p><span style=\"color: #000080;\"> <\/span><span style=\"font-family: Arial;\"><br \/>\n<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ce lundi 9 d\u00e9cembre, avec la reprise des activit\u00e9s et des conditions m\u00e9t\u00e9orologiques d\u00e9favorables \u00e0 la dispersion des polluants, les concentrations de poussi\u00e8res ont vu leurs niveaux augmenter fortement. Le seuil d\u2019alerte a \u00e9t\u00e9 atteint sur le Bassin Lyonnais &#8211; Nord Is\u00e8re. <\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[3981,4418],"class_list":["post-41508","post","type-post","status-publish","format-standard","hentry","category-pollution","tag-nord-isere","tag-pollution"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00c9pisode de pollution de l\u2019air sur la zone du bassin lyonnais et Nord Is\u00e8re Limitation de la vitesse -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sillon38.com\/blog\/2013\/12\/10\/episode-de-pollution-de-lair-sur-la-zone-du-bassin-lyonnais-et-nord-isere-limitation-de-la-vitesse\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c9pisode de pollution de l\u2019air sur la zone du bassin lyonnais et Nord Is\u00e8re Limitation de la vitesse -\" \/>\n<meta property=\"og:description\" content=\"Ce lundi 9 d\u00e9cembre, avec la reprise des activit\u00e9s et des conditions m\u00e9t\u00e9orologiques d\u00e9favorables \u00e0 la dispersion des polluants, les concentrations de poussi\u00e8res ont vu leurs niveaux augmenter fortement. Le seuil d\u2019alerte a \u00e9t\u00e9 atteint sur le Bassin Lyonnais - Nord Is\u00e8re.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sillon38.com\/blog\/2013\/12\/10\/episode-de-pollution-de-lair-sur-la-zone-du-bassin-lyonnais-et-nord-isere-limitation-de-la-vitesse\/\" \/>\n<meta property=\"article:published_time\" content=\"2013-12-10T17:41:37+00:00\" \/>\n<meta name=\"author\" content=\"Gilbert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gilbert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2013\\\/12\\\/10\\\/episode-de-pollution-de-lair-sur-la-zone-du-bassin-lyonnais-et-nord-isere-limitation-de-la-vitesse\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2013\\\/12\\\/10\\\/episode-de-pollution-de-lair-sur-la-zone-du-bassin-lyonnais-et-nord-isere-limitation-de-la-vitesse\\\/\"},\"author\":{\"name\":\"Gilbert\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"headline\":\"\u00c9pisode de pollution de l\u2019air sur la zone du bassin lyonnais et Nord Is\u00e8re Limitation de la vitesse\",\"datePublished\":\"2013-12-10T17:41:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2013\\\/12\\\/10\\\/episode-de-pollution-de-lair-sur-la-zone-du-bassin-lyonnais-et-nord-isere-limitation-de-la-vitesse\\\/\"},\"wordCount\":424,\"commentCount\":0,\"keywords\":[\"Nord-Is\u00e8re\",\"pollution\"],\"articleSection\":[\"pollution\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2013\\\/12\\\/10\\\/episode-de-pollution-de-lair-sur-la-zone-du-bassin-lyonnais-et-nord-isere-limitation-de-la-vitesse\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2013\\\/12\\\/10\\\/episode-de-pollution-de-lair-sur-la-zone-du-bassin-lyonnais-et-nord-isere-limitation-de-la-vitesse\\\/\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2013\\\/12\\\/10\\\/episode-de-pollution-de-lair-sur-la-zone-du-bassin-lyonnais-et-nord-isere-limitation-de-la-vitesse\\\/\",\"name\":\"\u00c9pisode de pollution de l\u2019air sur la zone du bassin lyonnais et Nord Is\u00e8re Limitation de la vitesse -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\"},\"datePublished\":\"2013-12-10T17:41:37+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2013\\\/12\\\/10\\\/episode-de-pollution-de-lair-sur-la-zone-du-bassin-lyonnais-et-nord-isere-limitation-de-la-vitesse\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2013\\\/12\\\/10\\\/episode-de-pollution-de-lair-sur-la-zone-du-bassin-lyonnais-et-nord-isere-limitation-de-la-vitesse\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2013\\\/12\\\/10\\\/episode-de-pollution-de-lair-sur-la-zone-du-bassin-lyonnais-et-nord-isere-limitation-de-la-vitesse\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9pisode de pollution de l\u2019air sur la zone du bassin lyonnais et Nord Is\u00e8re Limitation de la vitesse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\",\"name\":\"\",\"description\":\"Le journal du monde rural\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\",\"name\":\"Gilbert\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c9pisode de pollution de l\u2019air sur la zone du bassin lyonnais et Nord Is\u00e8re Limitation de la vitesse -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sillon38.com\/blog\/2013\/12\/10\/episode-de-pollution-de-lair-sur-la-zone-du-bassin-lyonnais-et-nord-isere-limitation-de-la-vitesse\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00c9pisode de pollution de l\u2019air sur la zone du bassin lyonnais et Nord Is\u00e8re Limitation de la vitesse -","og_description":"Ce lundi 9 d\u00e9cembre, avec la reprise des activit\u00e9s et des conditions m\u00e9t\u00e9orologiques d\u00e9favorables \u00e0 la dispersion des polluants, les concentrations de poussi\u00e8res ont vu leurs niveaux augmenter fortement. Le seuil d\u2019alerte a \u00e9t\u00e9 atteint sur le Bassin Lyonnais - Nord Is\u00e8re.","og_url":"https:\/\/www.sillon38.com\/blog\/2013\/12\/10\/episode-de-pollution-de-lair-sur-la-zone-du-bassin-lyonnais-et-nord-isere-limitation-de-la-vitesse\/","article_published_time":"2013-12-10T17:41:37+00:00","author":"Gilbert","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Gilbert","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sillon38.com\/blog\/2013\/12\/10\/episode-de-pollution-de-lair-sur-la-zone-du-bassin-lyonnais-et-nord-isere-limitation-de-la-vitesse\/#article","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/2013\/12\/10\/episode-de-pollution-de-lair-sur-la-zone-du-bassin-lyonnais-et-nord-isere-limitation-de-la-vitesse\/"},"author":{"name":"Gilbert","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"headline":"\u00c9pisode de pollution de l\u2019air sur la zone du bassin lyonnais et Nord Is\u00e8re Limitation de la vitesse","datePublished":"2013-12-10T17:41:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sillon38.com\/blog\/2013\/12\/10\/episode-de-pollution-de-lair-sur-la-zone-du-bassin-lyonnais-et-nord-isere-limitation-de-la-vitesse\/"},"wordCount":424,"commentCount":0,"keywords":["Nord-Is\u00e8re","pollution"],"articleSection":["pollution"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.sillon38.com\/blog\/2013\/12\/10\/episode-de-pollution-de-lair-sur-la-zone-du-bassin-lyonnais-et-nord-isere-limitation-de-la-vitesse\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.sillon38.com\/blog\/2013\/12\/10\/episode-de-pollution-de-lair-sur-la-zone-du-bassin-lyonnais-et-nord-isere-limitation-de-la-vitesse\/","url":"https:\/\/www.sillon38.com\/blog\/2013\/12\/10\/episode-de-pollution-de-lair-sur-la-zone-du-bassin-lyonnais-et-nord-isere-limitation-de-la-vitesse\/","name":"\u00c9pisode de pollution de l\u2019air sur la zone du bassin lyonnais et Nord Is\u00e8re Limitation de la vitesse -","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/#website"},"datePublished":"2013-12-10T17:41:37+00:00","author":{"@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"breadcrumb":{"@id":"https:\/\/www.sillon38.com\/blog\/2013\/12\/10\/episode-de-pollution-de-lair-sur-la-zone-du-bassin-lyonnais-et-nord-isere-limitation-de-la-vitesse\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sillon38.com\/blog\/2013\/12\/10\/episode-de-pollution-de-lair-sur-la-zone-du-bassin-lyonnais-et-nord-isere-limitation-de-la-vitesse\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sillon38.com\/blog\/2013\/12\/10\/episode-de-pollution-de-lair-sur-la-zone-du-bassin-lyonnais-et-nord-isere-limitation-de-la-vitesse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.sillon38.com\/blog\/"},{"@type":"ListItem","position":2,"name":"\u00c9pisode de pollution de l\u2019air sur la zone du bassin lyonnais et Nord Is\u00e8re Limitation de la vitesse"}]},{"@type":"WebSite","@id":"https:\/\/www.sillon38.com\/blog\/#website","url":"https:\/\/www.sillon38.com\/blog\/","name":"","description":"Le journal du monde rural","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sillon38.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1","name":"Gilbert"}]}},"_links":{"self":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/41508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/comments?post=41508"}],"version-history":[{"count":0,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/41508\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/media?parent=41508"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/categories?post=41508"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/tags?post=41508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}