{"id":5320,"date":"2009-01-28T15:03:44","date_gmt":"2009-01-28T13:03:44","guid":{"rendered":"http:\/\/staging.sillon38.com\/2009\/01\/28\/deconstruction-automobile-un-partenariat-avec-les-lycees\/"},"modified":"2009-01-28T15:03:44","modified_gmt":"2009-01-28T13:03:44","slug":"deconstruction-automobile-un-partenariat-avec-les-lycees","status":"publish","type":"post","link":"https:\/\/www.sillon38.com\/blog\/2009\/01\/28\/deconstruction-automobile-un-partenariat-avec-les-lycees\/","title":{"rendered":"D\u00e9construction automobile: un partenariat avec les lyc\u00e9es"},"content":{"rendered":"<p>Ce matin, au lyc\u00e9e des m\u00e9tiers de l\u2019automobile Gabriel Voisin (Bourg-en-Bresse, Ain), Jean-Jack Queyranne, Pr\u00e9sident du Conseil r\u00e9gional Rh\u00f4ne-Alpes, Roland Debbasch, recteur de l\u2019acad\u00e9mie de Lyon, et Anick Kadoche, Directrice de la soci\u00e9t\u00e9 INDRA*, ont sign\u00e9 la Convention de partenariat industriel sur la d\u00e9construction automobile dans les lyc\u00e9es professionnels.<\/p>\n<p>Les v\u00e9hicules en fin de vie ne pouvant \u00eatre remis qu&rsquo;\u00e0 des d\u00e9molisseurs agr\u00e9\u00e9s ou \u00e0 des centres de regroupement cr\u00e9\u00e9s par les producteurs, les lyc\u00e9es des m\u00e9tiers de l\u2019automobile sont dans l\u2019impossibilit\u00e9 de r\u00e9cup\u00e9rer des v\u00e9hicules hors d\u2019usage comme supports p\u00e9dagogiques.<br \/>\nPour pallier ces difficult\u00e9s, la R\u00e9gion Rh\u00f4ne-Alpes, l\u2019Acad\u00e9mie de Lyon et la soci\u00e9t\u00e9 INDRA, proposent un dispositif innovant : le groupe INDRA va mettre gracieusement \u00e0 la disposition des lyc\u00e9es des v\u00e9hicules qui seront utilis\u00e9s comme support p\u00e9dagogique puis elle les r\u00e9cup\u00e9rera pour en assurer la d\u00e9construction.<\/p>\n<p>Outre le respect de la r\u00e9glementation sur les v\u00e9hicules hors d\u2019usage, cette convention permet aux six lyc\u00e9es professionnels de l\u2019automobile de l&rsquo;Acad\u00e9mie de Lyon de r\u00e9cup\u00e9rer correctement certains d\u00e9chets automobiles qui pr\u00e9sentaient un danger de manipulation et d\u2019int\u00e9grer la premi\u00e8re \u00e9tape de d\u00e9construction des v\u00e9hicules (r\u00e9cup\u00e9ration des fluides) dans l\u2019\u00e9laboration des<br \/>\ndocuments p\u00e9dagogiques.<\/p>\n<p>L\u2019Education Nationale d\u00e9signe un chef de travaux par d\u00e9partement charg\u00e9 de collecter les besoins en v\u00e9hicules hors d\u2019usage et de les transmettre \u00e0 l\u2019entreprise INDRA qui organise les dotations par lyc\u00e9e et le cycle de rotation des v\u00e9hicules hors d\u2019usage sur l\u2019ann\u00e9e (plus de 100 v\u00e9hicules vont \u00eatre mis \u00e0 disposition annuellement).<\/p>\n<p>La R\u00e9gion Rh\u00f4ne-Alpes va coupler ce dispositif avec l\u2019op\u00e9ration \u00ab Evacuation et valorisation des d\u00e9chets toxiques \u00bb, venant compl\u00e9ter la politique r\u00e9gionale de gestion durable des d\u00e9chets dans les lyc\u00e9es (385 tonnes de d\u00e9chets collect\u00e9es en 3 ans). La cr\u00e9ation d\u2019un CAP ou d\u2019une mention compl\u00e9mentaire de \u00ab d\u00e9constructeur option Automobile \u00bb est \u00e9galement en projet.<\/p>\n<p>Par la suite, ce dispositif sera \u00e9tendu aux cinq lyc\u00e9es professionnels de l\u2019Acad\u00e9mie de Grenoble.<br \/>\nCette action contribue \u00e0 d\u00e9velopper des m\u00e9tiers \u00e9mergents dans le secteur de la d\u00e9construction automobile, s\u2019inscrit dans le cadre de la d\u00e9marche r\u00e9gionale pour un d\u00e9veloppement durable et participe \u00e0 l\u2019\u00e9ducation des jeunes rh\u00f4nalpins \u00e0 l\u2019environnement.<\/p>\n<p>* <em>Le Groupe INDRA f\u00e9d\u00e8re 200 entreprises agr\u00e9\u00e9es sp\u00e9cialis\u00e9es dans la d\u00e9construction, la valorisation et le recyclage<br \/>\nautomobile en France. A travers ce partenariat, l\u2019entreprise souhaite offrir une image r\u00e9nov\u00e9e et professionnelle de son<br \/>\nactivit\u00e9 et pallier \u00e0 des difficult\u00e9s de recrutement.\u00a0 <\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ce matin, au lyc\u00e9e des m\u00e9tiers de l\u2019automobile Gabriel Voisin (Bourg-en-Bresse, Ain), Jean-Jack Queyranne, Pr\u00e9sident du Conseil r\u00e9gional Rh\u00f4ne-Alpes, Roland Debbasch, recteur de l\u2019acad\u00e9mie de Lyon, et Anick Kadoche, Directrice de la soci\u00e9t\u00e9 INDRA*, ont sign\u00e9 la Convention de partenariat&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-5320","post","type-post","status-publish","format-standard","hentry","category-enseignementformation"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D\u00e9construction automobile: un partenariat avec les lyc\u00e9es -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sillon38.com\/blog\/2009\/01\/28\/deconstruction-automobile-un-partenariat-avec-les-lycees\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00e9construction automobile: un partenariat avec les lyc\u00e9es -\" \/>\n<meta property=\"og:description\" content=\"Ce matin, au lyc\u00e9e des m\u00e9tiers de l\u2019automobile Gabriel Voisin (Bourg-en-Bresse, Ain), Jean-Jack Queyranne, Pr\u00e9sident du Conseil r\u00e9gional Rh\u00f4ne-Alpes, Roland Debbasch, recteur de l\u2019acad\u00e9mie de Lyon, et Anick Kadoche, Directrice de la soci\u00e9t\u00e9 INDRA*, ont sign\u00e9 la Convention de partenariat...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sillon38.com\/blog\/2009\/01\/28\/deconstruction-automobile-un-partenariat-avec-les-lycees\/\" \/>\n<meta property=\"article:published_time\" content=\"2009-01-28T13:03:44+00:00\" \/>\n<meta name=\"author\" content=\"Gilbert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gilbert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/01\\\/28\\\/deconstruction-automobile-un-partenariat-avec-les-lycees\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/01\\\/28\\\/deconstruction-automobile-un-partenariat-avec-les-lycees\\\/\"},\"author\":{\"name\":\"Gilbert\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"headline\":\"D\u00e9construction automobile: un partenariat avec les lyc\u00e9es\",\"datePublished\":\"2009-01-28T13:03:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/01\\\/28\\\/deconstruction-automobile-un-partenariat-avec-les-lycees\\\/\"},\"wordCount\":491,\"commentCount\":0,\"articleSection\":[\"enseignement-formation\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/01\\\/28\\\/deconstruction-automobile-un-partenariat-avec-les-lycees\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/01\\\/28\\\/deconstruction-automobile-un-partenariat-avec-les-lycees\\\/\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/01\\\/28\\\/deconstruction-automobile-un-partenariat-avec-les-lycees\\\/\",\"name\":\"D\u00e9construction automobile: un partenariat avec les lyc\u00e9es -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\"},\"datePublished\":\"2009-01-28T13:03:44+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/01\\\/28\\\/deconstruction-automobile-un-partenariat-avec-les-lycees\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/01\\\/28\\\/deconstruction-automobile-un-partenariat-avec-les-lycees\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/01\\\/28\\\/deconstruction-automobile-un-partenariat-avec-les-lycees\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D\u00e9construction automobile: un partenariat avec les lyc\u00e9es\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\",\"name\":\"\",\"description\":\"Le journal du monde rural\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\",\"name\":\"Gilbert\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00e9construction automobile: un partenariat avec les lyc\u00e9es -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sillon38.com\/blog\/2009\/01\/28\/deconstruction-automobile-un-partenariat-avec-les-lycees\/","og_locale":"fr_FR","og_type":"article","og_title":"D\u00e9construction automobile: un partenariat avec les lyc\u00e9es -","og_description":"Ce matin, au lyc\u00e9e des m\u00e9tiers de l\u2019automobile Gabriel Voisin (Bourg-en-Bresse, Ain), Jean-Jack Queyranne, Pr\u00e9sident du Conseil r\u00e9gional Rh\u00f4ne-Alpes, Roland Debbasch, recteur de l\u2019acad\u00e9mie de Lyon, et Anick Kadoche, Directrice de la soci\u00e9t\u00e9 INDRA*, ont sign\u00e9 la Convention de partenariat...","og_url":"https:\/\/www.sillon38.com\/blog\/2009\/01\/28\/deconstruction-automobile-un-partenariat-avec-les-lycees\/","article_published_time":"2009-01-28T13:03:44+00:00","author":"Gilbert","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Gilbert","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sillon38.com\/blog\/2009\/01\/28\/deconstruction-automobile-un-partenariat-avec-les-lycees\/#article","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/2009\/01\/28\/deconstruction-automobile-un-partenariat-avec-les-lycees\/"},"author":{"name":"Gilbert","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"headline":"D\u00e9construction automobile: un partenariat avec les lyc\u00e9es","datePublished":"2009-01-28T13:03:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sillon38.com\/blog\/2009\/01\/28\/deconstruction-automobile-un-partenariat-avec-les-lycees\/"},"wordCount":491,"commentCount":0,"articleSection":["enseignement-formation"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.sillon38.com\/blog\/2009\/01\/28\/deconstruction-automobile-un-partenariat-avec-les-lycees\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.sillon38.com\/blog\/2009\/01\/28\/deconstruction-automobile-un-partenariat-avec-les-lycees\/","url":"https:\/\/www.sillon38.com\/blog\/2009\/01\/28\/deconstruction-automobile-un-partenariat-avec-les-lycees\/","name":"D\u00e9construction automobile: un partenariat avec les lyc\u00e9es -","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/#website"},"datePublished":"2009-01-28T13:03:44+00:00","author":{"@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"breadcrumb":{"@id":"https:\/\/www.sillon38.com\/blog\/2009\/01\/28\/deconstruction-automobile-un-partenariat-avec-les-lycees\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sillon38.com\/blog\/2009\/01\/28\/deconstruction-automobile-un-partenariat-avec-les-lycees\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sillon38.com\/blog\/2009\/01\/28\/deconstruction-automobile-un-partenariat-avec-les-lycees\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.sillon38.com\/blog\/"},{"@type":"ListItem","position":2,"name":"D\u00e9construction automobile: un partenariat avec les lyc\u00e9es"}]},{"@type":"WebSite","@id":"https:\/\/www.sillon38.com\/blog\/#website","url":"https:\/\/www.sillon38.com\/blog\/","name":"","description":"Le journal du monde rural","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sillon38.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1","name":"Gilbert"}]}},"_links":{"self":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/5320","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/comments?post=5320"}],"version-history":[{"count":0,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/5320\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/media?parent=5320"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/categories?post=5320"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/tags?post=5320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}