{"id":53272,"date":"2015-03-02T23:05:42","date_gmt":"2015-03-02T21:05:42","guid":{"rendered":"http:\/\/staging.sillon38.com\/?p=53272"},"modified":"2015-03-02T23:05:42","modified_gmt":"2015-03-02T21:05:42","slug":"les-nouveaux-cantons-du-departement-de-lisere","status":"publish","type":"post","link":"https:\/\/www.sillon38.com\/blog\/2015\/03\/02\/les-nouveaux-cantons-du-departement-de-lisere\/","title":{"rendered":"Les nouveaux cantons du d\u00e9partement de l\u2019Is\u00e8re"},"content":{"rendered":"<p><span style=\"color: #000080;\">Au lendemain de l\u2019\u00e9lection d\u00e9partementale de mars\u00a02015, le d\u00e9partement  de l\u2019Is\u00e8re comprendra 29\u00a0cantons au lieu de 58. Il comptera alors  58\u00a0conseillers d\u00e9partementaux, 29\u00a0femmes et 29\u00a0hommes. <\/span><\/p>\n<p><span style=\"color: #000080;\">La carte  cantonale du d\u00e9partement a \u00e9t\u00e9 modifi\u00e9e pour constituer des cantons plus  homog\u00e8nes en termes de population. Ainsi, les nouveaux cantons auront  une population comprise entre 28\u00a0000 et 50\u00a0000\u00a0habitants, contre une  fourchette comprise entre 4\u00a0000 et 40\u00a0000\u00a0habitants auparavant.<\/span><\/p>\n<h3 id=\"inter1\"><span style=\"color: #000080;\">L\u2019Is\u00e8re comprendra 29\u00a0cantons<\/span><\/h3>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<p><span style=\"color: #000080;\">En Is\u00e8re, la nouvelle carte des cantons a \u00e9t\u00e9 d\u00e9finie par d\u00e9cret du  18\u00a0f\u00e9vrier\u00a02014. Les changements se traduiront \u00e0 partir de mars 2015 par  la d\u00e9finition de 29\u00a0cantons, au lieu de 58\u00a0actuellement.<\/span><\/p>\n<p><span style=\"color: #000080;\">Avec un peu  plus de 50\u00a0000\u00a0habitants en 2012, les cantons de Bourgoin-Jallieu-1 et  de Charvieu-Chavagneux sont les plus peupl\u00e9s. \u00c0 l\u2019inverse, celui de la  Matheysine-Tri\u00e8ves avec 28\u00a0300\u00a0habitants est celui qui l&rsquo;est le moins.  Ce canton au caract\u00e8re montagneux est par ailleurs celui qui regroupe le  plus grand nombre de communes (72). Les cantons de Grenoble-1, 3 et 4  ne comprennent que des fractions de la commune de Grenoble. Le canton de  Grenoble-2 int\u00e8gre sept communes situ\u00e9es au nord de Grenoble. C\u2019est  aussi le cas pour Vienne, \u00e9clat\u00e9e entre le canton de Vienne-1 au nord,  qui compte 9\u00a0autres communes et le canton de Vienne-2 au sud, aux c\u00f4t\u00e9s  de 17\u00a0autres communes.<\/span><\/p>\n<h3 id=\"inter2\"><span style=\"color: #000080;\">De fortes disparit\u00e9s entre les cantons<\/span><\/h3>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<p><span style=\"color: #000080;\">Les caract\u00e9ristiques d\u00e9mographiques sont ainsi assez diff\u00e9rentes  entre les cantons de L\u2019Isle-d\u2019Abeau, o\u00f9 la part des moins de 20\u00a0ans  atteint 33\u00a0%, et le canton de Grenoble-1, o\u00f9 cette proportion n\u2019atteint  pas 20\u00a0%.<\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<p><span style=\"color: #000080;\">De la m\u00eame fa\u00e7on, la r\u00e9partition par cat\u00e9gorie socioprofessionnelle  fluctue entre les diff\u00e9rents cantons de l\u2019Is\u00e8re, et m\u00eame au sein des  diff\u00e9rents cantons de Grenoble.<\/span><\/p>\n<p><span style=\"color: #000080;\"><a href=\"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2015\/03\/Sans-titre1.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-53273\" title=\"Sans titre\" src=\"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2015\/03\/Sans-titre1.png\" alt=\"Sans titre\" width=\"474\" height=\"500\" srcset=\"https:\/\/www.sillon38.com\/blog\/wp-content\/uploads\/2015\/03\/Sans-titre1.png 474w, https:\/\/www.sillon38.com\/blog\/wp-content\/uploads\/2015\/03\/Sans-titre1-284x300.png 284w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><\/a><\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<h3 id=\"definitions\"><span style=\"color: #000080;\">Pour comprendre<\/span><\/h3>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<div id=\"def1\">\n<p><span style=\"color: #000080;\">La loi du 17\u00a0mai\u00a02013 instaure un nouveau mode d&rsquo;\u00e9lection pour les  membres des conseils d\u00e9partementaux, nouvelle appellation des conseils  g\u00e9n\u00e9raux. Lors du prochain renouvellement g\u00e9n\u00e9ral des 22\u00a0et  29\u00a0mars\u00a02015, les candidats se pr\u00e9senteront en bin\u00f4me compos\u00e9 d&rsquo;un homme  et d\u2019une femme. Dans chaque canton, un bin\u00f4me, donc deux conseillers  d\u00e9partementaux, seront \u00e9lus au scrutin majoritaire \u00e0 deux tours.<\/span><\/p>\n<p><span style=\"color: #000080;\"> Ces  modifications s\u2019inscrivent dans le cadre des objectifs d\u00e9finis par le  Pr\u00e9sident de la R\u00e9publique lors des \u00c9tats g\u00e9n\u00e9raux de la d\u00e9mocratie  territoriale. Ce mode de scrutin garantit la parit\u00e9 homme-femme, alors  que les assembl\u00e9es d\u00e9partementales ne comptent aujourd\u2019hui que 13,8\u00a0% de  femmes.<\/span><\/p>\n<p><span style=\"color: #000080;\">Le nombre d\u2019\u00e9lus restant inchang\u00e9, la carte cantonale de chaque  d\u00e9partement a \u00e9t\u00e9 modifi\u00e9e afin de permettre l\u2019\u00e9lection de deux  conseillers d\u00e9partementaux par canton et d\u2019am\u00e9liorer leur  repr\u00e9sentativit\u00e9 d\u00e9mographique. Pr\u00e8s des trois cinqui\u00e8mes des cantons  n\u2019ont pas connu de modification de leurs limites g\u00e9ographiques depuis  1801.<\/span><\/div>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<h3 id=\"bibliographie\"><span style=\"color: #000080;\">Pour en savoir plus<\/span><\/h3>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<ul>\n<li><span style=\"color: #000080;\"><a href=\"http:\/\/www.legifrance.gouv.fr\/affichTexte.do?cidTexte=JORFTEXT000028637316\">D\u00e9cret n\u00b0 2014-147 du 13 f\u00e9vrier 2014 portant d\u00e9limitation des cantons dans le d\u00e9partement de l&rsquo;Is\u00e8re,<\/a><\/span><\/li>\n<li><span style=\"color: #000080;\"><a href=\"http:\/\/www.insee.fr\/fr\/themes\/detail.asp?reg_id=0&amp;ref_id=cantons-2015\">Les populations l\u00e9gales 2012 des cantons &#8211;\u00a0d\u00e9coupage\u00a02015\u00a0sur\u00a0Insee.fr <\/a><\/span><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Au lendemain de l\u2019\u00e9lection d\u00e9partementale de mars 2015, le d\u00e9partement de l\u2019Is\u00e8re comprendra 29 cantons au lieu de 58. Il comptera alors 58 conseillers d\u00e9partementaux, 29 femmes et 29 hommes. La carte cantonale du d\u00e9partement a \u00e9t\u00e9 modifi\u00e9e pour constituer des cantons plus homog\u00e8nes en termes de population.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[70],"tags":[958,2776,2994],"class_list":["post-53272","post","type-post","status-publish","format-standard","hentry","category-territoires-isere","tag-cantons","tag-grenoble","tag-isere"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les nouveaux cantons du d\u00e9partement de l\u2019Is\u00e8re -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sillon38.com\/blog\/2015\/03\/02\/les-nouveaux-cantons-du-departement-de-lisere\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les nouveaux cantons du d\u00e9partement de l\u2019Is\u00e8re -\" \/>\n<meta property=\"og:description\" content=\"Au lendemain de l\u2019\u00e9lection d\u00e9partementale de mars 2015, le d\u00e9partement de l\u2019Is\u00e8re comprendra 29 cantons au lieu de 58. Il comptera alors 58 conseillers d\u00e9partementaux, 29 femmes et 29 hommes. La carte cantonale du d\u00e9partement a \u00e9t\u00e9 modifi\u00e9e pour constituer des cantons plus homog\u00e8nes en termes de population.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sillon38.com\/blog\/2015\/03\/02\/les-nouveaux-cantons-du-departement-de-lisere\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-03-02T21:05:42+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2015\/03\/Sans-titre1.png\" \/>\n<meta name=\"author\" content=\"Gilbert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gilbert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2015\\\/03\\\/02\\\/les-nouveaux-cantons-du-departement-de-lisere\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2015\\\/03\\\/02\\\/les-nouveaux-cantons-du-departement-de-lisere\\\/\"},\"author\":{\"name\":\"Gilbert\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"headline\":\"Les nouveaux cantons du d\u00e9partement de l\u2019Is\u00e8re\",\"datePublished\":\"2015-03-02T21:05:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2015\\\/03\\\/02\\\/les-nouveaux-cantons-du-departement-de-lisere\\\/\"},\"wordCount\":529,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2015\\\/03\\\/02\\\/les-nouveaux-cantons-du-departement-de-lisere\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/staging.sillon38.com\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/Sans-titre1.png\",\"keywords\":[\"cantons\",\"Grenoble\",\"Is\u00e8re\"],\"articleSection\":[\"territoires\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2015\\\/03\\\/02\\\/les-nouveaux-cantons-du-departement-de-lisere\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2015\\\/03\\\/02\\\/les-nouveaux-cantons-du-departement-de-lisere\\\/\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2015\\\/03\\\/02\\\/les-nouveaux-cantons-du-departement-de-lisere\\\/\",\"name\":\"Les nouveaux cantons du d\u00e9partement de l\u2019Is\u00e8re -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2015\\\/03\\\/02\\\/les-nouveaux-cantons-du-departement-de-lisere\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2015\\\/03\\\/02\\\/les-nouveaux-cantons-du-departement-de-lisere\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/staging.sillon38.com\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/Sans-titre1.png\",\"datePublished\":\"2015-03-02T21:05:42+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2015\\\/03\\\/02\\\/les-nouveaux-cantons-du-departement-de-lisere\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2015\\\/03\\\/02\\\/les-nouveaux-cantons-du-departement-de-lisere\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2015\\\/03\\\/02\\\/les-nouveaux-cantons-du-departement-de-lisere\\\/#primaryimage\",\"url\":\"http:\\\/\\\/staging.sillon38.com\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/Sans-titre1.png\",\"contentUrl\":\"http:\\\/\\\/staging.sillon38.com\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/Sans-titre1.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2015\\\/03\\\/02\\\/les-nouveaux-cantons-du-departement-de-lisere\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les nouveaux cantons du d\u00e9partement de l\u2019Is\u00e8re\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\",\"name\":\"\",\"description\":\"Le journal du monde rural\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\",\"name\":\"Gilbert\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les nouveaux cantons du d\u00e9partement de l\u2019Is\u00e8re -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sillon38.com\/blog\/2015\/03\/02\/les-nouveaux-cantons-du-departement-de-lisere\/","og_locale":"fr_FR","og_type":"article","og_title":"Les nouveaux cantons du d\u00e9partement de l\u2019Is\u00e8re -","og_description":"Au lendemain de l\u2019\u00e9lection d\u00e9partementale de mars 2015, le d\u00e9partement de l\u2019Is\u00e8re comprendra 29 cantons au lieu de 58. Il comptera alors 58 conseillers d\u00e9partementaux, 29 femmes et 29 hommes. La carte cantonale du d\u00e9partement a \u00e9t\u00e9 modifi\u00e9e pour constituer des cantons plus homog\u00e8nes en termes de population.","og_url":"https:\/\/www.sillon38.com\/blog\/2015\/03\/02\/les-nouveaux-cantons-du-departement-de-lisere\/","article_published_time":"2015-03-02T21:05:42+00:00","og_image":[{"url":"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2015\/03\/Sans-titre1.png","type":"","width":"","height":""}],"author":"Gilbert","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Gilbert","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sillon38.com\/blog\/2015\/03\/02\/les-nouveaux-cantons-du-departement-de-lisere\/#article","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/2015\/03\/02\/les-nouveaux-cantons-du-departement-de-lisere\/"},"author":{"name":"Gilbert","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"headline":"Les nouveaux cantons du d\u00e9partement de l\u2019Is\u00e8re","datePublished":"2015-03-02T21:05:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sillon38.com\/blog\/2015\/03\/02\/les-nouveaux-cantons-du-departement-de-lisere\/"},"wordCount":529,"commentCount":0,"image":{"@id":"https:\/\/www.sillon38.com\/blog\/2015\/03\/02\/les-nouveaux-cantons-du-departement-de-lisere\/#primaryimage"},"thumbnailUrl":"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2015\/03\/Sans-titre1.png","keywords":["cantons","Grenoble","Is\u00e8re"],"articleSection":["territoires"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.sillon38.com\/blog\/2015\/03\/02\/les-nouveaux-cantons-du-departement-de-lisere\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.sillon38.com\/blog\/2015\/03\/02\/les-nouveaux-cantons-du-departement-de-lisere\/","url":"https:\/\/www.sillon38.com\/blog\/2015\/03\/02\/les-nouveaux-cantons-du-departement-de-lisere\/","name":"Les nouveaux cantons du d\u00e9partement de l\u2019Is\u00e8re -","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sillon38.com\/blog\/2015\/03\/02\/les-nouveaux-cantons-du-departement-de-lisere\/#primaryimage"},"image":{"@id":"https:\/\/www.sillon38.com\/blog\/2015\/03\/02\/les-nouveaux-cantons-du-departement-de-lisere\/#primaryimage"},"thumbnailUrl":"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2015\/03\/Sans-titre1.png","datePublished":"2015-03-02T21:05:42+00:00","author":{"@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"breadcrumb":{"@id":"https:\/\/www.sillon38.com\/blog\/2015\/03\/02\/les-nouveaux-cantons-du-departement-de-lisere\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sillon38.com\/blog\/2015\/03\/02\/les-nouveaux-cantons-du-departement-de-lisere\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.sillon38.com\/blog\/2015\/03\/02\/les-nouveaux-cantons-du-departement-de-lisere\/#primaryimage","url":"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2015\/03\/Sans-titre1.png","contentUrl":"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2015\/03\/Sans-titre1.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.sillon38.com\/blog\/2015\/03\/02\/les-nouveaux-cantons-du-departement-de-lisere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.sillon38.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Les nouveaux cantons du d\u00e9partement de l\u2019Is\u00e8re"}]},{"@type":"WebSite","@id":"https:\/\/www.sillon38.com\/blog\/#website","url":"https:\/\/www.sillon38.com\/blog\/","name":"","description":"Le journal du monde rural","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sillon38.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1","name":"Gilbert"}]}},"_links":{"self":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/53272","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/comments?post=53272"}],"version-history":[{"count":0,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/53272\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/media?parent=53272"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/categories?post=53272"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/tags?post=53272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}