{"id":55754,"date":"2015-06-01T11:46:43","date_gmt":"2015-06-01T09:46:43","guid":{"rendered":"http:\/\/staging.sillon38.com\/?p=55754"},"modified":"2015-06-01T11:46:43","modified_gmt":"2015-06-01T09:46:43","slug":"enfin-le-juste-prix-pour-les-producteurs-de-noix","status":"publish","type":"post","link":"https:\/\/www.sillon38.com\/blog\/2015\/06\/01\/enfin-le-juste-prix-pour-les-producteurs-de-noix\/","title":{"rendered":"Enfin le \u00a0\u00bb juste prix\u00a0\u00bb pour les producteurs de noix"},"content":{"rendered":"<p><span style=\"color: #000080;\"><strong>Une \u00e9tude commandit\u00e9e par la profession et r\u00e9alis\u00e9e par CER France a \u00e9t\u00e9 r\u00e9alis\u00e9e sur\u00a0 les co\u00fbts de production en nuciculture pour les ann\u00e9es 2010-2012. Celui ci se situe dans une fourchette de 2 euros \u00e0 2 euros 20.<\/strong><\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<p><span style=\"color: #000080;\">Pierre Gallin-Martel, nuciculteur, membre de la chambre d&rsquo;agriculture, vice pr\u00e9sident du Comit\u00e9 Interprofessionnel de la noix de Grenoble pr\u00e9cise: \u00a0\u00bb cette \u00e9tude est tout \u00e0 fait fiable. Beaucoup ont \u00e9t\u00e9 surpris par le co\u00fbt \u00e9lev\u00e9 de production. Les r\u00e9sultats de cette analyse d\u00e9montrent aussi que le prix pay\u00e9 aux producteurs n&rsquo;est pas un prix excessif. \u00ab\u00a0<\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<p><span style=\"color: #000080;\">Bien entendu \u00e0 cela il faut rajouter le revenu du producteur. \u00a0\u00bb Personnellement je pense qu&rsquo;un prix se situant autour des 3 euros le kilo me semble tout \u00e0 fait raisonnable. C&rsquo;est en effet un prix correct et r\u00e9mun\u00e9rateur. N&rsquo;oublions pas que depuis 5 ans le prix des intrants et de la m\u00e9canisation ont vertigineusement augment\u00e9s.\u00a0\u00bb<br \/>\n<\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<p><span style=\"color: #000080;\">Pierre Gallin-Martel estime que\u00a0 la saison 2014 est tr\u00e8s correcte m\u00eame si la r\u00e9colte est inf\u00e9rieure \u00e0 20% par rapport \u00e0 la campagne 2013. 2013 \u00e9tait une grosse ann\u00e9e et 2014 a une production inf\u00e9rieure de 10% par rapport une ann\u00e9e moyenne.<\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<p><span style=\"color: #000080;\">Les calibres sont corrects \u00e0 \u00e9quilibr\u00e9s et la qualit\u00e9 est bonne surtout pour les noix r\u00e9colt\u00e9es avant la p\u00e9riode pluvieuse qui a suivi le 18 octobre \u00a0\u00bb d&rsquo;ou l&rsquo;int\u00e9r\u00eat de s&rsquo;\u00e9quiper afin d&rsquo;organiser une r\u00e9colte rapide.<\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<p><span style=\"color: #000080;\">La commercialisation a \u00e9t\u00e9 bonne du fait qu&rsquo;il n&rsquo; avait pas de stock, que la parit\u00e9 euro\/dollar est favorable, ceci associ\u00e9 un un d\u00e9ficit d&rsquo;offre par rapport \u00e0 la demande.<\/span><\/p>\n<p><span style=\"color: #000080;\">\u00ab\u00a0Il n&rsquo;y a aucune raison s\u00e9rieuse pour que cette situation ne perdure pas, \u00e0 condition que nous soyons vigilants sur la qualit\u00e9.\u00a0\u00bb<br \/>\n<\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<p><span style=\"color: #000080;\">Ce d\u00e9ficit est un gros probl\u00e8me et risque h\u00e9las de s&rsquo;accentuer du fait que la plantation d&rsquo;arbres est insuffisante\u00a0\u00bb m\u00eame si on constate un redressement et que les prix r\u00e9mun\u00e9rateurs incitent \u00e0 la reprise d&rsquo;exploitations ou \u00e0 l&rsquo;installation. \u00ab\u00a0&#8230;<\/span><\/p>\n<p><span style=\"color: #000080;\">&#8230;\u00a0\u00bb On peut se poser la question de savoir pourquoi les organisations de producteurs n&rsquo;aident pas les producteurs adh\u00e9rents aux investissements de plantation dans le cadre de leurs programmes op\u00e9rationnels. D&rsquo;autant plus que les organisations de producteurs n&rsquo;utilisent pas la totalit\u00e9 de leurs potentiels d&rsquo;aides que l&rsquo;Europe leur propose.. C&rsquo;est un choix strat\u00e9gique pour l&rsquo;avenir&#8230;\u00a0\u00bb<br \/>\n<\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<p><span style=\"color: #000080;\">Le vice -pr\u00e9sident du CING constate \u00e9galement un manque de foncier: \u00a0\u00bb l&#8217;emprise est de plus en plus forte \u00ab\u00a0.<\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<p><span style=\"color: #000080;\">Il est \u00e0 noter que l&rsquo; Etat va arr\u00eater d\u00e8s le 31\/12\/2015 de financer le CTIFL et les stations de recherche \u00a0\u00bb qui ont un r\u00f4le important \u00a0\u00bb comme la Senura.<\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<p><span style=\"color: #000080;\">Pierre Gallin-Martel pr\u00e9cise:\u00a0\u00bb il y aura une contre partie puisque l&rsquo;Etat propose ENFIN la mise en place une contribution volontaire obligatoire sur tous les produits ou surfaces plant\u00e9es. Cela permettra de financer la recherche et l&rsquo;exp\u00e9rimentation.\u00a0\u00bb<\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<p><span style=\"color: #000080;\">Membre de la chambre d&rsquo;Agriculture de l&rsquo;Is\u00e8re, il conclue\u00a0\u00bb la chambre d&rsquo;Agriculture joue un r\u00f4le important, elle oriente et insuffle la politique agricole d\u00e9partementale. En un mot la chambre a un r\u00f4le f\u00e9d\u00e9rateur et moteur au niveau du dynamisme des fili\u00e8res.\u00a0\u00bb<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rencontre avec Pierre Gallin-Martel, membre de la chambre d&rsquo;agriculture de l&rsquo;Is\u00e8re, vice pr\u00e9sident du CING.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,48],"tags":[1104,1267,1692,3973,4297],"class_list":["post-55754","post","type-post","status-publish","format-standard","hentry","category-a-la-une","category-nuciculture","tag-chambre-dagriculture-de-lisere","tag-cing","tag-ctifl","tag-noix","tag-pierre-gallin-martel"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Enfin le &quot; juste prix&quot; pour les producteurs de noix -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sillon38.com\/blog\/2015\/06\/01\/enfin-le-juste-prix-pour-les-producteurs-de-noix\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Enfin le &quot; juste prix&quot; pour les producteurs de noix -\" \/>\n<meta property=\"og:description\" content=\"Rencontre avec Pierre Gallin-Martel, membre de la chambre d&#039;agriculture de l&#039;Is\u00e8re, vice pr\u00e9sident du CING.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sillon38.com\/blog\/2015\/06\/01\/enfin-le-juste-prix-pour-les-producteurs-de-noix\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-06-01T09:46:43+00:00\" \/>\n<meta name=\"author\" content=\"Gilbert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gilbert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2015\\\/06\\\/01\\\/enfin-le-juste-prix-pour-les-producteurs-de-noix\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2015\\\/06\\\/01\\\/enfin-le-juste-prix-pour-les-producteurs-de-noix\\\/\"},\"author\":{\"name\":\"Gilbert\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"headline\":\"Enfin le \u00a0\u00bb juste prix\u00a0\u00bb pour les producteurs de noix\",\"datePublished\":\"2015-06-01T09:46:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2015\\\/06\\\/01\\\/enfin-le-juste-prix-pour-les-producteurs-de-noix\\\/\"},\"wordCount\":562,\"commentCount\":0,\"keywords\":[\"Chambre d'agriculture de l'Is\u00e8re\",\"CING\",\"CTIFL\",\"noix\",\"Pierre Gallin-Martel\"],\"articleSection\":[\"\u00c0 la une\",\"nuciculture\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2015\\\/06\\\/01\\\/enfin-le-juste-prix-pour-les-producteurs-de-noix\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2015\\\/06\\\/01\\\/enfin-le-juste-prix-pour-les-producteurs-de-noix\\\/\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2015\\\/06\\\/01\\\/enfin-le-juste-prix-pour-les-producteurs-de-noix\\\/\",\"name\":\"Enfin le \\\" juste prix\\\" pour les producteurs de noix -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\"},\"datePublished\":\"2015-06-01T09:46:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2015\\\/06\\\/01\\\/enfin-le-juste-prix-pour-les-producteurs-de-noix\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2015\\\/06\\\/01\\\/enfin-le-juste-prix-pour-les-producteurs-de-noix\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2015\\\/06\\\/01\\\/enfin-le-juste-prix-pour-les-producteurs-de-noix\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Enfin le \u00a0\u00bb juste prix\u00a0\u00bb pour les producteurs de noix\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\",\"name\":\"\",\"description\":\"Le journal du monde rural\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\",\"name\":\"Gilbert\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Enfin le \" juste prix\" pour les producteurs de noix -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sillon38.com\/blog\/2015\/06\/01\/enfin-le-juste-prix-pour-les-producteurs-de-noix\/","og_locale":"fr_FR","og_type":"article","og_title":"Enfin le \" juste prix\" pour les producteurs de noix -","og_description":"Rencontre avec Pierre Gallin-Martel, membre de la chambre d'agriculture de l'Is\u00e8re, vice pr\u00e9sident du CING.","og_url":"https:\/\/www.sillon38.com\/blog\/2015\/06\/01\/enfin-le-juste-prix-pour-les-producteurs-de-noix\/","article_published_time":"2015-06-01T09:46:43+00:00","author":"Gilbert","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Gilbert","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sillon38.com\/blog\/2015\/06\/01\/enfin-le-juste-prix-pour-les-producteurs-de-noix\/#article","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/2015\/06\/01\/enfin-le-juste-prix-pour-les-producteurs-de-noix\/"},"author":{"name":"Gilbert","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"headline":"Enfin le \u00a0\u00bb juste prix\u00a0\u00bb pour les producteurs de noix","datePublished":"2015-06-01T09:46:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sillon38.com\/blog\/2015\/06\/01\/enfin-le-juste-prix-pour-les-producteurs-de-noix\/"},"wordCount":562,"commentCount":0,"keywords":["Chambre d'agriculture de l'Is\u00e8re","CING","CTIFL","noix","Pierre Gallin-Martel"],"articleSection":["\u00c0 la une","nuciculture"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.sillon38.com\/blog\/2015\/06\/01\/enfin-le-juste-prix-pour-les-producteurs-de-noix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.sillon38.com\/blog\/2015\/06\/01\/enfin-le-juste-prix-pour-les-producteurs-de-noix\/","url":"https:\/\/www.sillon38.com\/blog\/2015\/06\/01\/enfin-le-juste-prix-pour-les-producteurs-de-noix\/","name":"Enfin le \" juste prix\" pour les producteurs de noix -","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/#website"},"datePublished":"2015-06-01T09:46:43+00:00","author":{"@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"breadcrumb":{"@id":"https:\/\/www.sillon38.com\/blog\/2015\/06\/01\/enfin-le-juste-prix-pour-les-producteurs-de-noix\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sillon38.com\/blog\/2015\/06\/01\/enfin-le-juste-prix-pour-les-producteurs-de-noix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sillon38.com\/blog\/2015\/06\/01\/enfin-le-juste-prix-pour-les-producteurs-de-noix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.sillon38.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Enfin le \u00a0\u00bb juste prix\u00a0\u00bb pour les producteurs de noix"}]},{"@type":"WebSite","@id":"https:\/\/www.sillon38.com\/blog\/#website","url":"https:\/\/www.sillon38.com\/blog\/","name":"","description":"Le journal du monde rural","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sillon38.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1","name":"Gilbert"}]}},"_links":{"self":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/55754","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/comments?post=55754"}],"version-history":[{"count":0,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/55754\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/media?parent=55754"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/categories?post=55754"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/tags?post=55754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}