{"id":5603,"date":"2009-02-23T21:38:23","date_gmt":"2009-02-23T19:38:23","guid":{"rendered":"http:\/\/staging.sillon38.com\/2009\/02\/23\/la-reorientation-des-aides-porte-sur-14-milliard-e\/"},"modified":"2009-02-23T21:38:23","modified_gmt":"2009-02-23T19:38:23","slug":"la-reorientation-des-aides-porte-sur-14-milliard-e","status":"publish","type":"post","link":"https:\/\/www.sillon38.com\/blog\/2009\/02\/23\/la-reorientation-des-aides-porte-sur-14-milliard-e\/","title":{"rendered":"La r\u00e9orientation des aides porte sur 1,4 milliard \u20ac"},"content":{"rendered":"<p>Depuis la conclusion de l\u2019accord du 20 novembre dernier sur le bilan de sant\u00e9 de la PAC, Michel Barnier, ministre de l\u2019Agriculture et de la P\u00eache, a ouvert une concertation continue avec les organisations syndicales et professionnelles de l\u2019agriculture, les ONG environnementales, les repr\u00e9sentants des commissions comp\u00e9tentes du Parlement et des associations d\u2019\u00e9lus ainsi que les nombreux partenaires de l\u2019agriculture.<br \/>\nA l\u2019issue de cette large concertation, le ministre a pr\u00e9sent\u00e9 aujourd&rsquo;hui devant le Conseil d\u2019orientation de l\u2019\u00e9conomie agricole et alimentaire (CSO) les modalit\u00e9s de mise en \u0153uvre du bilan de sant\u00e9 de la PAC.<\/p>\n<p>Les mesures d\u00e9cid\u00e9es conform\u00e9ment aux orientations voulues par le Chef de l\u2019Etat et sous l\u2019autorit\u00e9 du Premier ministre conduisent \u00e0 r\u00e9orienter en 2010 pr\u00e8s de 1,4 milliard d\u2019euros, soit 18% des aides directes re\u00e7ues par les agriculteurs sur les 4 objectifs suivants :<br \/>\n1) Consolider l\u2019\u00e9conomie agricole et l\u2019emploi sur l\u2019ensemble du territoire. La r\u00e9orientation des aides permet en particulier de r\u00e9\u00e9quilibrer le soutien en faveur des productions structurellement fragiles, telles que l\u2019\u00e9levage ovin et caprin, et de revaloriser l\u2019indemnit\u00e9 compensatoire de handicaps naturels (ICHN) dont b\u00e9n\u00e9ficient les territoires de montagne.<br \/>\n2) Instaurer un nouveau mode de soutien pour l\u2019\u00e9levage \u00e0 l\u2019herbe. Pr\u00e8s d\u20191 milliard d\u2019euros sont ainsi mobilis\u00e9s pour cr\u00e9er, \u00e0 hauteur de 700 millions d\u2019euros, un soutien sp\u00e9cifique aux surfaces en herbe consacr\u00e9es \u00e0 l\u2019\u00e9levage et pour pr\u00e9server, \u00e0 hauteur de 240 millions d\u2019euros, la prime herbag\u00e8re agro-environnementales (PHAE).<br \/>\n3) Accompagner un mode de d\u00e9veloppement durable de l\u2019agriculture. Les d\u00e9cisions prises conduisent \u00e0 soutenir le d\u00e9veloppement de la production de prot\u00e9ines v\u00e9g\u00e9tales, augmenter les moyens consacr\u00e9s \u00e0 l\u2019agriculture biologique et r\u00e9pondre aux d\u00e9fis de la performance \u00e9nerg\u00e9tique des entreprises agricoles, de la gestion de l\u2019eau et de la biodiversit\u00e9.<br \/>\n4) Instaurer des outils de couverture des risques climatiques et sanitaires. 140 millions d\u2019euros sont mobilis\u00e9s \u00e0 ce titre. Le bilan de sant\u00e9 est ainsi mis \u00e0 profit d\u00e8s \u00e0 pr\u00e9sent pour contribuer financi\u00e8rement, avec les fonds europ\u00e9ens, \u00e0 la g\u00e9n\u00e9ralisation de l\u2019assurance r\u00e9colte et \u00e0 la cr\u00e9ation d\u2019un fonds sanitaire.<br \/>\nCes objectifs traduisent l\u2019ambition d\u2019une Politique Agricole Commune plus juste, plus durable, plus pr\u00e9ventive et en fin de compte plus \u00e9quilibr\u00e9e. Les d\u00e9cisions arr\u00eat\u00e9es prennent en compte la r\u00e9alit\u00e9 d\u2019un contexte agricole difficile. Elles seront mises en \u0153uvre de fa\u00e7on pragmatique et efficace pour une premi\u00e8re application en d\u00e9cembre 2010.<br \/>\nCes d\u00e9cisions aboutissent \u00e0 une r\u00e9duction des \u00e9carts entre les montants des aides attribu\u00e9es aux exploitations agricoles.<br \/>\nIl est de l\u2019int\u00e9r\u00eat de tous de donner \u00e0 la PAC une l\u00e9gitimit\u00e9 nouvelle pour la rendre plus forte dans la perspective de 2013<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Depuis la conclusion de l\u2019accord du 20 novembre dernier sur le bilan de sant\u00e9 de la PAC, Michel Barnier, ministre de l\u2019Agriculture et de la P\u00eache, a ouvert une concertation continue avec les organisations syndicales et professionnelles de l\u2019agriculture, les&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[51],"tags":[],"class_list":["post-5603","post","type-post","status-publish","format-standard","hentry","category-pac"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La r\u00e9orientation des aides porte sur 1,4 milliard \u20ac -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sillon38.com\/blog\/2009\/02\/23\/la-reorientation-des-aides-porte-sur-14-milliard-e\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La r\u00e9orientation des aides porte sur 1,4 milliard \u20ac -\" \/>\n<meta property=\"og:description\" content=\"Depuis la conclusion de l\u2019accord du 20 novembre dernier sur le bilan de sant\u00e9 de la PAC, Michel Barnier, ministre de l\u2019Agriculture et de la P\u00eache, a ouvert une concertation continue avec les organisations syndicales et professionnelles de l\u2019agriculture, les...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sillon38.com\/blog\/2009\/02\/23\/la-reorientation-des-aides-porte-sur-14-milliard-e\/\" \/>\n<meta property=\"article:published_time\" content=\"2009-02-23T19:38:23+00:00\" \/>\n<meta name=\"author\" content=\"Gilbert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gilbert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/02\\\/23\\\/la-reorientation-des-aides-porte-sur-14-milliard-e\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/02\\\/23\\\/la-reorientation-des-aides-porte-sur-14-milliard-e\\\/\"},\"author\":{\"name\":\"Gilbert\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"headline\":\"La r\u00e9orientation des aides porte sur 1,4 milliard \u20ac\",\"datePublished\":\"2009-02-23T19:38:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/02\\\/23\\\/la-reorientation-des-aides-porte-sur-14-milliard-e\\\/\"},\"wordCount\":495,\"commentCount\":0,\"articleSection\":[\"PAC\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/02\\\/23\\\/la-reorientation-des-aides-porte-sur-14-milliard-e\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/02\\\/23\\\/la-reorientation-des-aides-porte-sur-14-milliard-e\\\/\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/02\\\/23\\\/la-reorientation-des-aides-porte-sur-14-milliard-e\\\/\",\"name\":\"La r\u00e9orientation des aides porte sur 1,4 milliard \u20ac -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\"},\"datePublished\":\"2009-02-23T19:38:23+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/02\\\/23\\\/la-reorientation-des-aides-porte-sur-14-milliard-e\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/02\\\/23\\\/la-reorientation-des-aides-porte-sur-14-milliard-e\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/02\\\/23\\\/la-reorientation-des-aides-porte-sur-14-milliard-e\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La r\u00e9orientation des aides porte sur 1,4 milliard \u20ac\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\",\"name\":\"\",\"description\":\"Le journal du monde rural\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\",\"name\":\"Gilbert\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La r\u00e9orientation des aides porte sur 1,4 milliard \u20ac -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sillon38.com\/blog\/2009\/02\/23\/la-reorientation-des-aides-porte-sur-14-milliard-e\/","og_locale":"fr_FR","og_type":"article","og_title":"La r\u00e9orientation des aides porte sur 1,4 milliard \u20ac -","og_description":"Depuis la conclusion de l\u2019accord du 20 novembre dernier sur le bilan de sant\u00e9 de la PAC, Michel Barnier, ministre de l\u2019Agriculture et de la P\u00eache, a ouvert une concertation continue avec les organisations syndicales et professionnelles de l\u2019agriculture, les...","og_url":"https:\/\/www.sillon38.com\/blog\/2009\/02\/23\/la-reorientation-des-aides-porte-sur-14-milliard-e\/","article_published_time":"2009-02-23T19:38:23+00:00","author":"Gilbert","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Gilbert","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sillon38.com\/blog\/2009\/02\/23\/la-reorientation-des-aides-porte-sur-14-milliard-e\/#article","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/2009\/02\/23\/la-reorientation-des-aides-porte-sur-14-milliard-e\/"},"author":{"name":"Gilbert","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"headline":"La r\u00e9orientation des aides porte sur 1,4 milliard \u20ac","datePublished":"2009-02-23T19:38:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sillon38.com\/blog\/2009\/02\/23\/la-reorientation-des-aides-porte-sur-14-milliard-e\/"},"wordCount":495,"commentCount":0,"articleSection":["PAC"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.sillon38.com\/blog\/2009\/02\/23\/la-reorientation-des-aides-porte-sur-14-milliard-e\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.sillon38.com\/blog\/2009\/02\/23\/la-reorientation-des-aides-porte-sur-14-milliard-e\/","url":"https:\/\/www.sillon38.com\/blog\/2009\/02\/23\/la-reorientation-des-aides-porte-sur-14-milliard-e\/","name":"La r\u00e9orientation des aides porte sur 1,4 milliard \u20ac -","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/#website"},"datePublished":"2009-02-23T19:38:23+00:00","author":{"@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"breadcrumb":{"@id":"https:\/\/www.sillon38.com\/blog\/2009\/02\/23\/la-reorientation-des-aides-porte-sur-14-milliard-e\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sillon38.com\/blog\/2009\/02\/23\/la-reorientation-des-aides-porte-sur-14-milliard-e\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sillon38.com\/blog\/2009\/02\/23\/la-reorientation-des-aides-porte-sur-14-milliard-e\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.sillon38.com\/blog\/"},{"@type":"ListItem","position":2,"name":"La r\u00e9orientation des aides porte sur 1,4 milliard \u20ac"}]},{"@type":"WebSite","@id":"https:\/\/www.sillon38.com\/blog\/#website","url":"https:\/\/www.sillon38.com\/blog\/","name":"","description":"Le journal du monde rural","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sillon38.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1","name":"Gilbert"}]}},"_links":{"self":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/5603","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/comments?post=5603"}],"version-history":[{"count":0,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/5603\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/media?parent=5603"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/categories?post=5603"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/tags?post=5603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}