{"id":58966,"date":"2015-09-28T17:55:34","date_gmt":"2015-09-28T15:55:34","guid":{"rendered":"http:\/\/staging.sillon38.com\/?p=58966"},"modified":"2015-09-28T17:55:34","modified_gmt":"2015-09-28T15:55:34","slug":"amenagement-de-lechangeur-du-rondeau","status":"publish","type":"post","link":"https:\/\/www.sillon38.com\/blog\/2015\/09\/28\/amenagement-de-lechangeur-du-rondeau\/","title":{"rendered":"Am\u00e9nagement de l\u2019\u00e9changeur du Rondeau"},"content":{"rendered":"<p style=\"margin-bottom: 0cm; font-weight: normal;\" align=\"justify\"><span style=\"font-family: Arial,sans-serif;\"><\/span><\/p>\n<p style=\"margin-bottom: 0cm; font-weight: normal;\" align=\"justify\"><strong><span style=\"color: #000080;\">L&rsquo;op\u00e9ration d&rsquo;am\u00e9nagement de l\u2019\u00e9changeur du Rondeau a \u00e9t\u00e9 inscrite au contrat de plan<br \/>\n\u00c9tat-R\u00e9gion (CPER) 2015-2020. Elle sera r\u00e9alis\u00e9e sous ma\u00eetrise d\u2019ouvrage de l\u2019\u00c9tat<br \/>\n(DREAL), en partenariat avec le D\u00e9partement et la M\u00e9tropole.<\/span><\/strong><\/p>\n<p style=\"margin-bottom: 0cm; font-weight: normal;\" align=\"justify\"><span style=\"color: #000080;\">Dans le cadre de la mise en oeuvre du plan de relance, le premier ministre, Manuel<br \/>\nVALLS, a confi\u00e9 \u00e0 la soci\u00e9t\u00e9 AREA la concession et l\u2019am\u00e9nagement des autoroutes A48 et<br \/>\nA480 entre St- EGREVE et CLAIX, sur environ 15 kilom\u00e8tres.<\/span><\/p>\n<p style=\"margin-bottom: 0cm; font-weight: normal;\" align=\"justify\"><span style=\"color: #000080;\">Cette d\u00e9cision fait l\u2019objet du d\u00e9cret n\u00b02015-1044 du 21 ao\u00fbt 2015 approuvant les avenants<br \/>\naux contrats de concession de APRR et AREA et publi\u00e9 au Journal Officiel du 23 ao\u00fbt<br \/>\n2015.<\/span><\/p>\n<p style=\"margin-bottom: 0cm; font-weight: normal;\" align=\"justify\"><span style=\"color: #000080;\">D\u00e8s lors, la soci\u00e9t\u00e9 AREA et l\u2019\u00c9tat se coordonnent pour la r\u00e9alisation des \u00e9tudes<br \/>\nn\u00e9cessaires qui se d\u00e9rouleront \u00e0 partir du 5 octobre 2015.<\/span><\/p>\n<p style=\"margin-bottom: 0cm; font-weight: normal;\" align=\"justify\"><span style=\"color: #000080;\">Ces \u00e9tudes comprennent d&rsquo;une part, une enqu\u00eate de caract\u00e9risation des origines et de<br \/>\ndestination des utilisateurs des grands axes grenoblois, d&rsquo;autre part des \u00e9tudes<br \/>\nenvironnementales n\u00e9cessaires \u00e0 la connaissance de l&rsquo;\u00e9tat initial pour ces projets.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;op\u00e9ration d&rsquo;am\u00e9nagement de l\u2019\u00e9changeur du Rondeau a \u00e9t\u00e9 inscrite au contrat de plan \u00c9tat-R\u00e9gion (CPER) 2015-2020. Elle sera r\u00e9alis\u00e9e sous ma\u00eetrise d\u2019ouvrage de l\u2019\u00c9tat (DREAL), en partenariat avec le D\u00e9partement et la M\u00e9tropole.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[85,37,38],"tags":[1892,1922,3246],"class_list":["post-58966","post","type-post","status-publish","format-standard","hentry","category-amenagement","category-la-metro","category-la-metro-la-metro","tag-dreal","tag-echangeur-du-rondeau","tag-la-metropole"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Am\u00e9nagement de l\u2019\u00e9changeur du Rondeau -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sillon38.com\/blog\/2015\/09\/28\/amenagement-de-lechangeur-du-rondeau\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Am\u00e9nagement de l\u2019\u00e9changeur du Rondeau -\" \/>\n<meta property=\"og:description\" content=\"L&#039;op\u00e9ration d&#039;am\u00e9nagement de l\u2019\u00e9changeur du Rondeau a \u00e9t\u00e9 inscrite au contrat de plan \u00c9tat-R\u00e9gion (CPER) 2015-2020. Elle sera r\u00e9alis\u00e9e sous ma\u00eetrise d\u2019ouvrage de l\u2019\u00c9tat (DREAL), en partenariat avec le D\u00e9partement et la M\u00e9tropole.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sillon38.com\/blog\/2015\/09\/28\/amenagement-de-lechangeur-du-rondeau\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-09-28T15:55:34+00:00\" \/>\n<meta name=\"author\" content=\"Gilbert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gilbert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2015\\\/09\\\/28\\\/amenagement-de-lechangeur-du-rondeau\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2015\\\/09\\\/28\\\/amenagement-de-lechangeur-du-rondeau\\\/\"},\"author\":{\"name\":\"Gilbert\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"headline\":\"Am\u00e9nagement de l\u2019\u00e9changeur du Rondeau\",\"datePublished\":\"2015-09-28T15:55:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2015\\\/09\\\/28\\\/amenagement-de-lechangeur-du-rondeau\\\/\"},\"wordCount\":196,\"commentCount\":0,\"keywords\":[\"DREAL\",\"\u00e9changeur du Rondeau\",\"la M\u00e9tropole\"],\"articleSection\":[\"am\u00e9nagement\",\"La M\u00e9tro\",\"La M\u00e9tro\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2015\\\/09\\\/28\\\/amenagement-de-lechangeur-du-rondeau\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2015\\\/09\\\/28\\\/amenagement-de-lechangeur-du-rondeau\\\/\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2015\\\/09\\\/28\\\/amenagement-de-lechangeur-du-rondeau\\\/\",\"name\":\"Am\u00e9nagement de l\u2019\u00e9changeur du Rondeau -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\"},\"datePublished\":\"2015-09-28T15:55:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2015\\\/09\\\/28\\\/amenagement-de-lechangeur-du-rondeau\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2015\\\/09\\\/28\\\/amenagement-de-lechangeur-du-rondeau\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2015\\\/09\\\/28\\\/amenagement-de-lechangeur-du-rondeau\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Am\u00e9nagement de l\u2019\u00e9changeur du Rondeau\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\",\"name\":\"\",\"description\":\"Le journal du monde rural\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\",\"name\":\"Gilbert\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Am\u00e9nagement de l\u2019\u00e9changeur du Rondeau -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sillon38.com\/blog\/2015\/09\/28\/amenagement-de-lechangeur-du-rondeau\/","og_locale":"fr_FR","og_type":"article","og_title":"Am\u00e9nagement de l\u2019\u00e9changeur du Rondeau -","og_description":"L'op\u00e9ration d'am\u00e9nagement de l\u2019\u00e9changeur du Rondeau a \u00e9t\u00e9 inscrite au contrat de plan \u00c9tat-R\u00e9gion (CPER) 2015-2020. Elle sera r\u00e9alis\u00e9e sous ma\u00eetrise d\u2019ouvrage de l\u2019\u00c9tat (DREAL), en partenariat avec le D\u00e9partement et la M\u00e9tropole.","og_url":"https:\/\/www.sillon38.com\/blog\/2015\/09\/28\/amenagement-de-lechangeur-du-rondeau\/","article_published_time":"2015-09-28T15:55:34+00:00","author":"Gilbert","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Gilbert","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sillon38.com\/blog\/2015\/09\/28\/amenagement-de-lechangeur-du-rondeau\/#article","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/2015\/09\/28\/amenagement-de-lechangeur-du-rondeau\/"},"author":{"name":"Gilbert","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"headline":"Am\u00e9nagement de l\u2019\u00e9changeur du Rondeau","datePublished":"2015-09-28T15:55:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sillon38.com\/blog\/2015\/09\/28\/amenagement-de-lechangeur-du-rondeau\/"},"wordCount":196,"commentCount":0,"keywords":["DREAL","\u00e9changeur du Rondeau","la M\u00e9tropole"],"articleSection":["am\u00e9nagement","La M\u00e9tro","La M\u00e9tro"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.sillon38.com\/blog\/2015\/09\/28\/amenagement-de-lechangeur-du-rondeau\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.sillon38.com\/blog\/2015\/09\/28\/amenagement-de-lechangeur-du-rondeau\/","url":"https:\/\/www.sillon38.com\/blog\/2015\/09\/28\/amenagement-de-lechangeur-du-rondeau\/","name":"Am\u00e9nagement de l\u2019\u00e9changeur du Rondeau -","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/#website"},"datePublished":"2015-09-28T15:55:34+00:00","author":{"@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"breadcrumb":{"@id":"https:\/\/www.sillon38.com\/blog\/2015\/09\/28\/amenagement-de-lechangeur-du-rondeau\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sillon38.com\/blog\/2015\/09\/28\/amenagement-de-lechangeur-du-rondeau\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sillon38.com\/blog\/2015\/09\/28\/amenagement-de-lechangeur-du-rondeau\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.sillon38.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Am\u00e9nagement de l\u2019\u00e9changeur du Rondeau"}]},{"@type":"WebSite","@id":"https:\/\/www.sillon38.com\/blog\/#website","url":"https:\/\/www.sillon38.com\/blog\/","name":"","description":"Le journal du monde rural","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sillon38.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1","name":"Gilbert"}]}},"_links":{"self":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/58966","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/comments?post=58966"}],"version-history":[{"count":0,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/58966\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/media?parent=58966"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/categories?post=58966"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/tags?post=58966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}