{"id":59237,"date":"2015-10-21T14:21:29","date_gmt":"2015-10-21T12:21:29","guid":{"rendered":"http:\/\/staging.sillon38.com\/?p=59237"},"modified":"2015-10-21T14:21:29","modified_gmt":"2015-10-21T12:21:29","slug":"transmettre-un-projet-qui-se-prepare-et-se-construit","status":"publish","type":"post","link":"https:\/\/www.sillon38.com\/blog\/2015\/10\/21\/transmettre-un-projet-qui-se-prepare-et-se-construit\/","title":{"rendered":"Transmettre, un projet qui se pr\u00e9pare et se construit"},"content":{"rendered":"<p><span style=\"color: #000080;\"><br \/>\n<span style=\"font-size: x-small;\"><strong>Dans le contexte difficile que traverse le secteur agricole, les agriculteurs s\u2019organisent et trouvent des solutions pour transmettre leur exploitation \u00e0 des porteurs de projets, \u00a0en famille ou hors cadre familial. Des perspectives de d\u00e9veloppement agricole existent et des opportunit\u00e9s de reprise sont bien pr\u00e9sentes dans les territoires de Rh\u00f4ne-Alpes. Le r\u00e9seau des Points Accueils Transmission des Chambres d\u2019agriculture de Rh\u00f4ne-Alpes accompagne les agriculteurs dans l\u2019ensemble de leur d\u00e9marche de cessation-transmission.<\/strong><\/span><br \/>\n<\/span> <span style=\"color: #000080;\"><br \/>\n<span style=\"font-size: x-small;\">Cette ann\u00e9e, malgr\u00e9 les difficult\u00e9s dans de nombreuses fili\u00e8res, \u00a0il est encore plus n\u00e9cessaire pour les chefs d\u2019entreprise agricole de r\u00e9fl\u00e9chir et de pr\u00e9parer \u00e0 l\u2019avance leur transmission, qu\u2019elle soit en entreprise individuelle ou soci\u00e9taire. L\u2019objectif est de prendre le temps pour :<\/span><br \/>\n<span style=\"font-size: x-small;\">&#8211; \u00a0r\u00e9fl\u00e9chir \u00e0 son projet \u00a0de transmission sous tous ses aspects (\u00e9conomiques, patrimoniaux, personnels\u2026) et envisager comment maintenir le potentiel de \u00a0son exploitation, <\/span><br \/>\n<span style=\"font-size: x-small;\">&#8211; prendre les contacts n\u00e9cessaires avec les diff\u00e9rents organismes et rencontrer de futurs repreneurs.<\/span><br \/>\n<span style=\"font-size: x-small;\">&#8211; pr\u00e9parer et s\u00e9curiser le passage entre c\u00e9dant et repreneur gr\u00e2ce au dispositif \u00ab stage reprise d\u2019exploitation agricole \u00bb<\/span><\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<p><span style=\"color: #000080;\">Tout au long de l\u2019ann\u00e9e, les agriculteurs sont invit\u00e9s \u00e0 des r\u00e9unions d\u2019informations, des visites, des formations\u2026 par le r\u00e9seau des Points Accueil Transmission. <\/span><\/p>\n<p><span style=\"color: #000080;\">En novembre, chaque ann\u00e9e, le mois de la transmission permet de sensibiliser les agriculteurs et leurs partenaires sur les enjeux de la transmission agricole. <strong>Il n\u2019y a pas d\u2019agriculture sans agriculteurs, et pas d\u2019agriculteurs demain, sans transmission aujourd\u2019hui !<\/strong><\/span><\/p>\n<p><span style=\"color: #000080;\"><strong>Pour en savoir plus :<\/strong> Le site internet www.transmettrenagriculture.fr met \u00e0 disposition de nombreuses informations sur les diff\u00e9rents dispositifs d\u2019accompagnement permettant de c\u00e9der une exploitation et proposent de nombreux rendez-vous et r\u00e9unions pour s\u2019informer.<\/span><span style=\"color: #000080;\"><br \/>\n<\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<table border=\"0\">\n<tbody>\n<tr>\n<td><span style=\"color: #000080;\"><a target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"mailbox:\/\/\/Users\/gilbert\/Library\/Thunderbird\/Profiles\/dvdzngs0.default\/Mail\/mail.gandi.net\/Inbox?number=1643291986&amp;part=1.1.2\" alt=\"\" \/><\/a><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans le contexte difficile que traverse le secteur agricole, les agriculteurs s\u2019organisent et trouvent des solutions pour transmettre leur exploitation \u00e0 des porteurs de projets,  en famille ou hors cadre familial.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,35],"tags":[1125,4394,4748],"class_list":["post-59237","post","type-post","status-publish","format-standard","hentry","category-agriculture","category-installation","tag-chambres-dagriculture-de-rhone-alpes","tag-points-accueils-transmission","tag-rhone-alpes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Transmettre, un projet qui se pr\u00e9pare et se construit -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sillon38.com\/blog\/2015\/10\/21\/transmettre-un-projet-qui-se-prepare-et-se-construit\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transmettre, un projet qui se pr\u00e9pare et se construit -\" \/>\n<meta property=\"og:description\" content=\"Dans le contexte difficile que traverse le secteur agricole, les agriculteurs s\u2019organisent et trouvent des solutions pour transmettre leur exploitation \u00e0 des porteurs de projets, en famille ou hors cadre familial.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sillon38.com\/blog\/2015\/10\/21\/transmettre-un-projet-qui-se-prepare-et-se-construit\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-21T12:21:29+00:00\" \/>\n<meta property=\"og:image\" content=\"\" \/>\n<meta name=\"author\" content=\"Gilbert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gilbert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2015\\\/10\\\/21\\\/transmettre-un-projet-qui-se-prepare-et-se-construit\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2015\\\/10\\\/21\\\/transmettre-un-projet-qui-se-prepare-et-se-construit\\\/\"},\"author\":{\"name\":\"Gilbert\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"headline\":\"Transmettre, un projet qui se pr\u00e9pare et se construit\",\"datePublished\":\"2015-10-21T12:21:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2015\\\/10\\\/21\\\/transmettre-un-projet-qui-se-prepare-et-se-construit\\\/\"},\"wordCount\":316,\"commentCount\":0,\"keywords\":[\"chambres d'agriculture de Rh\u00f4ne-Alpes\",\"Points Accueils Transmission\",\"Rh\u00f4ne Alpes\"],\"articleSection\":[\"agriculture\",\"installation\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2015\\\/10\\\/21\\\/transmettre-un-projet-qui-se-prepare-et-se-construit\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2015\\\/10\\\/21\\\/transmettre-un-projet-qui-se-prepare-et-se-construit\\\/\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2015\\\/10\\\/21\\\/transmettre-un-projet-qui-se-prepare-et-se-construit\\\/\",\"name\":\"Transmettre, un projet qui se pr\u00e9pare et se construit -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\"},\"datePublished\":\"2015-10-21T12:21:29+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2015\\\/10\\\/21\\\/transmettre-un-projet-qui-se-prepare-et-se-construit\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2015\\\/10\\\/21\\\/transmettre-un-projet-qui-se-prepare-et-se-construit\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2015\\\/10\\\/21\\\/transmettre-un-projet-qui-se-prepare-et-se-construit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Transmettre, un projet qui se pr\u00e9pare et se construit\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\",\"name\":\"\",\"description\":\"Le journal du monde rural\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\",\"name\":\"Gilbert\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Transmettre, un projet qui se pr\u00e9pare et se construit -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sillon38.com\/blog\/2015\/10\/21\/transmettre-un-projet-qui-se-prepare-et-se-construit\/","og_locale":"fr_FR","og_type":"article","og_title":"Transmettre, un projet qui se pr\u00e9pare et se construit -","og_description":"Dans le contexte difficile que traverse le secteur agricole, les agriculteurs s\u2019organisent et trouvent des solutions pour transmettre leur exploitation \u00e0 des porteurs de projets, en famille ou hors cadre familial.","og_url":"https:\/\/www.sillon38.com\/blog\/2015\/10\/21\/transmettre-un-projet-qui-se-prepare-et-se-construit\/","article_published_time":"2015-10-21T12:21:29+00:00","og_image":[{"url":"mailbox:\/\/\/Users\/gilbert\/Library\/Thunderbird\/Profiles\/dvdzngs0.default\/Mail\/mail.gandi.net\/Inbox?number=1643291986&amp;part=1.1.2","type":"","width":"","height":""}],"author":"Gilbert","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Gilbert","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sillon38.com\/blog\/2015\/10\/21\/transmettre-un-projet-qui-se-prepare-et-se-construit\/#article","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/2015\/10\/21\/transmettre-un-projet-qui-se-prepare-et-se-construit\/"},"author":{"name":"Gilbert","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"headline":"Transmettre, un projet qui se pr\u00e9pare et se construit","datePublished":"2015-10-21T12:21:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sillon38.com\/blog\/2015\/10\/21\/transmettre-un-projet-qui-se-prepare-et-se-construit\/"},"wordCount":316,"commentCount":0,"keywords":["chambres d'agriculture de Rh\u00f4ne-Alpes","Points Accueils Transmission","Rh\u00f4ne Alpes"],"articleSection":["agriculture","installation"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.sillon38.com\/blog\/2015\/10\/21\/transmettre-un-projet-qui-se-prepare-et-se-construit\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.sillon38.com\/blog\/2015\/10\/21\/transmettre-un-projet-qui-se-prepare-et-se-construit\/","url":"https:\/\/www.sillon38.com\/blog\/2015\/10\/21\/transmettre-un-projet-qui-se-prepare-et-se-construit\/","name":"Transmettre, un projet qui se pr\u00e9pare et se construit -","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/#website"},"datePublished":"2015-10-21T12:21:29+00:00","author":{"@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"breadcrumb":{"@id":"https:\/\/www.sillon38.com\/blog\/2015\/10\/21\/transmettre-un-projet-qui-se-prepare-et-se-construit\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sillon38.com\/blog\/2015\/10\/21\/transmettre-un-projet-qui-se-prepare-et-se-construit\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sillon38.com\/blog\/2015\/10\/21\/transmettre-un-projet-qui-se-prepare-et-se-construit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.sillon38.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Transmettre, un projet qui se pr\u00e9pare et se construit"}]},{"@type":"WebSite","@id":"https:\/\/www.sillon38.com\/blog\/#website","url":"https:\/\/www.sillon38.com\/blog\/","name":"","description":"Le journal du monde rural","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sillon38.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1","name":"Gilbert"}]}},"_links":{"self":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/59237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/comments?post=59237"}],"version-history":[{"count":0,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/59237\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/media?parent=59237"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/categories?post=59237"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/tags?post=59237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}