{"id":60440,"date":"2015-12-20T22:31:19","date_gmt":"2015-12-20T20:31:19","guid":{"rendered":"http:\/\/staging.sillon38.com\/?p=60440"},"modified":"2015-12-20T22:31:19","modified_gmt":"2015-12-20T20:31:19","slug":"pensez-aux-volailles-de-la-ferme-des-pres","status":"publish","type":"post","link":"https:\/\/www.sillon38.com\/blog\/2015\/12\/20\/pensez-aux-volailles-de-la-ferme-des-pres\/","title":{"rendered":"Pensez aux volailles de la ferme des pr\u00e8s&#8230;"},"content":{"rendered":"<p><span style=\"color: #000080;\">La ferme des pr\u00e8s, \u00e0 Bri\u00e9 et Angonnes est un Gaec constitu\u00e9 par le p\u00e8re et le fils Finet. <\/span><\/p>\n<p><span style=\"color: #000080;\">Jean Michel et\u00a0 Ren\u00e9 ont transform\u00e9 la ferme familiale sp\u00e9cialis\u00e9e en bovins lait\u00a0 en une exploitation avicole. <\/span><\/p>\n<p><span style=\"color: #000080;\">\u00a0\u00bb Le lait n&rsquo;avait plus d&rsquo;avenir.. On a cherch\u00e9 une activit\u00e9 \u00e9conomiquement viable, on s&rsquo;est donc lanc\u00e9 dans la volaille..\u00a0\u00bb Motiv\u00e9s par le fait que l&rsquo;exploitation est sur les hauteurs de l&rsquo;agglom\u00e9ration Grenobloise, donc proche du bassin de consommation. <\/span><\/p>\n<p><span style=\"color: #000080;\">L&rsquo;espace est constitu\u00e9 de 35 hectares..Poulets, pintades, canards dindes ont tout loisir \u00e0 se d\u00e9velopper : \u00a0\u00bb Nous sommes \u00e7\u00e0 une altitude\u00a0 id\u00e9ale de 480 m\u00e8tres, avec un tr\u00e8s bon ensoleillement..Nos animaux ne sont nourris qu&rsquo;avec une alimentation d&rsquo;excellence compl\u00e9t\u00e9e par des aliments issus de notre exploitation. \u00a0\u00bb Les Finet nous expliquent \u00a0\u00bb l&rsquo;eau est l&rsquo;aliment principal des volailles. Celle ci est exceptionnelle. L&rsquo; eau de Casserousse ( qui descends de Chamrousse) est une eau sans calcaire ni nitrate ni chlore.. ceci de fa\u00e7on naturelle.\u00a0\u00bb<\/span><\/p>\n<p><span style=\"color: #000080;\">Inutile de dire que les volailles sont heureuse\u00a0\u00bb on attache une grande importance au bien \u00eatre animal\u00a0\u00bb..<\/span><\/p>\n<p><span style=\"color: #000080;\"><a rel=\"attachment wp-att-60442\" href=\"http:\/\/staging.sillon38.com\/2015\/12\/20\/pensez-aux-volailles-de-la-ferme-des-pres\/a-7\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-60442\" title=\"a\" src=\"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2015\/12\/a1.jpg\" alt=\"a\" width=\"595\" height=\"335\" srcset=\"https:\/\/www.sillon38.com\/blog\/wp-content\/uploads\/2015\/12\/a1.jpg 595w, https:\/\/www.sillon38.com\/blog\/wp-content\/uploads\/2015\/12\/a1-300x169.jpg 300w\" sizes=\"auto, (max-width: 595px) 100vw, 595px\" \/><\/a><\/span><\/p>\n<p><span style=\"color: #000080;\"><a rel=\"attachment wp-att-60442\" href=\"http:\/\/staging.sillon38.com\/2015\/12\/20\/pensez-aux-volailles-de-la-ferme-des-pres\/a-7\/\"><\/a>Elles sont bien entendu \u00e9lev\u00e9es en plein air et ont comme poulailler un \u00a0\u00bb technig\u00eete\u00a0\u00bb. Il s&rsquo;agit de poulaillers de 150 places d\u00e9pla\u00e7ables..<\/span><\/p>\n<p><span style=\"color: #000080;\">Les b\u00eates sont abattues et conditionn\u00e9es en laboratoire. \u00a0\u00bb 80% d&rsquo;entre elles partent en vente directe soit sur l&rsquo;exploitation elle m\u00eame, soit par le biais d&rsquo;un magasin de producteurs ou via le march\u00e9 de producteurs de St Egr\u00e8ve. <\/span><\/p>\n<p><span style=\"color: #000080;\">\u00a0\u00bb Nous avons de tr\u00e8s bon retours et notre publicit\u00e9 se fait uniquement par le bouche \u00e0 oreilles\u00a0\u00bb. <\/span><\/p>\n<p><span style=\"color: #000080;\">\u00a0\u00bb Nos clients cherchent une viande\u00a0 de qualit\u00e9 tendre et gouteuse. Nous avons donc su et pu nous adapter en trouvant les races ad\u00e9quates, \u00e0 croissance lente. Le compl\u00e9ment d&rsquo;alimentation fait \u00e0 base de foin donnant un plus: une viande persill\u00e9e..\u00a0\u00bb<\/span><\/p>\n<p><span style=\"color: #000080;\">Les poulets sont vendus \u00e0 un poids compris entre 1,8 et 2,5 kilos. <\/span><\/p>\n<p><span style=\"color: #000080;\">Pour les f\u00eates, le Gaec la ferme des pr\u00e8s propose bien entendu des volailles telles que des chapons, des pintades chaponn\u00e9es mais aussi des poulardes.. Ces derni\u00e8res connaissent de plus en plus de succ\u00e8s aupr\u00e8s de notre client\u00e8le..\u00a0\u00bb<\/span><\/p>\n<p><span style=\"color: #000080;\">Comme on le voit, inutile de faire des kilom\u00e8tres pour trouver des bons produits.. On les trouvent facilement sur l&rsquo;agglom\u00e9ration grenobloise.<\/span><\/p>\n<p><span style=\"color: #000080;\"><strong>Gilbert Precz<\/strong><\/span><\/p>\n<p><span style=\"color: #000080;\"><a rel=\"attachment wp-att-60443\" href=\"http:\/\/staging.sillon38.com\/2015\/12\/20\/pensez-aux-volailles-de-la-ferme-des-pres\/20151211_104034\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-60443\" title=\"20151211_104034\" src=\"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2015\/12\/20151211_104034.jpg\" alt=\"20151211_104034\" width=\"490\" height=\"595\" srcset=\"https:\/\/www.sillon38.com\/blog\/wp-content\/uploads\/2015\/12\/20151211_104034.jpg 490w, https:\/\/www.sillon38.com\/blog\/wp-content\/uploads\/2015\/12\/20151211_104034-247x300.jpg 247w\" sizes=\"auto, (max-width: 490px) 100vw, 490px\" \/><\/a><br \/>\n<\/span><\/p>\n<p><span style=\"color: #000080;\"><br \/>\n<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Gaec de la ferme des pr\u00e8s tenu par le p\u00e8re et le fils Finet, \u00e0 Bri\u00e9 et Angonnes vous proposent des volailles de qualit\u00e9.. <\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[95,19,37],"tags":[261,876,2291,2419,2696],"class_list":["post-60440","post","type-post","status-publish","format-standard","hentry","category-consommation","category-elevage","category-la-metro","tag-aglomeration-grenobloise","tag-brie-et-angonne","tag-ferme-des-pres","tag-finet-pere-et-fils","tag-gilbert-precz"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pensez aux volailles de la ferme des pr\u00e8s... -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sillon38.com\/blog\/2015\/12\/20\/pensez-aux-volailles-de-la-ferme-des-pres\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pensez aux volailles de la ferme des pr\u00e8s... -\" \/>\n<meta property=\"og:description\" content=\"Le Gaec de la ferme des pr\u00e8s tenu par le p\u00e8re et le fils Finet, \u00e0 Bri\u00e9 et Angonnes vous proposent des volailles de qualit\u00e9..\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sillon38.com\/blog\/2015\/12\/20\/pensez-aux-volailles-de-la-ferme-des-pres\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-12-20T20:31:19+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2015\/12\/a1.jpg\" \/>\n<meta name=\"author\" content=\"Gilbert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gilbert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2015\\\/12\\\/20\\\/pensez-aux-volailles-de-la-ferme-des-pres\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2015\\\/12\\\/20\\\/pensez-aux-volailles-de-la-ferme-des-pres\\\/\"},\"author\":{\"name\":\"Gilbert\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"headline\":\"Pensez aux volailles de la ferme des pr\u00e8s&#8230;\",\"datePublished\":\"2015-12-20T20:31:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2015\\\/12\\\/20\\\/pensez-aux-volailles-de-la-ferme-des-pres\\\/\"},\"wordCount\":409,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2015\\\/12\\\/20\\\/pensez-aux-volailles-de-la-ferme-des-pres\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/staging.sillon38.com\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/a1.jpg\",\"keywords\":[\"Aglom\u00e9ration Grenobloise\",\"Bri\u00e9 et angonne\",\"ferme des pr\u00e8s\",\"Finet p\u00e8re et fils\",\"Gilbert precz\"],\"articleSection\":[\"consommation\",\"\u00e9levage\",\"La M\u00e9tro\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2015\\\/12\\\/20\\\/pensez-aux-volailles-de-la-ferme-des-pres\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2015\\\/12\\\/20\\\/pensez-aux-volailles-de-la-ferme-des-pres\\\/\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2015\\\/12\\\/20\\\/pensez-aux-volailles-de-la-ferme-des-pres\\\/\",\"name\":\"Pensez aux volailles de la ferme des pr\u00e8s... -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2015\\\/12\\\/20\\\/pensez-aux-volailles-de-la-ferme-des-pres\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2015\\\/12\\\/20\\\/pensez-aux-volailles-de-la-ferme-des-pres\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/staging.sillon38.com\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/a1.jpg\",\"datePublished\":\"2015-12-20T20:31:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2015\\\/12\\\/20\\\/pensez-aux-volailles-de-la-ferme-des-pres\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2015\\\/12\\\/20\\\/pensez-aux-volailles-de-la-ferme-des-pres\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2015\\\/12\\\/20\\\/pensez-aux-volailles-de-la-ferme-des-pres\\\/#primaryimage\",\"url\":\"http:\\\/\\\/staging.sillon38.com\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/a1.jpg\",\"contentUrl\":\"http:\\\/\\\/staging.sillon38.com\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/a1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2015\\\/12\\\/20\\\/pensez-aux-volailles-de-la-ferme-des-pres\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pensez aux volailles de la ferme des pr\u00e8s&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\",\"name\":\"\",\"description\":\"Le journal du monde rural\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\",\"name\":\"Gilbert\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pensez aux volailles de la ferme des pr\u00e8s... -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sillon38.com\/blog\/2015\/12\/20\/pensez-aux-volailles-de-la-ferme-des-pres\/","og_locale":"fr_FR","og_type":"article","og_title":"Pensez aux volailles de la ferme des pr\u00e8s... -","og_description":"Le Gaec de la ferme des pr\u00e8s tenu par le p\u00e8re et le fils Finet, \u00e0 Bri\u00e9 et Angonnes vous proposent des volailles de qualit\u00e9..","og_url":"https:\/\/www.sillon38.com\/blog\/2015\/12\/20\/pensez-aux-volailles-de-la-ferme-des-pres\/","article_published_time":"2015-12-20T20:31:19+00:00","og_image":[{"url":"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2015\/12\/a1.jpg","type":"","width":"","height":""}],"author":"Gilbert","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Gilbert","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sillon38.com\/blog\/2015\/12\/20\/pensez-aux-volailles-de-la-ferme-des-pres\/#article","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/2015\/12\/20\/pensez-aux-volailles-de-la-ferme-des-pres\/"},"author":{"name":"Gilbert","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"headline":"Pensez aux volailles de la ferme des pr\u00e8s&#8230;","datePublished":"2015-12-20T20:31:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sillon38.com\/blog\/2015\/12\/20\/pensez-aux-volailles-de-la-ferme-des-pres\/"},"wordCount":409,"commentCount":0,"image":{"@id":"https:\/\/www.sillon38.com\/blog\/2015\/12\/20\/pensez-aux-volailles-de-la-ferme-des-pres\/#primaryimage"},"thumbnailUrl":"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2015\/12\/a1.jpg","keywords":["Aglom\u00e9ration Grenobloise","Bri\u00e9 et angonne","ferme des pr\u00e8s","Finet p\u00e8re et fils","Gilbert precz"],"articleSection":["consommation","\u00e9levage","La M\u00e9tro"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.sillon38.com\/blog\/2015\/12\/20\/pensez-aux-volailles-de-la-ferme-des-pres\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.sillon38.com\/blog\/2015\/12\/20\/pensez-aux-volailles-de-la-ferme-des-pres\/","url":"https:\/\/www.sillon38.com\/blog\/2015\/12\/20\/pensez-aux-volailles-de-la-ferme-des-pres\/","name":"Pensez aux volailles de la ferme des pr\u00e8s... -","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sillon38.com\/blog\/2015\/12\/20\/pensez-aux-volailles-de-la-ferme-des-pres\/#primaryimage"},"image":{"@id":"https:\/\/www.sillon38.com\/blog\/2015\/12\/20\/pensez-aux-volailles-de-la-ferme-des-pres\/#primaryimage"},"thumbnailUrl":"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2015\/12\/a1.jpg","datePublished":"2015-12-20T20:31:19+00:00","author":{"@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"breadcrumb":{"@id":"https:\/\/www.sillon38.com\/blog\/2015\/12\/20\/pensez-aux-volailles-de-la-ferme-des-pres\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sillon38.com\/blog\/2015\/12\/20\/pensez-aux-volailles-de-la-ferme-des-pres\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.sillon38.com\/blog\/2015\/12\/20\/pensez-aux-volailles-de-la-ferme-des-pres\/#primaryimage","url":"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2015\/12\/a1.jpg","contentUrl":"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2015\/12\/a1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.sillon38.com\/blog\/2015\/12\/20\/pensez-aux-volailles-de-la-ferme-des-pres\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.sillon38.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Pensez aux volailles de la ferme des pr\u00e8s&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/www.sillon38.com\/blog\/#website","url":"https:\/\/www.sillon38.com\/blog\/","name":"","description":"Le journal du monde rural","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sillon38.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1","name":"Gilbert"}]}},"_links":{"self":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/60440","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/comments?post=60440"}],"version-history":[{"count":0,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/60440\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/media?parent=60440"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/categories?post=60440"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/tags?post=60440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}