{"id":61911,"date":"2016-03-16T00:00:26","date_gmt":"2016-03-15T22:00:26","guid":{"rendered":"http:\/\/staging.sillon38.com\/?p=61911"},"modified":"2016-03-16T00:00:26","modified_gmt":"2016-03-15T22:00:26","slug":"mesures-exceptionnelles-pour-soutenir-les-agriculteurs-europeens-en-periode-de-crise","status":"publish","type":"post","link":"https:\/\/www.sillon38.com\/blog\/2016\/03\/16\/mesures-exceptionnelles-pour-soutenir-les-agriculteurs-europeens-en-periode-de-crise\/","title":{"rendered":"Mesures exceptionnelles pour soutenir les agriculteurs europ\u00e9ens en p\u00e9riode de crise"},"content":{"rendered":"<div>\n<p><span style=\"color: #000080;\">\u00abCe train de mesures peut avoir une incidence  r\u00e9elle et positive sur les march\u00e9s agricoles europ\u00e9ens. Il faut  maintenant lui donner toutes les chances de r\u00e9ussir\u00bb.<\/span><\/div>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<p><span style=\"color: #000080;\">La Commission europ\u00e9enne annonce ce jour l\u2019octroi d\u2019une enveloppe  suppl\u00e9mentaire de mesures exceptionnelles utilisant tous les outils \u00e0  disposition de la politique agricole commune (PAC) en vue de soutenir  les agriculteurs de l\u2019UE.<\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<p><span style=\"color: #000080;\">La Commission reconna\u00eet l\u2019ampleur et la dur\u00e9e de la crise agricole  actuelle ainsi que les efforts consid\u00e9rables consentis au niveau des  \u00c9tats membres afin d\u2019aider leurs agriculteurs et r\u00e9pond avec un nouveau  train de mesures utiles.<\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<p><span style=\"color: #000080;\">La s\u00e9rie de mesures d\u00e9crites par le commissaire <strong>Hogan<\/strong> aux ministres de l\u2019agriculture de l\u2019Union europ\u00e9enne vient compl\u00e9ter  l\u2019aide globale de\u00a0500\u00a0millions\u00a0d\u2019EUR de septembre dernier et t\u00e9moigne de  la d\u00e9termination de la Commission \u00e0 jouer pleinement son r\u00f4le pour  aider les agriculteurs europ\u00e9ens.<\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<p><span style=\"color: #000080;\"><em>\u00abDans l\u2019int\u00e9r\u00eat des agriculteurs de l\u2019Union, je suis pr\u00eat \u00e0  recourir \u00e0 tous les instruments que les l\u00e9gislateurs ont mis \u00e0 notre  disposition, tant les mesures \u00e0 court terme qu&rsquo;\u00e0 long terme. Nous devons  utiliser les instruments appropri\u00e9s et les actions visant \u00e0 permettre  aux agriculteurs de faire preuve de r\u00e9silience face \u00e0 la volatilit\u00e9,  tout en fournissant une aide imm\u00e9diate \u00e0 ces derniers. La r\u00e9ponse que  nous donnons aujourd\u2019hui est une r\u00e9ponse globale, tenant compte de bon  nombre des propositions soumises, dans les limites des contraintes  juridiques et budg\u00e9taires qui s\u2019appliquent \u00e0 chacun d\u2019entre nous.  J\u2019estime qu\u2019il s\u2019agit d\u2019un train de mesures qui, avec la pleine mise en  \u0153uvre du paquet de solidarit\u00e9 de septembre, peut avoir une incidence  r\u00e9elle et positive sur les march\u00e9s agricoles europ\u00e9ens. Il faut  maintenant lui donner toutes les chances de r\u00e9ussir\u00bb <\/em>a d\u00e9clar\u00e9 le commissaire <strong>Hogan<\/strong> aujourd\u2019hui lors du Conseil des ministres de l\u2019agriculture.<\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<p><span style=\"color: #000080;\">En ces temps de crises multiples et de restrictions budg\u00e9taires, la  Commission a mobilis\u00e9 plus d&rsquo;1 milliard d\u2019euros sur deux ans, y compris  l\u2019aide globale de\u00a0500\u00a0millions\u00a0d\u2019EUR \u00e0 partir de septembre 2015. Nous  sommes aux c\u00f4t\u00e9s de nos agriculteurs et nous leur assurons, gr\u00e2ce \u00e0 la  mise en \u0153uvre quotidienne de la PAC et l\u2019utilisation de mesures  exceptionnelles, un soutien entier et une assistance pour pr\u00e9server  notre mod\u00e8le agricole.<\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<p><span style=\"color: #000080;\">Les mesures mises en places aujourd\u2019hui sont ajustables afin que les  \u00c9tats membres puissent les utiliser au mieux de leurs capacit\u00e9s, en  fonction de leur situation nationale particuli\u00e8re. Les secteurs du lait,  de la viande de porc ainsi que des fruits et l\u00e9gumes constituent l&rsquo;axe  principal de ce train de mesures. On trouvera ci-apr\u00e8s une synth\u00e8se des  propositions pr\u00e9sent\u00e9es lors de la r\u00e9union d\u2019aujourd\u2019hui.<\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<p><span style=\"color: #000080;\"><strong>Application de mesures volontaires de gestion (article\u00a0222)<\/strong><\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<p><span style=\"color: #000080;\">La Commission permettra \u00e0 des organisations de producteurs, des  organisations interprofessionnelles et des coop\u00e9ratives d\u2019\u00e9tablir des  accords volontaires sur leur production ou leur offre. C\u2019est ce que l\u2019on  appelle l\u2019article\u00a0222 de l\u2019organisation commune de march\u00e9 (OCM). Son  application conduit \u00e0 l\u2019autorisation par la Commission d\u2019exempter de  tels accords de l\u2019application de l\u2019article\u00a0101 du trait\u00e9 sur le droit de  la concurrence en cas de grave d\u00e9s\u00e9quilibre sur le march\u00e9. Il s\u2019agit  d\u2019une mesure exceptionnelle, pr\u00e9vue par les l\u00e9gislateurs dans le cadre  de la r\u00e9forme de la PAC en 2013, mais qui n&rsquo;a jamais \u00e9t\u00e9 utilis\u00e9e  auparavant.<\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<p><span style=\"color: #000080;\"><strong>Augmentation temporaire des aides d\u2019\u00c9tat<\/strong><\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<p><span style=\"color: #000080;\">La Commission acceptera une augmentation temporaire des aides d\u2019\u00c9tat  qui permettra aux \u00c9tats membres de fournir un maximum de 15,000\u00a0EUR par  agriculteur et par an et sans qu&rsquo;aucun plafond national ne s\u2019applique.  Cela peut se faire imm\u00e9diatement et bien plus rapidement qu\u2019une  augmentation des plafonds de minimis.<\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<p><span style=\"color: #000080;\"><strong>Doublement des plafonds d\u2019intervention pour le lait \u00e9cr\u00e9m\u00e9 en poudre et le beurre<\/strong><\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<p><span style=\"color: #000080;\">La Commission va augmenter les limites quantitatives pour le lait  \u00e9cr\u00e9m\u00e9 en poudre et le beurre mises \u00e0 l\u2019intervention de respectivement  109\u00a0000 tonnes et 60\u00a0000 tonnes \u00e0 218\u00a0000 tonnes et 100\u00a0000 tonnes. De  cette mani\u00e8re, nous nous engageons clairement \u00e0 soutenir les prix  d\u2019intervention fixes.<\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<p><span style=\"color: #000080;\"><strong>Renforcement du producteur dans la cha\u00eene d\u2019approvisionnement<\/strong><\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<p><span style=\"color: #000080;\">Le r\u00f4le et la position des producteurs dans la cha\u00eene  d\u2019approvisionnement alimentaire reste au c\u0153ur de nos pr\u00e9occupations. Le  groupe de travail \u00abmarch\u00e9s agricoles\u00bb, lanc\u00e9 dans le cadre de l\u2019aide  globale de\u00a0500\u00a0millions\u00a0d\u2019EUR de septembre 2015, rendra ses conclusions  et ses recommandations l\u00e9gislatives \u00e0 l&rsquo;automne afin de parvenir \u00e0 un  meilleur \u00e9quilibre de la cha\u00eene d\u2019approvisionnement. Il a \u00e9t\u00e9 d\u00e9cid\u00e9  aujourd\u2019hui que les repr\u00e9sentants nationaux de haut niveau se r\u00e9uniront  le groupe de travail \u00abmarch\u00e9s agricoles\u00bb afin d\u2019examiner sp\u00e9cifiquement  la situation dans le secteur laitier.<\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<p><span style=\"color: #000080;\"><strong>Soutien au secteur de la viande de porc<\/strong><\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<p><span style=\"color: #000080;\">En r\u00e9ponse aux propositions concernant un nouveau r\u00e9gime d\u2019aide au stockage priv\u00e9 pour la viande de porc, le commissaire <strong>Hogan <\/strong>envisagera  l\u2019instauration d\u2019un nouveau r\u00e9gime. Les modalit\u00e9s de ce r\u00e9gime, y  compris le calendrier d\u2019introduction, devront \u00eatre confirm\u00e9es.<\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<p><span style=\"color: #000080;\"><strong>Mise en place d\u2019un Observatoire du march\u00e9 de la viande<\/strong><\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<p><span style=\"color: #000080;\">Les Etats membres ont tous reconnu et salu\u00e9 le travail de la  Commission dans la surveillance du march\u00e9 et le partage d&rsquo;informations  pr\u00e9cieuses sur les tendances. \u00c0 la suite de l\u2019Observatoire du march\u00e9 du  lait \u00e9tabli en 2014, un Observatoire du march\u00e9 de la viande sera cr\u00e9\u00e9,  couvrant la viande bovine et porcine.<\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<p><span style=\"color: #000080;\"><strong>Commerce international<\/strong><\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<p><span style=\"color: #000080;\">En ce qui concerne les n\u00e9gociations sur le TTIP et le Mercosur, la  Commission est bien consciente des sensibilit\u00e9s du secteur agricole. Le  commissaire <strong>Hogan<\/strong> et le coll\u00e8ge des commissaires sont  r\u00e9solus \u00e0 promouvoir les int\u00e9r\u00eats de l\u2019Union et \u00e0 ouvrir de nouveaux  march\u00e9s pour les produits de l\u2019UE, tout en n\u00e9gociant un traitement  diff\u00e9renci\u00e9 pour les produits sensibles. Si de nouveaux march\u00e9s sont  essentiels pour l\u2019agriculture europ\u00e9enne, il est \u00e9galement essentiel de  garantir un traitement diff\u00e9renci\u00e9 aux produits sensibles.<\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<p><span style=\"color: #000080;\"><strong>Promotion<\/strong><\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<p><span style=\"color: #000080;\">Les campagnes de promotion sont un instrument cl\u00e9 pour trouver de  nouveaux march\u00e9s et plus de 110\u00a0millions d\u2019euros sont disponibles en  2016 uniquement pour le soutien de la promotion des produits agricoles  de l\u2019UE au sein de l\u2019Union et dans les pays tiers. Plus de 30 millions  d\u2019euros sont sp\u00e9cifiquement allou\u00e9s \u00e0 la viande de porc et au secteur  laitier, un engagement pris en septembre dernier. Un montant  suppl\u00e9mentaire est ajout\u00e9 aujourd\u2019hui aux 30 millions d\u2019euros afin de  tenir compte les perturbations du march\u00e9 dans ces secteurs.<\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<p><span style=\"color: #000080;\"><strong>Embargo russe\/mesures sanitaires et phytosanitaires<\/strong><\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<p><span style=\"color: #000080;\">La Commission dans son ensemble poursuit sans rel\u00e2che ses efforts  pour lever l\u2019embargo russe. Malgr\u00e9 nos efforts en vue d\u2019essayer de  garantir une reprise rapide du commerce entre l\u2019UE et la Russie, tr\u00e8s  peu a \u00e9t\u00e9 fait \u00e0 ce jour. Des progr\u00e8s importants ont toutefois \u00e9t\u00e9  accomplis dans la lev\u00e9e des mesures phytosanitaires injustifi\u00e9es ou  disproportionn\u00e9es par les pays tiers, ce qui contribuera \u00e0 une  augmentation substantielle des flux commerciaux. Cela suppose que des  progr\u00e8s soient accomplis en la mati\u00e8re aux Etats-Unis et sur les march\u00e9s  japonais, br\u00e9silien et ukrainien.<\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<p><span style=\"color: #000080;\"><strong>Instruments financiers\/Banque europ\u00e9enne d\u2019investissement\/Fonds europ\u00e9en pour les investissements strat\u00e9giques<\/strong><\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<p><span style=\"color: #000080;\">La Commission fera de son dialogue avec la BEI une priorit\u00e9 afin  d\u2019\u00e9laborer des instruments financiers appropri\u00e9s pour aider les  agriculteurs et les transformateurs \u00e0 investir dans leurs entreprises  pour am\u00e9liorer leur comp\u00e9titivit\u00e9 ou proc\u00e9der aux adaptations  structurelles n\u00e9cessaires.<\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<p><span style=\"color: #000080;\">Les \u00c9tats membres sont \u00e9galement encourag\u00e9s \u00e0 tirer pleinement parti  des possibilit\u00e9s offertes par le Fonds europ\u00e9en pour les investissements  strat\u00e9giques en ce qui concerne les investissements dans le secteur  agricole et \u00e0 examiner les possibilit\u00e9s de cr\u00e9ation de plateformes  sp\u00e9cialis\u00e9es pour un financement par le FEIS.<\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<p><span style=\"color: #000080;\"><strong>Cr\u00e9dits \u00e0 l\u2019exportation<\/strong><\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<p><span style=\"color: #000080;\">La Commission examine actuellement la faisabilit\u00e9 d\u2019un r\u00e9gime de  cr\u00e9dit \u00e0 l\u2019exportation qui pourrait compl\u00e9ter les r\u00e9gimes que les \u00c9tats  membres g\u00e8rent sur une base nationale. \u00c0 cet \u00e9gard, la direction  g\u00e9n\u00e9rale de l\u2019agriculture est en train d\u2019intensifier ses contacts avec  la BEI et les organismes comp\u00e9tents dans les \u00c9tats membres.<\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<p><span style=\"color: #000080;\"><strong>Secteur des fruits et l\u00e9gumes<\/strong><\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<p><span style=\"color: #000080;\">La Commission envisage une prorogation des mesures exceptionnelles  pour le secteur des fruits et l\u00e9gumes, d\u00e9coulant de l\u2019embargo russe et  qui expirent le 30 juin.<\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<p><span style=\"color: #000080;\"><strong>D\u00e9veloppement rural<\/strong><\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<p><span style=\"color: #000080;\">La Commission collaborera avec les \u00c9tats membres pour voir o\u00f9 et  comment les programmes de d\u00e9veloppement rural peuvent \u00eatre adapt\u00e9s afin  de les rendre plus r\u00e9actifs \u00e0 la crise actuelle.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abCe train de mesures peut avoir une incidence r\u00e9elle et positive sur les march\u00e9s agricoles europ\u00e9ens. Il faut maintenant lui donner toutes les chances de r\u00e9ussir\u00bb.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,76],"tags":[1425],"class_list":["post-61911","post","type-post","status-publish","format-standard","hentry","category-agriculture","category-union-europeenne","tag-commissaire-hogan"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mesures exceptionnelles pour soutenir les agriculteurs europ\u00e9ens en p\u00e9riode de crise -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sillon38.com\/blog\/2016\/03\/16\/mesures-exceptionnelles-pour-soutenir-les-agriculteurs-europeens-en-periode-de-crise\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mesures exceptionnelles pour soutenir les agriculteurs europ\u00e9ens en p\u00e9riode de crise -\" \/>\n<meta property=\"og:description\" content=\"\u00abCe train de mesures peut avoir une incidence r\u00e9elle et positive sur les march\u00e9s agricoles europ\u00e9ens. Il faut maintenant lui donner toutes les chances de r\u00e9ussir\u00bb.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sillon38.com\/blog\/2016\/03\/16\/mesures-exceptionnelles-pour-soutenir-les-agriculteurs-europeens-en-periode-de-crise\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-03-15T22:00:26+00:00\" \/>\n<meta name=\"author\" content=\"Gilbert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gilbert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2016\\\/03\\\/16\\\/mesures-exceptionnelles-pour-soutenir-les-agriculteurs-europeens-en-periode-de-crise\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2016\\\/03\\\/16\\\/mesures-exceptionnelles-pour-soutenir-les-agriculteurs-europeens-en-periode-de-crise\\\/\"},\"author\":{\"name\":\"Gilbert\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"headline\":\"Mesures exceptionnelles pour soutenir les agriculteurs europ\u00e9ens en p\u00e9riode de crise\",\"datePublished\":\"2016-03-15T22:00:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2016\\\/03\\\/16\\\/mesures-exceptionnelles-pour-soutenir-les-agriculteurs-europeens-en-periode-de-crise\\\/\"},\"wordCount\":1505,\"commentCount\":0,\"keywords\":[\"commissaire Hogan\"],\"articleSection\":[\"agriculture\",\"Union europ\u00e9enne\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2016\\\/03\\\/16\\\/mesures-exceptionnelles-pour-soutenir-les-agriculteurs-europeens-en-periode-de-crise\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2016\\\/03\\\/16\\\/mesures-exceptionnelles-pour-soutenir-les-agriculteurs-europeens-en-periode-de-crise\\\/\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2016\\\/03\\\/16\\\/mesures-exceptionnelles-pour-soutenir-les-agriculteurs-europeens-en-periode-de-crise\\\/\",\"name\":\"Mesures exceptionnelles pour soutenir les agriculteurs europ\u00e9ens en p\u00e9riode de crise -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\"},\"datePublished\":\"2016-03-15T22:00:26+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2016\\\/03\\\/16\\\/mesures-exceptionnelles-pour-soutenir-les-agriculteurs-europeens-en-periode-de-crise\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2016\\\/03\\\/16\\\/mesures-exceptionnelles-pour-soutenir-les-agriculteurs-europeens-en-periode-de-crise\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2016\\\/03\\\/16\\\/mesures-exceptionnelles-pour-soutenir-les-agriculteurs-europeens-en-periode-de-crise\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mesures exceptionnelles pour soutenir les agriculteurs europ\u00e9ens en p\u00e9riode de crise\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\",\"name\":\"\",\"description\":\"Le journal du monde rural\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\",\"name\":\"Gilbert\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mesures exceptionnelles pour soutenir les agriculteurs europ\u00e9ens en p\u00e9riode de crise -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sillon38.com\/blog\/2016\/03\/16\/mesures-exceptionnelles-pour-soutenir-les-agriculteurs-europeens-en-periode-de-crise\/","og_locale":"fr_FR","og_type":"article","og_title":"Mesures exceptionnelles pour soutenir les agriculteurs europ\u00e9ens en p\u00e9riode de crise -","og_description":"\u00abCe train de mesures peut avoir une incidence r\u00e9elle et positive sur les march\u00e9s agricoles europ\u00e9ens. Il faut maintenant lui donner toutes les chances de r\u00e9ussir\u00bb.","og_url":"https:\/\/www.sillon38.com\/blog\/2016\/03\/16\/mesures-exceptionnelles-pour-soutenir-les-agriculteurs-europeens-en-periode-de-crise\/","article_published_time":"2016-03-15T22:00:26+00:00","author":"Gilbert","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Gilbert","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sillon38.com\/blog\/2016\/03\/16\/mesures-exceptionnelles-pour-soutenir-les-agriculteurs-europeens-en-periode-de-crise\/#article","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/2016\/03\/16\/mesures-exceptionnelles-pour-soutenir-les-agriculteurs-europeens-en-periode-de-crise\/"},"author":{"name":"Gilbert","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"headline":"Mesures exceptionnelles pour soutenir les agriculteurs europ\u00e9ens en p\u00e9riode de crise","datePublished":"2016-03-15T22:00:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sillon38.com\/blog\/2016\/03\/16\/mesures-exceptionnelles-pour-soutenir-les-agriculteurs-europeens-en-periode-de-crise\/"},"wordCount":1505,"commentCount":0,"keywords":["commissaire Hogan"],"articleSection":["agriculture","Union europ\u00e9enne"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.sillon38.com\/blog\/2016\/03\/16\/mesures-exceptionnelles-pour-soutenir-les-agriculteurs-europeens-en-periode-de-crise\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.sillon38.com\/blog\/2016\/03\/16\/mesures-exceptionnelles-pour-soutenir-les-agriculteurs-europeens-en-periode-de-crise\/","url":"https:\/\/www.sillon38.com\/blog\/2016\/03\/16\/mesures-exceptionnelles-pour-soutenir-les-agriculteurs-europeens-en-periode-de-crise\/","name":"Mesures exceptionnelles pour soutenir les agriculteurs europ\u00e9ens en p\u00e9riode de crise -","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/#website"},"datePublished":"2016-03-15T22:00:26+00:00","author":{"@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"breadcrumb":{"@id":"https:\/\/www.sillon38.com\/blog\/2016\/03\/16\/mesures-exceptionnelles-pour-soutenir-les-agriculteurs-europeens-en-periode-de-crise\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sillon38.com\/blog\/2016\/03\/16\/mesures-exceptionnelles-pour-soutenir-les-agriculteurs-europeens-en-periode-de-crise\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sillon38.com\/blog\/2016\/03\/16\/mesures-exceptionnelles-pour-soutenir-les-agriculteurs-europeens-en-periode-de-crise\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.sillon38.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Mesures exceptionnelles pour soutenir les agriculteurs europ\u00e9ens en p\u00e9riode de crise"}]},{"@type":"WebSite","@id":"https:\/\/www.sillon38.com\/blog\/#website","url":"https:\/\/www.sillon38.com\/blog\/","name":"","description":"Le journal du monde rural","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sillon38.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1","name":"Gilbert"}]}},"_links":{"self":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/61911","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/comments?post=61911"}],"version-history":[{"count":0,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/61911\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/media?parent=61911"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/categories?post=61911"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/tags?post=61911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}