{"id":63400,"date":"2016-07-28T15:37:54","date_gmt":"2016-07-28T13:37:54","guid":{"rendered":"http:\/\/staging.sillon38.com\/?p=63400"},"modified":"2016-07-28T15:37:54","modified_gmt":"2016-07-28T13:37:54","slug":"le-cheval-rend-service-biassu-en-fait-son-actu","status":"publish","type":"post","link":"https:\/\/www.sillon38.com\/blog\/2016\/07\/28\/le-cheval-rend-service-biassu-en-fait-son-actu\/","title":{"rendered":"Le cheval rend service, Biassu en fait son actu&#8230;"},"content":{"rendered":"<p>Le cheval est au service des espaces agricoles, naturels mais aussi ruraux et urbain., voir notre article:<\/p>\n<p><a title=\"Permanent Link to Le cheval au service des espaces agricoles, naturels, ruraux et urbains\" rel=\"bookmark\" href=\"http:\/\/staging.sillon38.com\/2016\/07\/18\/le-cheval-au-service-des-espaces-agricoles-naturels-ruraux-et-urbains\/\">Le cheval au service des espaces agricoles, naturels, ruraux et urbains<\/a><\/p>\n<p>Biassu qui colle \u00e0 l&rsquo;actualit\u00e9 a trouv\u00e9 une autre action que pourrait mener le cheval&#8230;<a href=\"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2016\/07\/La-plus-belle-conquete-de-lhomme-19.07.16-reduit-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63401\" title=\"La plus belle conqu\u00eate de l'homme 19.07.16 r\u00e9duit-1\" src=\"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2016\/07\/La-plus-belle-conquete-de-lhomme-19.07.16-reduit-1.jpg\" alt=\"La plus belle conqu\u00eate de l'homme 19.07.16 r\u00e9duit-1\" width=\"595\" height=\"518\" srcset=\"https:\/\/www.sillon38.com\/blog\/wp-content\/uploads\/2016\/07\/La-plus-belle-conquete-de-lhomme-19.07.16-reduit-1.jpg 595w, https:\/\/www.sillon38.com\/blog\/wp-content\/uploads\/2016\/07\/La-plus-belle-conquete-de-lhomme-19.07.16-reduit-1-300x261.jpg 300w\" sizes=\"auto, (max-width: 595px) 100vw, 595px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le cheval est au service des espaces agricoles, naturels mais aussi ruraux et urbain.. Biassu qui colle \u00e0l&rsquo;actualit\u00e9 a trouv\u00e9 une autre action que pourrait mener le cheval&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-63400","post","type-post","status-publish","format-standard","hentry","category-biassu"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le cheval rend service, Biassu en fait son actu... -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sillon38.com\/blog\/2016\/07\/28\/le-cheval-rend-service-biassu-en-fait-son-actu\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le cheval rend service, Biassu en fait son actu... -\" \/>\n<meta property=\"og:description\" content=\"Le cheval est au service des espaces agricoles, naturels mais aussi ruraux et urbain.. Biassu qui colle \u00e0l&#039;actualit\u00e9 a trouv\u00e9 une autre action que pourrait mener le cheval...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sillon38.com\/blog\/2016\/07\/28\/le-cheval-rend-service-biassu-en-fait-son-actu\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-07-28T13:37:54+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2016\/07\/La-plus-belle-conquete-de-lhomme-19.07.16-reduit-1.jpg\" \/>\n<meta name=\"author\" content=\"Gilbert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gilbert\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2016\\\/07\\\/28\\\/le-cheval-rend-service-biassu-en-fait-son-actu\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2016\\\/07\\\/28\\\/le-cheval-rend-service-biassu-en-fait-son-actu\\\/\"},\"author\":{\"name\":\"Gilbert\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"headline\":\"Le cheval rend service, Biassu en fait son actu&#8230;\",\"datePublished\":\"2016-07-28T13:37:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2016\\\/07\\\/28\\\/le-cheval-rend-service-biassu-en-fait-son-actu\\\/\"},\"wordCount\":52,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2016\\\/07\\\/28\\\/le-cheval-rend-service-biassu-en-fait-son-actu\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/staging.sillon38.com\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/La-plus-belle-conquete-de-lhomme-19.07.16-reduit-1.jpg\",\"articleSection\":[\"Biassu\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2016\\\/07\\\/28\\\/le-cheval-rend-service-biassu-en-fait-son-actu\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2016\\\/07\\\/28\\\/le-cheval-rend-service-biassu-en-fait-son-actu\\\/\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2016\\\/07\\\/28\\\/le-cheval-rend-service-biassu-en-fait-son-actu\\\/\",\"name\":\"Le cheval rend service, Biassu en fait son actu... -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2016\\\/07\\\/28\\\/le-cheval-rend-service-biassu-en-fait-son-actu\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2016\\\/07\\\/28\\\/le-cheval-rend-service-biassu-en-fait-son-actu\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/staging.sillon38.com\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/La-plus-belle-conquete-de-lhomme-19.07.16-reduit-1.jpg\",\"datePublished\":\"2016-07-28T13:37:54+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2016\\\/07\\\/28\\\/le-cheval-rend-service-biassu-en-fait-son-actu\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2016\\\/07\\\/28\\\/le-cheval-rend-service-biassu-en-fait-son-actu\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2016\\\/07\\\/28\\\/le-cheval-rend-service-biassu-en-fait-son-actu\\\/#primaryimage\",\"url\":\"http:\\\/\\\/staging.sillon38.com\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/La-plus-belle-conquete-de-lhomme-19.07.16-reduit-1.jpg\",\"contentUrl\":\"http:\\\/\\\/staging.sillon38.com\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/La-plus-belle-conquete-de-lhomme-19.07.16-reduit-1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2016\\\/07\\\/28\\\/le-cheval-rend-service-biassu-en-fait-son-actu\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le cheval rend service, Biassu en fait son actu&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\",\"name\":\"\",\"description\":\"Le journal du monde rural\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\",\"name\":\"Gilbert\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le cheval rend service, Biassu en fait son actu... -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sillon38.com\/blog\/2016\/07\/28\/le-cheval-rend-service-biassu-en-fait-son-actu\/","og_locale":"fr_FR","og_type":"article","og_title":"Le cheval rend service, Biassu en fait son actu... -","og_description":"Le cheval est au service des espaces agricoles, naturels mais aussi ruraux et urbain.. Biassu qui colle \u00e0l'actualit\u00e9 a trouv\u00e9 une autre action que pourrait mener le cheval...","og_url":"https:\/\/www.sillon38.com\/blog\/2016\/07\/28\/le-cheval-rend-service-biassu-en-fait-son-actu\/","article_published_time":"2016-07-28T13:37:54+00:00","og_image":[{"url":"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2016\/07\/La-plus-belle-conquete-de-lhomme-19.07.16-reduit-1.jpg","type":"","width":"","height":""}],"author":"Gilbert","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Gilbert"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sillon38.com\/blog\/2016\/07\/28\/le-cheval-rend-service-biassu-en-fait-son-actu\/#article","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/2016\/07\/28\/le-cheval-rend-service-biassu-en-fait-son-actu\/"},"author":{"name":"Gilbert","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"headline":"Le cheval rend service, Biassu en fait son actu&#8230;","datePublished":"2016-07-28T13:37:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sillon38.com\/blog\/2016\/07\/28\/le-cheval-rend-service-biassu-en-fait-son-actu\/"},"wordCount":52,"commentCount":0,"image":{"@id":"https:\/\/www.sillon38.com\/blog\/2016\/07\/28\/le-cheval-rend-service-biassu-en-fait-son-actu\/#primaryimage"},"thumbnailUrl":"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2016\/07\/La-plus-belle-conquete-de-lhomme-19.07.16-reduit-1.jpg","articleSection":["Biassu"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.sillon38.com\/blog\/2016\/07\/28\/le-cheval-rend-service-biassu-en-fait-son-actu\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.sillon38.com\/blog\/2016\/07\/28\/le-cheval-rend-service-biassu-en-fait-son-actu\/","url":"https:\/\/www.sillon38.com\/blog\/2016\/07\/28\/le-cheval-rend-service-biassu-en-fait-son-actu\/","name":"Le cheval rend service, Biassu en fait son actu... -","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sillon38.com\/blog\/2016\/07\/28\/le-cheval-rend-service-biassu-en-fait-son-actu\/#primaryimage"},"image":{"@id":"https:\/\/www.sillon38.com\/blog\/2016\/07\/28\/le-cheval-rend-service-biassu-en-fait-son-actu\/#primaryimage"},"thumbnailUrl":"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2016\/07\/La-plus-belle-conquete-de-lhomme-19.07.16-reduit-1.jpg","datePublished":"2016-07-28T13:37:54+00:00","author":{"@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"breadcrumb":{"@id":"https:\/\/www.sillon38.com\/blog\/2016\/07\/28\/le-cheval-rend-service-biassu-en-fait-son-actu\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sillon38.com\/blog\/2016\/07\/28\/le-cheval-rend-service-biassu-en-fait-son-actu\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.sillon38.com\/blog\/2016\/07\/28\/le-cheval-rend-service-biassu-en-fait-son-actu\/#primaryimage","url":"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2016\/07\/La-plus-belle-conquete-de-lhomme-19.07.16-reduit-1.jpg","contentUrl":"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2016\/07\/La-plus-belle-conquete-de-lhomme-19.07.16-reduit-1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.sillon38.com\/blog\/2016\/07\/28\/le-cheval-rend-service-biassu-en-fait-son-actu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.sillon38.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Le cheval rend service, Biassu en fait son actu&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/www.sillon38.com\/blog\/#website","url":"https:\/\/www.sillon38.com\/blog\/","name":"","description":"Le journal du monde rural","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sillon38.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1","name":"Gilbert"}]}},"_links":{"self":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/63400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/comments?post=63400"}],"version-history":[{"count":0,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/63400\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/media?parent=63400"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/categories?post=63400"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/tags?post=63400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}