{"id":6567,"date":"2009-07-02T16:37:41","date_gmt":"2009-07-02T14:37:41","guid":{"rendered":"http:\/\/staging.sillon38.com\/?p=6567"},"modified":"2009-07-02T16:37:41","modified_gmt":"2009-07-02T14:37:41","slug":"ladtc-lance-un-sos-trolleybus","status":"publish","type":"post","link":"https:\/\/www.sillon38.com\/blog\/2009\/07\/02\/ladtc-lance-un-sos-trolleybus\/","title":{"rendered":"L&rsquo;ADTC lance un SOS trolleybus"},"content":{"rendered":"<p>L&rsquo;ADTC (association pour le d\u00e9veloppement des transports en commun) est plus qu&rsquo;inqui\u00e8te. Dans la nuit du mardi 30 juin au mercredi 1er juillet, des \u00e9quipes de techniciens du SMTC ont\u00a0 d\u00e9mont\u00e9 les lignes a\u00e9riennes qui alimentaient les trolleybus dans le secteur de la place Jean Achard et sur le quai Xavier Jouvin. Elle lance un v\u00e9ritable SOS.<\/p>\n<p>Quatre autres tron\u00e7ons pourraient subir le m\u00eame sort pendant ce mois de juillet.\u00a0 Pour l&rsquo;ADTC, le trolleybus, gr\u00e2ce \u00e0 son r\u00e9seau d\u2019alimentation \u00e9lectrique,\u00a0 offre le niveau de performances d\u2019un \u00ab petit tram \u00bb : silencieux, souple, confortable, non polluant, et capable de fonctionner \u00e0 une vitesse moyenne plus \u00e9lev\u00e9e qu\u2019un bus Diesel.\u00a0 Et pourtant, dans la nuit du mardi 30 juin au mercredi 1er juillet, des \u00e9quipes de techniciens ont\u00a0 d\u00e9mont\u00e9 les lignes a\u00e9riennes qui alimentaient les trolleybus dans le secteur de la place Jean Achard et sur le quai Xavier Jouvin<br \/>\nLe SMTC a expliqu\u00e9 r\u00e9cemment aux Grenoblois que la baisse des recettes et l\u2019augmentation des charges des collectivit\u00e9s locales devait le rendre tr\u00e8s rigoureux quant aux d\u00e9penses de fonctionnement.<br \/>\nEt pourtant, alors que cinq autres villes fran\u00e7aises b\u00e9n\u00e9ficient du Plan de relance gouvernemental pour cr\u00e9er des lignes de trolleybus (83 km nouveaux d\u2019ici 2013), et alors que les performances d\u2019un trolleybus permettent d\u2019offrir un meilleur service pour un co\u00fbt de fonctionnement moins \u00e9lev\u00e9 qu\u2019un bus Diesel, \u00e0 Grenoble, le SMTC d\u00e9pense de l\u2019argent public pour faire d\u00e9monter les lignes \u00e9lectriques qui alimentaient<br \/>\njusqu\u2019en 1999 les trolleybus des lignes 31 et 32.<\/p>\n<p>L\u2019ADTC, alert\u00e9e sur ces projets de d\u00e9montage, a interpell\u00e9 les \u00e9lus du SMTC pour d\u00e9noncer trois fausses id\u00e9es malheureusement encore trop r\u00e9pandues :<\/p>\n<p>1- \u00ab Les lignes existantes ne pourront jamais resservir, \u00e0 cause d\u2019une \u00e9volution des normes sur les lignes \u00e9lectriques \u00bb : c\u2019est faux, l\u2019arr\u00eat\u00e9 minist\u00e9riel du 21 mai 2001, article 100, permet de continuer \u00e0 utiliser des lignes \u00e9lectriques existantes, et de les mettre \u00e0 niveau progressivement au fil de travaux de voirie ou des modifications de parcours des trolleybus. C\u2019est d\u2019ailleurs le cas des lignes de tramway A et B, construites avant l\u2019\u00e9volution de la norme en 2001, dont la hauteur de plusieurs sections est inf\u00e9rieure \u00e0 cette norme.<\/p>\n<p>2- \u00ab La non-conformit\u00e9 aux recommandations des services de transports guid\u00e9s oblige \u00e0 d\u00e9monter les lignes pour des raisons d\u2019accessibilit\u00e9 des services de s\u00e9curit\u00e9 incendie\u00bb : c\u2019est faux, il est souvent possible de les mettre en conformit\u00e9 en d\u00e9calant les fils sur les supports pour permettre aux v\u00e9hicules de secours de man\u0153uvrer plus facilement, et les pompiers disposent d\u2019une certaine marge d\u2019adaptation. Le SMTC n\u2019a pas \u00e9tudi\u00e9 les alternatives possibles avant de donner l\u2019ordre de d\u00e9monter les lignes.<\/p>\n<p>3- \u00ab\u00a0 Le trolleybus qu\u2019on a connu, c\u2019est d\u00e9pass\u00e9, les v\u00e9hicules \u00e9lectriques du futur fonctionneront avec de mini sections de fils a\u00e9riens \u00bb : c\u2019est faux : outre que ce type de trolleybus sans fils sera plus cher qu\u2019un classique tant \u00e0 l\u2019achat qu\u2019en exploitation, les performances \u00e9nerg\u00e9tiques, \u00e9conomiques et\u00a0 m\u00e9caniques des dispositifs fonctionnant sur batterie, et des prototypes de v\u00e9hicules \u00e0 pile \u00e0 combustible, sont tr\u00e8s inf\u00e9rieures \u00e0 celles des trolleybus classiques \u00ab \u00e0 fils \u00bb.<\/p>\n<p>L\u2019ADTC d\u00e9plore que ses observations n\u2019aient pas \u00e9t\u00e9 entendues. Elle demande un moratoire sur la d\u00e9pose des lignes de trolleybus, et l\u2019\u00e9valuation de solutions non destructives sur les quelques tron\u00e7ons qui<br \/>\npourraient \u00e9ventuellement occasionner des difficult\u00e9s pour les pompiers.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;ADTC (association pour le d\u00e9veloppement des transports en commun) est plus qu&rsquo;inqui\u00e8te. Dans la nuit du mardi 30 juin au mercredi 1er juillet, des \u00e9quipes de techniciens du SMTC ont\u00a0 d\u00e9mont\u00e9 les lignes a\u00e9riennes qui alimentaient les trolleybus dans le&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[216,2776,5462],"class_list":["post-6567","post","type-post","status-publish","format-standard","hentry","category-energies","tag-adtc","tag-grenoble","tag-trolleybus"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;ADTC lance un SOS trolleybus -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sillon38.com\/blog\/2009\/07\/02\/ladtc-lance-un-sos-trolleybus\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;ADTC lance un SOS trolleybus -\" \/>\n<meta property=\"og:description\" content=\"L&rsquo;ADTC (association pour le d\u00e9veloppement des transports en commun) est plus qu&rsquo;inqui\u00e8te. Dans la nuit du mardi 30 juin au mercredi 1er juillet, des \u00e9quipes de techniciens du SMTC ont\u00a0 d\u00e9mont\u00e9 les lignes a\u00e9riennes qui alimentaient les trolleybus dans le...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sillon38.com\/blog\/2009\/07\/02\/ladtc-lance-un-sos-trolleybus\/\" \/>\n<meta property=\"article:published_time\" content=\"2009-07-02T14:37:41+00:00\" \/>\n<meta name=\"author\" content=\"Gilbert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gilbert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/07\\\/02\\\/ladtc-lance-un-sos-trolleybus\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/07\\\/02\\\/ladtc-lance-un-sos-trolleybus\\\/\"},\"author\":{\"name\":\"Gilbert\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"headline\":\"L&rsquo;ADTC lance un SOS trolleybus\",\"datePublished\":\"2009-07-02T14:37:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/07\\\/02\\\/ladtc-lance-un-sos-trolleybus\\\/\"},\"wordCount\":609,\"commentCount\":0,\"keywords\":[\"ADTC\",\"Grenoble\",\"trolleybus\"],\"articleSection\":[\"\u00e9nergies\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/07\\\/02\\\/ladtc-lance-un-sos-trolleybus\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/07\\\/02\\\/ladtc-lance-un-sos-trolleybus\\\/\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/07\\\/02\\\/ladtc-lance-un-sos-trolleybus\\\/\",\"name\":\"L'ADTC lance un SOS trolleybus -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\"},\"datePublished\":\"2009-07-02T14:37:41+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/07\\\/02\\\/ladtc-lance-un-sos-trolleybus\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/07\\\/02\\\/ladtc-lance-un-sos-trolleybus\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/07\\\/02\\\/ladtc-lance-un-sos-trolleybus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&rsquo;ADTC lance un SOS trolleybus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\",\"name\":\"\",\"description\":\"Le journal du monde rural\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\",\"name\":\"Gilbert\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'ADTC lance un SOS trolleybus -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sillon38.com\/blog\/2009\/07\/02\/ladtc-lance-un-sos-trolleybus\/","og_locale":"fr_FR","og_type":"article","og_title":"L'ADTC lance un SOS trolleybus -","og_description":"L&rsquo;ADTC (association pour le d\u00e9veloppement des transports en commun) est plus qu&rsquo;inqui\u00e8te. Dans la nuit du mardi 30 juin au mercredi 1er juillet, des \u00e9quipes de techniciens du SMTC ont\u00a0 d\u00e9mont\u00e9 les lignes a\u00e9riennes qui alimentaient les trolleybus dans le...","og_url":"https:\/\/www.sillon38.com\/blog\/2009\/07\/02\/ladtc-lance-un-sos-trolleybus\/","article_published_time":"2009-07-02T14:37:41+00:00","author":"Gilbert","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Gilbert","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sillon38.com\/blog\/2009\/07\/02\/ladtc-lance-un-sos-trolleybus\/#article","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/2009\/07\/02\/ladtc-lance-un-sos-trolleybus\/"},"author":{"name":"Gilbert","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"headline":"L&rsquo;ADTC lance un SOS trolleybus","datePublished":"2009-07-02T14:37:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sillon38.com\/blog\/2009\/07\/02\/ladtc-lance-un-sos-trolleybus\/"},"wordCount":609,"commentCount":0,"keywords":["ADTC","Grenoble","trolleybus"],"articleSection":["\u00e9nergies"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.sillon38.com\/blog\/2009\/07\/02\/ladtc-lance-un-sos-trolleybus\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.sillon38.com\/blog\/2009\/07\/02\/ladtc-lance-un-sos-trolleybus\/","url":"https:\/\/www.sillon38.com\/blog\/2009\/07\/02\/ladtc-lance-un-sos-trolleybus\/","name":"L'ADTC lance un SOS trolleybus -","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/#website"},"datePublished":"2009-07-02T14:37:41+00:00","author":{"@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"breadcrumb":{"@id":"https:\/\/www.sillon38.com\/blog\/2009\/07\/02\/ladtc-lance-un-sos-trolleybus\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sillon38.com\/blog\/2009\/07\/02\/ladtc-lance-un-sos-trolleybus\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sillon38.com\/blog\/2009\/07\/02\/ladtc-lance-un-sos-trolleybus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.sillon38.com\/blog\/"},{"@type":"ListItem","position":2,"name":"L&rsquo;ADTC lance un SOS trolleybus"}]},{"@type":"WebSite","@id":"https:\/\/www.sillon38.com\/blog\/#website","url":"https:\/\/www.sillon38.com\/blog\/","name":"","description":"Le journal du monde rural","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sillon38.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1","name":"Gilbert"}]}},"_links":{"self":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/6567","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/comments?post=6567"}],"version-history":[{"count":0,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/6567\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/media?parent=6567"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/categories?post=6567"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/tags?post=6567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}