{"id":6601,"date":"2009-06-25T18:03:16","date_gmt":"2009-06-25T16:03:16","guid":{"rendered":"http:\/\/staging.sillon38.com\/?p=6601"},"modified":"2009-06-25T18:03:16","modified_gmt":"2009-06-25T16:03:16","slug":"la-region-lance-le-cheque-energie","status":"publish","type":"post","link":"https:\/\/www.sillon38.com\/blog\/2009\/06\/25\/la-region-lance-le-cheque-energie\/","title":{"rendered":"La R\u00e9gion lance le ch\u00e8que \u00e9nergie"},"content":{"rendered":"<p>D\u00e8s le 1er juillet, le Ch\u00e8que Energie Rh\u00f4ne-Alpes, permettra aux particuliers rh\u00f4nalpins de r\u00e9gler une partie de leur facture d&rsquo;installation d&rsquo;\u00e9quipements d\u00e9di\u00e9s aux \u00e9nergies renouvelables: chauffe-eau solaire, syst\u00e8me solaire combin\u00e9 individuel, chaudi\u00e8re automatique au bois.<\/p>\n<p>Leader en mati\u00e8re de politique de l\u2019\u00e9nergie, la R\u00e9gion Rh\u00f4ne-Alpes a adopt\u00e9, en 2005, un Plan Energie ambitieux visant au d\u00e9veloppement des \u00e9nergies renouvelables et \u00e0 la ma\u00eetrise de la consommation \u00e9nerg\u00e9tique, notamment gr\u00e2ce aux aides destin\u00e9es aux particuliers.<br \/>\nAvec 90 M\u20ac investis depuis 2005, le Plan Energie permet, chaque ann\u00e9e, de diminuer de 23 M\u20ac la facture \u00e9nerg\u00e9tique de l\u2019ensemble des foyers b\u00e9n\u00e9ficiaires des aides et d\u2019\u00e9conomiser 165 000 tonnes d\u2019\u00e9quivalents CO2. \u00ab La R\u00e9gion Rh\u00f4ne-Alpes n\u2019a pas attendu le Grenelle de l\u2019Environnement. Nous prouvons que nos engagements en faveur du d\u00e9veloppement durable se concr\u00e9tisent par des actes aux effets quantifiables \u00bb explique Jean-Jack Queyranne, Pr\u00e9sident de la R\u00e9gion Rh\u00f4ne-Alpes.<\/p>\n<p>Le soutien aux m\u00e9nages les plus modestes qui souhaitent r\u00e9aliser des investissements dans des \u00e9quipements utilisateurs d\u2019\u00e9nergies renouvelables est au c\u0153ur de ce Plan Energie. Depuis 2005, ce sont plus de 20 000 aides individuelles qui ont \u00e9t\u00e9 accord\u00e9es aux Rh\u00f4nalpins.<\/p>\n<p>Face \u00e0 ce succ\u00e8s, la R\u00e9gion a d\u00e9cid\u00e9 de modifier le mode d\u2019attribution de ces aides. Plus simple et plus rapide, l\u2019aide sera d\u00e9sormais d\u00e9livr\u00e9e sous la forme d\u2019un ch\u00e8que forfaitaire, le Ch\u00e8que Energie Rh\u00f4ne-Alpes, permettant aux particuliers de r\u00e9gler une partie de leur facture d&rsquo;installation d&rsquo;\u00e9quipements d\u00e9di\u00e9s aux \u00e9nergies renouvelables.<\/p>\n<p>A compter du 1er juillet 2009, un num\u00e9ro Cristal (0969 322 169) et une page sur le site de la R\u00e9gion, chequeenergie.rhonealpes.fr seront mis en place, pour que tout Rh\u00f4nalpin &#8211; respectant les conditions d\u2019\u00e9ligibilit\u00e9 &#8211; puisse adresser une demande de Ch\u00e8que Energie pour l\u2019installation d\u2019un :<br \/>\n&#8211; Chauffe-eau solaire individuel :\u00a0\u00a0 300 \u20ac<br \/>\n&#8211; Syst\u00e8me Solaire Combin\u00e9 individuel :\u00a0 1000 \u20ac<br \/>\n&#8211; Chaudi\u00e8re automatique au bois :\u00a0\u00a0 1000 \u20ac<br \/>\nDans un d\u00e9lai de 10 jours, le Ch\u00e8que Energie nominatif sera envoy\u00e9.<\/p>\n<p>Les avantages du Ch\u00e8que Energie Rh\u00f4ne-Alpes devraient inciter les Rh\u00f4nalpins \u00e0 investir dans les \u00e9nergies renouvelables :<br \/>\n&#8211; Formalit\u00e9s simplifi\u00e9es et obtention rapide ;<br \/>\n&#8211; Pas d\u2019avance par le particulier \u00e0 l\u2019installateur du montant du Ch\u00e8que Energie ;<br \/>\n&#8211; Qualit\u00e9 garantie des futures installations (seuls les installateurs disposant d\u2019une appellation Qualit\u2019EnR et installant un mat\u00e9riel agr\u00e9\u00e9 sont associ\u00e9s aux dispositifs).<\/p>\n<p>En 2009, ce sont pr\u00e8s de 3 000 foyers qui devraient b\u00e9n\u00e9ficier d\u2019une aide \u00e9nergie renouvelable, la R\u00e9gion soutenant le dynamisme de cette fili\u00e8re \u00e9conomique, \u00e0 hauteur de 2 M\u20ac.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>D\u00e8s le 1er juillet, le Ch\u00e8que Energie Rh\u00f4ne-Alpes, permettra aux particuliers rh\u00f4nalpins de r\u00e9gler une partie de leur facture d&rsquo;installation d&rsquo;\u00e9quipements d\u00e9di\u00e9s aux \u00e9nergies renouvelables: chauffe-eau solaire, syst\u00e8me solaire combin\u00e9 individuel, chaudi\u00e8re automatique au bois. Leader en mati\u00e8re de politique&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[98],"tags":[],"class_list":["post-6601","post","type-post","status-publish","format-standard","hentry","category-ecologie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La R\u00e9gion lance le ch\u00e8que \u00e9nergie -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sillon38.com\/blog\/2009\/06\/25\/la-region-lance-le-cheque-energie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La R\u00e9gion lance le ch\u00e8que \u00e9nergie -\" \/>\n<meta property=\"og:description\" content=\"D\u00e8s le 1er juillet, le Ch\u00e8que Energie Rh\u00f4ne-Alpes, permettra aux particuliers rh\u00f4nalpins de r\u00e9gler une partie de leur facture d&rsquo;installation d&rsquo;\u00e9quipements d\u00e9di\u00e9s aux \u00e9nergies renouvelables: chauffe-eau solaire, syst\u00e8me solaire combin\u00e9 individuel, chaudi\u00e8re automatique au bois. Leader en mati\u00e8re de politique...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sillon38.com\/blog\/2009\/06\/25\/la-region-lance-le-cheque-energie\/\" \/>\n<meta property=\"article:published_time\" content=\"2009-06-25T16:03:16+00:00\" \/>\n<meta name=\"author\" content=\"Gilbert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gilbert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/06\\\/25\\\/la-region-lance-le-cheque-energie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/06\\\/25\\\/la-region-lance-le-cheque-energie\\\/\"},\"author\":{\"name\":\"Gilbert\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"headline\":\"La R\u00e9gion lance le ch\u00e8que \u00e9nergie\",\"datePublished\":\"2009-06-25T16:03:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/06\\\/25\\\/la-region-lance-le-cheque-energie\\\/\"},\"wordCount\":470,\"commentCount\":0,\"articleSection\":[\"\u00e9cologie\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/06\\\/25\\\/la-region-lance-le-cheque-energie\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/06\\\/25\\\/la-region-lance-le-cheque-energie\\\/\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/06\\\/25\\\/la-region-lance-le-cheque-energie\\\/\",\"name\":\"La R\u00e9gion lance le ch\u00e8que \u00e9nergie -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\"},\"datePublished\":\"2009-06-25T16:03:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/06\\\/25\\\/la-region-lance-le-cheque-energie\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/06\\\/25\\\/la-region-lance-le-cheque-energie\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/06\\\/25\\\/la-region-lance-le-cheque-energie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La R\u00e9gion lance le ch\u00e8que \u00e9nergie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\",\"name\":\"\",\"description\":\"Le journal du monde rural\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\",\"name\":\"Gilbert\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La R\u00e9gion lance le ch\u00e8que \u00e9nergie -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sillon38.com\/blog\/2009\/06\/25\/la-region-lance-le-cheque-energie\/","og_locale":"fr_FR","og_type":"article","og_title":"La R\u00e9gion lance le ch\u00e8que \u00e9nergie -","og_description":"D\u00e8s le 1er juillet, le Ch\u00e8que Energie Rh\u00f4ne-Alpes, permettra aux particuliers rh\u00f4nalpins de r\u00e9gler une partie de leur facture d&rsquo;installation d&rsquo;\u00e9quipements d\u00e9di\u00e9s aux \u00e9nergies renouvelables: chauffe-eau solaire, syst\u00e8me solaire combin\u00e9 individuel, chaudi\u00e8re automatique au bois. Leader en mati\u00e8re de politique...","og_url":"https:\/\/www.sillon38.com\/blog\/2009\/06\/25\/la-region-lance-le-cheque-energie\/","article_published_time":"2009-06-25T16:03:16+00:00","author":"Gilbert","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Gilbert","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sillon38.com\/blog\/2009\/06\/25\/la-region-lance-le-cheque-energie\/#article","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/2009\/06\/25\/la-region-lance-le-cheque-energie\/"},"author":{"name":"Gilbert","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"headline":"La R\u00e9gion lance le ch\u00e8que \u00e9nergie","datePublished":"2009-06-25T16:03:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sillon38.com\/blog\/2009\/06\/25\/la-region-lance-le-cheque-energie\/"},"wordCount":470,"commentCount":0,"articleSection":["\u00e9cologie"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.sillon38.com\/blog\/2009\/06\/25\/la-region-lance-le-cheque-energie\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.sillon38.com\/blog\/2009\/06\/25\/la-region-lance-le-cheque-energie\/","url":"https:\/\/www.sillon38.com\/blog\/2009\/06\/25\/la-region-lance-le-cheque-energie\/","name":"La R\u00e9gion lance le ch\u00e8que \u00e9nergie -","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/#website"},"datePublished":"2009-06-25T16:03:16+00:00","author":{"@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"breadcrumb":{"@id":"https:\/\/www.sillon38.com\/blog\/2009\/06\/25\/la-region-lance-le-cheque-energie\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sillon38.com\/blog\/2009\/06\/25\/la-region-lance-le-cheque-energie\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sillon38.com\/blog\/2009\/06\/25\/la-region-lance-le-cheque-energie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.sillon38.com\/blog\/"},{"@type":"ListItem","position":2,"name":"La R\u00e9gion lance le ch\u00e8que \u00e9nergie"}]},{"@type":"WebSite","@id":"https:\/\/www.sillon38.com\/blog\/#website","url":"https:\/\/www.sillon38.com\/blog\/","name":"","description":"Le journal du monde rural","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sillon38.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1","name":"Gilbert"}]}},"_links":{"self":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/6601","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/comments?post=6601"}],"version-history":[{"count":0,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/6601\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/media?parent=6601"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/categories?post=6601"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/tags?post=6601"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}