{"id":72061,"date":"2017-10-30T20:20:45","date_gmt":"2017-10-30T18:20:45","guid":{"rendered":"http:\/\/staging.sillon38.com\/?p=72061"},"modified":"2017-10-30T20:20:45","modified_gmt":"2017-10-30T18:20:45","slug":"vendredi-3-novembre-la-foire-de-grenoble-ouvre-ses-portes","status":"publish","type":"post","link":"https:\/\/www.sillon38.com\/blog\/2017\/10\/30\/vendredi-3-novembre-la-foire-de-grenoble-ouvre-ses-portes\/","title":{"rendered":"Vendredi 3 novembre : la foire de Grenoble ouvre ses portes!"},"content":{"rendered":"<p><strong><span style=\"color: #000080;\">Le vendredi 3 novembre \u00e0 10h, La Foire de Grenoble ouvre ses portes pour une nouvelle \u00e9dition aux couleurs olympiques.<\/span><\/strong><\/p>\n<p><span style=\"color: #000080;\"> <\/span><\/p>\n<p><span style=\"color: #000080;\">Avec pr\u00e8s de 500 exposants,10 restaurants, des animations tous les jours et trois nocturnes, la Foire de Grenoble, organis\u00e9e par les \u00e9quipes d\u2019Alpexpo, est un \u00e9v\u00e9nement incontournable et repr\u00e9sente la plus grande vitrine commerciale en Is\u00e8re.<\/span><\/p>\n<p><span style=\"color: #000080;\">Elle totalise cette ann\u00e9e pr\u00e8s 42000 m\u00b2 de surface d\u2019exposition.<\/span><\/p>\n<p><span style=\"color: #000080;\"> \u00a0\u00bb Ce grand rendez vous, \u00e0 la fois convivial et festif, offrira l&rsquo;occasion de d\u00e9couvrir sur un m\u00eame endroit une large palette d\u2019exposants dans des univers tr\u00e8s vari\u00e9s. Le public peut comparer un grand nombre de produits en un lieu unique, d\u00e9couvrir des nouveaut\u00e9s, des nouvelles tendances, d\u00e9nicher l\u2019objet introuvable ou encore faire de bonnes affaires ! La Foire offre un large choix pour toutes les envies: d\u00e9corer, r\u00e9nover, am\u00e9nager, s\u2019\u00e9quiper&#8230;\u00ab pr\u00e9cise le Directeur G\u00e9n\u00e9ral d\u2019Alpexpo, Fran\u00e7ois Heid.<\/span><\/p>\n<p><span style=\"color: #000080;\"><strong>Pour son \u00e9dition 2017, la Foire de Grenoble met les 50 ans des JO \u00e0 l\u2019honneur. <\/strong><\/span><\/p>\n<p><span style=\"color: #000080;\">Cette c\u00e9l\u00e9bration des JO de Grenoble s\u2019organise autour d\u2019une exposition et d\u2019un programme d\u2019animations \u00e0 la fois dense et <\/span><span style=\"color: #000080;\"><a rel=\"attachment wp-att-72063\" href=\"http:\/\/staging.sillon38.com\/2017\/10\/30\/vendredi-3-novembre-la-foire-de-grenoble-ouvre-ses-portes\/sans-titre-270\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-72063\" title=\"Sans titre\" src=\"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2017\/10\/Sans-titre6-194x300.png\" alt=\"Sans titre\" width=\"194\" height=\"300\" \/><\/a><\/span><span style=\"color: #000080;\">vari\u00e9. R\u00e9alis\u00e9 avec la complicit\u00e9 du Coljog (Conservatoire, Observatoire et Laboratoire des JO de Grenoble) l\u2019exposition \u00e0 d\u00e9couvrir sur les 11 jours de la Foire propose de revivre cette page d\u2019histoire de Grenoble \u00e0 travers des anecdotes, des objets collectors,une pr\u00e9sentation de photos origina les sans oublier le Shuss, la mascotte des JO qui accueillera le public de la Foire.<\/span><\/p>\n<p><span style=\"color: #000080;\">Pour la premi\u00e8re fois, la Foire accueillera une patinoire pour des initiations et des d\u00e9monstrations par des m\u00e9daill\u00e9s olympiques, une piste de curling, du biathlon, des chiens tra\u00eeneaux pour le plaisir des enfants mais aussi des exp\u00e9riences interactives avec des jeux vid\u00e9o et un espace escape gam..<\/span><\/p>\n<p><span style=\"color: #000080;\">Parmi les personnalit\u00e9s attendues on citera Philippe Cand\u00e9loro\u00a0 accompagn\u00e9 de son complice Nelson Montfort, le samedi 4 novembre, Brian joubert, Marielle et Christine Goitschel&#8230;<\/span><\/p>\n<blockquote><p><span style=\"color: #000080;\">Pour sa premi\u00e8re journ\u00e9e, vendredi 3 novembre, l\u2019entr\u00e9e \u00e0 la Foire est gratuite et se prolonge jusqu\u2019\u00e0 23h avec un spectacle qui replonge le public dans l\u2019ambiance des ann\u00e9es 60. Pour c\u00e9l\u00e9brer les JO de 1968 et marquer l\u2019ouverture de cette Foire de Grenoble 2017, un feu d\u2019Artifice gratuit est tir\u00e9 \u00e0 19h30..<\/span><\/p><\/blockquote>\n<p><span style=\"color: #000080;\">On retiendra \u00e9galement la pr\u00e9sence tout au long de la foire des \u00e9quipes des bruleurs de loup, du FCG, du GF38&#8230;<\/span><\/p>\n<p><span style=\"color: #000080;\"><strong>Gastronomie..<\/strong><\/span><\/p>\n<p><span style=\"color: #000080;\">La gastronomie ne sera pas en reste avec le hall 89 qui lui sera enti\u00e8rement d\u00e9di\u00e9.<\/span><\/p>\n<p><span style=\"color: #000080;\">Moments conviviaux tr\u00e8s appr\u00e9ci\u00e9s des visiteurs, les restaurants sont aussi au rendez-vous et proposent de savourer les cuisines de tous les terroirs : cr\u00eapes, aligot, ravioles, couscous, choucroute, cuisine Corse, Antillaise, Br\u00e9silienne, du Sud-Ouest et Bretonne. Et cette ann\u00e9e, un p\u00f4le cuisine italienne sera propos\u00e9&#8230; <\/span><\/p>\n<p><span style=\"color: #000080;\">Bien entendu on ne passera pas sous silence les diff\u00e9rents stands qui pr\u00e9senteront les produits du terroir dont ceux de l&rsquo;Is\u00e8re. <\/span><\/p>\n<blockquote><p><span style=\"color: #000080;\"><strong>En effet l&rsquo;Is\u00e8re sera pr\u00e9sente en plein centre du hall de la gastronomie. On pourra y d\u00e9couvrir les produits fleurons de notre d\u00e9partement que sont:\u00a0 le bleu du Vercors Sassenage, le St Marcellin, Le Mur\u00e7on Matheysin, la noix de Grenoble accompagn\u00e9s par leurs confr\u00e9ries mais aussi la truffe, les fromages du Vercors, le safran du Drac&#8230; Un espace incontournable!<\/strong><br \/>\n<\/span><\/p><\/blockquote>\n<p><span style=\"color: #000080;\"><strong><br \/>\n<\/strong><\/span><\/p>\n<p><span style=\"color: #000080;\"> <\/span><a rel=\"attachment wp-att-72062\" href=\"http:\/\/staging.sillon38.com\/2017\/10\/30\/vendredi-3-novembre-la-foire-de-grenoble-ouvre-ses-portes\/sans-titre-269\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-72062\" title=\"Sans titre\" src=\"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2017\/10\/Sans-titre5.png\" alt=\"Sans titre\" width=\"585\" height=\"695\" srcset=\"https:\/\/www.sillon38.com\/blog\/wp-content\/uploads\/2017\/10\/Sans-titre5.png 585w, https:\/\/www.sillon38.com\/blog\/wp-content\/uploads\/2017\/10\/Sans-titre5-253x300.png 253w\" sizes=\"auto, (max-width: 585px) 100vw, 585px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jeux olympiques et gastronomie \u00e0 l&rsquo;honneur!<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,26],"tags":[399,2473,3332,3390,4259],"class_list":["post-72061","post","type-post","status-publish","format-standard","hentry","category-a-la-une","category-foires-et-fetes","tag-alpexpo","tag-foire-de-grenoble","tag-le-bleu-du-vercors-sassenage","tag-le-shuss","tag-philippe-candeloro"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vendredi 3 novembre : la foire de Grenoble ouvre ses portes! -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sillon38.com\/blog\/2017\/10\/30\/vendredi-3-novembre-la-foire-de-grenoble-ouvre-ses-portes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vendredi 3 novembre : la foire de Grenoble ouvre ses portes! -\" \/>\n<meta property=\"og:description\" content=\"Jeux olympiques et gastronomie \u00e0 l&#039;honneur!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sillon38.com\/blog\/2017\/10\/30\/vendredi-3-novembre-la-foire-de-grenoble-ouvre-ses-portes\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-10-30T18:20:45+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2017\/10\/Sans-titre6-194x300.png\" \/>\n<meta name=\"author\" content=\"Gilbert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gilbert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2017\\\/10\\\/30\\\/vendredi-3-novembre-la-foire-de-grenoble-ouvre-ses-portes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2017\\\/10\\\/30\\\/vendredi-3-novembre-la-foire-de-grenoble-ouvre-ses-portes\\\/\"},\"author\":{\"name\":\"Gilbert\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"headline\":\"Vendredi 3 novembre : la foire de Grenoble ouvre ses portes!\",\"datePublished\":\"2017-10-30T18:20:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2017\\\/10\\\/30\\\/vendredi-3-novembre-la-foire-de-grenoble-ouvre-ses-portes\\\/\"},\"wordCount\":594,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2017\\\/10\\\/30\\\/vendredi-3-novembre-la-foire-de-grenoble-ouvre-ses-portes\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/staging.sillon38.com\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/Sans-titre6-194x300.png\",\"keywords\":[\"Alpexpo\",\"Foire de Grenoble\",\"le bleu du Vercors Sassenage\",\"le Shuss\",\"Philippe Cand\u00e9loro\"],\"articleSection\":[\"\u00c0 la une\",\"foires et f\u00eates\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2017\\\/10\\\/30\\\/vendredi-3-novembre-la-foire-de-grenoble-ouvre-ses-portes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2017\\\/10\\\/30\\\/vendredi-3-novembre-la-foire-de-grenoble-ouvre-ses-portes\\\/\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2017\\\/10\\\/30\\\/vendredi-3-novembre-la-foire-de-grenoble-ouvre-ses-portes\\\/\",\"name\":\"Vendredi 3 novembre : la foire de Grenoble ouvre ses portes! -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2017\\\/10\\\/30\\\/vendredi-3-novembre-la-foire-de-grenoble-ouvre-ses-portes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2017\\\/10\\\/30\\\/vendredi-3-novembre-la-foire-de-grenoble-ouvre-ses-portes\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/staging.sillon38.com\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/Sans-titre6-194x300.png\",\"datePublished\":\"2017-10-30T18:20:45+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2017\\\/10\\\/30\\\/vendredi-3-novembre-la-foire-de-grenoble-ouvre-ses-portes\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2017\\\/10\\\/30\\\/vendredi-3-novembre-la-foire-de-grenoble-ouvre-ses-portes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2017\\\/10\\\/30\\\/vendredi-3-novembre-la-foire-de-grenoble-ouvre-ses-portes\\\/#primaryimage\",\"url\":\"http:\\\/\\\/staging.sillon38.com\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/Sans-titre6-194x300.png\",\"contentUrl\":\"http:\\\/\\\/staging.sillon38.com\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/Sans-titre6-194x300.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2017\\\/10\\\/30\\\/vendredi-3-novembre-la-foire-de-grenoble-ouvre-ses-portes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vendredi 3 novembre : la foire de Grenoble ouvre ses portes!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\",\"name\":\"\",\"description\":\"Le journal du monde rural\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\",\"name\":\"Gilbert\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vendredi 3 novembre : la foire de Grenoble ouvre ses portes! -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sillon38.com\/blog\/2017\/10\/30\/vendredi-3-novembre-la-foire-de-grenoble-ouvre-ses-portes\/","og_locale":"fr_FR","og_type":"article","og_title":"Vendredi 3 novembre : la foire de Grenoble ouvre ses portes! -","og_description":"Jeux olympiques et gastronomie \u00e0 l'honneur!","og_url":"https:\/\/www.sillon38.com\/blog\/2017\/10\/30\/vendredi-3-novembre-la-foire-de-grenoble-ouvre-ses-portes\/","article_published_time":"2017-10-30T18:20:45+00:00","og_image":[{"url":"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2017\/10\/Sans-titre6-194x300.png","type":"","width":"","height":""}],"author":"Gilbert","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Gilbert","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sillon38.com\/blog\/2017\/10\/30\/vendredi-3-novembre-la-foire-de-grenoble-ouvre-ses-portes\/#article","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/2017\/10\/30\/vendredi-3-novembre-la-foire-de-grenoble-ouvre-ses-portes\/"},"author":{"name":"Gilbert","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"headline":"Vendredi 3 novembre : la foire de Grenoble ouvre ses portes!","datePublished":"2017-10-30T18:20:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sillon38.com\/blog\/2017\/10\/30\/vendredi-3-novembre-la-foire-de-grenoble-ouvre-ses-portes\/"},"wordCount":594,"commentCount":0,"image":{"@id":"https:\/\/www.sillon38.com\/blog\/2017\/10\/30\/vendredi-3-novembre-la-foire-de-grenoble-ouvre-ses-portes\/#primaryimage"},"thumbnailUrl":"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2017\/10\/Sans-titre6-194x300.png","keywords":["Alpexpo","Foire de Grenoble","le bleu du Vercors Sassenage","le Shuss","Philippe Cand\u00e9loro"],"articleSection":["\u00c0 la une","foires et f\u00eates"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.sillon38.com\/blog\/2017\/10\/30\/vendredi-3-novembre-la-foire-de-grenoble-ouvre-ses-portes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.sillon38.com\/blog\/2017\/10\/30\/vendredi-3-novembre-la-foire-de-grenoble-ouvre-ses-portes\/","url":"https:\/\/www.sillon38.com\/blog\/2017\/10\/30\/vendredi-3-novembre-la-foire-de-grenoble-ouvre-ses-portes\/","name":"Vendredi 3 novembre : la foire de Grenoble ouvre ses portes! -","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sillon38.com\/blog\/2017\/10\/30\/vendredi-3-novembre-la-foire-de-grenoble-ouvre-ses-portes\/#primaryimage"},"image":{"@id":"https:\/\/www.sillon38.com\/blog\/2017\/10\/30\/vendredi-3-novembre-la-foire-de-grenoble-ouvre-ses-portes\/#primaryimage"},"thumbnailUrl":"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2017\/10\/Sans-titre6-194x300.png","datePublished":"2017-10-30T18:20:45+00:00","author":{"@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"breadcrumb":{"@id":"https:\/\/www.sillon38.com\/blog\/2017\/10\/30\/vendredi-3-novembre-la-foire-de-grenoble-ouvre-ses-portes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sillon38.com\/blog\/2017\/10\/30\/vendredi-3-novembre-la-foire-de-grenoble-ouvre-ses-portes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.sillon38.com\/blog\/2017\/10\/30\/vendredi-3-novembre-la-foire-de-grenoble-ouvre-ses-portes\/#primaryimage","url":"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2017\/10\/Sans-titre6-194x300.png","contentUrl":"http:\/\/staging.sillon38.com\/wp-content\/uploads\/2017\/10\/Sans-titre6-194x300.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.sillon38.com\/blog\/2017\/10\/30\/vendredi-3-novembre-la-foire-de-grenoble-ouvre-ses-portes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.sillon38.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Vendredi 3 novembre : la foire de Grenoble ouvre ses portes!"}]},{"@type":"WebSite","@id":"https:\/\/www.sillon38.com\/blog\/#website","url":"https:\/\/www.sillon38.com\/blog\/","name":"","description":"Le journal du monde rural","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sillon38.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1","name":"Gilbert"}]}},"_links":{"self":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/72061","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/comments?post=72061"}],"version-history":[{"count":0,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/72061\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/media?parent=72061"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/categories?post=72061"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/tags?post=72061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}