{"id":74268,"date":"2018-04-06T21:26:43","date_gmt":"2018-04-06T19:26:43","guid":{"rendered":"http:\/\/staging.sillon38.com\/?p=74268"},"modified":"2018-04-06T21:26:43","modified_gmt":"2018-04-06T19:26:43","slug":"ag-des-gites-de-france-isere-2","status":"publish","type":"post","link":"https:\/\/www.sillon38.com\/blog\/2018\/04\/06\/ag-des-gites-de-france-isere-2\/","title":{"rendered":"AG des g\u00eetes de France Is\u00e8re"},"content":{"rendered":"<p><span style=\"color: #000080;\">L &lsquo;assembl\u00e9e G\u00e9n\u00e9rale des g\u00eetes de France Is\u00e8re s&rsquo;est tenue dans le cadre prestigieux du mus\u00e9e de la mine \u00e0 La Motte d&rsquo;Aveillans.\u00a0 En Matheysine donc, un territoire qui compte plus de 70 h\u00e9bergements labellis\u00e9s.<\/span><\/p>\n<p><span style=\"color: #000080;\">Fort de ces 60 ans d \u2019existence (en 2017), les G\u00eetes de France demeurent un acteur incontournable du d\u00e9veloppement local.<\/span><\/p>\n<p><span style=\"color: #000080;\">Cette Assembl\u00e9e G\u00e9n\u00e9rale a \u00e9t\u00e9\u00a0 l\u2019occasion de faire le point sur l\u2019activit\u00e9 G\u00eetes de France en Is\u00e8re, tant en terme de d\u00e9veloppement (Pr\u00e8s de 50 nouveaux h\u00e9bergements ont ouvert leurs portes en 2017) que sur le plan commercial (le service r\u00e9servation des G\u00eetes de France de l\u2019Is\u00e8re g\u00e9n\u00e8re un volume d\u2019affaires de pr\u00e8s de 3 millions d\u2019Euros ce qui en fait la plus importante centrale de r\u00e9servation d\u00e9partementale).<\/span><\/p>\n<p><span style=\"color: #000080;\">G\u00eetes de France en Is\u00e8re, ce sont aujourd\u2019hui plus de 850 structures d\u2019accueils (G\u00eetes ruraux, Chambres et tables d\u2019h\u00f4tes, G\u00eetes de Groupes, G\u00eetes d\u2019enfants, campings\u2026) r\u00e9parties sur plus de 200communes en Is\u00e8re.<br \/>\nUn g\u00eete rural est lou\u00e9 en moyenne 17 semaines par an. Pour une chambre d\u2019h\u00f4te, on compte une occupation moyenne de 110 nuit\u00e9es annuelles.<\/span><\/p>\n<p><span style=\"color: #000080;\">Philippe Riboulleau pr\u00e9sident des g\u00eetes de France Is\u00e8re a rappel\u00e9 les nouvelles priorit\u00e9s pour les ann\u00e9es \u00e0 venir: \u00a0\u00bb la d\u00e9finition d&rsquo;un mod\u00e8le \u00e9conomique plus attractif vis \u00e0 vis de nos porteurs de projets et nos adh\u00e9rents ainsi que le renforcement de notre r\u00f4le incontournable du d\u00e9veloppement touristique local en sont les axes majeurs\u00a0\u00bb.<\/span><\/p>\n<p><span style=\"color: #000080;\">Il a \u00e9galement indiqu\u00e9 que malgr\u00e9 le dynamisme de l&rsquo;antenne \u00a0\u00bb nous avons ouvert un travail de r\u00e9flexion destin\u00e9 \u00e0 recruter des adh\u00e9rents, de s\u00e9duire de nouveaux porteurs de projets..\u00a0\u00bb<\/span><\/p>\n<p><span style=\"color: #000080;\">Vincent Delaitre, directeur d&rsquo;Is\u00e8re tourisme, invit\u00e9 \u00e0 cette AG a indiqu\u00e9 pour sa part que les mentalit\u00e9s, les recherches des clients ont \u00e9volu\u00e9 et que les h\u00e9bergeurs devront s&rsquo;adapter aux nouvelles exigences de leurs clients..<br \/>\n<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L &lsquo;assembl\u00e9e G\u00e9n\u00e9rale des g\u00eetes de France Is\u00e8re s&rsquo;est tenue dans le cadre prestigieux du mus\u00e9e de la mine \u00e0 La Motte d&rsquo;Aveillans.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[72],"tags":[2722,3250,4270],"class_list":["post-74268","post","type-post","status-publish","format-standard","hentry","category-tourisme","tag-gites-de-france-isere","tag-la-motte-daveillans","tag-philippe-riboulleau"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AG des g\u00eetes de France Is\u00e8re -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sillon38.com\/blog\/2018\/04\/06\/ag-des-gites-de-france-isere-2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AG des g\u00eetes de France Is\u00e8re -\" \/>\n<meta property=\"og:description\" content=\"L &#039;assembl\u00e9e G\u00e9n\u00e9rale des g\u00eetes de France Is\u00e8re s&#039;est tenue dans le cadre prestigieux du mus\u00e9e de la mine \u00e0 La Motte d&#039;Aveillans.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sillon38.com\/blog\/2018\/04\/06\/ag-des-gites-de-france-isere-2\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-06T19:26:43+00:00\" \/>\n<meta name=\"author\" content=\"Gilbert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gilbert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2018\\\/04\\\/06\\\/ag-des-gites-de-france-isere-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2018\\\/04\\\/06\\\/ag-des-gites-de-france-isere-2\\\/\"},\"author\":{\"name\":\"Gilbert\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"headline\":\"AG des g\u00eetes de France Is\u00e8re\",\"datePublished\":\"2018-04-06T19:26:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2018\\\/04\\\/06\\\/ag-des-gites-de-france-isere-2\\\/\"},\"wordCount\":359,\"commentCount\":0,\"keywords\":[\"g\u00eetes de France Is\u00e8re\",\"La Motte d'Aveillans\",\"Philippe Riboulleau\"],\"articleSection\":[\"tourisme\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2018\\\/04\\\/06\\\/ag-des-gites-de-france-isere-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2018\\\/04\\\/06\\\/ag-des-gites-de-france-isere-2\\\/\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2018\\\/04\\\/06\\\/ag-des-gites-de-france-isere-2\\\/\",\"name\":\"AG des g\u00eetes de France Is\u00e8re -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\"},\"datePublished\":\"2018-04-06T19:26:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2018\\\/04\\\/06\\\/ag-des-gites-de-france-isere-2\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2018\\\/04\\\/06\\\/ag-des-gites-de-france-isere-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2018\\\/04\\\/06\\\/ag-des-gites-de-france-isere-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AG des g\u00eetes de France Is\u00e8re\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\",\"name\":\"\",\"description\":\"Le journal du monde rural\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\",\"name\":\"Gilbert\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AG des g\u00eetes de France Is\u00e8re -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sillon38.com\/blog\/2018\/04\/06\/ag-des-gites-de-france-isere-2\/","og_locale":"fr_FR","og_type":"article","og_title":"AG des g\u00eetes de France Is\u00e8re -","og_description":"L 'assembl\u00e9e G\u00e9n\u00e9rale des g\u00eetes de France Is\u00e8re s'est tenue dans le cadre prestigieux du mus\u00e9e de la mine \u00e0 La Motte d'Aveillans.","og_url":"https:\/\/www.sillon38.com\/blog\/2018\/04\/06\/ag-des-gites-de-france-isere-2\/","article_published_time":"2018-04-06T19:26:43+00:00","author":"Gilbert","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Gilbert","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sillon38.com\/blog\/2018\/04\/06\/ag-des-gites-de-france-isere-2\/#article","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/2018\/04\/06\/ag-des-gites-de-france-isere-2\/"},"author":{"name":"Gilbert","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"headline":"AG des g\u00eetes de France Is\u00e8re","datePublished":"2018-04-06T19:26:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sillon38.com\/blog\/2018\/04\/06\/ag-des-gites-de-france-isere-2\/"},"wordCount":359,"commentCount":0,"keywords":["g\u00eetes de France Is\u00e8re","La Motte d'Aveillans","Philippe Riboulleau"],"articleSection":["tourisme"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.sillon38.com\/blog\/2018\/04\/06\/ag-des-gites-de-france-isere-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.sillon38.com\/blog\/2018\/04\/06\/ag-des-gites-de-france-isere-2\/","url":"https:\/\/www.sillon38.com\/blog\/2018\/04\/06\/ag-des-gites-de-france-isere-2\/","name":"AG des g\u00eetes de France Is\u00e8re -","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/#website"},"datePublished":"2018-04-06T19:26:43+00:00","author":{"@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"breadcrumb":{"@id":"https:\/\/www.sillon38.com\/blog\/2018\/04\/06\/ag-des-gites-de-france-isere-2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sillon38.com\/blog\/2018\/04\/06\/ag-des-gites-de-france-isere-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sillon38.com\/blog\/2018\/04\/06\/ag-des-gites-de-france-isere-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.sillon38.com\/blog\/"},{"@type":"ListItem","position":2,"name":"AG des g\u00eetes de France Is\u00e8re"}]},{"@type":"WebSite","@id":"https:\/\/www.sillon38.com\/blog\/#website","url":"https:\/\/www.sillon38.com\/blog\/","name":"","description":"Le journal du monde rural","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sillon38.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1","name":"Gilbert"}]}},"_links":{"self":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/74268","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/comments?post=74268"}],"version-history":[{"count":0,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/74268\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/media?parent=74268"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/categories?post=74268"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/tags?post=74268"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}