{"id":77281,"date":"2019-09-19T14:14:00","date_gmt":"2019-09-19T12:14:00","guid":{"rendered":"http:\/\/staging.sillon38.com\/?p=77281"},"modified":"2019-09-19T14:14:00","modified_gmt":"2019-09-19T12:14:00","slug":"bientot-une-voie-reservee-au-covoiturage-sur-la48","status":"publish","type":"post","link":"https:\/\/www.sillon38.com\/blog\/2019\/09\/19\/bientot-une-voie-reservee-au-covoiturage-sur-la48\/","title":{"rendered":"Bient\u00f4t une voie r\u00e9serv\u00e9e au covoiturage sur l\u2019A48 !"},"content":{"rendered":"<p><span style=\"color: #003366;\">Jean-Baptiste DJEBBARI, Secr\u00e9taire d\u2019Etat charg\u00e9 des transports confirme ce jour la mise en place d\u2019une<br \/>\nvoie r\u00e9serv\u00e9e au covoiturage sur l\u2019A48 entre la barri\u00e8re de p\u00e9age de Voreppe et la bifurcation entre l\u2019A48<br \/>\net l\u2019A480 \u00e0 l\u2019\u00e9t\u00e9 2020.<br \/>\nComme le soulignent Christophe FERRARI, Pr\u00e9sident de Grenoble-Alpes M\u00e9tropole, et Ludovic BUSTOS,<br \/>\nVice-Pr\u00e9sident d\u00e9l\u00e9gu\u00e9 aux espaces publics et \u00e0 la voirie, cette d\u00e9cision marque une nouvelle \u00e9tape<br \/>\nimportante dans la mise en oeuvre des engagements pris dans le cadre du projet de r\u00e9am\u00e9nagement de<br \/>\nl\u2019\u00e9changeur du Rondeau et de l\u2019A480 :<br \/>\n\u00ab Apr\u00e8s la d\u00e9cision pr\u00e9fectorale d\u2019une mod\u00e9ration de vitesse permanente \u00e0 70 km\/h sur la s\u00e9quence<br \/>\ncentrale de l\u2019A480, est aujourd\u2019hui confirm\u00e9e la mise en place d\u2019une voie r\u00e9serv\u00e9e au covoiturage sur l\u2019A48<br \/>\n\u00e0 l\u2019\u00e9t\u00e9 2020.<br \/>\nC\u2019est le fruit de la mobilisation ininterrompue de la M\u00e9tropole depuis le d\u00e9but de la mandature en cours et<br \/>\nqui a notamment permis la signature du protocole d\u2019intention partenarial du 10 novembre 2016, une<br \/>\nmobilisation qui a \u00e9t\u00e9 entendue par le Gouvernement et c\u2019est une excellente nouvelle !<br \/>\nLe territoire m\u00e9tropolitain accueillera ainsi l\u2019une des premi\u00e8res voies de ce type \u00e0 l\u2019\u00e9chelle nationale, fid\u00e8le<br \/>\n\u00e0 sa tradition d\u2019innovation. Elle permettra de r\u00e9duire la congestion en amont du coeur urbain au b\u00e9n\u00e9fice<br \/>\nde l\u2019environnement en r\u00e9duisant la pollution atmosph\u00e9rique mais \u00e9galement du portefeuille de nos<br \/>\nconcitoyennes et concitoyens, le covoiturage repr\u00e9sentant une \u00e9conomie pouvant s\u2019\u00e9lever jusqu\u2019\u00e0<br \/>\nplusieurs centaines d\u2019euros par an.<br \/>\nNous nous f\u00e9licitons \u00e9galement de la confirmation re\u00e7ue r\u00e9cemment d\u2019Elisabeth BORNE, Ministre de la<br \/>\ntransition \u00e9cologique et solidaire, du lancement des \u00e9tudes n\u00e9cessaires \u00e0 la cr\u00e9ation d\u2019une voie r\u00e9serv\u00e9e<br \/>\naux transports en commun au sud de l\u2019\u00e9changeur du Rondeau et, possiblement, jusqu\u2019\u00e0 l\u2019\u00e9changeur Louise<br \/>\nMichel.<br \/>\nDe telles avanc\u00e9es b\u00e9n\u00e9ficieront \u00e0 toutes et \u00e0 tous, riverains, usagers, m\u00e9tropolitains, habitants des<br \/>\nterritoires voisins, urbains, ruraux. Elles t\u00e9moignent \u00e9galement de la force du collectif rassemblant la<br \/>\nM\u00e9tropole et ses communes qui ont su parler d\u2019une seule voix. \u00bb<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jean-Baptiste DJEBBARI, Secr\u00e9taire d\u2019Etat charg\u00e9 des transports confirme ce jour la mise en place d\u2019une<br \/>\nvoie r\u00e9serv\u00e9e au covoiturage sur l\u2019A48 entre la barri\u00e8re de p\u00e9age de Voreppe et la bifurcation entre l\u2019A48<br \/>\net l\u2019A480 \u00e0 l\u2019\u00e9t\u00e9 2020.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,37],"tags":[151,1253],"class_list":["post-77281","post","type-post","status-publish","format-standard","hentry","category-la-metro-la-metro","category-la-metro","tag-a48","tag-christophe-ferrari"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bient\u00f4t une voie r\u00e9serv\u00e9e au covoiturage sur l\u2019A48 ! -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sillon38.com\/blog\/2019\/09\/19\/bientot-une-voie-reservee-au-covoiturage-sur-la48\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bient\u00f4t une voie r\u00e9serv\u00e9e au covoiturage sur l\u2019A48 ! -\" \/>\n<meta property=\"og:description\" content=\"Jean-Baptiste DJEBBARI, Secr\u00e9taire d\u2019Etat charg\u00e9 des transports confirme ce jour la mise en place d\u2019une voie r\u00e9serv\u00e9e au covoiturage sur l\u2019A48 entre la barri\u00e8re de p\u00e9age de Voreppe et la bifurcation entre l\u2019A48 et l\u2019A480 \u00e0 l\u2019\u00e9t\u00e9 2020.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sillon38.com\/blog\/2019\/09\/19\/bientot-une-voie-reservee-au-covoiturage-sur-la48\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-19T12:14:00+00:00\" \/>\n<meta name=\"author\" content=\"Gilbert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gilbert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2019\\\/09\\\/19\\\/bientot-une-voie-reservee-au-covoiturage-sur-la48\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2019\\\/09\\\/19\\\/bientot-une-voie-reservee-au-covoiturage-sur-la48\\\/\"},\"author\":{\"name\":\"Gilbert\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"headline\":\"Bient\u00f4t une voie r\u00e9serv\u00e9e au covoiturage sur l\u2019A48 !\",\"datePublished\":\"2019-09-19T12:14:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2019\\\/09\\\/19\\\/bientot-une-voie-reservee-au-covoiturage-sur-la48\\\/\"},\"wordCount\":388,\"commentCount\":0,\"keywords\":[\"A48\",\"Christophe Ferrari\"],\"articleSection\":[\"La M\u00e9tro\",\"La M\u00e9tro\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2019\\\/09\\\/19\\\/bientot-une-voie-reservee-au-covoiturage-sur-la48\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2019\\\/09\\\/19\\\/bientot-une-voie-reservee-au-covoiturage-sur-la48\\\/\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2019\\\/09\\\/19\\\/bientot-une-voie-reservee-au-covoiturage-sur-la48\\\/\",\"name\":\"Bient\u00f4t une voie r\u00e9serv\u00e9e au covoiturage sur l\u2019A48 ! -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\"},\"datePublished\":\"2019-09-19T12:14:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2019\\\/09\\\/19\\\/bientot-une-voie-reservee-au-covoiturage-sur-la48\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2019\\\/09\\\/19\\\/bientot-une-voie-reservee-au-covoiturage-sur-la48\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2019\\\/09\\\/19\\\/bientot-une-voie-reservee-au-covoiturage-sur-la48\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bient\u00f4t une voie r\u00e9serv\u00e9e au covoiturage sur l\u2019A48 !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\",\"name\":\"\",\"description\":\"Le journal du monde rural\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\",\"name\":\"Gilbert\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bient\u00f4t une voie r\u00e9serv\u00e9e au covoiturage sur l\u2019A48 ! -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sillon38.com\/blog\/2019\/09\/19\/bientot-une-voie-reservee-au-covoiturage-sur-la48\/","og_locale":"fr_FR","og_type":"article","og_title":"Bient\u00f4t une voie r\u00e9serv\u00e9e au covoiturage sur l\u2019A48 ! -","og_description":"Jean-Baptiste DJEBBARI, Secr\u00e9taire d\u2019Etat charg\u00e9 des transports confirme ce jour la mise en place d\u2019une voie r\u00e9serv\u00e9e au covoiturage sur l\u2019A48 entre la barri\u00e8re de p\u00e9age de Voreppe et la bifurcation entre l\u2019A48 et l\u2019A480 \u00e0 l\u2019\u00e9t\u00e9 2020.","og_url":"https:\/\/www.sillon38.com\/blog\/2019\/09\/19\/bientot-une-voie-reservee-au-covoiturage-sur-la48\/","article_published_time":"2019-09-19T12:14:00+00:00","author":"Gilbert","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Gilbert","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sillon38.com\/blog\/2019\/09\/19\/bientot-une-voie-reservee-au-covoiturage-sur-la48\/#article","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/2019\/09\/19\/bientot-une-voie-reservee-au-covoiturage-sur-la48\/"},"author":{"name":"Gilbert","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"headline":"Bient\u00f4t une voie r\u00e9serv\u00e9e au covoiturage sur l\u2019A48 !","datePublished":"2019-09-19T12:14:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sillon38.com\/blog\/2019\/09\/19\/bientot-une-voie-reservee-au-covoiturage-sur-la48\/"},"wordCount":388,"commentCount":0,"keywords":["A48","Christophe Ferrari"],"articleSection":["La M\u00e9tro","La M\u00e9tro"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.sillon38.com\/blog\/2019\/09\/19\/bientot-une-voie-reservee-au-covoiturage-sur-la48\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.sillon38.com\/blog\/2019\/09\/19\/bientot-une-voie-reservee-au-covoiturage-sur-la48\/","url":"https:\/\/www.sillon38.com\/blog\/2019\/09\/19\/bientot-une-voie-reservee-au-covoiturage-sur-la48\/","name":"Bient\u00f4t une voie r\u00e9serv\u00e9e au covoiturage sur l\u2019A48 ! -","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/#website"},"datePublished":"2019-09-19T12:14:00+00:00","author":{"@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"breadcrumb":{"@id":"https:\/\/www.sillon38.com\/blog\/2019\/09\/19\/bientot-une-voie-reservee-au-covoiturage-sur-la48\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sillon38.com\/blog\/2019\/09\/19\/bientot-une-voie-reservee-au-covoiturage-sur-la48\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sillon38.com\/blog\/2019\/09\/19\/bientot-une-voie-reservee-au-covoiturage-sur-la48\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.sillon38.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Bient\u00f4t une voie r\u00e9serv\u00e9e au covoiturage sur l\u2019A48 !"}]},{"@type":"WebSite","@id":"https:\/\/www.sillon38.com\/blog\/#website","url":"https:\/\/www.sillon38.com\/blog\/","name":"","description":"Le journal du monde rural","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sillon38.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1","name":"Gilbert"}]}},"_links":{"self":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/77281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/comments?post=77281"}],"version-history":[{"count":0,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/77281\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/media?parent=77281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/categories?post=77281"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/tags?post=77281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}