{"id":77591,"date":"2020-02-29T17:54:58","date_gmt":"2020-02-29T15:54:58","guid":{"rendered":"http:\/\/staging.sillon38.com\/?p=77591"},"modified":"2020-02-29T17:54:58","modified_gmt":"2020-02-29T15:54:58","slug":"lisere-labelisee-velo-fromages","status":"publish","type":"post","link":"https:\/\/www.sillon38.com\/blog\/2020\/02\/29\/lisere-labelisee-velo-fromages\/","title":{"rendered":"L&rsquo;ISERE  LABELISEE \u201cVELO &#038; FROMAGES\u201d"},"content":{"rendered":"<p><span style=\"color: #000080;\">Parmi les itin\u00e9raires cyclotouristiques labellis\u00e9s d\u00e9rni\u00e8rement \u00ab V\u00e9lo &amp; Fromages \u00bb par l\u2019Assembl\u00e9e des D\u00e9partements de France, figurent deux parcours is\u00e9rois ! <\/span><\/p>\n<p><span style=\"color: #000080;\">Il faut dire que gastronomie et v\u00e9lo sont inscrits dans l\u2019ADN de l\u2019Is\u00e8re. Rendez-vous au Pays de Saint-Marcellin, par le plateau bois\u00e9 de Chambaran, et au Tour des Quatre-Montagnes, servi sur le plateau du Vercors pour d\u00e9guster ce nouveau concept !<\/span><\/p>\n<p><span style=\"color: #000080;\"><strong>Le label \u00ab V\u00e9lo et Fromages \u00bb en Is\u00e8re<\/strong><\/span><\/p>\n<p><span style=\"color: #000080;\">L\u2019Is\u00e8re fait d\u00e9sormais partie des 45 D\u00e9partements fran\u00e7ais labellis\u00e9s \u201cV\u00e9lo &amp; Fromages\u201d. Ce label, cr\u00e9\u00e9 \u00e0 l\u2019initiative de l\u2019Assembl\u00e9e des D\u00e9partements de France, du Centre national interprofessionnel de l\u2019\u00e9conomie laiti\u00e8re (Cniel) et de Tourisme &amp; Territoires et V\u00e9lo &amp; Territoires en avril 2019, identifie les itin\u00e9raires mariant cyclotourisme et d\u00e9couverte des fromages du terroir. <\/span><\/p>\n<p><span style=\"color: #000080;\">Une nouveaut\u00e9 qui donne tout son sens \u00e0 l\u2019expression \u00ab apr\u00e8s l\u2019effort le r\u00e9confort \u00bb ! Rien de tel en effet qu\u2019une d\u00e9couverte des saveurs fromag\u00e8res pour ponctuer une balade \u00e0 v\u00e9lo qui garantit un rythme id\u00e9al pour prendre le temps de d\u00e9couvrir, rencontrer et partager. Bonne route et bonne d\u00e9gustation !<\/span><\/p>\n<p><span style=\"color: #000080;\"><span style=\"color: #ff6600;\"><strong>Au Pays de Saint-Marcellin, par le plateau bois\u00e9 de Chambaran<\/strong><\/span><br \/>\nDifficult\u00e9 : 3\/4<br \/>\nDistance : 51 km<br \/>\nAlt min : 274 m<br \/>\nAlt max : 713 m<br \/>\nD\u00e9nivel\u00e9 : 677 m<br \/>\nDur\u00e9e : 3h30<br \/>\nCette balade m\u00e8ne de Saint-Marcellin dans le sud-Gr\u00e9sivaudan jusqu\u2019\u00e0 Roybon sur le plateau bois\u00e9 de Chambaran. Un itin\u00e9raire id\u00e9al pour les cyclotouristes gourmands qui pourront s\u2019arr\u00eater pour go\u00fbter les produits phares de cette r\u00e9gion de l\u2019Is\u00e8re : le fromage Saint-Marcellin (IGP), la noix de Grenoble (AOP) et les Ravioles du Royans (IGP).<br \/>\nA noter : tous les ans, la Saint-Marcellin (le 6 avril sur le calendrier) est l\u2019occasion d\u2019une grande f\u00eate le dimanche le plus proche. En 2020, la F\u00eate du Saint-Marcellin se tiendra le dimanche 5 avril.<br \/>\n<strong>\u2022 7 sites fromagers :<\/strong><br \/>\nFromagerie du Dauphin\u00e9 (38470 T\u00eache)<br \/>\nLes Carmes \u2013 vins et fromages (38160 Saint-Marcellin)<br \/>\nFromagerie Le Murinois (38160 Murinais)<br \/>\nFromagerie Rochas (38470 Quincieu)<br \/>\nLa Ch\u00e8vrerie de la Gabotte (38160 Saint-V\u00e9rand)<br \/>\nMaison du Saint-Marcellin (38160 Saint-Marcellin)<br \/>\nRestaurant La Tivolli\u00e8re (38160 Saint-Marcellin)<br \/>\nRetrouvez cet itin\u00e9raire : https:\/\/www.cyclo-alpes.com\/boucles-cyclotouristiques\/8-au-pays-de-saint-marcellin<\/span><\/p>\n<p><span style=\"color: #000080;\"><span style=\"color: #ff6600;\"><strong>Le Tour des Quatre-Montagnes, servi sur le plateau du Vercors !<\/strong><\/span><br \/>\nDifficult\u00e9 : 2\/4<br \/>\nDistance : 42 km<br \/>\nAlt min : 988 m<br \/>\nAlt max : 1223 m<br \/>\nD\u00e9nivel\u00e9 : 564 m<br \/>\nDur\u00e9e : 3h<br \/>\nQuatre montagnes pour quatre communaut\u00e9s paroissiales : M\u00e9audre, Autrans, Lans-en-Vercors et Villard-de-Lans. Cet itin\u00e9raire sillonne de vastes prairies bord\u00e9es de for\u00eats \u00e0 l\u2019ombre desquelles il fait bon s\u2019attarder. <\/span><\/p>\n<p><span style=\"color: #000080;\">Le Vercors, site historique, est aujourd\u2019hui un cadre privil\u00e9gi\u00e9 pour les amateurs de tourisme et de sports, surtout depuis les JO d\u2019hiver de 1968. L\u2019agriculture et la gastronomie font aussi sa renomm\u00e9e, notamment gr\u00e2ce \u00e0 son fromage AOP Bleu du Vercors-Sassenage.<br \/>\nCet itin\u00e9raire suit l\u2019ancienne route entre Lans-en Vercors et Villard-de-Lans ; elle longe ainsi une partie du parcours de la 16e \u00e9tape du Tour de France 2020 avec son arriv\u00e9e \u00e0 Villard-de-Lans.<\/span><\/p>\n<p><span style=\"color: #000080;\">La boucle cyclotouristique \u00ab Le Tour des Quatre-Montagnes \u00bb \u00e9vite le plus possible les routes \u00e0 grande circulation. Elle emprunte partiellement l\u2019itin\u00e9raire jalonn\u00e9 \u00ab entre Autrans et M\u00e9audre \u00bb.<br \/>\n<strong>\u2022 15 sites fromagers :<\/strong><br \/>\nFerme de la Grand M\u00e8che (38250 Lans-en-Vercors)<br \/>\nLa Ferme du Pic Saint-Michel (38250 Lans-en-Vercors)<br \/>\nFerme de La Bourri\u00e8re (38112 Autrans-M\u00e9audre)<br \/>\nCoop\u00e9rative Vercors Lait (38250 Villard-de-Lans)<br \/>\nLa Ch\u00e8vrerie des Cabrioles (38250 Corren\u00e7on-en-Vercors)<br \/>\nLa Ferme des Perce-Neige (38250 Corren\u00e7on-en-Vercors)<br \/>\nLa Ferme des Rapilles (38360 Engins)<br \/>\nH\u00f4tel Restaurant Le Col de l\u2019Arc (38250 Lans-en-Vercors)<br \/>\nLa Table de la Fontaine (38112 Autrans-M\u00e9audre)<br \/>\nLe Sabot de V\u00e9nus (38112 Autrans-M\u00e9audre)<br \/>\nH\u00f4tel Restaurant Le Vernay (38112 Autrans-M\u00e9audre)<br \/>\nL\u2019Auberge des Montauds (38250 Villard-de-Lans)<br \/>\nGrand H\u00f4tel de Paris (38250 Villard-de-Lans)<br \/>\nH\u00f4tel Restaurant Le Christiana (38250 Villard-de-Lans)<br \/>\nLa Roseraie \u2013 La Doline (38250 Villard-de-Lans)<\/span><\/p>\n<p>Retrouvez cet itin\u00e9raire : https:\/\/www.cyclo-alpes.com\/boucles-cyclotouristiques\/16-le-tour-des-quatre-montagnes<\/p>\n<blockquote><p><span style=\"color: #000080;\">\u00ab Nous sommes tr\u00e8s fiers d\u2019avoir re\u00e7u le label \u00ab V\u00e9lo et Fromages \u00bb et invitons tous les fondus de v\u00e9los et les amoureux du fromage \u00e0 venir d\u00e9couvrir les deux superbes boucles is\u00e9roises ! \u00bb, souligne Jean-Pierre Barbier, le Pr\u00e9sident du D\u00e9partement.<br \/>\n\u00ab Ce label est une formidable vitrine pour notre terroir, ses produits de qualit\u00e9 et ses producteurs laitiers. Les cyclistes pourront allier sport et visites de fermes, de productions laiti\u00e8res, de caves d\u2019affinage, d\u2019atelier de transformation, d\u2019 haltes aux march\u00e9s \u00bb, indique Fabien Mulyk, Vice-pr\u00e9sident d\u00e9l\u00e9gu\u00e9 \u00e0 la fili\u00e8re bois, \u00e0 l\u2019am\u00e9nagement des rivi\u00e8res et \u00e0 l\u2019environnement.<\/span><\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Parmi les itin\u00e9raires cyclotouristiques  figurent deux parcours is\u00e9rois ! <\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,15],"tags":[525,5613],"class_list":["post-77591","post","type-post","status-publish","format-standard","hentry","category-a-la-une","category-departement-de-lisere","tag-assemblee-des-departements-de-france","tag-velo-fromages"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;ISERE LABELISEE \u201cVELO &amp; FROMAGES\u201d -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sillon38.com\/blog\/2020\/02\/29\/lisere-labelisee-velo-fromages\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;ISERE LABELISEE \u201cVELO &amp; FROMAGES\u201d -\" \/>\n<meta property=\"og:description\" content=\"Parmi les itin\u00e9raires cyclotouristiques figurent deux parcours is\u00e9rois !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sillon38.com\/blog\/2020\/02\/29\/lisere-labelisee-velo-fromages\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-29T15:54:58+00:00\" \/>\n<meta name=\"author\" content=\"Gilbert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gilbert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2020\\\/02\\\/29\\\/lisere-labelisee-velo-fromages\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2020\\\/02\\\/29\\\/lisere-labelisee-velo-fromages\\\/\"},\"author\":{\"name\":\"Gilbert\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"headline\":\"L&rsquo;ISERE LABELISEE \u201cVELO &#038; FROMAGES\u201d\",\"datePublished\":\"2020-02-29T15:54:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2020\\\/02\\\/29\\\/lisere-labelisee-velo-fromages\\\/\"},\"wordCount\":759,\"commentCount\":0,\"keywords\":[\"Assembl\u00e9e des D\u00e9partements de France\",\"VELO &amp; FROMAGES\"],\"articleSection\":[\"\u00c0 la une\",\"D\u00e9partement de l'Is\u00e8re\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2020\\\/02\\\/29\\\/lisere-labelisee-velo-fromages\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2020\\\/02\\\/29\\\/lisere-labelisee-velo-fromages\\\/\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2020\\\/02\\\/29\\\/lisere-labelisee-velo-fromages\\\/\",\"name\":\"L'ISERE LABELISEE \u201cVELO & FROMAGES\u201d -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\"},\"datePublished\":\"2020-02-29T15:54:58+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2020\\\/02\\\/29\\\/lisere-labelisee-velo-fromages\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2020\\\/02\\\/29\\\/lisere-labelisee-velo-fromages\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2020\\\/02\\\/29\\\/lisere-labelisee-velo-fromages\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&rsquo;ISERE LABELISEE \u201cVELO &#038; FROMAGES\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\",\"name\":\"\",\"description\":\"Le journal du monde rural\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\",\"name\":\"Gilbert\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'ISERE LABELISEE \u201cVELO & FROMAGES\u201d -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sillon38.com\/blog\/2020\/02\/29\/lisere-labelisee-velo-fromages\/","og_locale":"fr_FR","og_type":"article","og_title":"L'ISERE LABELISEE \u201cVELO & FROMAGES\u201d -","og_description":"Parmi les itin\u00e9raires cyclotouristiques figurent deux parcours is\u00e9rois !","og_url":"https:\/\/www.sillon38.com\/blog\/2020\/02\/29\/lisere-labelisee-velo-fromages\/","article_published_time":"2020-02-29T15:54:58+00:00","author":"Gilbert","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Gilbert","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sillon38.com\/blog\/2020\/02\/29\/lisere-labelisee-velo-fromages\/#article","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/2020\/02\/29\/lisere-labelisee-velo-fromages\/"},"author":{"name":"Gilbert","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"headline":"L&rsquo;ISERE LABELISEE \u201cVELO &#038; FROMAGES\u201d","datePublished":"2020-02-29T15:54:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sillon38.com\/blog\/2020\/02\/29\/lisere-labelisee-velo-fromages\/"},"wordCount":759,"commentCount":0,"keywords":["Assembl\u00e9e des D\u00e9partements de France","VELO &amp; FROMAGES"],"articleSection":["\u00c0 la une","D\u00e9partement de l'Is\u00e8re"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.sillon38.com\/blog\/2020\/02\/29\/lisere-labelisee-velo-fromages\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.sillon38.com\/blog\/2020\/02\/29\/lisere-labelisee-velo-fromages\/","url":"https:\/\/www.sillon38.com\/blog\/2020\/02\/29\/lisere-labelisee-velo-fromages\/","name":"L'ISERE LABELISEE \u201cVELO & FROMAGES\u201d -","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/#website"},"datePublished":"2020-02-29T15:54:58+00:00","author":{"@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"breadcrumb":{"@id":"https:\/\/www.sillon38.com\/blog\/2020\/02\/29\/lisere-labelisee-velo-fromages\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sillon38.com\/blog\/2020\/02\/29\/lisere-labelisee-velo-fromages\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sillon38.com\/blog\/2020\/02\/29\/lisere-labelisee-velo-fromages\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.sillon38.com\/blog\/"},{"@type":"ListItem","position":2,"name":"L&rsquo;ISERE LABELISEE \u201cVELO &#038; FROMAGES\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.sillon38.com\/blog\/#website","url":"https:\/\/www.sillon38.com\/blog\/","name":"","description":"Le journal du monde rural","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sillon38.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1","name":"Gilbert"}]}},"_links":{"self":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/77591","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/comments?post=77591"}],"version-history":[{"count":0,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/77591\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/media?parent=77591"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/categories?post=77591"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/tags?post=77591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}