{"id":8789,"date":"2009-09-23T11:20:05","date_gmt":"2009-09-23T09:20:05","guid":{"rendered":"http:\/\/staging.sillon38.com\/?p=8789"},"modified":"2009-09-23T11:20:05","modified_gmt":"2009-09-23T09:20:05","slug":"comment-nourrir-le-monde-en-2050","status":"publish","type":"post","link":"https:\/\/www.sillon38.com\/blog\/2009\/09\/23\/comment-nourrir-le-monde-en-2050\/","title":{"rendered":"Comment nourrir le monde en 2050?"},"content":{"rendered":"<p>Selon un rapport diffus\u00e9 aujourd&rsquo;hui par la FAO, l&rsquo;agriculture mondiale doit relever des d\u00e9fis de taille: augmenter la production alimentaire de 70% pour nourrir 2,3 milliards de personnes de plus d&rsquo;ici \u00e0 2050, intensifier la lutte contre la pauvret\u00e9 et la faim, utiliser plus efficacement les ressources naturelles qui s&rsquo;amenuisent et s&rsquo;adapter au changement climatique.<\/p>\n<p>La FAO a convoqu\u00e9 pour le 12 et 13 octobre\u00a0 un Forum d&rsquo;experts de haut niveau pour discuter des strat\u00e9gies \u00e0 mettre en oeuvre pour relever ces d\u00e9fis.<\/p>\n<p>Le Forum, intitul\u00e9 \u00ab\u00a0Comment nourrir le monde en 2050\u00a0\u00bb rassemblera quelque 300 experts (universitaires, chercheurs, ONG, secteur priv\u00e9) de pays d\u00e9velopp\u00e9s et en d\u00e9veloppement. Il pr\u00e9parera le terrain \u00e0 la tenue du 16 au 18 novembre 2009 d&rsquo;un nouveau Sommet mondial sur la s\u00e9curit\u00e9 alimentaire.<\/p>\n<p>Selon les projections mondiales, pour am\u00e9liorer l&rsquo;acc\u00e8s \u00e0 la nourriture de gros investissements sont n\u00e9cessaires qui devront s&rsquo;ajouter aux investissements actuels. Sinon, quelque 370 millions de personnes continueraient \u00e0 souffrir de la faim en 2050, soit pr\u00e8s de 5% de la population mondiale.<\/p>\n<p>La population mondiale, selon les derni\u00e8res projections des Nations Unies, doit passer de 6,8 milliards \u00e0 9,1 milliards en 2050, soit un tiers de bouches de plus \u00e0 nourrir qu&rsquo;il n&rsquo;y en a aujourd&rsquo;hui.<\/p>\n<p>Le gros de la croissance d\u00e9mographique se produira dans les pays en d\u00e9veloppement. C&rsquo;est en Afrique subsaharienne, que le taux de croissance sera le plus fort (+108%, soit 910 millions de personnes). En revanche, il sera le plus faible en Asie de l&rsquo;est et du sud-est (+11%, soit 228 millions de personnes).<\/p>\n<p>Environ 70% de la population mondiale vivra dans les villes ou les r\u00e9gions urbaines \u00e0 l&rsquo;horizon 2050, soit une augmentation de 49% par rapport \u00e0 aujourd&rsquo;hui.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En 2050, 2,3 milliards de bouches de plus \u00e0 nourrir. C&rsquo;est ce que met en avant un rapport de la FAO diffus\u00e9 aujourd&rsquo;hui. La production alimentaire devra augmenter de 70%!  <\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[59],"tags":[2203,4997],"class_list":["post-8789","post","type-post","status-publish","format-standard","hentry","category-planete-terre","tag-fao","tag-securite-alimentaire"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comment nourrir le monde en 2050? -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sillon38.com\/blog\/2009\/09\/23\/comment-nourrir-le-monde-en-2050\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comment nourrir le monde en 2050? -\" \/>\n<meta property=\"og:description\" content=\"En 2050, 2,3 milliards de bouches de plus \u00e0 nourrir. C&#039;est ce que met en avant un rapport de la FAO diffus\u00e9 aujourd&#039;hui. La production alimentaire devra augmenter de 70%!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sillon38.com\/blog\/2009\/09\/23\/comment-nourrir-le-monde-en-2050\/\" \/>\n<meta property=\"article:published_time\" content=\"2009-09-23T09:20:05+00:00\" \/>\n<meta name=\"author\" content=\"Gilbert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gilbert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/09\\\/23\\\/comment-nourrir-le-monde-en-2050\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/09\\\/23\\\/comment-nourrir-le-monde-en-2050\\\/\"},\"author\":{\"name\":\"Gilbert\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"headline\":\"Comment nourrir le monde en 2050?\",\"datePublished\":\"2009-09-23T09:20:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/09\\\/23\\\/comment-nourrir-le-monde-en-2050\\\/\"},\"wordCount\":288,\"commentCount\":0,\"keywords\":[\"FAO\",\"s\u00e9curit\u00e9 alimentaire\"],\"articleSection\":[\"plan\u00e8te Terre\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/09\\\/23\\\/comment-nourrir-le-monde-en-2050\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/09\\\/23\\\/comment-nourrir-le-monde-en-2050\\\/\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/09\\\/23\\\/comment-nourrir-le-monde-en-2050\\\/\",\"name\":\"Comment nourrir le monde en 2050? -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\"},\"datePublished\":\"2009-09-23T09:20:05+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/09\\\/23\\\/comment-nourrir-le-monde-en-2050\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/09\\\/23\\\/comment-nourrir-le-monde-en-2050\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/09\\\/23\\\/comment-nourrir-le-monde-en-2050\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comment nourrir le monde en 2050?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\",\"name\":\"\",\"description\":\"Le journal du monde rural\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\",\"name\":\"Gilbert\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comment nourrir le monde en 2050? -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sillon38.com\/blog\/2009\/09\/23\/comment-nourrir-le-monde-en-2050\/","og_locale":"fr_FR","og_type":"article","og_title":"Comment nourrir le monde en 2050? -","og_description":"En 2050, 2,3 milliards de bouches de plus \u00e0 nourrir. C'est ce que met en avant un rapport de la FAO diffus\u00e9 aujourd'hui. La production alimentaire devra augmenter de 70%!","og_url":"https:\/\/www.sillon38.com\/blog\/2009\/09\/23\/comment-nourrir-le-monde-en-2050\/","article_published_time":"2009-09-23T09:20:05+00:00","author":"Gilbert","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Gilbert","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sillon38.com\/blog\/2009\/09\/23\/comment-nourrir-le-monde-en-2050\/#article","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/2009\/09\/23\/comment-nourrir-le-monde-en-2050\/"},"author":{"name":"Gilbert","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"headline":"Comment nourrir le monde en 2050?","datePublished":"2009-09-23T09:20:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sillon38.com\/blog\/2009\/09\/23\/comment-nourrir-le-monde-en-2050\/"},"wordCount":288,"commentCount":0,"keywords":["FAO","s\u00e9curit\u00e9 alimentaire"],"articleSection":["plan\u00e8te Terre"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.sillon38.com\/blog\/2009\/09\/23\/comment-nourrir-le-monde-en-2050\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.sillon38.com\/blog\/2009\/09\/23\/comment-nourrir-le-monde-en-2050\/","url":"https:\/\/www.sillon38.com\/blog\/2009\/09\/23\/comment-nourrir-le-monde-en-2050\/","name":"Comment nourrir le monde en 2050? -","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/#website"},"datePublished":"2009-09-23T09:20:05+00:00","author":{"@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"breadcrumb":{"@id":"https:\/\/www.sillon38.com\/blog\/2009\/09\/23\/comment-nourrir-le-monde-en-2050\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sillon38.com\/blog\/2009\/09\/23\/comment-nourrir-le-monde-en-2050\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sillon38.com\/blog\/2009\/09\/23\/comment-nourrir-le-monde-en-2050\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.sillon38.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Comment nourrir le monde en 2050?"}]},{"@type":"WebSite","@id":"https:\/\/www.sillon38.com\/blog\/#website","url":"https:\/\/www.sillon38.com\/blog\/","name":"","description":"Le journal du monde rural","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sillon38.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1","name":"Gilbert"}]}},"_links":{"self":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/8789","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/comments?post=8789"}],"version-history":[{"count":0,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/8789\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/media?parent=8789"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/categories?post=8789"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/tags?post=8789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}