{"id":9591,"date":"2009-10-14T09:11:51","date_gmt":"2009-10-14T07:11:51","guid":{"rendered":"http:\/\/staging.sillon38.com\/?p=9591"},"modified":"2009-10-14T09:11:51","modified_gmt":"2009-10-14T07:11:51","slug":"2eme-marche-des-saveurs-samedi-17-octobre-2009-st-chef","status":"publish","type":"post","link":"https:\/\/www.sillon38.com\/blog\/2009\/10\/14\/2eme-marche-des-saveurs-samedi-17-octobre-2009-st-chef\/","title":{"rendered":"2\u00e8me march\u00e9 des saveurs, samedi \u00e0 Saint-Chef"},"content":{"rendered":"<p><strong>A l\u2019occasion de la semaine du go\u00fbt, la Municipalit\u00e9 de Saint-Chef\u00a0 organise samedi 17 octobre \u00e0 partir de 15h son march\u00e9 des saveurs, deuxi\u00e8me \u00e9dition, au c\u0153ur du centre historique du village. <\/strong><br \/>\nParce que le march\u00e9 des saveurs fut une r\u00e9ussite l\u2019an pass\u00e9, la Municipalit\u00e9 renouvelle cette ann\u00e9e cet \u00e9v\u00e9nement sous le signe de la convivialit\u00e9 et de la bonne humeur le samedi 17 octobre, entre 15h et 19h sur la place de la mairie.<\/p>\n<p><strong>Au programme des r\u00e9jouissances gratuites : <\/strong><\/p>\n<p>&#8211; Producteurs locaux et commer\u00e7ants saint-cheffois vont faire d\u00e9couvrir aux plus gourmands leurs sp\u00e9cialit\u00e9s mises en vente,<br \/>\n&#8211; A 17H30, place \u00e0 la Compagnie Gourmande, troupe th\u00e9\u00e2trale du Nord-Is\u00e8re, qui propose \u00ab Bon app\u00e9tit ! \u00bb, un spectacle mis en sc\u00e8ne par L\u00e9on Rodrigues.<br \/>\n&#8211; A moins que vous ne pr\u00e9f\u00e9riez apporter votre bol pour go\u00fbter aux soupes pr\u00e9par\u00e9es sp\u00e9cialement pour l\u2019occasion sur la place de la Mairie apr\u00e8s le spectacle et d\u00e9couvrir avec humour le chaudron de soupe des \u00ab irr\u00e9ductibles saint- cheffois \u00bb !<br \/>\n&#8211; Et pourquoi ne pas jeter un coup d\u2019\u0153il le matin, avant le march\u00e9, \u00e0 la Biblioth\u00e8que intercommunale de Saint-Chef pour aller r\u00e9cup\u00e9rer des ouvrages de cuisine ou sur les saveurs d\u2019autrefois ? Biblioth\u00e8que ouverte le samedi de 10H \u00e0 12H + les lundis et mercredis de 14H30 \u00e0 18H30.<\/p>\n<p>UN\u00a0 PEU\u00a0 D\u2019HISTOIRE : Puisque l\u2019on parle de gourmandise et de produits du terroir, un texte datant de 993 signale une donation de vignes aux moines de Vienne sur les limites du territoire de Saint-Chef. Depuis, le vin des Balmes Dauphinoises est le seul vin du Nord-Is\u00e8re \u00e0 avoir la d\u00e9nomination \u00ab Vin de pays \u00bb.<\/p>\n<p><strong>March\u00e9 ouvert de 15H \u00e0 19H sur la place de la Mairie<br \/>\nRenseignement au 04 74 92 50 31<br \/>\nOu sur www.saint-chef.fr<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A l\u2019occasion de la semaine du go\u00fbt, la Municipalit\u00e9 de Saint-Chef  organise samedi 17 octobre \u00e0 partir de 15h son march\u00e9 des saveurs, deuxi\u00e8me \u00e9dition, au c\u0153ur du centre historique du village.  <\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[95,104],"tags":[],"class_list":["post-9591","post","type-post","status-publish","format-standard","hentry","category-consommation","category-la-vie-des-communes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>2\u00e8me march\u00e9 des saveurs, samedi \u00e0 Saint-Chef -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sillon38.com\/blog\/2009\/10\/14\/2eme-marche-des-saveurs-samedi-17-octobre-2009-st-chef\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"2\u00e8me march\u00e9 des saveurs, samedi \u00e0 Saint-Chef -\" \/>\n<meta property=\"og:description\" content=\"A l\u2019occasion de la semaine du go\u00fbt, la Municipalit\u00e9 de Saint-Chef organise samedi 17 octobre \u00e0 partir de 15h son march\u00e9 des saveurs, deuxi\u00e8me \u00e9dition, au c\u0153ur du centre historique du village.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sillon38.com\/blog\/2009\/10\/14\/2eme-marche-des-saveurs-samedi-17-octobre-2009-st-chef\/\" \/>\n<meta property=\"article:published_time\" content=\"2009-10-14T07:11:51+00:00\" \/>\n<meta name=\"author\" content=\"Gilbert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gilbert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/10\\\/14\\\/2eme-marche-des-saveurs-samedi-17-octobre-2009-st-chef\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/10\\\/14\\\/2eme-marche-des-saveurs-samedi-17-octobre-2009-st-chef\\\/\"},\"author\":{\"name\":\"Gilbert\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"headline\":\"2\u00e8me march\u00e9 des saveurs, samedi \u00e0 Saint-Chef\",\"datePublished\":\"2009-10-14T07:11:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/10\\\/14\\\/2eme-marche-des-saveurs-samedi-17-octobre-2009-st-chef\\\/\"},\"wordCount\":314,\"commentCount\":0,\"articleSection\":[\"consommation\",\"la vie des communes\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/10\\\/14\\\/2eme-marche-des-saveurs-samedi-17-octobre-2009-st-chef\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/10\\\/14\\\/2eme-marche-des-saveurs-samedi-17-octobre-2009-st-chef\\\/\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/10\\\/14\\\/2eme-marche-des-saveurs-samedi-17-octobre-2009-st-chef\\\/\",\"name\":\"2\u00e8me march\u00e9 des saveurs, samedi \u00e0 Saint-Chef -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\"},\"datePublished\":\"2009-10-14T07:11:51+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/10\\\/14\\\/2eme-marche-des-saveurs-samedi-17-octobre-2009-st-chef\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/10\\\/14\\\/2eme-marche-des-saveurs-samedi-17-octobre-2009-st-chef\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/2009\\\/10\\\/14\\\/2eme-marche-des-saveurs-samedi-17-octobre-2009-st-chef\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"2\u00e8me march\u00e9 des saveurs, samedi \u00e0 Saint-Chef\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/\",\"name\":\"\",\"description\":\"Le journal du monde rural\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sillon38.com\\\/blog\\\/#\\\/schema\\\/person\\\/72f06b5f0494d1edc8f4e5bf63651ff1\",\"name\":\"Gilbert\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"2\u00e8me march\u00e9 des saveurs, samedi \u00e0 Saint-Chef -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sillon38.com\/blog\/2009\/10\/14\/2eme-marche-des-saveurs-samedi-17-octobre-2009-st-chef\/","og_locale":"fr_FR","og_type":"article","og_title":"2\u00e8me march\u00e9 des saveurs, samedi \u00e0 Saint-Chef -","og_description":"A l\u2019occasion de la semaine du go\u00fbt, la Municipalit\u00e9 de Saint-Chef organise samedi 17 octobre \u00e0 partir de 15h son march\u00e9 des saveurs, deuxi\u00e8me \u00e9dition, au c\u0153ur du centre historique du village.","og_url":"https:\/\/www.sillon38.com\/blog\/2009\/10\/14\/2eme-marche-des-saveurs-samedi-17-octobre-2009-st-chef\/","article_published_time":"2009-10-14T07:11:51+00:00","author":"Gilbert","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Gilbert","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sillon38.com\/blog\/2009\/10\/14\/2eme-marche-des-saveurs-samedi-17-octobre-2009-st-chef\/#article","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/2009\/10\/14\/2eme-marche-des-saveurs-samedi-17-octobre-2009-st-chef\/"},"author":{"name":"Gilbert","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"headline":"2\u00e8me march\u00e9 des saveurs, samedi \u00e0 Saint-Chef","datePublished":"2009-10-14T07:11:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sillon38.com\/blog\/2009\/10\/14\/2eme-marche-des-saveurs-samedi-17-octobre-2009-st-chef\/"},"wordCount":314,"commentCount":0,"articleSection":["consommation","la vie des communes"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.sillon38.com\/blog\/2009\/10\/14\/2eme-marche-des-saveurs-samedi-17-octobre-2009-st-chef\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.sillon38.com\/blog\/2009\/10\/14\/2eme-marche-des-saveurs-samedi-17-octobre-2009-st-chef\/","url":"https:\/\/www.sillon38.com\/blog\/2009\/10\/14\/2eme-marche-des-saveurs-samedi-17-octobre-2009-st-chef\/","name":"2\u00e8me march\u00e9 des saveurs, samedi \u00e0 Saint-Chef -","isPartOf":{"@id":"https:\/\/www.sillon38.com\/blog\/#website"},"datePublished":"2009-10-14T07:11:51+00:00","author":{"@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1"},"breadcrumb":{"@id":"https:\/\/www.sillon38.com\/blog\/2009\/10\/14\/2eme-marche-des-saveurs-samedi-17-octobre-2009-st-chef\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sillon38.com\/blog\/2009\/10\/14\/2eme-marche-des-saveurs-samedi-17-octobre-2009-st-chef\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sillon38.com\/blog\/2009\/10\/14\/2eme-marche-des-saveurs-samedi-17-octobre-2009-st-chef\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.sillon38.com\/blog\/"},{"@type":"ListItem","position":2,"name":"2\u00e8me march\u00e9 des saveurs, samedi \u00e0 Saint-Chef"}]},{"@type":"WebSite","@id":"https:\/\/www.sillon38.com\/blog\/#website","url":"https:\/\/www.sillon38.com\/blog\/","name":"","description":"Le journal du monde rural","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sillon38.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.sillon38.com\/blog\/#\/schema\/person\/72f06b5f0494d1edc8f4e5bf63651ff1","name":"Gilbert"}]}},"_links":{"self":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/9591","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/comments?post=9591"}],"version-history":[{"count":0,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/posts\/9591\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/media?parent=9591"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/categories?post=9591"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sillon38.com\/blog\/wp-json\/wp\/v2\/tags?post=9591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}